{"id":10899,"date":"2021-04-22T06:00:00","date_gmt":"2021-04-22T13:00:00","guid":{"rendered":"https:\/\/orato.world\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/"},"modified":"2022-04-20T08:36:52","modified_gmt":"2022-04-20T15:36:52","slug":"el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/","title":{"rendered":"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne-500x375.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Jess-Browne-500x375.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/Jess-Browne-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Jess-Browne-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Jess-Browne-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Jess-Browne-293x220.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/Jess-Browne.jpg 1280w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Jess Browne es argentina y vive en Londres. En 12 meses murieron sus padres y su hijo Ignacio, de 28 a\u00f1os, quien dej\u00f3 cuatro cartas y se quit\u00f3 la vida. Con el alma destrozada, abri\u00f3 una cuenta de Facebook e Instagram y un blog, con miles de seguidores, donde comparte sus sentimientos m\u00e1s profundos y su forma de empezar de nuevo.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">M\u00e1s de 800.000 personas se suicidan cada a\u00f1o, seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS). Es decir, cada 40 segundos muere una persona por esta causa.<br>Argentina (10,3) ocupa el puesto 66 en el ranking de 172 pa\u00edses con mayor tasa de suicidios, despu\u00e9s de Ruman\u00eda (10,5) y seguida de la Rep\u00fablica Democr\u00e1tica del Congo (10,1).<br>Seg\u00fan el Ministerio de Salud de Argentina, hay m\u00e1s de 3.000 suicidios al a\u00f1o en el pa\u00eds. La Patagonia es la regi\u00f3n con mayor tasa de suicidios. En contraposici\u00f3n, Cuyo es la regi\u00f3n con el menor n\u00famero de casos.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">Recib\u00ed la noticia que ninguna madre quiere escuchar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi hijo Ignacio se suicid\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con tan solo 28 a\u00f1os, \u00abNacho\u00bb decidi\u00f3 dejar este mundo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sufr\u00eda el machismo de esta sociedad y una profunda enfermedad silenciosa: la depresi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca lo sospech\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la pandemia, no pude viajar para despedirme de mi amado hijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde entonces,<a href=\"https:\/\/www.facebook.com\/empesares\" target=\"_blank\" rel=\"noreferrer noopener\">dediqu\u00e9 mi blog<\/a>a conectar con personas para ayudarlas a superar las mismas experiencias que yo sufr\u00ed.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sent-que-algo-andaba-mal\">Sent\u00ed que algo andaba mal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vivo en Londres desde hace 21 a\u00f1os y Nacho viv\u00eda en Argentina. Miles de kil\u00f3metros nos separaban.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, siempre nos mantuvimos en contacto por tel\u00e9fono. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche anterior al episodio me dijo adi\u00f3s: \u00abMam\u00e1, si ma\u00f1ana no te contesto no te preocupes, me voy a dormir porque estoy agotado\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, me despert\u00e9 sinti\u00e9ndome rara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No sab\u00eda por qu\u00e9, pero sent\u00ed que estaba sucediendo algo extra\u00f1o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Horas despu\u00e9s, recib\u00ed la peor noticia. Yo no lo pod\u00eda creer. Pens\u00e9 que los m\u00e9dicos estaban equivocados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no, \u00e9l hab\u00eda decidido dejar este mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sent\u00ed que un rayo me part\u00eda en dos y que el dolor me paralizaba. No pod\u00eda reaccionar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nadie est\u00e1 dispuesto a enterrar a un hijo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda tantos pensamientos en mi mente que no pod\u00eda hacer nada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La distancia se sent\u00eda m\u00e1s que nunca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-despedida-a-la-distancia\">La despedida a la distancia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Me dej\u00f3 unas cartas con un profundo y sincero adi\u00f3s: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Mam\u00e1, te amo como a nadie, y te cuidar\u00e9 desde donde est\u00e9. S\u00e9 fuerte. Me voy con Nan\u00e1 (su abuela). Lo siento y gracias, Nacho.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Me explic\u00f3 que este mundo machista no le dejaba pedir ayuda. Repetidamente dec\u00eda que no deber\u00eda sentirme culpable, que era algo que \u00e9l ya hab\u00eda planeado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfc\u00f3mo no sentirme culpable si soy su madre?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Argentina, los cementerios se cerraron y los familiares no pudieron asistir al funeral. La despedida fue por Zoom.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llegar a mi pa\u00eds natal, deber\u00eda aislarme durante dos semanas en un hotel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ni siquiera iba a poder enterrarlo y fue imposible empezar el duelo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No pude ver a mi hijo, ni besar su frente, ni despedirme por \u00faltima vez.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-otra-p-rdida\">Otra p\u00e9rdida<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Meses despu\u00e9s, mis padres fallecieron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dolor que sent\u00ed fue inexplicable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Perd\u00ed a las personas que m\u00e1s amaba en menos de un a\u00f1o, pero no pude comenzar el duelo de mis padres. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ignacio se llev\u00f3 todo lo que ten\u00eda: mi vida, mi fuerza, mi voluntad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00fanico lugar donde encontr\u00e9 algo de consuelo fue en el cementerio cuando viaj\u00e9 a Buenos Aires. S\u00f3lo all\u00ed pude sentarme y charlar con \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me cost\u00f3 mucho dejar ese lugar; Sent\u00ed que lo estaba abandonando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, cuando el contexto mundial me acompa\u00f1e, regresar\u00e9 a Argentina por un largo tiempo para visitar su lugar de descanso tantas veces como necesite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-legado\">El legado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En las cartas que me dejaba Nacho me dec\u00eda que las mostrara a quien quisiera leerlo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All\u00ed, entend\u00ed que necesitaba compartir mi experiencia para crear conciencia y aliviar el dolor de otras personas que no pueden hablar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta afirmaci\u00f3n mi blog <a href=\"https:\/\/www.facebook.com\/empesares\" target=\"_blank\" rel=\"noreferrer noopener\">EMPESARES<\/a>dio un giro, all\u00ed escribo lo que siento, conect\u00e1ndome con personas que han estado viviendo lo mismo que yo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es mi nueva misi\u00f3n en la vida. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiero ayudar a los padres y las v\u00edctimas a aliviar su sufrimiento. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiero militar sobre la importancia de la salud mental y advertir a familiares y amigos que la depresi\u00f3n es una enfermedad que, muchas veces, no presenta s\u00edntomas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transformo mi dolor en una causa que aporta algo a la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diariamente, recibo mensajes de personas agradeci\u00e9ndome por mi ayuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los j\u00f3venes y adultos encuentran en mi blog un lugar para ser escuchados, donde pueden tomar conciencia de sus acciones antes de tomar decisiones irreversibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, me ayuda a sobrellevar este inmenso dolor. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo hago porque es lo que \u00e9l hubiera querido para que su alma finalmente descanse en paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La paz que no ten\u00eda en este mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sent\u00ed c\u00f3mo un rayo me parti\u00f3 en dos, el dolor me paraliz\u00f3. Nadie est\u00e1 dispuesto a enterrar a un hijo.<\/p>\n","protected":false},"author":56,"featured_media":10712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2771,188],"tags":[541,538,5250,1259],"class_list":["post-10899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latinoamerica","category-salud","tag-activism-es","tag-mental-health-es","tag-prevencion-del-suicidio-es","tag-suicidio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo - Orato<\/title>\n<meta name=\"description\" content=\"Despu\u00e9s del suicidio de mi hijo a los 28 a\u00f1os, dediqu\u00e9 mi blog a contar mi experiencia para ayudar a quienes est\u00e1n atravesando lo mismo que yo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo\" \/>\n<meta property=\"og:description\" content=\"Sent\u00ed c\u00f3mo un rayo me parti\u00f3 en dos, el dolor me paraliz\u00f3. Nadie est\u00e1 dispuesto a enterrar a un hijo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-22T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T15:36:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucila Argiles\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucila Argiles\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/\"},\"author\":{\"name\":\"Lucila Argiles\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/21009a1f8661d64d64f4006f6cd30cc7\"},\"headline\":\"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo\",\"datePublished\":\"2021-04-22T13:00:00+00:00\",\"dateModified\":\"2022-04-20T15:36:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/\"},\"wordCount\":708,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Jess-Browne.jpg\",\"keywords\":[\"Activism\",\"Mental health\",\"Prevenci\u00f3n del suicidio\",\"Suicidio\"],\"articleSection\":[\"Latinoam\u00e9rica\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/\",\"name\":\"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo - Orato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Jess-Browne.jpg\",\"datePublished\":\"2021-04-22T13:00:00+00:00\",\"dateModified\":\"2022-04-20T15:36:52+00:00\",\"description\":\"Despu\u00e9s del suicidio de mi hijo a los 28 a\u00f1os, dediqu\u00e9 mi blog a contar mi experiencia para ayudar a quienes est\u00e1n atravesando lo mismo que yo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Jess-Browne.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Jess-Browne.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Nacho y su sonrisa caracter\u00edstica. | Jess Brown\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/04\\\/22\\\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/21009a1f8661d64d64f4006f6cd30cc7\",\"name\":\"Lucila Argiles\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Lucila Argiles\"},\"description\":\"Lucila Argiles is an Argentine journalist with a degree in Social Communication. She is currently studying Sports Journalism at the National University of La Plata.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/lucila-argiles\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo - Orato","description":"Despu\u00e9s del suicidio de mi hijo a los 28 a\u00f1os, dediqu\u00e9 mi blog a contar mi experiencia para ayudar a quienes est\u00e1n atravesando lo mismo que yo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/","og_locale":"es_ES","og_type":"article","og_title":"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo","og_description":"Sent\u00ed c\u00f3mo un rayo me parti\u00f3 en dos, el dolor me paraliz\u00f3. Nadie est\u00e1 dispuesto a enterrar a un hijo.","og_url":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2021-04-22T13:00:00+00:00","article_modified_time":"2022-04-20T15:36:52+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg","type":"image\/jpeg"}],"author":"Lucila Argiles","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Lucila Argiles","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/"},"author":{"name":"Lucila Argiles","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/21009a1f8661d64d64f4006f6cd30cc7"},"headline":"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo","datePublished":"2021-04-22T13:00:00+00:00","dateModified":"2022-04-20T15:36:52+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/"},"wordCount":708,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg","keywords":["Activism","Mental health","Prevenci\u00f3n del suicidio","Suicidio"],"articleSection":["Latinoam\u00e9rica","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/","url":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/","name":"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo - Orato","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg","datePublished":"2021-04-22T13:00:00+00:00","dateModified":"2022-04-20T15:36:52+00:00","description":"Despu\u00e9s del suicidio de mi hijo a los 28 a\u00f1os, dediqu\u00e9 mi blog a contar mi experiencia para ayudar a quienes est\u00e1n atravesando lo mismo que yo.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg","width":1280,"height":960,"caption":"Nacho y su sonrisa caracter\u00edstica. | Jess Brown"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2021\/04\/22\/el-suicidio-de-un-hijo-estimula-el-intercambio-social-y-el-apoyo-a-quienes-estan-pasando-por-lo-mismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"El suicidio de un hijo estimula el intercambio social y el apoyo a quienes est\u00e1n pasando por lo mismo"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/21009a1f8661d64d64f4006f6cd30cc7","name":"Lucila Argiles","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Lucila Argiles"},"description":"Lucila Argiles is an Argentine journalist with a degree in Social Communication. She is currently studying Sports Journalism at the National University of La Plata.","url":"https:\/\/orato.world\/es\/author\/lucila-argiles\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",533,400,false],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",320,240,false],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Jess-Browne-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Lucila Argiles","author_link":"https:\/\/orato.world\/es\/author\/lucila-argiles\/"},"uagb_comment_info":0,"uagb_excerpt":"Sent\u00ed c\u00f3mo un rayo me parti\u00f3 en dos, el dolor me paraliz\u00f3. Nadie est\u00e1 dispuesto a enterrar a un hijo.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/10899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=10899"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/10899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/10712"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=10899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=10899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=10899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}