{"id":15634,"date":"2021-07-23T06:49:24","date_gmt":"2021-07-23T13:49:24","guid":{"rendered":"https:\/\/orato.world\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/"},"modified":"2022-04-20T08:54:55","modified_gmt":"2022-04-20T15:54:55","slug":"huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/","title":{"rendered":"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"375\" src=\"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0013-500x375.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/IMG-20210717-WA0013-500x375.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG-20210717-WA0013-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG-20210717-WA0013-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG-20210717-WA0013-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG-20210717-WA0013-293x220.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG-20210717-WA0013.jpg 1040w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Rahul, de 13 a\u00f1os, perdi\u00f3 a su madre, a su padre y a dos de sus abuelos en 12 meses durante la pandemia por COVID-19. Ha dado un paso al frente para criar a sus dos hermanos menores, asegur\u00e1ndose de que contin\u00faen con su educaci\u00f3n, y est\u00e1 administrando la granja familiar mientras toma clases en l\u00ednea por la noche.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">La COVID-19 ha devastado familias en toda la India, dejando hu\u00e9rfanos a muchos ni\u00f1os peque\u00f1os. Los medios de comunicaci\u00f3n de todo el mundo han informado sobre este tema tan generalizado.<br><br>Hay m\u00e1s de 1.000 hu\u00e9rfanos producto de fallecidos por COVID-19 en Uttar Pradesh, <a href=\"https:\/\/www.bbc.com\/news\/world-asia-india-57264629\">seg\u00fan una entrevista de la BBC<\/a> con el Dr. Preeti Verma, miembro de la comisi\u00f3n estatal de bienestar infantil.<br><br>Los vecinos y familiares a menudo se mantienen alejados por temor a contraer COVID, dejando a los hu\u00e9rfanos a su suerte. Ahora pueden surgir temores de tr\u00e1fico sexual y explotaci\u00f3n del trabajo infantil, ya que la gente ofrece un pago por la supuesta adopci\u00f3n de estos ni\u00f1os abandonados.<br><br>Se les ofrece poco apoyo financiero y no existe un esfuerzo coordinado para proteger su bienestar.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\"><div id=\"tw-container\" class=\"YQaNob\" data-cp=\"1\" data-is-ver=\"false\" data-nnttsvi=\"1\" data-sm=\"1\" data-sugg-time=\"500\" data-sugg-url=\"https:\/\/clients1.google.com\/complete\/search\" data-uilc=\"es-419\">&#13;\n<div>&#13;\n<div>&#13;\n<div id=\"tw-ob\" class=\"tw-src-ltr\">&#13;\n<div class=\"oSioSc\">&#13;\n<div id=\"tw-target\">&#13;\n<div id=\"kAz1tf\" class=\"g9WsWb\">&#13;\n<div id=\"tw-target-text-container\" class=\"tw-ta-container F0azHf tw-nfl\" tabindex=\"0\">&#13;\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large XcVN5d tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci&#xF3;n\"><em><span class=\"Y2IQFc\" lang=\"es\">Se han cambiado los nombres para proteger la identidad del sujeto de la entrevista y sus hermanos menores de edad.<\/span><\/em><\/p>&#13;\n&#13;\n<\/div>&#13;\n<div id=\"tw-target-rmn-container\" class=\"tw-target-rmn tw-ta-container F0azHf tw-nfl\"><\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<div class=\"KFFQ0c xKf9F\"><\/div><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SHAMLI, Uttar Pradesh, India &#8211; Despu\u00e9s de que mi padre muri\u00f3 por COVID-19 en abril del a\u00f1o pasado, mi madre nos abrazaba a mis hermanos y a m\u00ed, ocultaba sus l\u00e1grimas y dolor y nos dec\u00eda que se hab\u00eda ido a trabajar.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No pod\u00eda entender por qu\u00e9 tard\u00f3 tanto en volver a casa. El era granjero. Nunca se hab\u00eda ido.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras trataba de asimilar su ausencia, tambi\u00e9n fallecieron mis abuelos murieron sucesivamente. Luego, la vida dio su golpe m\u00e1s duro. Cuatro meses despu\u00e9s, perd\u00ed a mi madre por Covid-19.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mis hermanos, Geeta (12) y Veer (11), y yo de repente nos quedamos solos y aislados. As\u00ed que nos las tuvimos que arreglar como pudimos. \n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><div id=\"tw-container\" class=\"YQaNob\" data-cp=\"1\" data-is-ver=\"false\" data-nnttsvi=\"1\" data-sm=\"1\" data-sugg-time=\"500\" data-sugg-url=\"https:\/\/clients1.google.com\/complete\/search\" data-uilc=\"es-419\">\n<div>\n<div>\n<div id=\"tw-ob\" class=\"tw-src-ltr\">\n<div class=\"oSioSc\">\n<div id=\"tw-target\" class=\"\">\n<div id=\"kAz1tf\" class=\"g9WsWb\">\n<div id=\"tw-target-text-container\" class=\"tw-ta-container F0azHf tw-nfl\" tabindex=\"0\">\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large XcVN5d tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci\u00f3n\"><strong><span class=\"Y2IQFc\" lang=\"es\">La desolaci\u00f3n de perder a mi familia por COVID-19<\/span><\/strong><\/p>\n\n<\/div>\n<div id=\"tw-target-rmn-container\" class=\"tw-target-rmn tw-ta-container F0azHf tw-nfl\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"KFFQ0c xKf9F\"><\/div><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca me dijeron que todos mueren, que tendr\u00eda que afrontar un d\u00eda sin mis padres, sin verlos ni sentir su amor. Nunca me dijeron que es el orden natural de la vida, que los padres mueren antes que sus hijos.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En s\u00f3lo un a\u00f1o, mis dos padres, quienes eran mi salvavidas, se fueron. Cuando escuch\u00e9 a los vecinos referirse a m\u00ed como hu\u00e9rfano, me desconcert\u00f3. \n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso. Mis padres nos hab\u00edan proporcionado un lugar seguro y nos hab\u00edan dado todas las herramientas para sentirnos c\u00f3modos en el mundo.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerdo que Geeta me dijo, aproximadamente un mes despu\u00e9s de la muerte de nuestra madre: \u00abOjal\u00e1 pudiera abrazar a mam\u00e1 ahora mismo. Extra\u00f1o hablar con ella. Extra\u00f1o su comida. Ojal\u00e1 estuviera aqu\u00ed\u00bb. Nos abrazamos y dejamos que las l\u00e1grimas rodaran por nuestras mejillas.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras buscaba respuestas, pregunt\u00e9 a amigos cuyos padres tambi\u00e9n hab\u00edan fallecido: \u00ab\u00bfC\u00f3mo se siente ser hu\u00e9rfano?\u00bb. Todas las personas con las que habl\u00e9 estaban tan desorientadas como yo, y experimentaban una continua sensaci\u00f3n de p\u00e9rdida.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vi a algunos de mis compa\u00f1eros recibir amor de sus padres y eso me hizo sentir a\u00fan m\u00e1s desolado. Mi madre siempre hab\u00eda sido mi defensora m\u00e1s feroz, independientemente de la situaci\u00f3n. Mi padre fue mi consejero. El destino no podr\u00eda haber asestado un golpe m\u00e1s cruel, pero nos esperaba algo peor.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Hu\u00e9rfanos y aislados<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los vecinos comenzaron a alejarse de nosotros, retirando el apoyo por temor a contraer COVID-19. Extra\u00f1os hicieron comentarios desafortunados. Sent\u00edan l\u00e1stima por nosotros, pero yo no quer\u00eda su l\u00e1stima. Necesitaba compasi\u00f3n.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estuvimos confinados en nuestra casa durante un mes. Geeta cocinaba y Veer ayudaba con la limpieza. Fue terrible. Se supon\u00eda que deb\u00edan estar estudiando, pero aqu\u00ed estaban lidiando con el dolor y tratando de sobrevivir en un mundo tan duro.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ninguno de nuestros familiares o vecinos pudo visitarnos para darnos el p\u00e9same por el cierre. Se cort\u00f3 la entrada a nuestra casa y nos pusieron en aislamiento.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><div id=\"tw-container\" class=\"YQaNob\" data-cp=\"1\" data-is-ver=\"false\" data-nnttsvi=\"1\" data-sm=\"1\" data-sugg-time=\"500\" data-sugg-url=\"https:\/\/clients1.google.com\/complete\/search\" data-uilc=\"es-419\">&#13;\n<div>&#13;\n<div>&#13;\n<div id=\"tw-ob\" class=\"tw-src-ltr\">&#13;\n<div class=\"oSioSc\">&#13;\n<div id=\"tw-target\" class=\"\">&#13;\n<div id=\"kAz1tf\" class=\"g9WsWb\">&#13;\n<div id=\"tw-target-text-container\" class=\"tw-ta-container F0azHf tw-nfl\" tabindex=\"0\">&#13;\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large XcVN5d tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci&#xF3;n\"><span class=\"Y2IQFc\" lang=\"es\">No pod\u00edamos salir a hacer las compras y no ten\u00edamos acceso a agua potable. A pesar de las promesas, nadie del <a href=\"https:\/\/wcdhry.gov.in\/child-welfare-committee\/\">Comit\u00e9 de Bienestar Infantil<\/a> vino a nuestra casa para desinfectarla o comprobar si est\u00e1bamos bien. Fue una lucha para nosotros permanecer all\u00ed.<\/span><\/p>&#13;\n&#13;\n<\/div>&#13;\n<div id=\"tw-target-rmn-container\" class=\"tw-target-rmn tw-ta-container F0azHf tw-nfl\"><\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<\/div>&#13;\n<div class=\"KFFQ0c xKf9F\"><\/div><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi padre era un granjero con nueve bigha (5,6 acres) de tierra y cinco b\u00fafalos. Cultivaba ca\u00f1a de az\u00facar y trigo en los campos. Una vez que se fue, quedaba mucho por hacer. La finca y el ganado tuvieron que ser administrados. Hab\u00eda que arreglar las finanzas, pero no ten\u00edamos a nadie que nos ayudara.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><p id=\"tw-target-text-masculine\" class=\"tw-data-text tw-text-large XcVN5d tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci\u00f3n\"><strong><span class=\"Y2IQFc\" lang=\"es\">En d\u00e9cimo grado y criando a mis hermanos solo<\/span><\/strong><\/p><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestras vidas est\u00e1n en desorden. Si bien mis hermanos y yo no sabemos c\u00f3mo lidiar con esto, lo estamos piloteando juntos.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geeta est\u00e1 en noveno grado, mientras que Veer est\u00e1 en s\u00e9ptimo. Son estudiantes brillantes y diligentes. Desafortunadamente, sus sue\u00f1os se han hecho a\u00f1icos. La verdad es que creceremos sin un padre y una madre, pero me asegurar\u00e9 de que la vida de mis hermanos no quede marcada para siempre.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me asegurar\u00e9 de que su educaci\u00f3n no se vea obstaculizada, de que sue\u00f1en y vivan felices. Trabajo duro para cuidar a mis hermanos y asegurar su futuro.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Geeta todav\u00eda cocina, pero estudia en l\u00ednea por la tarde. Veer ayuda con la limpieza, pero aprende nuevas habilidades y se mantiene al d\u00eda con sus lecciones por la noche.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estoy en d\u00e9cimo grado. Aro el campo bajo el sol abrasador y tomo clases en l\u00ednea por la noche.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El hambre se cierne sobre nosotros<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los ni\u00f1os de mi edad no tienen que preocuparse por pagar la escuela. S\u00e9 que estoy involucrado en las peores formas de trabajo infantil, pero si no lo hago, moriremos de hambre.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los vecinos me ven con ropas andrajosas y zapatos gastados, empapado en sudor cortando plantas de ca\u00f1a de az\u00facar que duplican mi altura, ya no miran para otro lado. Muy por el contrario, me brindan informaci\u00f3n relacionada con las plantaciones de ca\u00f1a de az\u00facar y el cultivo de alimentos de manera rentable.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mi pueblo, muchos ni\u00f1os se quedan se abandonan. Se encuentran en un estado emocional muy fr\u00e1gil y se sienten solos y sin apoyo. Yo tambi\u00e9n me siento solo, pero tengo que cuidar a mis hermanos hasta que se conviertan en adultos.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando mis padres estaban aqu\u00ed, todo lo que ten\u00eda que hacer era concentrarme en mi educaci\u00f3n, pero ahora paso la mayor parte del tiempo en el campo, cuidando de mis hermanos y manejando las tareas del hogar.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No tengo opci\u00f3n, ya que el gobierno a\u00fan no se ha puesto en contacto con nosotros para brindarnos ayuda.\n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-es-poco-probable-que-cumplan-las-promesas-de-ayuda\"><strong>Es poco probable que cumplan las promesas de ayuda<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que murieron nuestros padres, nos quedamos en nuestra propia casa, y nuestro t\u00edo materno, que ha sido declarado nuestro tutor, nos visita de vez en cuando.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me dijeron que el gobierno estatal aprob\u00f3 una orden, bajo el Mukhya Mantri Bal Seva Yojana, que dice que los hu\u00e9rfanos recibir\u00e1n una ayuda mensual de 4.000 rupias (53,73 d\u00f3lares).\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, los ni\u00f1os menores de diez a\u00f1os no califican para este programa. Eso significa que Veer y yo no aplicamos. Geeta tambi\u00e9n est\u00e1 descartada, porque, t\u00e9cnicamente, tenemos un guardi\u00e1n.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer ministro Narendra Modi dice que los ni\u00f1os que perdieron a sus padres a causa de la Covid-19 recibir\u00e1n un corpus de un mill\u00f3n de rupias cuando cumplan 18 a\u00f1os ($ 13,432 USC), pero nuestros nombres no aparecen en la lista de beneficiarios.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A veces me pregunto, \u00bfsomos siquiera visibles? Perder a ambos padres no es lo mismo que perder a uno dos veces. Cuando mis padres murieron, perd\u00ed mi identidad como hijo de alguien. Perd\u00ed a la familia y los amigos que s\u00f3lo estaban conectados conmigo a trav\u00e9s de ellos.\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Perder a mis padres ha sido un golpe incalculable y duradero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espero que mis padres est\u00e9n orgullosos de m\u00ed y de c\u00f3mo cri\u00e9 a mis hermanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.<\/p>\n","protected":false},"author":80,"featured_media":15385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2772,188,190],"tags":[3498,194,1587,1585,1586],"class_list":["post-15634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-salud","category-virus","tag-asia-es","tag-covid-19-es","tag-india-es","tag-orfanato","tag-trabajo-infantil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores - Orato<\/title>\n<meta name=\"description\" content=\"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores\" \/>\n<meta property=\"og:description\" content=\"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-23T13:49:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T15:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vandita Agrawal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vandita Agrawal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/\"},\"author\":{\"name\":\"Vandita Agrawal\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/ca770d574273c399de8ddb79d31a1289\"},\"headline\":\"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores\",\"datePublished\":\"2021-07-23T13:49:24+00:00\",\"dateModified\":\"2022-04-20T15:54:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/\"},\"wordCount\":1246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20210717-WA0014-copy.jpg\",\"keywords\":[\"Asia\",\"Covid-19\",\"India\",\"orfanato\",\"Trabajo infantil\"],\"articleSection\":[\"Asia\",\"Salud\",\"Virus\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/\",\"name\":\"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores - Orato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20210717-WA0014-copy.jpg\",\"datePublished\":\"2021-07-23T13:49:24+00:00\",\"dateModified\":\"2022-04-20T15:54:55+00:00\",\"description\":\"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20210717-WA0014-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20210717-WA0014-copy.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Rahul con sus hermanos menores.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2021\\\/07\\\/23\\\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/ca770d574273c399de8ddb79d31a1289\",\"name\":\"Vandita Agrawal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Vandita Agrawal\"},\"description\":\"Vandita Agrawal is an experienced journalist, published in The Times of India, Times Internet, Zenger News, and Dkoding Media. She holds Bachelor of Arts (Honors) and Master of Arts degrees in Political Science, a Master of Business Administration degree, and a Post Graduate Diploma in Journalism (Gold Medalist). She is skilled in writing investigative articles, news analysis, and breaking news and has written extensively on US and international politics, current affairs, police brutality, injustice, sustainability, climate change, health, activism, inspirational stories, psychology, and animal rights.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/vandita-agrawal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores - Orato","description":"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/","og_locale":"es_ES","og_type":"article","og_title":"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores","og_description":"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.","og_url":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2021-07-23T13:49:24+00:00","article_modified_time":"2022-04-20T15:54:55+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg","type":"image\/jpeg"}],"author":"Vandita Agrawal","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Vandita Agrawal","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/"},"author":{"name":"Vandita Agrawal","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/ca770d574273c399de8ddb79d31a1289"},"headline":"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores","datePublished":"2021-07-23T13:49:24+00:00","dateModified":"2022-04-20T15:54:55+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/"},"wordCount":1246,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg","keywords":["Asia","Covid-19","India","orfanato","Trabajo infantil"],"articleSection":["Asia","Salud","Virus"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/","url":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/","name":"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores - Orato","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg","datePublished":"2021-07-23T13:49:24+00:00","dateModified":"2022-04-20T15:54:55+00:00","description":"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg","width":1280,"height":960,"caption":"Rahul con sus hermanos menores."},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2021\/07\/23\/huerfano-de-victimas-de-covid-19-se-convierte-en-trabajador-infantil-y-cria-a-sus-hermanos-menores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Hu\u00e9rfano de v\u00edctimas de COVID-19 se convierte en trabajador infantil y cr\u00eda a sus hermanos menores"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/ca770d574273c399de8ddb79d31a1289","name":"Vandita Agrawal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Vandita Agrawal"},"description":"Vandita Agrawal is an experienced journalist, published in The Times of India, Times Internet, Zenger News, and Dkoding Media. She holds Bachelor of Arts (Honors) and Master of Arts degrees in Political Science, a Master of Business Administration degree, and a Post Graduate Diploma in Journalism (Gold Medalist). She is skilled in writing investigative articles, news analysis, and breaking news and has written extensively on US and international politics, current affairs, police brutality, injustice, sustainability, climate change, health, activism, inspirational stories, psychology, and animal rights.","url":"https:\/\/orato.world\/es\/author\/vandita-agrawal\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",533,400,false],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",320,240,false],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20210717-WA0014-copy-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Vandita Agrawal","author_link":"https:\/\/orato.world\/es\/author\/vandita-agrawal\/"},"uagb_comment_info":0,"uagb_excerpt":"No ten\u00eda dimensi\u00f3n de mi p\u00e9rdida y lo que significaba. Pero me sent\u00eda abandonado, solo y ansioso.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/15634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=15634"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/15634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/15385"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=15634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=15634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=15634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}