{"id":34694,"date":"2022-04-06T12:45:18","date_gmt":"2022-04-06T19:45:18","guid":{"rendered":"https:\/\/orato.world\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/"},"modified":"2022-04-20T07:56:10","modified_gmt":"2022-04-20T14:56:10","slug":"comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/","title":{"rendered":"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Bogota-interview-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\u00c1ngel Queragama\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-1024x1024.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-770x770.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-1536x1536.jpg 1536w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-2048x2048.jpg 2048w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-390x390.jpg 390w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-585x585.jpg 585w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-900x900.jpg 900w, https:\/\/orato.world\/wp-content\/uploads\/\/Bogota-interview-1400x1400.jpg 1400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">\u00c1ngel Queragama es miembro de la comunidad ind\u00edgena Embera Kat\u00edo, <a href=\"https:\/\/centrodememoriahistorica.gov.co\/pueblos-indigenas-victimas-de-violencias-de-larga-duracion\/\">una de las m\u00e1s afectadas por los a\u00f1os de conflicto armado entre el gobierno y la guerrilla en Colombia.<\/a> Vive en el Parque Nacional Bogot\u00e1 con su esposa, cuatro hijos, suegra, cu\u00f1ada y sobrinos.<br><br>\u00c1ngel abandon\u00f3 su territorio en el municipio de Pueblo Rico, en Risaralda (ubicado en el centro-occidente de Colombia) en 2016 debido a la <a href=\"https:\/\/www.eldiario.com.co\/actualidad\/comunidad-indigena-de-pueblo-rico-nuevamente-en-la-mira-de-los-violentos\/\">presencia de militantes armados que amenazaban a la comunidad en general <\/a>y a la poblaci\u00f3n ind\u00edgena en particular.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">CONTEXTO<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Seg\u00fan el censo de poblaci\u00f3n de Colombia de 2018, la <a href=\"https:\/\/www.larepublica.co\/economia\/poblacion-indigena-crecio-36-y-llego-a-19-millones-de-personas-2909134\">poblaci\u00f3n ind\u00edgena del pa\u00eds es de 1,9 millones de personas, el 4,4% de la poblaci\u00f3n total.<\/a> En el pa\u00eds existen 115 poblaciones ind\u00edgenas, de las cuales <a href=\"https:\/\/comisiondelaverdad.co\/actualidad\/noticias\/impactos-del-conflicto-en-los-territorios-pueblos-indigenas-region-andina\">68 se encuentran en riesgo de exterminio f\u00edsico y cultural por causas asociadas al prolongado conflicto armado<\/a> interno colombiano.<br><br>Estas causas incluyen \u201cdespojo de tierras, actos terroristas, amenazas, delitos contra la integridad sexual, desaparici\u00f3n forzada, desplazamiento, homicidios, minas terrestres, p\u00e9rdida de bienes muebles e inmuebles, secuestro, tortura y participaci\u00f3n de ni\u00f1os, ni\u00f1as y adolescentes en el conflicto armado\u201d.<br><br>M\u00e1s de 1300 compa\u00f1eros ind\u00edgenas de 13 comunidades diferentes en todo el pa\u00eds, en su mayor\u00eda mujeres, ni\u00f1os y ancianos, han estado viviendo en el Parque Nacional Bogot\u00e1 en refugios improvisados desde septiembre de 2021, luego de que se agotaron los subsidios para alimentos y vivienda. Exigen que se cumplan sus derechos b\u00e1sicos y garant\u00edas de seguridad antes de regresar a sus territorios, a la espera de que alguien en el gobierno resuelva esta <a href=\"https:\/\/www.france24.com\/es\/am%C3%A9rica-latina\/20211025-colombia-indigenas-desplazados-protesta-bogota\">emergencia humanitaria.<\/a><br><br>A pesar de una pr\u00f3rroga de la Ley de V\u00edctimas y Restituci\u00f3n de Tierras y una tutela reciente que establece que <a href=\"https:\/\/justiceforcolombia.org\/news\/colombia-extends-victims-law-until-2031\/\">la alcald\u00eda de Bogot\u00e1 est\u00e1 obligada a garantizar a los desplazados servicios b\u00e1sicos de salud, alimentaci\u00f3n y acceso a agua potable<\/a>, los residentes del parque <a href=\"https:\/\/www.personeriabogota.gov.co\/sala-de-prensa\/notas-de-prensa\/item\/942-tutela-instaurada-por-el-personero-de-bogota-que-busca-garantizar-derechos-de-poblacion-indigena-fue-fallada-de-manera-positiva\">han visto pocos avances.<\/a><\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">BOGOT\u00c1, Colombia\u2014Dej\u00e9 mi tierra hace seis a\u00f1os, amenazada por los grupos armados all\u00ed. No puedo volver, me matar\u00e1n. No hay garant\u00edas de seguridad, incluso despu\u00e9s de todos estos a\u00f1os. Ahora, mi familia y yo vivimos en refugios improvisados en el Parque Nacional de Bogot\u00e1, esperando que el gobierno brinde las protecciones que necesitamos para regresar a nuestros hogares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salimos de nuestros territorios por el conflicto armado y la violencia entre el gobierno y los grupos guerrilleros y paramilitares y no nos retiraremos de este parque hasta que el gobierno nacional cumpla sus promesas de seguridad, vivienda, empleo, educaci\u00f3n y salud. No vamos a desocupar hasta que nos garanticen unas condiciones de vida dignas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno nacional y el alcalde de Bogot\u00e1 tienen que entender que el peligro a\u00fan persiste. No tenemos a d\u00f3nde ir hasta que podamos regresar y vivir vidas seguras de donde venimos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Un desplazado m\u00e1s en un pa\u00eds de desplazados<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de mudarme al parque en septiembre de 2021, viv\u00eda en el barrio de Santa F\u00e9, uno de los m\u00e1s peligrosos de Bogot\u00e1. Viv\u00edamos en una habitaci\u00f3n en lo que se conoce como <a href=\"https:\/\/orato.world\/wp-admin\/blank\">pagadiarios<\/a>: mansiones viejas y abandonadas que se encuentran en condiciones ruinosas e insalubres. Sin embargo, a veces no pod\u00eda reunir el dinero para pagar la habitaci\u00f3n y por eso vinimos al parque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de 1300 de nosotros vivimos en el parque; aproximadamente la mitad son ni\u00f1os. Vivimos en refugios informales tipo carpas, o <em>cambuches<\/em>, en el parque, y algunos ni siquiera tienen eso como protecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace mucho fr\u00edo aqu\u00ed, con temperaturas que descienden por debajo del punto de congelaci\u00f3n en las ma\u00f1anas, y llueve mucho; <a href=\"https:\/\/www.elespectador.com\/bogota\/lluvias-y-posible-mal-manejo-de-basuras-causaron-inundaciones-en-cambuches-del-parque-nacional\/\">luchamos para proteger a nuestras familias de los elementos<\/a>. El clima es duro y dif\u00edcil de soportar en la edad adulta, y m\u00e1s a\u00fan para los ni\u00f1os y los beb\u00e9s. Algunos de ellos han sido hospitalizados debido a las duras condiciones clim\u00e1ticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los que pertenecemos a una minga permanente, o a un grupo de defensa colectiva de sus comunidades y derechos ind\u00edgenas, pertenecemos a 13 pueblos ind\u00edgenas, con 13 lenguas diferentes. La mayor\u00eda de ellos no habla espa\u00f1ol y ninguno tiene a d\u00f3nde ir, ni el dinero para obtener una vivienda m\u00e1s permanente o m\u00e1s saludable.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sin comida, vivienda y condiciones dignas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos aguantado muchos d\u00edas solo con lentejas y arroz para comer, y muchos otros solo con arroz. Los adultos y los ni\u00f1os est\u00e1n perdiendo peso. Algunos transe\u00fantes y vecinos nos dan ropa y comida, pero no es suficiente. El gobierno no nos da nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Demasiados d\u00edas, no podemos encontrar un mercado para nuestras artesan\u00edas u oportunidades para trabajar, y es entonces cuando tenemos que pedir limosna en la calle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada familia cocina en su cambuche y recoge le\u00f1a y agua. Para evadir el fr\u00edo, dormimos amontonados, como cerdos, bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Instituto Colombiano de Bienestar Familiar viene casi a diario a pesar a los ni\u00f1os y les da harina como complemento alimenticio a los que tienen bajo peso. A veces llega el Ministerio de Salud con ambulancias. Ese es el \u00fanico apoyo institucional que recibimos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-seeking-a-dignified-life\"><h2>Buscando una vida digna<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno nos discrimina, un prejuicio que hemos vivido desde la \u00e9poca colonial cuando los espa\u00f1oles vinieron a saquearnos. Nada ha cambiado desde entonces; somos ciudadanos de segunda clase. Nos han matado, robado nuestro oro y tomado nuestra tierra. Incluso nos sentimos discriminados por otros pueblos ind\u00edgenas y organizaciones ind\u00edgenas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos a seguir presionando al gobierno hasta que cumpla con nuestro derecho a una vida digna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro grupo ha solicitado en varias ocasiones a la alcaldesa de Bogot\u00e1, Claudia L\u00f3pez, que nos d\u00e9 audiencia, pero no ha dado la cara, sino que nos remite a delegados desinformados que no pueden establecer compromisos ni al <a href=\"https:\/\/actualidad.rt.com\/actualidad\/407671-indigenas-colombianos-protestan-bogota-temor-esmad\">Escuadr\u00f3n M\u00f3vil Antidisturbios (ESMAD<\/a> ). No hemos recibido nada de la administraci\u00f3n distrital, solo presiones para volver a nuestras reservas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, no queremos m\u00e1s masacres, m\u00e1s violencia, m\u00e1s discriminaci\u00f3n. No podemos regresar hasta que nuestra seguridad y capacidad para mantenernos a nosotros mismos est\u00e9n garantizadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados, como cerdos, bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.<\/p>\n","protected":false},"author":106,"featured_media":64835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,534,2771,534,523],"tags":[541,2541,2707,302,1497,1471,2706,723,2214,2708],"class_list":["post-34694","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-conflicto","category-galeria-de-fotos","category-latinoamerica","category-racismo","tag-activism-es","tag-acuerdo-de-paz-en-colombia","tag-angel-queragama-es","tag-bogota-es","tag-bogota-es-2","tag-colombia-es","tag-embera-katio-es","tag-indigenous-rights-es","tag-latinoamerica","tag-parque-nacional-bogota","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad - Orato<\/title>\n<meta name=\"description\" content=\"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad\" \/>\n<meta property=\"og:description\" content=\"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados, como cerdos, bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-06T19:45:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T14:56:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Delgado Baron\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Delgado Baron\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/\"},\"author\":{\"name\":\"Mariana Delgado Baron\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/6e500933e0fc93546a81b6eafbf90fc3\"},\"headline\":\"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad\",\"datePublished\":\"2022-04-06T19:45:18+00:00\",\"dateModified\":\"2022-04-20T14:56:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/\"},\"wordCount\":739,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG_20211026_120312_092-1400x795-1.jpg\",\"keywords\":[\"Activism\",\"Acuerdo de Paz en Colombia\",\"\u00c1ngel Queragama\",\"Bogot\u00e1\",\"Bogota\",\"Colombia\",\"Embera Kat\u00edo\",\"Indigenous Rights\",\"Latinoam\u00e9rica\",\"Parque Nacional Bogot\u00e1\"],\"articleSection\":[\"Conflicto\",\"Galer\u00eda de fotos\",\"Latinoam\u00e9rica\",\"Galer\u00eda de fotos\",\"Racismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/\",\"name\":\"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad - Orato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG_20211026_120312_092-1400x795-1.jpg\",\"datePublished\":\"2022-04-06T19:45:18+00:00\",\"dateModified\":\"2022-04-20T14:56:10+00:00\",\"description\":\"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG_20211026_120312_092-1400x795-1.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG_20211026_120312_092-1400x795-1.jpg\",\"width\":1400,\"height\":795},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/06\\\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/6e500933e0fc93546a81b6eafbf90fc3\",\"name\":\"Mariana Delgado Baron\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariana Delgado Baron\"},\"description\":\"Freelance journalist interested in investigative journalism, migration, armed conflict, political violence, peacebuilding, transitional justice, human rights and development. I have experience working in the field with communities affected by the armed conflict in Colombia, in the reconstruction of the memories of victims and survivors. Political scientist and doctor in Social Sciences. I live in Bogota. marianadelgadobaron.com\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariana-delgado-baron\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad - Orato","description":"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/","og_locale":"es_ES","og_type":"article","og_title":"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad","og_description":"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados, como cerdos, bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.","og_url":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-04-06T19:45:18+00:00","article_modified_time":"2022-04-20T14:56:10+00:00","og_image":[{"width":1400,"height":795,"url":"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg","type":"image\/jpeg"}],"author":"Mariana Delgado Baron","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariana Delgado Baron","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/"},"author":{"name":"Mariana Delgado Baron","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/6e500933e0fc93546a81b6eafbf90fc3"},"headline":"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad","datePublished":"2022-04-06T19:45:18+00:00","dateModified":"2022-04-20T14:56:10+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/"},"wordCount":739,"commentCount":1,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg","keywords":["Activism","Acuerdo de Paz en Colombia","\u00c1ngel Queragama","Bogot\u00e1","Bogota","Colombia","Embera Kat\u00edo","Indigenous Rights","Latinoam\u00e9rica","Parque Nacional Bogot\u00e1"],"articleSection":["Conflicto","Galer\u00eda de fotos","Latinoam\u00e9rica","Galer\u00eda de fotos","Racismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/","url":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/","name":"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad - Orato","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg","datePublished":"2022-04-06T19:45:18+00:00","dateModified":"2022-04-20T14:56:10+00:00","description":"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg","width":1400,"height":795},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/04\/06\/comunidad-indigena-desplazada-que-vive-en-parque-de-bogota-exige-derechos-basicos-y-seguridad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Comunidad ind\u00edgena desplazada que vive en parque de Bogot\u00e1 exige derechos b\u00e1sicos y seguridad"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/6e500933e0fc93546a81b6eafbf90fc3","name":"Mariana Delgado Baron","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariana Delgado Baron"},"description":"Freelance journalist interested in investigative journalism, migration, armed conflict, political violence, peacebuilding, transitional justice, human rights and development. I have experience working in the field with communities affected by the armed conflict in Colombia, in the reconstruction of the memories of victims and survivors. Political scientist and doctor in Social Sciences. I live in Bogota. marianadelgadobaron.com","url":"https:\/\/orato.world\/es\/author\/mariana-delgado-baron\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg",1400,795,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-300x170.jpg",300,170,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-770x437.jpg",640,363,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-1024x581.jpg",640,363,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg",1400,795,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg",1400,795,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-704x400.jpg",704,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg",300,170,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg",400,227,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1.jpg",600,341,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/IMG_20211026_120312_092-1400x795-1-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Mariana Delgado Baron","author_link":"https:\/\/orato.world\/es\/author\/mariana-delgado-baron\/"},"uagb_comment_info":1,"uagb_excerpt":"Hemos aguantado muchos d\u00edas comiendo solo lentejas y arroz. Para evadir el fr\u00edo, dormimos amontonados, como cerdos, bajo pl\u00e1stico. Los ni\u00f1os a menudo se despiertan llorando.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/34694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/106"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=34694"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/34694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/64835"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=34694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=34694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=34694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}