{"id":34895,"date":"2022-04-13T00:00:00","date_gmt":"2022-04-13T07:00:00","guid":{"rendered":"https:\/\/orato.world\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/"},"modified":"2022-04-18T11:19:38","modified_gmt":"2022-04-18T18:19:38","slug":"jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/","title":{"rendered":"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido."},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Judge-interview-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Marzia Babakarkhail\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-1024x1024.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-770x770.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-390x390.jpg 390w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-585x585.jpg 585w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview-900x900.jpg 900w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-interview.jpg 1094w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/twitter.com\/marziababakarkh?lang=en\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Marzia Babakarkhail<\/strong><\/a> se desempe\u00f1\u00f3 como jueza en PuliKhumri Baghlan, Afganist\u00e1n, de 1991 a 1998. Estableci\u00f3 la Organizaci\u00f3n Social y Cultural de Mujeres Afganas y se desempe\u00f1\u00f3 como presidenta del comit\u00e9 de mujeres en la Oficina de Coordinaci\u00f3n de ONG Afganas (ANCB).<br><br>Cuando Marzia <a href=\"https:\/\/www.youtube.com\/watch?v=HFI1qPqrmPY\" target=\"_blank\" rel=\"noreferrer noopener\">se convirti\u00f3 en blanco de la agresi\u00f3n talib\u00e1n<\/a>, huy\u00f3 primero a Pakist\u00e1n y luego al Reino Unido. Marzia lleg\u00f3 al Reino Unido sin poder hablar una sola palabra de ingl\u00e9s. Como solicitante de asilo, no pudo obtener un trabajo remunerado, pero aprovech\u00f3 las oportunidades de voluntariado.<br><br>Obtuvo el estatus de refugiada en 2009 y se centr\u00f3 en mejorar su ingl\u00e9s. Marzia habla cinco idiomas y contin\u00faa estudiando ingl\u00e9s hoy en Oldham College. Obtuvo la ciudadan\u00eda brit\u00e1nica en 2016.<br><br>Al a\u00f1o siguiente, gan\u00f3 el premio <a href=\"https:\/\/www.oldham-chronicle.co.uk\/news-features\/8\/news-headlines\/103558\/champion-of-girls-is-woman-of-the-year\">Fusion Woman of the Year<\/a> y recientemente fue preseleccionada para el premio Northern Powerhouse Women&#8217;s Award como mentora destacada.<br><br>El trabajo continuo de Marzia para las personas desfavorecidas, en particular las de la comunidad de refugiados, cre\u00f3 oportunidades de liderazgo en el Reino Unido. Ahora es trabajadora social a tiempo parcial, cabildera, activista y defensora. <br><a href=\"https:\/\/www.huffingtonpost.co.uk\/entry\/female-judge-afghanistan-warns-womrn-ebing-followed-for-taking-part-in-protests_uk_6138d236e4b04778c00cd57d\">Los medios internacionales <\/a>la entrevistan peri\u00f3dicamente sobre las experiencias de las mujeres afganas y ha obtenido m\u00e1s de <a href=\"https:\/\/www.change.org\/p\/female-afghan-judges-are-at-extreme-risk-of-violence-and-need-emergency-visas-urgently?source_location=topic_page\">50.000 firmas para su petici\u00f3n de evacuar y reasentar a las juezas afganas.<\/a><br><br>Este mayo, <a href=\"https:\/\/www.thenationalnews.com\/world\/uk-news\/2022\/03\/25\/afghan-activist-and-former-refugee-attacked-by-taliban-stands-in-uk-council-election\/\">se presenta a las elecciones locales en su ciudad <\/a>en representaci\u00f3n del Partido Laborista.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">CONTEXTO<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Seg\u00fan el <a href=\"https:\/\/www.cfr.org\/backgrounder\/taliban-afghanistan\">Consejo de Relaciones Exteriores<\/a>, los talibanes son un \u201cgrupo fundamentalista isl\u00e1mico predominantemente past\u00fan que volvi\u00f3 al poder en Afganist\u00e1n en 2021 despu\u00e9s de librar una insurgencia de veinte a\u00f1os\u201d.<br><br>La <a href=\"https:\/\/en.wikipedia.org\/wiki\/History_of_the_Taliban\">larga historia del ascenso y la ca\u00edda del poder de los talibanes en Afganist\u00e1n abarca m\u00e1s de 40 a\u00f1os<\/a>. Parte de esta historia incluye abusos generalizados contra los derechos humanos. En la toma del pa\u00eds en 2021, seg\u00fan <a href=\"https:\/\/www.hrw.org\/world-report\/2022\/country-chapters\/afghanistan?gclid=CjwKCAjwur-SBhB6EiwA5sKtjjeSIUdkH6M03PiJhcks66NcHU871vhSHsmym3DZ8XJKRbP-4pUD9RoCUI8QAvD_BwE\">Human Rights Watch<\/a>, los talibanes han despojado a ni\u00f1as y mujeres de la educaci\u00f3n y la libertad period\u00edstica. Fueron removidos de casi todos los cargos gubernamentales y contin\u00faan siendo excluidos de la educaci\u00f3n secundaria. La inseguridad alimentaria y las bajas civiles han aumentado considerablemente.<br><br><a href=\"https:\/\/www.reuters.com\/article\/us-afghanistan-attack-judges\/gunmen-kill-two-female-supreme-court-judges-in-afghanistan-police-idUSKBN29M076\">Entre los asesinados se encontraban dos juezas<\/a>. Adem\u00e1s, los talibanes eliminaron el Ministerio de Asuntos de la Mujer y lo reemplazaron con un departamento para legislar las reglas de vestimenta de las mujeres y la capacidad de moverse fuera del hogar. Se cerraron los albergues para mujeres v\u00edctimas de la violencia y algunas de las que viv\u00edan all\u00ed fueron trasladadas a prisi\u00f3n.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">OLDHAM, Gran Manchester, Inglaterra\u2014No tengo respuesta sobre por qu\u00e9 me convert\u00ed en activista. Siempre ha estado dentro de m\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Forzada a irme de mi tierra natal por los talibanes, mi lucha contin\u00faa desde el Reino Unido. Intentaron matarme, pero sobreviv\u00ed y constru\u00ed una nueva vida para m\u00ed.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Escondida en una alcantarilla, escap\u00e9 de la ejecuci\u00f3n de los talibanes<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mi ciudad natal es PuliKhumri, una ciudad en el norte de Afganist\u00e1n, donde crec\u00ed con mis padres y hermanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viv\u00ed dentro del patriarcado, pero cuando era joven en la d\u00e9cada de 1990, serv\u00ed como jueza de familia. Solo hab\u00eda 26 juezas en ese momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando entr\u00e9 en la posici\u00f3n, me di cuenta de mi ingenuidad. La ley en Afganist\u00e1n trataba a las mujeres de manera marcadamente diferente. Habiendo sido testigo de las discrepancias, comenc\u00e9 un peque\u00f1o refugio para mujeres divorciadas. Mi familia y yo ayudamos de tres a cinco mujeres a la vez. Proporcionamos comida y trabajamos en su alfabetizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora en su tercera d\u00e9cada de existencia, los talibanes comenzaron como un grupo armado que surgi\u00f3 en la d\u00e9cada de 1990 a ra\u00edz de la Guerra Civil de Afganist\u00e1n. Para 1996, hab\u00edan llegado a gobernar la mayor parte del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e1pidamente aprendieron mi nombre. Hab\u00eda susurros que dec\u00edan: \u201cMira lo que est\u00e1 haciendo\u201d. Una tarde de 1997, mis peores temores se hicieron realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Once soldados talibanes llegaron a nuestra casa. Afuera de la casa, golpearon a nuestro conductor antes de romper la puerta principal. Todos sab\u00edamos a qui\u00e9n persegu\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escap\u00e9 a las alcantarillas en un callej\u00f3n detr\u00e1s de la casa, mientras mis padres y hermanos permanecieron adentro. \u00bfD\u00f3nde est\u00e1 Marzia? exigieron saber. Durante cuatro horas, me acurruqu\u00e9 all\u00ed, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme. En mi escondite, pens\u00e9 que me encontrar\u00edan. Estaba esperando a que me dispararan, pero se fueron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa misma noche hu\u00ed a Pakist\u00e1n. Por primera vez, pero no la \u00faltima, me convert\u00ed en refugiada.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ellos me atropellaron con un auto para tratar de silenciarme.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Me qued\u00e9 con un amigo en Pakist\u00e1n mientras otros acog\u00edan a mi familia. Los talibanes nos despojaron de todo. Confiscaron todas nuestras pertenencias y propiedades, dejando atr\u00e1s una casa vac\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1bamos a salvo en ese momento, pero nuestro trabajo apenas comenzaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caminando por las calles de Pakist\u00e1n, vimos a ni\u00f1os refugiados afganos vendiendo art\u00edculos para sobrevivir. Mi madre es maestra y nos sentimos llamados a ayudarlos, as\u00ed que abrimos una escuela para ni\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A veces ven\u00edan los talibanes a amenazarnos, pero segu\u00ed luchando. Llev\u00e9 mi mensaje a los medios y defend\u00ed a mi pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los talibanes perdieron el poder en 2001, aprovech\u00e9 la oportunidad de regresar y ayudar a sanar mi patria. De vuelta en Afganist\u00e1n como Presidenta del Comit\u00e9 de Mujeres de la Oficina de Coordinaci\u00f3n de ONG afganas, ten\u00eda la esperanza de que las cosas cambiaran. Incluso me sent\u00ed lo suficientemente valiente como para apoyar los eventos de la Fundaci\u00f3n Asia para el D\u00eda de la Mujer. Tristemente, mi alegr\u00eda no durar\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los talibanes no gobernaban el pa\u00eds, segu\u00edan siendo extremadamente activos y nuestra sensaci\u00f3n de seguridad se hizo a\u00f1icos una vez m\u00e1s en 2005 cuando mataron a una joven periodista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este tiempo, viaj\u00e9 de un lado a otro entre Kabul y Pakist\u00e1n. Arriesgu\u00e9 mi vida con cada viaje, y pronto lo pagu\u00e9. Primero, los talibanes comenzaron una campa\u00f1a de desinformaci\u00f3n, cuestionando la integridad de nuestra escuela. Sus esfuerzos nos cerraron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, en 2007, me encontraron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un viernes t\u00edpico, sal\u00ed de Kabul para ver a mi madre, que estaba enferma en un hospital de Peshawar. De repente, un autom\u00f3vil aceler\u00f3 hacia m\u00ed mientras caminaba afuera. No tuve tiempo de reaccionar, y esto no fue un accidente; yo era un objetivo. El auto me atropell\u00f3 y casi me mata en un terrible golpe y fuga.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Refugiada en el Reino Unido, luch\u00e9 por la ciudadan\u00eda<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durante seis meses, mi cuerpo luch\u00f3 por sanar, envuelto en un yeso en una cama de hospital y luego en una cl\u00ednica. Los talibanes casi hab\u00edan logrado su objetivo de matar a otra mujer afgana abiertamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi madre sufri\u00f3 al ver mi cuerpo destrozado en mi cama. Su instinto de proteger a sus hijos la consum\u00eda. Ella me rog\u00f3 que huyera y, por segunda vez, me convirtiera en un refugiado en una tierra extranjera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi coraz\u00f3n se desgarr\u00f3 al pensar en ello. Durante a\u00f1os, puse todas estas semillas en la tierra con la esperanza de verlas florecer. Sufr\u00ed y me sacrifiqu\u00e9 para servir y ayudar a mi pueblo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sab\u00eda que alg\u00fan d\u00eda morir\u00eda y no le ten\u00eda miedo a la muerte. M\u00e1s bien, estaba triste por dejar atr\u00e1s a mi gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tom\u00e9 la decisi\u00f3n de irme y amigos en el Reino Unido me consiguieron un boleto. A las dos de la ma\u00f1ana me puse una burka y viaj\u00e9 al aeropuerto de Pakist\u00e1n con mi madre. Dej\u00e9 todo atr\u00e1s: el amor, el cuidado, el estatus, el trabajo. Lo dej\u00e9 todo por seguridad, pero encontr\u00e9 un nuevo conjunto de problemas cuando llegu\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrar en el Reino Unido comenz\u00f3 otro viaje. No conoc\u00eda a nadie, no hablaba el idioma y no ten\u00eda asilo garantizado. Al bajar del avi\u00f3n, mi mente se arremolinaba con preguntas. Me encontr\u00e9 con un oficial en el aeropuerto que era indio. \u201c\u00bfPuedo hablar urdu?\u201d, le pregunt\u00e9, y \u00e9l respondi\u00f3 afirmativamente. Aliviada de tener ayuda, me conect\u00e9 con amigos de Londres que me dieron un lugar para quedarme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esos primeros d\u00edas, el p\u00e1nico me consum\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de la noche, involuntariamente dejaba de respirar. Mis pulmones se comprim\u00edan mientras sal\u00eda corriendo e inhalaba grandes bocanadas del aire fresco de la noche. No ten\u00eda futuro ni plan, y se sent\u00eda tortuoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, sentada frente a mi abogada en su oficina, me sent\u00ed insegura mientras trat\u00e1bamos de determinar mis pr\u00f3ximos pasos. \u201c\u00bfQu\u00e9 pruebas tienes de tu caso?\u201d ella pregunt\u00f3. \u201cNinguno\u201d, respond\u00ed. Me mir\u00f3 durante un largo rato y luego dijo: \u201cMarzia, puedo ver la evidencia. Es el dolor en toda tu cara\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella comenz\u00f3 una investigaci\u00f3n y pronto se acumularon las pruebas de lo que los talibanes me hab\u00edan hecho en Afganist\u00e1n y m\u00e1s all\u00e1. Finalmente, el Reino Unido me concedi\u00f3 el <a href=\"https:\/\/freemovement.org.uk\/what-is-the-difference-between-refugee-status-and-humanitarian-protection\/\">estatus de refugiado<\/a>. Me permite permanecer en el Reino Unido durante cinco a\u00f1os, as\u00ed como permiso para trabajar y estudiar; acceder a prestaciones, vivienda y Sistema Nacional de Salud; y buscar la reunificaci\u00f3n familiar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"563\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Judge-screenshot-1-1024x563.jpg\" alt=\"\" class=\"wp-image-34752\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-1024x563.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-300x165.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-770x423.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-1536x844.jpg 1536w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-180x100.jpg 180w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-293x161.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1-1400x769.jpg 1400w, https:\/\/orato.world\/wp-content\/uploads\/\/Judge-screenshot-1.jpg 1776w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Marzia habla a menudo con organizaciones de medios internacionales sobre el estado de los derechos de las mujeres en su Afganist\u00e1n natal. Aqu\u00ed, da una entrevista a India Today durante la toma de poder de los talibanes en 2021 | <strong>Captura de pantalla cortes\u00eda de <a href=\"https:\/\/www.youtube.com\/watch?v=HFI1qPqrmPY\">India Today<\/a><\/strong><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-2021-taliban-takeover-stripped-my-vision-and-my-hope\"><h2>La toma de poder de los talibanes en 2021 me quit\u00f3 la visi\u00f3n y la esperanza<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al ver caer Afganist\u00e1n nuevamente en 2021, todo mi cuerpo solloz\u00f3. Inmediatamente despu\u00e9s de la toma del poder, los talibanes mataron a dos juezas en Kabul. Asesinaron a civiles, mujeres y ni\u00f1os. Esto no fue f\u00e1cil de aceptar. S\u00e9 lo duro que trabajamos, y parece que lo perdimos todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos desarrollos me hicieron sentir como si me hubiera quedado ciega; como si perdiera toda la visi\u00f3n de mis ojos. Sin embargo, nunca dejar\u00e9 de luchar. Hoy, el ingl\u00e9s es como mi ox\u00edgeno. puedo estar viva; Puedo hablar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una y otra vez les digo a los periodistas: los talibanes pueden obligarme a salir de mi pa\u00eds, pero no pueden obligarme a cambiar de opini\u00f3n. Este es mi prop\u00f3sito, y mi esp\u00edritu no morir\u00e1 antes que mi cuerpo. Creo que puedo luchar contra la injusticia toda mi vida.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"How I escaped the Taliban\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/5B-GyYJTwE8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.<\/p>\n","protected":false},"author":73,"featured_media":65341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"no","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,191,2774],"tags":[541,1789,866,3060,2762,2761,502,1790],"class_list":["post-34895","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-conflicto","category-denunciante","category-europa","tag-activism-es","tag-afghanistan-es","tag-derechos-de-la-mujer","tag-europa","tag-gran-manchester","tag-marzia-babakarkhail-es","tag-refugee-es","tag-taliban-es","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido. - Orato<\/title>\n<meta name=\"description\" content=\"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido.\" \/>\n<meta property=\"og:description\" content=\"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-13T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T18:19:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Pamela Say\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pamela Say\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/\"},\"author\":{\"name\":\"Pamela Say\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/8763f3be94965bec0c582d052c418b00\"},\"headline\":\"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido.\",\"datePublished\":\"2022-04-13T07:00:00+00:00\",\"dateModified\":\"2022-04-18T18:19:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/\"},\"wordCount\":1386,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp\",\"keywords\":[\"Activism\",\"Afghanistan\",\"Derechos de la mujer\",\"Europa\",\"Gran M\u00e1nchester\",\"Marzia Babakarkhail\",\"Refugee\",\"Taliban\"],\"articleSection\":[\"Conflicto\",\"Denunciante\",\"Europa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/\",\"name\":\"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido. - Orato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp\",\"datePublished\":\"2022-04-13T07:00:00+00:00\",\"dateModified\":\"2022-04-18T18:19:38+00:00\",\"description\":\"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp\",\"width\":1400,\"height\":1050,\"caption\":\"Women in England protest the violence of the Taliban takeover of Afghanistan in August 2021 | Photo by Ehimetalor Akhere Unuabona on Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/13\\\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/8763f3be94965bec0c582d052c418b00\",\"name\":\"Pamela Say\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Pamela Say\"},\"description\":\"Pamela H. Say, MBA, CFRE is a sought-after, nationally-published author and speaker, veteran administrator, and currently serves as the CEO for Orato World Media. She is a trained journalist and has been featured in Advancing Philanthropy Magazine, the Chronicle of Philanthropy, and the Wiley Journal Fundraising Success. Her award-winning work in fundraising, marketing, writing, and leading high-performance teams commands international attention.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/pamela-say\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido. - Orato","description":"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/","og_locale":"es_ES","og_type":"article","og_title":"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido.","og_description":"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.","og_url":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-04-13T07:00:00+00:00","article_modified_time":"2022-04-18T18:19:38+00:00","og_image":[{"width":1400,"height":1050,"url":"https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp","type":"image\/webp"}],"author":"Pamela Say","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Pamela Say","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/"},"author":{"name":"Pamela Say","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/8763f3be94965bec0c582d052c418b00"},"headline":"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido.","datePublished":"2022-04-13T07:00:00+00:00","dateModified":"2022-04-18T18:19:38+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/"},"wordCount":1386,"commentCount":1,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp","keywords":["Activism","Afghanistan","Derechos de la mujer","Europa","Gran M\u00e1nchester","Marzia Babakarkhail","Refugee","Taliban"],"articleSection":["Conflicto","Denunciante","Europa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/","url":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/","name":"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido. - Orato","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp","datePublished":"2022-04-13T07:00:00+00:00","dateModified":"2022-04-18T18:19:38+00:00","description":"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp","width":1400,"height":1050,"caption":"Women in England protest the violence of the Taliban takeover of Afghanistan in August 2021 | Photo by Ehimetalor Akhere Unuabona on Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/04\/13\/jueza-afgana-activista-sobrevive-a-los-intentos-de-asesinato-de-los-talibanes-por-postularse-para-un-cargo-en-el-reino-unido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Jueza afgana, activista, sobrevive a los intentos de asesinato de los talibanes y se postula para un cargo en el Reino Unido."}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/8763f3be94965bec0c582d052c418b00","name":"Pamela Say","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Pamela Say"},"description":"Pamela H. Say, MBA, CFRE is a sought-after, nationally-published author and speaker, veteran administrator, and currently serves as the CEO for Orato World Media. She is a trained journalist and has been featured in Advancing Philanthropy Magazine, the Chronicle of Philanthropy, and the Wiley Journal Fundraising Success. Her award-winning work in fundraising, marketing, writing, and leading high-performance teams commands international attention.","url":"https:\/\/orato.world\/es\/author\/pamela-say\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp",1400,1050,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-100x100.webp",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-300x225.webp",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-770x578.webp",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-1024x768.webp",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp",1400,1050,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp",1400,1050,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-533x400.webp",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-360x240.webp",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1.webp",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/ehimetalor-akhere-unuabona-KnBrAkEg7RM-unsplash-1400x1050-1-500x500.webp",500,500,true]},"uagb_author_info":{"display_name":"Pamela Say","author_link":"https:\/\/orato.world\/es\/author\/pamela-say\/"},"uagb_comment_info":1,"uagb_excerpt":"Me acurruqu\u00e9 en la alcantarilla durante cuatro horas, rodeada de suciedad y hedor, las moscas me picaban por todas partes. Sab\u00eda que los talibanes hab\u00edan venido a matarme.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/34895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=34895"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/34895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/65341"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=34895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=34895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=34895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}