{"id":35435,"date":"2022-04-19T15:39:40","date_gmt":"2022-04-19T22:39:40","guid":{"rendered":"https:\/\/orato.world\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/"},"modified":"2023-01-25T04:06:13","modified_gmt":"2023-01-25T12:06:13","slug":"mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/","title":{"rendered":"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-interview-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Paula Manzaba\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-1024x1024.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-770x770.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-390x390.jpg 390w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-585x585.jpg 585w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-900x900.jpg 900w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview-1400x1400.jpg 1400w, https:\/\/orato.world\/wp-content\/uploads\/\/Paula-Manzaba-interview.jpg 1448w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Interview Subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><strong>Paula Manzaba<\/strong>, 48, is a mother of four and president and founder of <a href=\"https:\/\/www.familias-upec.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fundaci\u00f3n Familias Unidas por el Cambio<\/a> (Families United for Change Foundation).<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Background Information<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">The <a href=\"http:\/\/www.familias-upec.org\/quienes-somos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Families United for Change Foundation<\/a> \u00abis an organization of men and women who fight for housing, decent jobs and for the rights of low-income families.\u00bb <br><br>Members seek to fight for the rights of women and men who have been deprived of their liberty to improve their living conditions.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">QUITO, Ecuador\u2014Nunca olvidar\u00e9 el martes 8 de abril de 2004.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo era auxiliar de enfermer\u00eda y acababa de salir del turno de noche cuando llegu\u00e9 a casa y encontr\u00e9 a mis hijos solos. Cuando le pregunt\u00e9 al mayor, que ten\u00eda 10 a\u00f1os, d\u00f3nde estaba su padre, me dijo que no hab\u00eda venido a dormir a casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prepar\u00e9 el desayuno y me acost\u00e9 un rato porque estaba exhausta. Mi esposo entr\u00f3 corriendo como loco, recogi\u00f3 algo y sali\u00f3 corriendo de la casa nuevamente. No pasaron ni 10 minutos cuando lleg\u00f3 la polic\u00eda y golpe\u00f3 la puerta con tanta fuerza que parec\u00eda que se iba a romper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Registraron la casa y encontraron una peque\u00f1a bolsa con algo que parec\u00eda harina. Ese fue el principio del fin de mi vida tal como la conoc\u00eda entonces.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-life-behind-bars\"><h2>La vida tras las rejas<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le dije a la polic\u00eda que las drogas no eran m\u00edas y que no sab\u00eda que mi esposo las ten\u00eda. Me hicieron pruebas de drogas, y como no ten\u00eda drogas en la sangre, me acusaron de posesi\u00f3n. El juez me conden\u00f3 a ocho a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cumpl\u00ed poco m\u00e1s de tres a\u00f1os por buena conducta. Mis hijos fueron criados por fundaciones ben\u00e9ficas o confiados a familiares y amigos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante ese tiempo, perd\u00ed peso y ca\u00ed en una profunda depresi\u00f3n. Varias veces pens\u00e9 en quitarme la vida. No dorm\u00eda nada y apenas com\u00eda. Estaba completamente sola, incluso mi familia me dio la espalda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la c\u00e1rcel no hay amigos. Detr\u00e1s de las rejas, una vez que se apagan las luces, se convierte en cada uno por su cuenta. A veces ten\u00eda que dormir en el suelo o en la parte superior de una litera sin colch\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, pas\u00f3 el tiempo. Empec\u00e9 a trabajar, aprendiendo oficios, como empaquetar gasas y hacer hisopos de algod\u00f3n. Tambi\u00e9n aprend\u00ed a hacer artesan\u00edas que luego vend\u00eda y lavaba la ropa de las presas extranjeras. El dinero que ganaba lo enviaba a mis hijos y lo usaba ocasionalmente en cosas como cremas para la piel, maquillaje y ropa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Tres a\u00f1os despu\u00e9s, libre al fin<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El 8 de agosto de 2008, puse un pie fuera de la c\u00e1rcel por primera vez en tres a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mis hijos estaban dispersos. Alan, que solo ten\u00eda 2 meses cuando me encarcelaron, ahora era un ni\u00f1o peque\u00f1o que viv\u00eda con mi hermana. Una fundaci\u00f3n les dio un estipendio mensual para alimentarlo. Juan Carlos trabajaba como conductor de autob\u00fas y Estefan\u00eda se cas\u00f3 con un hombre mucho mayor que ella cuando ella ten\u00eda 17 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Javier estuvo en un centro de rehabilitaci\u00f3n porque cay\u00f3 en el mismo mundo de las drogas que su padre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque se puso sobrio, su nuevo camino dur\u00f3 poco; unos hombres lo asesinaron hace siete a\u00f1os por un par de zapatillas de deporte. Solo ten\u00eda 23 a\u00f1os. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras tanto, obviamente hab\u00eda perdido mi trabajo como auxiliar de enfermer\u00eda y me era imposible conseguir otro porque nadie me quer\u00eda contratar con mis antecedentes penales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque libre al fin, me sent\u00eda moralmente destru\u00edda. Siempre hab\u00eda sido una buena madre, preocup\u00e1ndome constantemente por el bienestar de mis hijos; cuando sal\u00ed de la c\u00e1rcel, mis peque\u00f1os estaban descuidados, flacos y sucios. Me rompi\u00f3 el coraz\u00f3n. La noticia de la adicci\u00f3n de Javier me destruy\u00f3 a\u00fan m\u00e1s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Ayudar a otros a superar el estigma social y ganarse la vida despu\u00e9s del encarcelamiento<\/h2><\/h2>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"293\" height=\"391\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-1-293x391-1.webp\" alt=\"\" class=\"wp-image-65948\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-1-293x391-1.webp 293w, https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-1-293x391-1-225x300.webp 225w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><figcaption class=\"wp-element-caption\">Paula muestra algunas de las joyas elaboradas por miembros de su fundaci\u00f3n | <strong>Foto por Pamela Castillo D\u00edaz<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cuando estuve en prisi\u00f3n, conoc\u00ed mujeres sentenciadas a 25 a\u00f1os de prisi\u00f3n por tener tan solo 1 gramo de drogas. Les promet\u00ed: \u201cUn d\u00eda, saldr\u00e9 y pelear\u00e9 por ustedes\u201d. En octubre de 2008 cre\u00e9 la Fundaci\u00f3n Mujeres Valientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empezamos con 22 mujeres, que luego involucraron a sus esposos o cu\u00f1ados. Me di cuenta de que este tipo de injusticia iba m\u00e1s all\u00e1 del g\u00e9nero, as\u00ed que cambi\u00e9 el nombre a Fundaci\u00f3n Familias Unidas por el Cambio (<a href=\"https:\/\/www.familias-upec.org\/\">Familias Unidas por el Cambio<\/a>). Trabajamos para ayudar a las personas que han estado encarceladas a reintegrarse en la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, trabajamos con m\u00e1s de 300 familias. Les ense\u00f1amos a hacer champ\u00fa para el cabello, cremas para la piel, gel antibacterial y otros productos de limpieza. Nuestros participantes hacen todo a mano y luego viven de los ingresos de las ventas de estos productos. Tambi\u00e9n vendemos artesan\u00edas, collares y correas para blusas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias, independientemente de nuestro pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias, independientemente de nuestro pasado.<\/p>\n","protected":false},"author":128,"featured_media":65443,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[417],"tags":[1681,1898,2820,2818,2819,3060,2816,2214,2817],"class_list":["post-35435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visionarios","tag-drogas","tag-ecuador-es","tag-emprendedora","tag-encarcelamiento","tag-estigmas-sociales","tag-europa","tag-fundacion-familias-unidas-por-el-cambio-es","tag-latinoamerica","tag-paula-manzaba-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad - Orato<\/title>\n<meta name=\"description\" content=\"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad\" \/>\n<meta property=\"og:description\" content=\"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias, independientemente de nuestro pasado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-19T22:39:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-25T12:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Pamela Castillo Diaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pamela Castillo Diaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/\"},\"author\":{\"name\":\"Pamela Castillo Diaz\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/98d563c9d8518e232fb08ec42e69120c\"},\"headline\":\"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad\",\"datePublished\":\"2022-04-19T22:39:40+00:00\",\"dateModified\":\"2023-01-25T12:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/\"},\"wordCount\":825,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Paula-Manzaba-feature-1400x1050-1.webp\",\"keywords\":[\"Drogas\",\"Ecuador\",\"Emprendedora\",\"Encarcelamiento\",\"Estigmas sociales\",\"Europa\",\"Fundaci\u00f3n Familias Unidas por el Cambio\",\"Latinoam\u00e9rica\",\"Paula Manzaba\"],\"articleSection\":[\"Visionarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/\",\"name\":\"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad - Orato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Paula-Manzaba-feature-1400x1050-1.webp\",\"datePublished\":\"2022-04-19T22:39:40+00:00\",\"dateModified\":\"2023-01-25T12:06:13+00:00\",\"description\":\"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Paula-Manzaba-feature-1400x1050-1.webp\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Paula-Manzaba-feature-1400x1050-1.webp\",\"width\":1400,\"height\":1050,\"caption\":\"The foundation sells handmade products, such as shampoo, creams, disinfectants, and jewelry.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/04\\\/19\\\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/98d563c9d8518e232fb08ec42e69120c\",\"name\":\"Pamela Castillo Diaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Pamela Castillo Diaz\"},\"description\":\"Pamela Castillo D\u00edaz, 35, has been an Ecuadorian journalist and storyteller for 15 years. She has worked as an editor in recognized Ecuadorian media, including Diario HOY, El Comercio, and Diario Extra. She currently develop and manage her website, pamelacastillodiaz.com.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/pamela-castillo-diaz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad - Orato","description":"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/","og_locale":"es_ES","og_type":"article","og_title":"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad","og_description":"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias, independientemente de nuestro pasado.","og_url":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-04-19T22:39:40+00:00","article_modified_time":"2023-01-25T12:06:13+00:00","og_image":[{"width":1400,"height":1050,"url":"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp","type":"image\/webp"}],"author":"Pamela Castillo Diaz","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Pamela Castillo Diaz","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/"},"author":{"name":"Pamela Castillo Diaz","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/98d563c9d8518e232fb08ec42e69120c"},"headline":"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad","datePublished":"2022-04-19T22:39:40+00:00","dateModified":"2023-01-25T12:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/"},"wordCount":825,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp","keywords":["Drogas","Ecuador","Emprendedora","Encarcelamiento","Estigmas sociales","Europa","Fundaci\u00f3n Familias Unidas por el Cambio","Latinoam\u00e9rica","Paula Manzaba"],"articleSection":["Visionarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/","url":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/","name":"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad - Orato","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp","datePublished":"2022-04-19T22:39:40+00:00","dateModified":"2023-01-25T12:06:13+00:00","description":"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp","width":1400,"height":1050,"caption":"The foundation sells handmade products, such as shampoo, creams, disinfectants, and jewelry."},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/04\/19\/mujer-ecuatoriana-ex-encarcelada-ayuda-a-otros-a-reintegrarse-a-la-sociedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Mujer ecuatoriana ex encarcelada ayuda a otros a reintegrarse a la sociedad"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/98d563c9d8518e232fb08ec42e69120c","name":"Pamela Castillo Diaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Pamela Castillo Diaz"},"description":"Pamela Castillo D\u00edaz, 35, has been an Ecuadorian journalist and storyteller for 15 years. She has worked as an editor in recognized Ecuadorian media, including Diario HOY, El Comercio, and Diario Extra. She currently develop and manage her website, pamelacastillodiaz.com.","url":"https:\/\/orato.world\/es\/author\/pamela-castillo-diaz\/"}]}},"modified_by":"Aurelie Msiza","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp",1400,1050,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-100x100.webp",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-300x225.webp",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-770x578.webp",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-1024x768.webp",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp",1400,1050,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp",1400,1050,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-533x400.webp",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-360x240.webp",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1.webp",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Paula-Manzaba-feature-1400x1050-1-500x500.webp",500,500,true]},"uagb_author_info":{"display_name":"Pamela Castillo Diaz","author_link":"https:\/\/orato.world\/es\/author\/pamela-castillo-diaz\/"},"uagb_comment_info":0,"uagb_excerpt":"Estoy orgullosa de ayudar a estas personas, que a menudo no tienen otras opciones. Todos merecemos ganarnos la vida y mantener a nuestras familias, independientemente de nuestro pasado.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/35435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=35435"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/35435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/65443"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=35435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=35435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=35435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}