{"id":40506,"date":"2022-06-09T07:00:00","date_gmt":"2022-06-09T14:00:00","guid":{"rendered":"https:\/\/orato.world\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/"},"modified":"2023-01-24T06:57:59","modified_gmt":"2023-01-24T14:57:59","slug":"ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/","title":{"rendered":"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/IMG_20211009_124654_214-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Roly Mamani\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-1024x1024.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-770x770.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-1536x1536.jpg 1536w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-2048x2048.jpg 2048w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-390x390.jpg 390w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-585x585.jpg 585w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-900x900.jpg 900w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_20211009_124654_214-1400x1400.jpg 1400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Roly Mamadi es un ingeniero boliviano que estudi\u00f3 Ingenier\u00eda Electr\u00f3nica con especialidad en Electromedicina. Actualmente trabaja en un laboratorio llamado <a href=\"https:\/\/www.facebook.com\/100057515138330\/videos\/?locale=ne_NP&amp;_rdr\">Creadores de Rob\u00f3tica<\/a> en Achocalla, a media hora de La Paz, en el que desarrolla toda la tecnolog\u00eda para hacer pr\u00f3tesis.<br><br>Gracias a su largo trabajo y pruebas ha conseguido ayudar a 200 familias. Sus pacientes incluyen adultos, personas mayores, ni\u00f1os e incluso mascotas.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">CONTEXTO<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Seg\u00fan datos de la <a href=\"https:\/\/www.paho.org\/en\">Organizaci\u00f3n Panamericana de la Salud<\/a>, m\u00e1s del 9 por ciento de la poblaci\u00f3n boliviana sufre alguna discapacidad. De los cuales, la mayor\u00eda se producen por lesiones por accidentes de tr\u00e1fico y laborales.<br><br>Seg\u00fan Roly Mamani, implementar la impresi\u00f3n 3D es una gran alternativa a las pr\u00f3tesis tradicionales, ya que uno de los principales problemas en los pa\u00edses latinoamericanos es que no cuentan con empresas que fabriquen materias primas de primera calidad para generar productos con mayores garant\u00edas y resistencias que en el extranjero.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">ACHOCALLA, Bolivia \ua7f7 De ni\u00f1o, me encantaba crear cosas nuevas y so\u00f1aba con hacer un robot. En la universidad estudi\u00e9 electr\u00f3nica y rob\u00f3tica. Como cualquier so\u00f1ador, cre\u00e9 prototipos, particip\u00e9 en competencias y constru\u00ed animatr\u00f3nics. Construir y competir result\u00f3 divertido y se convirti\u00f3 en una parte hermosa de mi vida, pero me preguntaba por qu\u00e9 importaba si no aplicaba este conocimiento a algo productivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Motivado por los valores y la empat\u00eda que me ense\u00f1aron mis padres, comenc\u00e9 a desarrollar tecnolog\u00eda relacionada con la salud. Mi trabajo podr\u00eda ayudar a la sociedad ya las personas con discapacidades como la p\u00e9rdida de brazos, antebrazos, dedos o falta de movilidad en las extremidades superiores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2016 hasta 2018 comenc\u00e9 a desarrollar soluciones para personas con discapacidad basadas en <a href=\"https:\/\/www.3dnatives.com\/en\/3d-printing-in-industry-4-0-150220215\/\">tecnolog\u00edas 4.0 como la impresi\u00f3n 3D<\/a>. Mi equipo y yo hemos ayudado a unas 200 familias con nuestras soluciones de bajo costo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pobres-amputados-en-bolivia-carecen-de-protesis\">Pobres amputados en Bolivia carecen de pr\u00f3tesis<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las pr\u00f3tesis son complicadas de desarrollar y, como resultado, terminan siendo muy caras. Me negu\u00e9 a sentirme impotente despu\u00e9s de haber visto a tanta gente en mi pa\u00eds con estos problemas. Me preguntaba por qu\u00e9 el problema se volvi\u00f3 tan frecuente. A menudo, las personas con recursos limitados experimentan una mayor exposici\u00f3n al peligro, como perder una extremidad en un accidente, operar maquinaria o manejar mal los explosivos. El problema se agrava porque no pueden pagar el alto precio de una pr\u00f3tesis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con muy poca experiencia, recursos o conocimientos, logramos crear nuestras primeras soluciones utilizando tecnolog\u00eda de impresi\u00f3n 3D revolucionaria, comenzando con dise\u00f1os simples para un antebrazo o f\u00f3rceps para manipular objetos. Con resultados aceptables, la gente acudi\u00f3 en busca de ayuda. Poco a poco fuimos conociendo a cada paciente y sus experiencias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prototipo prot\u00e9sico permite al paciente sostener una galleta y abrir la puerta de un auto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tuve que arriesgarme para vivir una vida que me apasionara, una pasi\u00f3n que me diera la fuerza para perseverar. Entonces, dej\u00e9 mi trabajo en electr\u00f3nica de autom\u00f3viles y un horario fijo y salario. Fue la decisi\u00f3n correcta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro primer paciente, Richard Vargas, lleg\u00f3 con dos amputaciones de antebrazo. Durante tres o cuatro meses, trabajamos para encontrar una soluci\u00f3n. A pesar de una educaci\u00f3n universitaria, aprend\u00ed dise\u00f1o 3D, programaci\u00f3n e impresi\u00f3n, y electr\u00f3nica relacionada. La combinaci\u00f3n de disciplinas asegur\u00f3 que logr\u00e1ramos el resultado necesario para Richard.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire. De repente no ve\u00edas a una persona a la que le faltaban partes de su cuerpo, ve\u00edas a alguien con el potencial de estar mental y f\u00edsicamente bien. Se sent\u00eda irreal ver a un hombre al que le faltaban extremidades donde deber\u00eda estar una mano o un brazo, pero cuando le pusimos los dos antebrazos, se volvi\u00f3 sim\u00e9trico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su autoestima mejor\u00f3 porque se sent\u00eda m\u00e1s agradable est\u00e9ticamente. De repente, pod\u00eda agarrar cosas y con facilidad. A Richard no le import\u00f3 que fuera un prototipo. Agarr\u00f3 una galleta y se estir\u00f3 para abrir la puerta de un auto. Un gran sentimiento nos invadi\u00f3 a cada uno de nosotros, sabiendo que encontramos el camino correcto. Son los pacientes los que te motivan a seguir mejorando.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@rolyronald\/video\/7029116165796400390\" data-video-id=\"7029116165796400390\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@rolyronald\" href=\"https:\/\/www.tiktok.com\/@rolyronald?refer=embed\">@rolyronald<\/a> <p>cumplimos con don Felipe<a title=\"tecnologia\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/tecnologia?refer=embed\">#tecnologia<\/a> <a title=\"3dprinting\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/3dprinting?refer=embed\">#3dprinting<\/a> <a title=\"technology\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/technology?refer=embed\">#technology<\/a> <a title=\"impresion3d\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/impresion3d?refer=embed\">#impresion3d<\/a> <a title=\"protesis\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/protesis?refer=embed\">#protesis<\/a> <a title=\"prosthetic\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/prosthetic?refer=embed\">#prosthetic<\/a><\/p> <a target=\"_blank\" title=\"\u266c sonido original - Roly Ronald\" href=\"https:\/\/www.tiktok.com\/music\/sonido-original-7029115957305985798?refer=embed\">\u266c sonido original &#8211; Roly Ronald<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">La tecnolog\u00eda 3D da nuevas extremidades a ni\u00f1os, animales y ancianos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mis pacientes, que ahora incluyen humanos y mascotas, me ense\u00f1an. Incluso los animales necesitan una segunda oportunidad. Son \u00fanicos en el sentido de que no se sienten discapacitados si les ofreces amor y atenci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos humanos que viven en un estado \u00f3ptimo se quejan de muchas cosas. Trabajando con mis pacientes aprend\u00ed a valorar mis dedos y mis manos porque son la expresi\u00f3n de mi alma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un saludo y un abrazo traen emoci\u00f3n al expresar a trav\u00e9s de tus manos lo que tu cerebro est\u00e1 pensando y sintiendo. Los pacientes llegan al laboratorio sin las cuatro extremidades. Sin piernas ni manos, buscan soluciones, pero llegan con una gran sonrisa en la cara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos muestran que la vida, a pesar de sus desaf\u00edos, contin\u00faa. Obtenemos una gran satisfacci\u00f3n sumando a esas sonrisas y disminuyendo la impotencia. Como personas, Muchas veces volteamos la mirada para otro lado para seguir con nuestra vida, cuando podr\u00edamos hacer algo positivo. La tecnolog\u00eda se ha convertido en mi aliada para resistirme a sentirme impotente ante estos desaf\u00edos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las soluciones pueden ser \u00f3ptimas o m\u00ednimamente aceptables, pero de cualquier manera me dan paz. Veo que los ni\u00f1os y los ancianos adquieren habilidades; y los ciegos tocan la guitarra. Puede que no sea mucho, pero el cambio debe comenzar en alguna parte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ajustando modelos de negocio para pr\u00f3tesis en Bolivia e inspirando a j\u00f3venes en STEM<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hacemos este trabajo con ayuda. Para las personas ricas que pueden pagar una pr\u00f3tesis, pagan los materiales y nosotros proporcionamos la mano de obra. El dinero recaudado nos permite apadrinar a quienes llegan a nuestra puerta desde provincias lejanas sin recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luchamos constantemente contra la falta de suministro y los altos costos de engranajes, microengranajes, aluminio y compuestos de aluminio, buscando siempre soluciones asequibles para personas de bajos ingresos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como tantas empresas, la <a href=\"https:\/\/www.3dnatives.com\/en\/3d-printing-in-industry-4-0-150220215\/\">Pandemia del COVID-19<\/a> retras\u00f3 proyectos e investigaci\u00f3n y desarrollo, por lo que nos reinventamos continuamente, ofreciendo insumos para el personal de salud y materiales de bioseguridad para m\u00e9dicos. Esto nos permite mantenernos a flote.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So\u00f1amos con completar un centro de rehabilitaci\u00f3n a gran escala para las extremidades inferiores y superiores, hacer exoesqueletos para personas en sillas de ruedas y pr\u00f3tesis para quienes no pueden mover los brazos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo, esperamos la apertura del primer museo de robots en La Paz, donde los j\u00f3venes pueden visitar y animarse a socializar. Nuestro objetivo es inspirar a m\u00e1s j\u00f3venes a elegir una carrera en el campo y brindarles un entorno para mostrarles nuestro trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si podemos abrir las mentes j\u00f3venes a las posibilidades, se convertir\u00e1n en los futuros creadores de soluciones para los necesitados en Bolivia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro primer paciente, Richard Vargas, lleg\u00f3 con dos amputaciones de antebrazo. Trabajamos para encontrar una soluci\u00f3n. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire. De repente no ve\u00edas a una persona a la que le faltaban partes de su cuerpo, ve\u00edas a alguien con el potencial de estar mental y f\u00edsicamente bien.<\/p>\n","protected":false},"author":119,"featured_media":40298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[188,270],"tags":[2233,1469,2362,1989,2214,3161,3159,3160,2343,2361],"class_list":["post-40506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","category-tecnologia-cientifica","tag-bolivia-es","tag-discapacidad-es-2","tag-impresion-3d","tag-ingenieria","tag-latinoamerica","tag-protesis","tag-robotica","tag-roly-mamani-es","tag-stem-es","tag-tecnologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM<\/title>\n<meta name=\"description\" content=\"Richard Vargas lleg\u00f3 con dos amputaciones de antebrazo. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM\" \/>\n<meta property=\"og:description\" content=\"Nuestro primer paciente, Richard Vargas, lleg\u00f3 con dos amputaciones de antebrazo. Trabajamos para encontrar una soluci\u00f3n. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire. De repente no ve\u00edas a una persona a la que le faltaban partes de su cuerpo, ve\u00edas a alguien con el potencial de estar mental y f\u00edsicamente bien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-24T14:57:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Iv\u00e1n Portillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ivoportillo\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iv\u00e1n Portillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/\"},\"author\":{\"name\":\"Iv\u00e1n Portillo\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/9c9c480f650a22a0d16907726ab1c99a\"},\"headline\":\"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM\",\"datePublished\":\"2022-06-09T14:00:00+00:00\",\"dateModified\":\"2023-01-24T14:57:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/\"},\"wordCount\":1068,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/export202205202126279670.jpg\",\"keywords\":[\"Bolivia\",\"Discapacidad\",\"Impresi\u00f3n 3d\",\"Ingenieria\",\"Latinoam\u00e9rica\",\"pr\u00f3tesis\",\"Rob\u00f3tica\",\"Roly Mamani\",\"STEM\",\"Tecnolog\u00eda\"],\"articleSection\":[\"Salud\",\"Tecnolog\u00eda cient\u00edfica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/\",\"name\":\"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/export202205202126279670.jpg\",\"datePublished\":\"2022-06-09T14:00:00+00:00\",\"dateModified\":\"2023-01-24T14:57:59+00:00\",\"description\":\"Richard Vargas lleg\u00f3 con dos amputaciones de antebrazo. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/export202205202126279670.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/export202205202126279670.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Don Felipe, a man from a province very far from La Paz, arrives to receive his prostheses from Roly Mamani | Photo courtesy of\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/09\\\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/9c9c480f650a22a0d16907726ab1c99a\",\"name\":\"Iv\u00e1n Portillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Iv\u00e1n Portillo\"},\"description\":\"Journalist specializing in animation.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ivoportillo\"],\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/ivan-portillo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM","description":"Richard Vargas lleg\u00f3 con dos amputaciones de antebrazo. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/","og_locale":"es_ES","og_type":"article","og_title":"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM","og_description":"Nuestro primer paciente, Richard Vargas, lleg\u00f3 con dos amputaciones de antebrazo. Trabajamos para encontrar una soluci\u00f3n. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire. De repente no ve\u00edas a una persona a la que le faltaban partes de su cuerpo, ve\u00edas a alguien con el potencial de estar mental y f\u00edsicamente bien.","og_url":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-06-09T14:00:00+00:00","article_modified_time":"2023-01-24T14:57:59+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg","type":"image\/jpeg"}],"author":"Iv\u00e1n Portillo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ivoportillo","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Iv\u00e1n Portillo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/"},"author":{"name":"Iv\u00e1n Portillo","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/9c9c480f650a22a0d16907726ab1c99a"},"headline":"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM","datePublished":"2022-06-09T14:00:00+00:00","dateModified":"2023-01-24T14:57:59+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/"},"wordCount":1068,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg","keywords":["Bolivia","Discapacidad","Impresi\u00f3n 3d","Ingenieria","Latinoam\u00e9rica","pr\u00f3tesis","Rob\u00f3tica","Roly Mamani","STEM","Tecnolog\u00eda"],"articleSection":["Salud","Tecnolog\u00eda cient\u00edfica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/","url":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/","name":"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg","datePublished":"2022-06-09T14:00:00+00:00","dateModified":"2023-01-24T14:57:59+00:00","description":"Richard Vargas lleg\u00f3 con dos amputaciones de antebrazo. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg","width":1280,"height":960,"caption":"Don Felipe, a man from a province very far from La Paz, arrives to receive his prostheses from Roly Mamani | Photo courtesy of"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/06\/09\/ingeniero-en-bolivia-produce-protesis-para-los-pobres-e-inspira-a-los-jovenes-en-stem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Ingeniero en Bolivia produce pr\u00f3tesis para los pobres e inspira a los j\u00f3venes en STEM"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/9c9c480f650a22a0d16907726ab1c99a","name":"Iv\u00e1n Portillo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Iv\u00e1n Portillo"},"description":"Journalist specializing in animation.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/ivoportillo"],"url":"https:\/\/orato.world\/es\/author\/ivan-portillo\/"}]}},"modified_by":"Aurelie Msiza","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",533,400,false],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/export202205202126279670-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Iv\u00e1n Portillo","author_link":"https:\/\/orato.world\/es\/author\/ivan-portillo\/"},"uagb_comment_info":0,"uagb_excerpt":"Nuestro primer paciente, Richard Vargas, lleg\u00f3 con dos amputaciones de antebrazo. Trabajamos para encontrar una soluci\u00f3n. En el momento en que le colocamos las pr\u00f3tesis, la magia llen\u00f3 el aire. De repente no ve\u00edas a una persona a la que le faltaban partes de su cuerpo, ve\u00edas a alguien con el potencial de estar mental&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/40506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/119"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=40506"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/40506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/40298"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=40506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=40506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=40506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}