{"id":41412,"date":"2022-06-15T04:19:12","date_gmt":"2022-06-15T11:19:12","guid":{"rendered":"https:\/\/orato.world\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/"},"modified":"2023-01-24T06:28:48","modified_gmt":"2023-01-24T14:28:48","slug":"esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/","title":{"rendered":"Esposa muere de COVID-19 tras dar a luz en Honduras"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/IMG_6453-500x500.jpeg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Luis Maldonado\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-500x500.jpeg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-300x300.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-1024x1024.jpeg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-100x100.jpeg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-770x770.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-150x150.jpeg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-70x70.jpeg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-293x293.jpeg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-390x390.jpeg 390w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-585x585.jpeg 585w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453-900x900.jpeg 900w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6453.jpeg 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.facebook.com\/lmaldonadofotografo\">Luis Maldonado es un fot\u00f3grafo hondure\u00f1o de 34 a\u00f1os<\/a> que perdi\u00f3 a su esposa a causa del Covid-19. Su esposa falleci\u00f3 despu\u00e9s de dar a luz a su segunda hija en agosto de 2021.<br><br>Luis tiene dos hijas, Darah (5 a\u00f1os) y Hanna (9 meses).<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">De enero a septiembre de 2021, Honduras registr\u00f3 alrededor de 100 muertes de mujeres embarazadas a consecuencia del Covid-19. Algunos sectores del pa\u00eds atribuyeron las muertes a que los pacientes no estaban vacunados.<br><br>En tanto, seg\u00fan Carissa F. Etienne, directora de la Organizaci\u00f3n Panamericana de la Salud (OPS), la falta de acceso a una atenci\u00f3n oportuna y la interrupci\u00f3n de los servicios prenatales son responsables del aumento de la mortalidad materna en las Am\u00e9ricas. <a href=\"https:\/\/www.paho.org\/es\/noticias\/2-3-2022-tercio-embarazadas-con-covid-19-no-pudo-acceder-tiempo-cuidados-criticos-que\">Durante la pandemia, una de cada tres mujeres embarazadas no pudo acceder a una atenci\u00f3n cr\u00edtica oportuna.<\/a><\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">SAN PEDRO SULA, Honduras \ua7f7 Era un lunes en medio de la niebla de la pandemia de <a href=\"https:\/\/orato.world\/es\/tag\/covid-19-es\/\">COVID-19.<\/a> Mi esposa embarazada comenz\u00f3 a mostrar s\u00edntomas de tener un resfriado. Le escribimos una nota a su ginec\u00f3logo y ella le recet\u00f3 un tratamiento. Para el martes, aparecieron fiebre y tos leve. No me gust\u00f3 lo que estaba viendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, llev\u00e9 a mi esposa a hacerse la prueba y dio positivo por COVID-19. Comenzamos la cuarentena y el miedo se apoder\u00f3 de m\u00ed. La curva de contagios en Honduras se mantuvo alta. Los centros de atenci\u00f3n estaban saturados de pacientes e incluso los hospitales privados ofrec\u00edan poco espacio. Empezamos a tratarla en casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-mujer-probablemente-contrajo-covid-19-de-un-taxista-sin-mascara\">La mujer probablemente contrajo COVID-19 de un taxista sin m\u00e1scara<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando el COVID-19 golpe\u00f3 a Honduras y el pa\u00eds entr\u00f3 en confinamiento, mi esposa Susely y yo disfrutamos el tiempo juntos como pareja. Nuestra relaci\u00f3n se hizo m\u00e1s fuerte cada d\u00eda. Trabajo como fot\u00f3grafa profesional y Susely se convirti\u00f3 en mi mano derecha. Hicimos un equipo extraordinario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la pandemia, qued\u00f3 embarazada. Ante la noticia de los primeros casos de Coronavirus en nuestro pa\u00eds, extremamos la precauci\u00f3n. Ella y mi hija Darah nunca sal\u00edan de casa. Cuando Susely qued\u00f3 embarazada, duplicamos nuestras precauciones. Cuando contrajo el virus, ten\u00eda poca idea de c\u00f3mo lo contrajo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/orato.world\/wp-content\/uploads\/IMG_6454-819x1024.jpg\" alt=\"\" class=\"wp-image-40771\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6454-819x1024.jpg 819w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6454-240x300.jpg 240w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6454-770x963.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6454-293x366.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6454.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Luis Maldonado con su esposa Susely y su hija Darah | <strong>Foto cortes\u00eda de Luis Maldonado-Fot\u00f3grafo<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mirando hacia atr\u00e1s, una cosa se destaca. El jueves por la tarde salimos de casa con nuestra hija para ir a la iglesia. Caminamos hasta all\u00ed para dejar una ofrenda especial. De regreso a casa, se hizo de noche y le pregunt\u00e9 a Susely si quer\u00eda regresar a pie o en taxi. En el momento en que respondi\u00f3 que quer\u00eda caminar a casa, ya hab\u00eda hecho se\u00f1as a un taxi. Ten\u00eda 33 semanas de embarazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella y Darah subieron al auto. Cuando sub\u00ed, me sorprendi\u00f3 ver al conductor sin m\u00e1scara. El miedo me llen\u00f3. Poco tiempo despu\u00e9s, me encontr\u00e9 contando los d\u00edas entre ese viaje en taxi y la aparici\u00f3n de los s\u00edntomas de Susely.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mujer embarazada se enferma cada vez m\u00e1s de COVID-19, busca ayuda<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cada tres horas med\u00e1mos su ox\u00edgeno. El jueves y viernes sus niveles eran normales, pero el s\u00e1bado por la ma\u00f1ana su saturaci\u00f3n de ox\u00edgeno baj\u00f3 de 96 a 92. Ese mismo d\u00eda la llev\u00e9 a la maternidad. La revisaron y me dijeron que estaba bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Continu\u00e9 preocup\u00e1ndome. Unos amigos que son m\u00e9dicos me dijeron que me hiciera un examen de pecho. Descubr\u00ed que uno de los pulmones de Susely estaba afectado en un 40 por ciento y el otro en un 20 por ciento. Esta vez, la llev\u00e9 a triaje, pero no recibi\u00f3 prioridad del hospital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un m\u00e9dico mir\u00f3 los ex\u00e1menes pero me dijo que no ten\u00edan espacio para ella. El m\u00e9dico nos dese\u00f3 buena suerte y me di\u00f3 los resultados. Toqu\u00e9 fondo. Haciendo un esfuerzo sobrehumano por mantener la calma, Susely no pudo ver las l\u00e1grimas que llenaban mis ojos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De regreso en el auto, se subi\u00f3 al asiento trasero y comenc\u00e9 a llorar. Me sent\u00ed impotente para salvar al amor de mi vida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tras dar a luz prematuramente, mujer muere por COVID-19<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Llegamos a otro triaje. Esta vez me dijeron que llevara a Susely a la maternidad y dijera que ten\u00eda dolores de parto. De esta manera no pod\u00edan negar su cuidado. El plan funcion\u00f3 y la admitieron el domingo por la ma\u00f1ana temprano. Desear\u00eda haberlo pensado antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El lunes por la ma\u00f1ana los m\u00e9dicos dijeron que realizar\u00edan una ces\u00e1rea. Cuando Susely entr\u00f3 a la sala de operaciones, mi mam\u00e1, mi cu\u00f1ada y yo nos quedamos despiertos, orando a Dios por un milagro. Mi hija Hannah naci\u00f3 34 semanas antes de tiempo y no necesitaba ox\u00edgeno ni incubadora. Dios contest\u00f3 una oraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, el martes, llegar\u00eda a ver a mi esposa. No pod\u00eda esperar para decirle lo orgulloso que estaba de su valent\u00eda. Aunque estaba demasiado d\u00e9bil para hablar, sab\u00eda que ver\u00eda su respuesta en sus ojos. Fui a casa a ducharme y a las 9:30 sal\u00eda para ver a Susely en el hospital. El tel\u00e9fono son\u00f3. El personal del hospital me dijo que mi esposa hab\u00eda muerto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Padre le cuenta a su hija que mami muri\u00f3<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sent\u00ed como si todo mi cuerpo se paralizara. No puedo recordar lo que le dije a la persona por tel\u00e9fono que me dio la peor noticia de mi vida. Me encontr\u00e9 detr\u00e1s del volante, cruzando la calle hacia el hospital como por inercia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/orato.world\/wp-content\/uploads\/IMG_6456-1024x683.jpg\" alt=\"\" class=\"wp-image-40774\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-1024x683.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-300x200.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-770x513.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-1536x1024.jpg 1536w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-360x240.jpg 360w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-1155x770.jpg 1155w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-370x247.jpg 370w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-293x195.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456-1400x933.jpg 1400w, https:\/\/orato.world\/wp-content\/uploads\/\/IMG_6456.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Luis Maldonado con sus hijas Darah y Hanna | <strong>Foto cortes\u00eda de Luis Maldonado-Fot\u00f3grafo<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Me detuve, llor\u00e9 y segu\u00ed por el camino hasta llegar al lugar donde hab\u00edan confluido la vida y la muerte; donde celebr\u00e9 el nacimiento de mi hija y lament\u00e9 la muerte de mi esposa. Pens\u00e9, Dios, dame fuerzas porque no puedo con esto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi hija mayor, Darah, ten\u00eda cuatro a\u00f1os. Contarle la noticia result\u00f3 intensamente dif\u00edcil. M\u00e1s tarde, en el cementerio, le dije a Darah que su mam\u00e1 se fue al cielo. Ella me mir\u00f3 y pregunt\u00f3: \u00ab\u00bfMam\u00e1 muri\u00f3?\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sent\u00ed como si algo me apretara el pecho; como si estuviera viviendo dentro de una pesadilla. Las l\u00e1grimas de Darah se unieron a las m\u00edas cuando la abrac\u00e9. Nos quedamos uno al lado del otro. Consol\u00e9 a Darah incluso cuando mi propio coraz\u00f3n se estaba rompiendo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Familia sobrevive a pesar del dolor<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde ese momento, sobrevivimos con el apoyo y el amor de mi familia y la de Susely. Me ayudan a cuidar a las ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tantas noches, llor\u00e9 despu\u00e9s de que Darah se fue a dormir. Aunque muestra fortaleza, Darah necesita saber d\u00f3nde estoy en todo momento. Ella necesita que le aseguremos regularmente que no la dejar\u00e9. A veces, me dice que siente el abrazo de su madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con todo el dolor de la ausencia de Susely, crece mi inspiraci\u00f3n al disfrutar a mis hijas. Cuido de Hannah de la misma manera que vi a mi esposa cuidar a Darah. No puedo reemplazar a Susely y nunca me considerar\u00e9 tan buen padre como lo fue Susely como madre; pero me pasar\u00e9 la vida d\u00e1ndole a mis hijas todo el amor que se merecen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada tres horas med\u00edamos su ox\u00edgeno. El jueves y viernes sus niveles eran normales, pero el s\u00e1bado por la ma\u00f1ana su saturaci\u00f3n de ox\u00edgeno baj\u00f3 de 96 a 92.<\/p>\n","protected":false},"author":143,"featured_media":40766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[188,190],"tags":[1788,194,3220,3116,2214,3219,3221],"class_list":["post-41412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","category-virus","tag-covid-es","tag-covid-19-es","tag-fotografo","tag-honduras-es","tag-latinoamerica","tag-muerte-por-covid","tag-prematura"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Esposa muere de COVID-19 tras dar a luz en Honduras<\/title>\n<meta name=\"description\" content=\"El jueves y viernes sus niveles de ox\u00edgeno eran normales. Para el s\u00e1bado, la saturaci\u00f3n de ox\u00edgeno baj\u00f3 a 92. Dio a luz y luego muri\u00f3 de COVID-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esposa muere de COVID-19 tras dar a luz en Honduras\" \/>\n<meta property=\"og:description\" content=\"Cada tres horas med\u00edamos su ox\u00edgeno. El jueves y viernes sus niveles eran normales, pero el s\u00e1bado por la ma\u00f1ana su saturaci\u00f3n de ox\u00edgeno baj\u00f3 de 96 a 92.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-15T11:19:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-24T14:28:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"953\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Xochilth Salome Rodriguez Garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Xochilth Salome Rodriguez Garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/\"},\"author\":{\"name\":\"Xochilth Salome Rodriguez Garcia\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/92873e46eb18924144f50f91de1ef175\"},\"headline\":\"Esposa muere de COVID-19 tras dar a luz en Honduras\",\"datePublished\":\"2022-06-15T11:19:12+00:00\",\"dateModified\":\"2023-01-24T14:28:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/\"},\"wordCount\":1112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/couple.jpeg\",\"keywords\":[\"Covid\",\"Covid-19\",\"Fot\u00f3grafo\",\"Honduras\",\"Latinoam\u00e9rica\",\"muerte por covid\",\"Prematura\"],\"articleSection\":[\"Salud\",\"Virus\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/\",\"name\":\"Esposa muere de COVID-19 tras dar a luz en Honduras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/couple.jpeg\",\"datePublished\":\"2022-06-15T11:19:12+00:00\",\"dateModified\":\"2023-01-24T14:28:48+00:00\",\"description\":\"El jueves y viernes sus niveles de ox\u00edgeno eran normales. Para el s\u00e1bado, la saturaci\u00f3n de ox\u00edgeno baj\u00f3 a 92. Dio a luz y luego muri\u00f3 de COVID-19.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/couple.jpeg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/couple.jpeg\",\"width\":953,\"height\":715,\"caption\":\"Luis Maldonado and his wife Susely on their wedding day | Photo courtesy of\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/06\\\/15\\\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esposa muere de COVID-19 tras dar a luz en Honduras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/92873e46eb18924144f50f91de1ef175\",\"name\":\"Xochilth Salome Rodriguez Garcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Xochilth Salome Rodriguez Garcia\"},\"description\":\"Honduran journalist with more than 12 years of experience in the media. A communication and advertising sciences graduate of the University of San Pedro Sulha, Xochilth has worked on different radio and television channels and taught at the university level. She currently collaborates as an editor of a digital newspaper.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/xochilth-salome-rodriguez-garcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Esposa muere de COVID-19 tras dar a luz en Honduras","description":"El jueves y viernes sus niveles de ox\u00edgeno eran normales. Para el s\u00e1bado, la saturaci\u00f3n de ox\u00edgeno baj\u00f3 a 92. Dio a luz y luego muri\u00f3 de COVID-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/","og_locale":"es_ES","og_type":"article","og_title":"Esposa muere de COVID-19 tras dar a luz en Honduras","og_description":"Cada tres horas med\u00edamos su ox\u00edgeno. El jueves y viernes sus niveles eran normales, pero el s\u00e1bado por la ma\u00f1ana su saturaci\u00f3n de ox\u00edgeno baj\u00f3 de 96 a 92.","og_url":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-06-15T11:19:12+00:00","article_modified_time":"2023-01-24T14:28:48+00:00","og_image":[{"width":953,"height":715,"url":"https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg","type":"image\/jpeg"}],"author":"Xochilth Salome Rodriguez Garcia","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Xochilth Salome Rodriguez Garcia","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/"},"author":{"name":"Xochilth Salome Rodriguez Garcia","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/92873e46eb18924144f50f91de1ef175"},"headline":"Esposa muere de COVID-19 tras dar a luz en Honduras","datePublished":"2022-06-15T11:19:12+00:00","dateModified":"2023-01-24T14:28:48+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/"},"wordCount":1112,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg","keywords":["Covid","Covid-19","Fot\u00f3grafo","Honduras","Latinoam\u00e9rica","muerte por covid","Prematura"],"articleSection":["Salud","Virus"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/","url":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/","name":"Esposa muere de COVID-19 tras dar a luz en Honduras","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg","datePublished":"2022-06-15T11:19:12+00:00","dateModified":"2023-01-24T14:28:48+00:00","description":"El jueves y viernes sus niveles de ox\u00edgeno eran normales. Para el s\u00e1bado, la saturaci\u00f3n de ox\u00edgeno baj\u00f3 a 92. Dio a luz y luego muri\u00f3 de COVID-19.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg","width":953,"height":715,"caption":"Luis Maldonado and his wife Susely on their wedding day | Photo courtesy of"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/06\/15\/esposa-muere-de-covid-19-tras-dar-a-luz-en-honduras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Esposa muere de COVID-19 tras dar a luz en Honduras"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/92873e46eb18924144f50f91de1ef175","name":"Xochilth Salome Rodriguez Garcia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Xochilth Salome Rodriguez Garcia"},"description":"Honduran journalist with more than 12 years of experience in the media. A communication and advertising sciences graduate of the University of San Pedro Sulha, Xochilth has worked on different radio and television channels and taught at the university level. She currently collaborates as an editor of a digital newspaper.","url":"https:\/\/orato.world\/es\/author\/xochilth-salome-rodriguez-garcia\/"}]}},"modified_by":"Aurelie Msiza","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",953,715,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/couple-100x100.jpeg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/couple-300x225.jpeg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/couple-770x578.jpeg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",640,480,false],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",953,715,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",953,715,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",533,400,false],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/couple-360x240.jpeg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/couple.jpeg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/couple-500x500.jpeg",500,500,true]},"uagb_author_info":{"display_name":"Xochilth Salome Rodriguez Garcia","author_link":"https:\/\/orato.world\/es\/author\/xochilth-salome-rodriguez-garcia\/"},"uagb_comment_info":0,"uagb_excerpt":"Cada tres horas med\u00edamos su ox\u00edgeno. El jueves y viernes sus niveles eran normales, pero el s\u00e1bado por la ma\u00f1ana su saturaci\u00f3n de ox\u00edgeno baj\u00f3 de 96 a 92.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/41412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=41412"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/41412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/40766"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=41412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=41412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=41412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}