{"id":50193,"date":"2022-09-05T04:42:17","date_gmt":"2022-09-05T11:42:17","guid":{"rendered":"https:\/\/orato.world\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/"},"modified":"2022-09-08T07:51:01","modified_gmt":"2022-09-08T14:51:01","slug":"una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/","title":{"rendered":"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-500x500.jpeg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Rheanna Cartier\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-500x500.jpeg 500w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-300x300.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-1024x1024.jpeg 1024w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-100x100.jpeg 100w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-770x770.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-150x150.jpeg 150w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-70x70.jpeg 70w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-293x293.jpeg 293w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-390x390.jpeg 390w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-585x585.jpeg 585w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub-900x900.jpeg 900w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-sub.jpeg 1184w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Rheanna Cartier es una modelo y estudiante de Cotswolds, un distrito de Gloucestershire de Inglaterra. Se present\u00f3 como candidata a Miss Inglaterra 2022, luego fue finalista y fue coronada como Miss Cotswolds. Actualmente, estudia Derecho en la Open University, donde compagina su carrera universitaria con el modelaje.<br>La Srta. Cartier empez\u00f3 a ejercer de modelo a los 17 a\u00f1os y desde entonces ha desfilado por varias pasarelas, convirti\u00e9ndose en uno de los rostros de las marcas de ropa. Modela para Holland Cooper Clothing y ostenta el t\u00edtulo de Miss Bare Face para Top Model England 2021.<br><\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">CONTEXTO<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Dos tercios de las escuelas del Reino Unido utilizan salas de aislamiento o espacios de intervenci\u00f3n como forma de castigo a los alumnos. Alumnos de tan s\u00f3lo cinco a\u00f1os son internados en estas salas por comportamientos no deseados. Es una soluci\u00f3n inmediata que las autoridades escolares creen que puede cambiar su comportamiento, pero tiene un efecto a largo plazo en estos estudiantes. Las autoridades escolares colocan a estas j\u00f3venes mentes en reclusi\u00f3n hasta cinco d\u00edas seguidos, e incluso m\u00e1s. Estas mentes j\u00f3venes pasan la mayor parte de su tiempo escolar en aislamiento que en el aprendizaje en clase.<br>El hecho de que los alumnos se vean privados del aprendizaje en clase y separados de sus compa\u00f1eros puede provocar problemas de salud mental. Estas salas de aislamiento suelen estar completamente separadas de las aulas. Las salas se denominan \u00abcabinas de consecuencias\u00bb, \u00abunidades de inclusi\u00f3n\u00bb, \u00absalas de calma\u00bb, \u00abespacios de tiempo muerto\u00bb y otros nombres similares. Las escuelas las etiquetan para utilizarlas como un m\u00e9todo de intervenci\u00f3n de gesti\u00f3n del comportamiento que les da tiempo para hacer otras tareas.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">COTSWOLDS, Inglaterra \ua7f7 A los 13 a\u00f1os, camin\u00e9 por los pasillos de mi nueva escuela en mi primer d\u00eda. Un grupo de chicas un a\u00f1o mayores que yo empezaron a gritar nombres repugnantes. Me llamaron \u00abslag\u00bb (palabra brit\u00e1nica que significa \u00abputa\u00bb), entre otras cosas. Durante las vacaciones de verano, un chico popular de su curso me hab\u00eda enviado un mensaje. Pens\u00e9 que deb\u00edan estar molestas porque les gustaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pronto se unieron otras chicas, y se unieron a m\u00ed. Me sorprend\u00ed cuando reconoc\u00ed a una de las chicas. Aunque hac\u00eda a\u00f1os que no nos ve\u00edamos, fuimos juntas a la guarder\u00eda y nuestras madres hab\u00edan sido amigas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo del d\u00eda, vi a las chicas muchas m\u00e1s veces. La gente escuchaba sus comentarios y se re\u00eda mientras mi verg\u00fcenza aumentaba. Sent\u00eda que todo el mundo me se\u00f1alaba.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-from-bullied-to-isolated\"><h2>Del acoso al aislamiento<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ese a\u00f1o, los rumores sobre m\u00ed circulaban por la <a href=\"https:\/\/orato.world\/?s=school\">escuela.<\/a> Todos los d\u00edas, durante el recreo, me met\u00eda en el ba\u00f1o para no ver a nadie. Empec\u00e9 a temblar y a tener migra\u00f1as, sinti\u00e9ndome siempre inc\u00f3moda. Un d\u00eda, la chica que hab\u00eda conocido de peque\u00f1a comparti\u00f3 informaci\u00f3n personal sobre m\u00ed. Fue la gota que colm\u00f3 el vaso y arremet\u00ed contra ella. Me pele\u00e9 con cinco o seis chicas mayores; no pod\u00eda creer lo que hab\u00eda hecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes, hab\u00eda contado a los profesores mis circunstancias. Les dije c\u00f3mo afectaba a mis tareas y c\u00f3mo empezaba a odiar la escuela, pero no hicieron nada. A nadie le import\u00f3. Despu\u00e9s de la pelea, me convocaron a una reuni\u00f3n con los profesores y los \u00abjefes de curso\u00bb. Sent\u00ed p\u00e1nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abr\u00ed la puerta y pregunt\u00e9 si ten\u00eda que entrar, luego me qued\u00e9 en silencio. Al poco tiempo, la chica y sus amigas llegaron golpeando la puerta de la recepci\u00f3n. Gritaron: \u00abTe voy a matar, joder. Eres un puto ciervo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de eso, los funcionarios de la escuela me pusieron en una sala de aislamiento. En el almuerzo, me sentaba sola. Me parec\u00eda un castigo, pero tambi\u00e9n me ayudaba a evitar a la gente. De vez en cuando, alg\u00fan otro estudiante ven\u00eda a la sala, como un chico que estaba castigado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Iba a mis clases pero nunca hac\u00eda mi tarea. Los profesores me rega\u00f1aban. Las normas de algunos colegios ingleses pueden ser extremas. En este colegio, te pod\u00edan castigar por olvidar simplemente un bol\u00edgrafo. Adem\u00e1s, seg\u00fan el sistema de clasificaci\u00f3n de los colegios del Reino Unido, \u00e9ste estaba clasificado bajo \u00abmedidas especiales\u00bb, la peor calificaci\u00f3n posible. Informes como el de que alguien es v\u00edctima de acoso escolar podr\u00edan cerrarlos. As\u00ed que nadie me ayud\u00f3. Los alumnos tem\u00edan ser castigados y los empleados de la escuela tem\u00edan ser sancionados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Los agresores se intensifican y la v\u00edctima es expulsada<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un d\u00eda, me quit\u00e9 la chaqueta y un profesor me sigui\u00f3. Me indic\u00f3 que me la volviera a poner. Un grupo de chicas empez\u00f3 a gritarme. El profesor lo oy\u00f3 todo y no hizo nada, as\u00ed que sal\u00ed corriendo. En mi siguiente clase, me pregunt\u00f3: \u00ab\u00bfPor qu\u00e9 has salido corriendo cuando te estaba hablando?\u00bb, como si no hubiera pasado nada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de entonces, acab\u00e9 metida en m\u00e1s y m\u00e1s problemas. Perd\u00ed todo el respeto por los profesores. A los 13 a\u00f1os, llevaba una inmensa cantidad de estr\u00e9s en el est\u00f3mago. Siempre ten\u00eda ganas de llorar y deseaba que la tierra me tragara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A menudo terminaba en aislamiento, a veces durante una semana. Al final de la semana, cuando llegaba el momento de volver a casa con mi familia, me liberaban.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde las 8:00 hasta las 15:05, me quedaba en esa habitaci\u00f3n. Pod\u00eda salir para ir al ba\u00f1o con supervisi\u00f3n. Si no llevaba mi almuerzo, no com\u00eda. Me sent\u00eda atrapada y frustrada. Muchos d\u00edas deseaba estar en una nueva escuela con amigos y sentirme normal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las reuniones con el director, el jefe de curso y el director de la escuela eran frecuentes. A veces asist\u00eda mi madre. Durante meses y meses, no dej\u00e9 de decir lo que hab\u00eda sucedido y de hablar de las chicas, pero parec\u00eda ser contraproducente. La gente me perd\u00eda el respeto, e incluso los ni\u00f1os m\u00e1s peque\u00f1os se sumaban. Les ayudaba a sentirse m\u00e1s poderosos y a ganar popularidad. Al final, los responsables del colegio quer\u00edan expulsarme.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Una nueva escuela, un nuevo comienzo y una nueva carrera<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Me acord\u00e9 de cuando busqu\u00e9 en Google la escuela antes de empezar all\u00ed. Record\u00e9 haber le\u00eddo una especie de petici\u00f3n sobre el acoso escolar y haber visto que algunos alumnos se hab\u00edan suicidado. Mi madre ya no me quer\u00eda all\u00ed. Despu\u00e9s de ser expulsada, no pod\u00eda ir a otro colegio ni permitirme uno privado.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"972\" height=\"729\" src=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-1.jpeg\" alt=\"\" class=\"wp-image-49540\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-1.jpeg 972w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-1-300x225.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-1-770x578.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-1-293x220.jpeg 293w\" sizes=\"auto, (max-width: 972px) 100vw, 972px\" \/><figcaption>Rheanna Cartier en un desfile | <strong>Foto cortes\u00eda de Rheanna Cartier<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Mi madre habl\u00f3 con un amigo dan\u00e9s que nos habl\u00f3 de una escuela asequible en Dinamarca. La buscamos y cuando mi madre me pregunt\u00f3 qu\u00e9 quer\u00eda, le dije que quer\u00eda empezar de nuevo. Completamos la inscripci\u00f3n, participamos en una llamada de Skype y me traslad\u00e9 all\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los 14 a\u00f1os, muchos de mis compa\u00f1eros del nuevo colegio eran mayores que yo, y crec\u00ed r\u00e1pidamente. Vi una cita que dec\u00eda que la vida es un 10% de lo que te ocurre y un 90% de c\u00f3mo lo afrontas. Al estar rodeada de gente m\u00e1s madura, decid\u00ed utilizar la experiencia de forma positiva. Me hice m\u00e1s fuerte; aprend\u00ed que la gente suele decir cosas que no son ciertas. Ahora, cuando la gente habla de otros o inicia rumores, nunca participo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los 16 a\u00f1os me inici\u00e9 en el mundo del modelaje. Despu\u00e9s de unas cuantas sesiones, me apunt\u00e9 a una agencia y pas\u00e9 a la ense\u00f1anza en l\u00ednea. Cuando fui a mi primera <a href=\"https:\/\/orato.world\/es\/2021\/04\/27\/nadador-paralimpico-se-convierte-en-modelo-y-rompe-los-estereotipos\/\">sesi\u00f3n profesiona<\/a>l, el nerviosismo me invadi\u00f3. No ten\u00eda ni idea de qu\u00e9 hacer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fot\u00f3grafo me dio instrucciones y, aunque ten\u00eda poca confianza, lo disfrut\u00e9. Despu\u00e9s de unas cinco sesiones, encontr\u00e9 mi ritmo y empez\u00f3 a gustarme llevar ropa diferente y conocer gente nueva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>Contando su historia y retribuyendo<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El modelaje me ayud\u00f3 mucho porque ya casi no soy t\u00edmida. Los pasatiempos pueden ayudar a despejar tu mente y el modelaje me hizo dar cuenta de que no soy esa cosa horrible que dec\u00edan que era. Ahora, a los 19 a\u00f1os, soy modelo para una popular marca llamada Holland Cooper.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1022\" height=\"767\" src=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-2.jpeg\" alt=\"\" class=\"wp-image-49542\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-2.jpeg 1022w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-2-300x225.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-2-770x578.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/rheanna-pic-2-293x220.jpeg 293w\" sizes=\"auto, (max-width: 1022px) 100vw, 1022px\" \/><figcaption>Rheanna Cartier modelando para Holland Cooper | <strong>Foto cortes\u00eda de Rheanna Cartier<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los chicos con los que fui a la escuela en aquel entonces siguen su <a href=\"https:\/\/www.instagram.com\/hollandcooperclothing\/?hl=en\">p\u00e1gina de Instagram<\/a>, pero no es que pienso demasiado en ello. Se siente bien tener confianza en mi misma ahora; tener una carrera, aficiones y amigos en todo el mundo. Hace poco me fui de viaje de esqu\u00ed por primera vez. Me toc\u00f3 ir a un intercambio de dos semanas a Vietnam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque el acoso que sufr\u00ed fue horrible, al final del viaje crec\u00ed gracias a \u00e9l. Segu\u00ed adelante, pero eso no es cierto para todo el mundo. Cuando alguien sufre acoso, puede arruinar toda su vida y frenar su educaci\u00f3n. Puede que nunca hagan lo que quieren, por miedo. Eso, para m\u00ed, es un crimen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuento mi historia para que otros ni\u00f1os puedan hablar del acoso y para que las escuelas puedan hacer campa\u00f1as. Si no hubiera ido a Dinamarca, probablemente mi vida se habr\u00eda arruinado. Las escuelas tienen que hacer m\u00e1s para apoyar a las v\u00edctimas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gente dice cosas desagradables porque ellos mismos son infelices. Ven a otras personas felices y quieren arruinarlas. Ahora, cuando la gente dice cosas horribles, me r\u00edo. Nunca he cambiado lo que soy y estoy agradecida por ello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando me acosaron y aislaron en mi escuela, me sent\u00ed ansiosa, desmotivada y extremadamente t\u00edmida. Aunque todav\u00eda puedo ser callada e introvertida, hoy soy una persona segura de s\u00ed misma. Antes me resultaba casi imposible establecer contacto visual con la gente, hablar con la gente en p\u00fablico, y hablaba en un susurro. Seis a\u00f1os despu\u00e9s, tengo esperanza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque el acoso que sufr\u00ed fue horrible, al final del viaje crec\u00ed gracias a \u00e9l. Segu\u00ed adelante, pero eso no sucede con todo el mundo. <\/p>\n","protected":false},"author":160,"featured_media":49537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,261],"tags":[3921,3060,3923,538,979,3922,727,3484],"class_list":["post-50193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-sexo-y-genero","tag-acoso","tag-europa","tag-inglaterra","tag-mental-health-es","tag-modelo","tag-reino-unido","tag-school-es","tag-sobreviviente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rheanna Cartier soport\u00f3 el bullying y se convierte en modelo<\/title>\n<meta name=\"description\" content=\"Rheanna Cartier, de 17 a\u00f1os, del Reino Unido, habla de haber soportado el acoso escolar y de haberse convertido en modelo para marcas como Holland Cooper.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas\" \/>\n<meta property=\"og:description\" content=\"Aunque el acoso que sufr\u00ed fue horrible, al final del viaje crec\u00ed gracias a \u00e9l. Segu\u00ed adelante, pero eso no sucede con todo el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-05T11:42:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T14:51:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1247\" \/>\n\t<meta property=\"og:image:height\" content=\"935\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Buid\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Buid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/\"},\"author\":{\"name\":\"George Buid\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/d13d9158bf76028624e46c550916e49f\"},\"headline\":\"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas\",\"datePublished\":\"2022-09-05T11:42:17+00:00\",\"dateModified\":\"2022-09-08T14:51:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/\"},\"wordCount\":1432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/rheanna-featured.jpeg\",\"keywords\":[\"Acoso\",\"Europa\",\"Inglaterra\",\"Mental health\",\"Modelo\",\"Reino Unido\",\"school\",\"Sobreviviente\"],\"articleSection\":[\"Conflicto\",\"Sexo y g\u00e9nero\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/\",\"name\":\"Rheanna Cartier soport\u00f3 el bullying y se convierte en modelo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/rheanna-featured.jpeg\",\"datePublished\":\"2022-09-05T11:42:17+00:00\",\"dateModified\":\"2022-09-08T14:51:01+00:00\",\"description\":\"Rheanna Cartier, de 17 a\u00f1os, del Reino Unido, habla de haber soportado el acoso escolar y de haberse convertido en modelo para marcas como Holland Cooper.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/rheanna-featured.jpeg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/rheanna-featured.jpeg\",\"width\":1247,\"height\":935,\"caption\":\"Rheanna Cartier took to modeling at the age of 17 and has come a long way since | Photo Courtesy of Rheanna Cartier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/05\\\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/d13d9158bf76028624e46c550916e49f\",\"name\":\"George Buid\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"George Buid\"},\"description\":\"George Buid is an independent photographer and journalist based in Metro Manila, Philippines. His work has been published in Stern Crime, Transcontinental Times, InterAksyon, and Deutsche Welle news. He also contributes to the news wire Zuma Press. In addition to writing journalism, George is a self-taught photographer who started his photojournalism career and visual documentary storytelling in 2014. He focuses on capturing stories of everyday individuals, communities, and culture. Occassionally, he also covers science, history, sports, politics, art, and human interest.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/george-buid\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rheanna Cartier soport\u00f3 el bullying y se convierte en modelo","description":"Rheanna Cartier, de 17 a\u00f1os, del Reino Unido, habla de haber soportado el acoso escolar y de haberse convertido en modelo para marcas como Holland Cooper.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/","og_locale":"es_ES","og_type":"article","og_title":"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas","og_description":"Aunque el acoso que sufr\u00ed fue horrible, al final del viaje crec\u00ed gracias a \u00e9l. Segu\u00ed adelante, pero eso no sucede con todo el mundo.","og_url":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-09-05T11:42:17+00:00","article_modified_time":"2022-09-08T14:51:01+00:00","og_image":[{"width":1247,"height":935,"url":"https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg","type":"image\/jpeg"}],"author":"George Buid","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"George Buid","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/"},"author":{"name":"George Buid","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/d13d9158bf76028624e46c550916e49f"},"headline":"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas","datePublished":"2022-09-05T11:42:17+00:00","dateModified":"2022-09-08T14:51:01+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/"},"wordCount":1432,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg","keywords":["Acoso","Europa","Inglaterra","Mental health","Modelo","Reino Unido","school","Sobreviviente"],"articleSection":["Conflicto","Sexo y g\u00e9nero"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/","url":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/","name":"Rheanna Cartier soport\u00f3 el bullying y se convierte en modelo","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg","datePublished":"2022-09-05T11:42:17+00:00","dateModified":"2022-09-08T14:51:01+00:00","description":"Rheanna Cartier, de 17 a\u00f1os, del Reino Unido, habla de haber soportado el acoso escolar y de haberse convertido en modelo para marcas como Holland Cooper.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg","width":1247,"height":935,"caption":"Rheanna Cartier took to modeling at the age of 17 and has come a long way since | Photo Courtesy of Rheanna Cartier"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/09\/05\/una-modelo-britanica-sufrio-un-terrible-acoso-escolar-y-habla-sobre-las-escuelas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Una modelo brit\u00e1nica sufri\u00f3 un terrible acoso escolar y habla sobre las escuelas"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/d13d9158bf76028624e46c550916e49f","name":"George Buid","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"George Buid"},"description":"George Buid is an independent photographer and journalist based in Metro Manila, Philippines. His work has been published in Stern Crime, Transcontinental Times, InterAksyon, and Deutsche Welle news. He also contributes to the news wire Zuma Press. In addition to writing journalism, George is a self-taught photographer who started his photojournalism career and visual documentary storytelling in 2014. He focuses on capturing stories of everyday individuals, communities, and culture. Occassionally, he also covers science, history, sports, politics, art, and human interest.","url":"https:\/\/orato.world\/es\/author\/george-buid\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",1247,935,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured-100x100.jpeg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured-300x225.jpeg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured-770x577.jpeg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured-1024x768.jpeg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",1247,935,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",1247,935,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",533,400,false],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured-360x240.jpeg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured.jpeg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/rheanna-featured-500x500.jpeg",500,500,true]},"uagb_author_info":{"display_name":"George Buid","author_link":"https:\/\/orato.world\/es\/author\/george-buid\/"},"uagb_comment_info":0,"uagb_excerpt":"Aunque el acoso que sufr\u00ed fue horrible, al final del viaje crec\u00ed gracias a \u00e9l. Segu\u00ed adelante, pero eso no sucede con todo el mundo.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/50193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=50193"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/50193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/49537"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=50193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=50193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=50193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}