{"id":52170,"date":"2022-09-18T05:00:00","date_gmt":"2022-09-18T12:00:00","guid":{"rendered":"https:\/\/orato.world\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/"},"modified":"2022-09-25T16:36:09","modified_gmt":"2022-09-25T23:36:09","slug":"paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/","title":{"rendered":"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-500x500.jpeg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Juan Ignacio Canale\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-500x500.jpeg 500w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-300x300.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-1024x1024.jpeg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-100x100.jpeg 100w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-770x770.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-1536x1536.jpeg 1536w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-2048x2048.jpeg 2048w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-150x150.jpeg 150w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-70x70.jpeg 70w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-293x293.jpeg 293w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-390x390.jpeg 390w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-585x585.jpeg 585w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-900x900.jpeg 900w, https:\/\/orato.world\/wp-content\/uploads\/Canale-con-una-falange-1400x1400.jpeg 1400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/independent.academia.edu\/JuanIgnacioCanale\" target=\"_blank\" rel=\"noreferrer noopener\">Juan Ignacio Canale<\/a> es licenciado en Biolog\u00eda con orientaci\u00f3n en Paleontolog\u00eda y doctor en Ciencias Naturales. Es investigador en el Consejo Nacional de Investigaciones Cient\u00edficas y T\u00e9cnicas <a href=\"https:\/\/www.conicet.gov.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\">(CONICET)<\/a> y el Museo Municipal de <a href=\"https:\/\/www.patagonia.com.ar\/El+Choc%C3%B3n\/200E_Villa+El+Choc%C3%B3n.html\" target=\"_blank\" rel=\"noreferrer noopener\">Villa El Choc\u00f3n<\/a>.<br><br><a href=\"https:\/\/www.researchgate.net\/profile\/Juan-Canale\" target=\"_blank\" rel=\"noreferrer noopener\">Juan I. Canale<\/a> forma parte del equipo responsable del descubrimiento de <a href=\"blank\" target=\"_blank\" rel=\"noreferrer noopener\">Meraxes Giga<\/a> en la ciudad de El Choc\u00f3n. El tema de su doctorado fue sobre los dinosaurios ter\u00f3podos y carcarodontos\u00e1uridos, grupos entre los que se encuentra ahora Meraxes Gigantis, la nueva especie que encontr\u00f3 junto a colegas de la Fundaci\u00f3n F\u00e9lix de Azara, en Buenos Aires, y de The Field Museum, en Chicago.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">CONTEXTO<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0960982222008600\" target=\"_blank\" rel=\"noreferrer noopener\">Meraxes<\/a> era un dinosaurio de unos 11 metros de largo que vivi\u00f3 hace 90 millones de a\u00f1os.<br><br>Su descubrimiento forma parte de una l<a href=\"https:\/\/www.conicet.gov.ar\/programas\/vocar\/mi-alfabeto-dinosaurios\/\">arga tradici\u00f3n de descubrimientos de restos f\u00f3siles similares en Argentina.<\/a><\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">NEUQUEN, Patagonia Argentina- Descubr\u00ed, junto a mis compa\u00f1eros de trabajo, una nueva especie de dinosaurio carn\u00edvoro. Fue uno de los momentos m\u00e1s importantes de mi carrera, y tuvo repercusi\u00f3n a nivel mundial. Lo llamamos, por sugerencia m\u00eda, Meraxes Gigantis, <a href=\"https:\/\/winteriscoming.net\/2022\/07\/13\/newly-discovered-dinosaur-named-after-meraxes-from-game-of-thrones\/\">por uno de los dragones de la saga Canci\u00f3n de hielo y fuego, que inspir\u00f3 Game of Thrones.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00edamos llegado a Ca\u00f1ad\u00f3n de Las Campanas, junto a colegas de la Fundaci\u00f3n F\u00e9lix de Azara, de Buenos Aires, y del Museo The Field, de Chicago. Queda a unos veinte kil\u00f3metros de El Choc\u00f3n, donde vivo. Pasamos la noche en una peque\u00f1a casa abandonada, donde viv\u00eda un pe\u00f3n del campo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la ma\u00f1ana siguiente caminamos cinco kil\u00f3metros hasta un cerro peque\u00f1o, que tiene una peque\u00f1a planicie de cincuenta metros por veinte. Hicimos la primera salida de prospecci\u00f3n. Nos separamos en grupos. Con el doctor Pablo Gallina nos metimos en un peque\u00f1o ca\u00f1ad\u00f3n y vimos algunos huesos de dinosaurios herb\u00edvoros de cuello largo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco m\u00e1s all\u00e1, apareci\u00f3 el cuerpo de una v\u00e9rtebra de gran tama\u00f1o partida por la mitad. Pudimos reconocerla como perteneciente a un gran dinosaurio carn\u00edvoro. Era un carcarodontos\u00e1urido, sin dudas. Buscamos de d\u00f3nde hab\u00eda venido esa v\u00e9rtebra y encontramos los primeros huesos de lo que termin\u00f3 siendo Meraxes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-paleontologos-descubren-una-nueva-especie-de-gran-dinosaurio\">Paleont\u00f3logos descubren una nueva especie de gran dinosaurio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Empezamos a excavar y salieron otros huesos, algunos muy buenos. De hecho, los huesos del brazo, que son las partes anat\u00f3micas m\u00e1s interesantes de este dinosaurio, aparecieron en los primeros d\u00edas. Muy temprano nos dimos cuenta de que era algo muy importante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El momento del hallazgo en el campo es incre\u00edble, es lo mejor de este trabajo. Hay una descarga grande de adrenalina. Adem\u00e1s, no es s\u00f3lo un momento: aparece algo, empez\u00e1s a excavar, te das cuenta de que est\u00e1 bueno, que hay m\u00e1s material, se saca, se trae al laboratorio para prepararlo y limpiarlo. Ah\u00ed aparecen m\u00e1s cosas. Uno no sabe efectivamente todo lo que se sac\u00f3, a veces nos damos cuenta reci\u00e9n en el laboratorio, cuando los t\u00e9cnicos hacen la preparaci\u00f3n de los f\u00f3siles.\r\n<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"775\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio-1024x775.jpg\" alt=\"\" class=\"wp-image-51038\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio-1024x775.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio-300x227.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio-770x583.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio-293x222.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio-1400x1060.jpg 1400w, https:\/\/orato.world\/wp-content\/uploads\/Meraxes-reconstruido-por-el-paleoartista-Carlos-Papolio.jpg 1417w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Maraxes reconstruidos por el paleoartista Carlos Papolio | <strong>Foto cortes\u00eda de Juan Ignacio Canale<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hay una tensi\u00f3n, que ya estamos acostumbrados a manejar, entre la ansiedad de querer tener los restos r\u00e1pido y no apurarse para poder sacaros limpios. No se puede sacar todo muy r\u00e1pido, ni siquiera en una misma campa\u00f1a. Llegamos a sacar casi dos metros de roca para descubrir algunos huesos de Meraxes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la primera campa\u00f1a que hicimos no ten\u00edamos herramientas pesadas. Fuimos con martillos, cinceles y pinceles. En la segunda excavaci\u00f3n, el a\u00f1o siguiente, llevamos martillos neum\u00e1ticos, generadores, cortadores de roca. Herramientas m\u00e1s pesadas para poder avanzar un poco m\u00e1s velozmente y que no sea tan pesado el trabajo.\r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primera vista supimos que era algo interesante: un dinosaurio carn\u00edvoro de gran tama\u00f1o. En esa misma formaci\u00f3n, en otros lugares de la provincia de Neuqu\u00e9n, hab\u00edan aparecido dinosaurios de este grupo. Entonces, ten\u00edamos que terminar de verificar si lo que hab\u00edamos encontrado era un nuevo ejemplar de esa especie ya conocida o si era una especie diferente. Para eso tenemos que tener todos los materiales preparados y poder comparar hueso por hueso entre ambas especies. Eso vino cuando ya tuvimos pr\u00e1cticamente todos los materiales limpios, preparados y en el laboratorio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contin\u00faan los descubrimientos que inspiran los sue\u00f1os de los j\u00f3venes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Yo empec\u00e9 a sospechar que era una nueva especie y se los coment\u00e9 a mis colegas en la segunda excavaci\u00f3n. Los huesos de la pelvis, que est\u00e1n muy bien preservados, son diferentes a los que se conocen del Mapusaurus, otro dinosaurio similar hallado en esa zona. Esa fue la primera se\u00f1al. \r\nFue otro motivo de celebraci\u00f3n porque, si bien es interesante encontrar un nuevo ejemplar de una especie ya conocida, poder darle nombre a una especie nueva es algo mucho m\u00e1s grande.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los paleont\u00f3logos somos nenes a los que nunca se les fueron las ganas, ni el gusto, ni la pasi\u00f3n por los dinos. Nos quedamos ah\u00ed. A m\u00ed me sigue encantando, asombrando el tema. Me apasiona. La posibilidad de trabajar de esto, salir a buscar y encontrar estos bichos, estudiarlos, presentarlos y darles nombres, es una satisfacci\u00f3n enorme.\r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soy de La Plata, nac\u00ed y crec\u00ed ah\u00ed. Les ped\u00eda a mis viejos siempre que me llevaran al museo de la ciudad, que es alucinante. Todo lo que hab\u00eda en ese lugar me asombraba. No sab\u00eda muy bien si lo que me gustaba m\u00e1s eran los dinosaurios o la arqueolog\u00eda, porque me interesaba cualquiera de las cosas que hab\u00eda en el museo. Cuando se estren\u00f3 Jurassic Park, en 1993, yo ten\u00eda catorce a\u00f1os. Ah\u00ed me termin\u00e9 de decidir.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-1024x768.jpg\" alt=\"\" class=\"wp-image-51040\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-1536x1152.jpg 1536w, https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-2048x1536.jpg 2048w, https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-293x220.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/Craneo-de-Meraxes-completo-reconstruccion-de-huesos-faltantes-por-Lautaro-Rodriguez-Blanco-1400x1050.jpg 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Cr\u00e1neo completo de Maraxes con reconstrucci\u00f3n de los huesos que faltan por Lautaro Rodr\u00edguez Blanco |<strong> Foto cortes\u00eda de Juan Ignacio Canale<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En El Choc\u00f3n, donde vivo y trabajo hoy, ese mismo a\u00f1o Rub\u00e9n Carolini encontr\u00f3 los restos del Giganotosaurus, un dinosaurio que fue protagonista de la \u00faltima pel\u00edcula de la saga, Jurassic World Dominion. \u00c9l era empleado de una central hidroel\u00e9ctrica, y les avis\u00f3 del hallazgo a los paleont\u00f3logos Leonardo Salgado y Rodolfo Coria. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El lugar donde trabajo es producto de ese hallazgo y de la intenci\u00f3n de la localidad de tener un lugar para poder proteger los restos y que se muestren en el sitio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El estudio de los dinosaurios despierta una curiosidad infantil<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A mi hijo m\u00e1s chico le encantan los dinosaurios, est\u00e1 obsesionado, aunque no es algo que yo haya fomentado mucho. Obviamente, le hablo y le hemos regalado cosas de dinosaurios a \u00e9l y a mi hija. Pero \u00e9l est\u00e1 enloquecido, est\u00e1 todo el tiempo hablando de eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me veo reflejado en \u00e9l, aunque en mi \u00e9poca no ten\u00edamos un acceso tan r\u00e1pido a la informaci\u00f3n. Hoy pod\u00e9s ver un video en el tel\u00e9fono, en la computadora, pero antes ten\u00eda que pedirle a mi vieja que me comprara un libro sobre el tema o ir a una biblioteca. Es incre\u00edble la fascinaci\u00f3n que producen los dinosaurios en los ni\u00f1os. Imagino que es porque se parecen a monstruos, son gigantes y, adem\u00e1s, tienen el plus de que realmente existieron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todav\u00eda nos queda much\u00edsimo por hacer con Meraxes. Lo que publicamos es un trabajo general, con algunos enfoques en temas evolutivos, describiendo la especie nueva. La publicaci\u00f3n tuvo mucha repercusi\u00f3n. Siempre una nueva especie de un dinosaurio carn\u00edvoro gigante llama la atenci\u00f3n. No s\u00f3lo eso, sino que el material est\u00e1 muy bueno, est\u00e1 muy completo. Hicimos algunas interpretaciones acerca de la evoluci\u00f3n que tiene que ver con el tama\u00f1o corporal y con el tama\u00f1o de los brazos, que eran bastante cortitos en el caso de Meraxes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Planteamos que existe una convergencia en cu\u00e1nto se reducen los brazos en estos dinosaurios carn\u00edvoros como los carcarodontos\u00e1uridos, donde est\u00e1 Meraxes, y los tiranos\u00e1uridos. Incluso en otros grupos, tambi\u00e9n. Ese tema llam\u00f3 mucho la atenci\u00f3n e hizo que el trabajo tuviera m\u00e1s repercusi\u00f3n. Tuvimos muchas consultas de colegas de varios lugares del mundo, lleg\u00f3 a todos lados. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todav\u00eda queda describir cada uno de los sectores en detalle. Las descripciones anat\u00f3micas de cada uno de los materiales, reconstrucci\u00f3n de musculatura, an\u00e1lisis de cortes histol\u00f3gicos de los huesos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empezamos a excavar y salieron otros huesos, algunos muy buenos. De hecho, los huesos del brazo, que son las partes anat\u00f3micas m\u00e1s interesantes de este dinosaurio, aparecieron en los primeros d\u00edas. Muy temprano nos dimos cuenta de que era algo muy importante.<\/p>\n","protected":false},"author":46,"featured_media":51019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[534,319,417],"tags":[193,4050,4052,4049,3044,4053,2214,4051],"class_list":["post-52170","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-galeria-de-fotos","category-medio-ambiente","category-visionarios","tag-argentina-es","tag-descubrimiento","tag-dinosaurio-carnivoro","tag-dinosaurios","tag-exclusiva","tag-juego-de-tronos","tag-latinoamerica","tag-meraxes-gigantis-es","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina<\/title>\n<meta name=\"description\" content=\"Un equipo en Argentina descubri\u00f3 una nueva especie de dinosaurio grande y carn\u00edvoro llamado Meraxes Gigantis, inspirado en Juego de Tronos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina\" \/>\n<meta property=\"og:description\" content=\"Empezamos a excavar y salieron otros huesos, algunos muy buenos. De hecho, los huesos del brazo, que son las partes anat\u00f3micas m\u00e1s interesantes de este dinosaurio, aparecieron en los primeros d\u00edas. Muy temprano nos dimos cuenta de que era algo muy importante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-18T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-25T23:36:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/\"},\"author\":{\"name\":\"Juan Martinez\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\"},\"headline\":\"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina\",\"datePublished\":\"2022-09-18T12:00:00+00:00\",\"dateModified\":\"2022-09-25T23:36:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/\"},\"wordCount\":1326,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/equipo-2013-marzo-scaled.jpg\",\"keywords\":[\"Argentina\",\"descubrimiento\",\"dinosaurio carn\u00edvoro\",\"Dinosaurios\",\"Exclusiva\",\"Juego de Tronos\",\"Latinoam\u00e9rica\",\"Meraxes Gigantis\"],\"articleSection\":[\"Galer\u00eda de fotos\",\"Medio ambiente\",\"Visionarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/\",\"name\":\"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/equipo-2013-marzo-scaled.jpg\",\"datePublished\":\"2022-09-18T12:00:00+00:00\",\"dateModified\":\"2022-09-25T23:36:09+00:00\",\"description\":\"Un equipo en Argentina descubri\u00f3 una nueva especie de dinosaurio grande y carn\u00edvoro llamado Meraxes Gigantis, inspirado en Juego de Tronos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/equipo-2013-marzo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/equipo-2013-marzo-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"The team that discovered Meraxes in the second excavation in 2013 | Photo courtesy of Juan Ignacio Canale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/09\\\/18\\\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\",\"name\":\"Juan Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"caption\":\"Juan Martinez\"},\"description\":\"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/juan-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina","description":"Un equipo en Argentina descubri\u00f3 una nueva especie de dinosaurio grande y carn\u00edvoro llamado Meraxes Gigantis, inspirado en Juego de Tronos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina","og_description":"Empezamos a excavar y salieron otros huesos, algunos muy buenos. De hecho, los huesos del brazo, que son las partes anat\u00f3micas m\u00e1s interesantes de este dinosaurio, aparecieron en los primeros d\u00edas. Muy temprano nos dimos cuenta de que era algo muy importante.","og_url":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-09-18T12:00:00+00:00","article_modified_time":"2022-09-25T23:36:09+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg","type":"image\/jpeg"}],"author":"Juan Martinez","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Juan Martinez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/"},"author":{"name":"Juan Martinez","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d"},"headline":"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina","datePublished":"2022-09-18T12:00:00+00:00","dateModified":"2022-09-25T23:36:09+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/"},"wordCount":1326,"commentCount":2,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg","keywords":["Argentina","descubrimiento","dinosaurio carn\u00edvoro","Dinosaurios","Exclusiva","Juego de Tronos","Latinoam\u00e9rica","Meraxes Gigantis"],"articleSection":["Galer\u00eda de fotos","Medio ambiente","Visionarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/","url":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/","name":"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg","datePublished":"2022-09-18T12:00:00+00:00","dateModified":"2022-09-25T23:36:09+00:00","description":"Un equipo en Argentina descubri\u00f3 una nueva especie de dinosaurio grande y carn\u00edvoro llamado Meraxes Gigantis, inspirado en Juego de Tronos","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg","width":2560,"height":1920,"caption":"The team that discovered Meraxes in the second excavation in 2013 | Photo courtesy of Juan Ignacio Canale"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/09\/18\/paleontologos-descubren-una-nueva-especie-de-dinosaurio-en-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Paleont\u00f3logos descubren una nueva especie de dinosaurio en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d","name":"Juan Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","url":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","caption":"Juan Martinez"},"description":"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.","url":"https:\/\/orato.world\/es\/author\/juan-martinez\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg",2560,1920,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-1536x1152.jpg",1536,1152,true],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-2048x1536.jpg",2048,1536,true],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg",533,400,false],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-scaled.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/equipo-2013-marzo-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Juan Martinez","author_link":"https:\/\/orato.world\/es\/author\/juan-martinez\/"},"uagb_comment_info":2,"uagb_excerpt":"Empezamos a excavar y salieron otros huesos, algunos muy buenos. De hecho, los huesos del brazo, que son las partes anat\u00f3micas m\u00e1s interesantes de este dinosaurio, aparecieron en los primeros d\u00edas. Muy temprano nos dimos cuenta de que era algo muy importante.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/52170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=52170"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/52170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/51019"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=52170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=52170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=52170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}