{"id":56406,"date":"2022-10-23T05:00:00","date_gmt":"2022-10-23T12:00:00","guid":{"rendered":"https:\/\/orato.world\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/"},"modified":"2023-01-24T03:17:47","modified_gmt":"2023-01-24T11:17:47","slug":"un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/","title":{"rendered":"Un barrendero representa a Argentina en un campeonato internacional de boxeo"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/acosta-500x500.jpeg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Miguel Acosta\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/acosta-500x500.jpeg 500w, https:\/\/orato.world\/wp-content\/uploads\/acosta-300x300.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/acosta-100x100.jpeg 100w, https:\/\/orato.world\/wp-content\/uploads\/acosta-770x770.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/acosta-150x150.jpeg 150w, https:\/\/orato.world\/wp-content\/uploads\/acosta-70x70.jpeg 70w, https:\/\/orato.world\/wp-content\/uploads\/acosta-293x293.jpeg 293w, https:\/\/orato.world\/wp-content\/uploads\/acosta-390x390.jpeg 390w, https:\/\/orato.world\/wp-content\/uploads\/acosta-585x585.jpeg 585w, https:\/\/orato.world\/wp-content\/uploads\/acosta-900x900.jpeg 900w, https:\/\/orato.world\/wp-content\/uploads\/acosta.jpeg 960w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Interview Subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/boxrec.com\/en\/box-pro\/668530\" target=\"_blank\" rel=\"noreferrer noopener\">Miguel \u00abZurdo\u00bb Acosta <\/a>discovered <a href=\"https:\/\/www.tapology.com\/fightcenter\/fighters\/205892-miguel-german-acosta\" target=\"_blank\" rel=\"noreferrer noopener\">boxing<\/a> while grappling with a weight issue and fighting in the streets. Fifteen years later, he works as a street sweeper in Argentina, but not stopped pursuing his passion. Recently, he fought at the IBO Championships in France and came close to being a <a href=\"https:\/\/www.conclusion.com.ar\/deportes\/el-boxeador-santafesino-miguel-acosta-se-consagro-campeon-latino-liviano\/03\/2018\/\" target=\"_blank\" rel=\"noreferrer noopener\">world champion<\/a>. <a href=\"https:\/\/primerlector.com.ar\/2022\/07\/05\/pascale-el-zurdito-es-una-de-las-personas-que-hacen-grande-a-vgg-y-la-fortalecen\/\" target=\"_blank\" rel=\"noreferrer noopener\">The athlete<\/a> competes within the framework of the International Boxing Organization and hopes to have more opportunities abroad.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Background Information<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.iboboxing.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">The International Boxing Organization (IBO)<\/a> is a non-profit organization that sanctions professional boxing matches and awards world and regional championships. It is recognized as a legitimate world championship organization by the <a href=\"https:\/\/www.boxebu.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">European Boxing Union<\/a> and <a href=\"https:\/\/boxrec.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">BoxRec<\/a>.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">VILLA GOBERNADOR G\u00c1LVEZ, Santa Fe, Argentina \u2013Trabajo como empleado municipal en la ciudad de Villa Gobernador G\u00e1lvez, que es donde vivo. Mi funci\u00f3n es en el servicio de limpieza y barrido y adem\u00e1s soy el encargado de organizar la log\u00edstica de las ferias de artesanos en una plaza. Cuando no trabajo para la ciudad, compito como boxeador internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comenc\u00e9 a los 15 a\u00f1os debido al sobrepeso que tuve desde los 11, que no era severo pero s\u00ed estaba excedido y necesitaba hacer actividad f\u00edsica. En aquel momento mi padre era presidente de un club de f\u00fatbol infantil y ten\u00eda la posibilidad de jugar ah\u00ed y tener algunos beneficios como que un amigo de la familia fuera mi entrenador o utilizar la camiseta que me gustaba que era la 10, pero me di cuenta temprano que eso no era lo m\u00edo.\r\n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong><a href=\"https:\/\/orato.world\/?s=boxing\">Lea m\u00e1s historias sobre boxeo de Orato.<\/a><\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Me gustaban los deportes de contacto y desde chico quise hacer boxeo pero en mi casa no me dejaban practicar. Adem\u00e1s, a medida que fui creciendo y conociendo la calle me di cuenta que ten\u00eda el problema de que sal\u00eda y quer\u00eda pelear. Ese era un problema que ten\u00eda con mi conducta y las ri\u00f1as callejera. A los 15 a\u00f1os conoc\u00ed el boxeo con un profesor que fue mi gu\u00eda y ah\u00ed logr\u00e9 empezar en el deporte y luchar contra el sobrepeso y las peleas en la calle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Eleg\u00ed reservarme la noticia de posibilidad de pelear fuera de mi pa\u00eds porque quise esperar al d\u00eda del padre y regalarle la novedad a mi pap\u00e1. Esa noticia que fue tan esperada por nosotros que lo so\u00f1amos mucho pero no cre\u00edamos que pudiera ser posible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-street-sweeper-represents-his-country-at-the-boxing-championships-in-europe\">Street sweeper represents his country at the boxing championships in Europe<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Llegu\u00e9 a Francia un d\u00eda antes, me prepar\u00e9 y al d\u00eda siguiente fue el pesaje, al d\u00eda siguiente el combate y el cuarto d\u00eda regresamos, si tuviera otra oportunidad me gustar\u00eda llegar con m\u00e1s tiempo al lugar de combate, ya que fui a pelear a Francia por el t\u00edtulo mundial <a href=\"https:\/\/www.iboboxing.com\/\">IBO<\/a> y reci\u00e9n al terminar el combate comenc\u00e9 a ser consciente de tama\u00f1a oportunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sent\u00ed muchas emociones al finalizar la pelea, me quebr\u00e9 en llanto y record\u00e9 todo el esfuerzo que me llev\u00f3 llegar hasta all\u00ed. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00e9 a mi familia, mi padre, mis tiempos en la calle buscando encontrar una actividad que me apasione y mis a\u00f1os de sobrepeso que fueron complicados para m\u00ed. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong><a href=\"https:\/\/orato.world\/?s=Argentina\">Lee m\u00e1s historias de Argentina de Orato.<\/a><\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De vuelta en la ciudad de Villa Gobernador G\u00e1lvez, vuelvo a los servicios de barrido. Levantado antes del amanecer, los colores del sol comienzan a encarar. Afronto de seis a ocho horas de duro trabajo, recorriendo la plaza. Algunos d\u00edas hago tres turnos, pero siempre consigo entrenar. Encuentro tiempo para mi trabajo y mi pasi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sue\u00f1o con dedicarme m\u00e1s a la lucha y volver a Europa. Anhelo la emoci\u00f3n de volver a representar a mi pa\u00eds. Sin embargo, sigo estando agradecido a todas las personas que me han ayudado hasta ahora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sent\u00ed muchas emociones al finalizar la pelea, me quebr\u00e9 en llanto y record\u00e9 todo el esfuerzo que me llev\u00f3 llegar hasta all\u00ed. Record\u00e9 a mi familia, mi padre, mis tiempos en la calle buscando encontrar una actividad que me apasione y mis a\u00f1os de sobrepeso que fueron complicados para m\u00ed. <\/p>\n","protected":false},"author":171,"featured_media":66389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[334],"tags":[193,4344,2006,4347,2214,4345,4346],"class_list":["post-56406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-argentina-es","tag-barrendero","tag-boxeo","tag-francia","tag-latinoamerica","tag-miguel-acosta-es","tag-organizacion-internacional-de-boxeo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un barrendero representa a Argentina en un campeonato de boxeo<\/title>\n<meta name=\"description\" content=\"Miguel Acosta trabaja como barrendero en Argentina mientras persigue su pasi\u00f3n por el boxeo; pele\u00f3 en el campeonato de la IBO en Francia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un barrendero representa a Argentina en un campeonato internacional de boxeo\" \/>\n<meta property=\"og:description\" content=\"Sent\u00ed muchas emociones al finalizar la pelea, me quebr\u00e9 en llanto y record\u00e9 todo el esfuerzo que me llev\u00f3 llegar hasta all\u00ed. Record\u00e9 a mi familia, mi padre, mis tiempos en la calle buscando encontrar una actividad que me apasione y mis a\u00f1os de sobrepeso que fueron complicados para m\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-23T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-24T11:17:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"643\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Mariano Junco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariano Junco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/\"},\"author\":{\"name\":\"Mariano Junco\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/79142d42b64e887a09c4f86e2baefd45\"},\"headline\":\"Un barrendero representa a Argentina en un campeonato internacional de boxeo\",\"datePublished\":\"2022-10-23T12:00:00+00:00\",\"dateModified\":\"2023-01-24T11:17:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Historia-Barrendero.webp\",\"keywords\":[\"Argentina\",\"barrendero\",\"Boxeo\",\"Francia\",\"Latinoam\u00e9rica\",\"Miguel Acosta\",\"Organizaci\u00f3n Internacional de Boxeo\"],\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/\",\"name\":\"Un barrendero representa a Argentina en un campeonato de boxeo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Historia-Barrendero.webp\",\"datePublished\":\"2022-10-23T12:00:00+00:00\",\"dateModified\":\"2023-01-24T11:17:47+00:00\",\"description\":\"Miguel Acosta trabaja como barrendero en Argentina mientras persigue su pasi\u00f3n por el boxeo; pele\u00f3 en el campeonato de la IBO en Francia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Historia-Barrendero.webp\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Historia-Barrendero.webp\",\"width\":643,\"height\":482,\"caption\":\"Miguel Acosta, a street sweeper in Argentina, fights at the IBO Championships in France | Photo courtesy of\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2022\\\/10\\\/23\\\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un barrendero representa a Argentina en un campeonato internacional de boxeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/79142d42b64e887a09c4f86e2baefd45\",\"name\":\"Mariano Junco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariano Junco\"},\"description\":\"Mariano Junco serves as a communicator and content manager. he began experimenting in 2004 at the age of 17. Between 2007 and today, he developed a national and international career in sports while training in journalism, communications, and politics. He currently works in digital, audiovisual, and graphic media. He is passionate about the world of amateur sports and the institutions that comprise it.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariano-junco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un barrendero representa a Argentina en un campeonato de boxeo","description":"Miguel Acosta trabaja como barrendero en Argentina mientras persigue su pasi\u00f3n por el boxeo; pele\u00f3 en el campeonato de la IBO en Francia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/","og_locale":"es_ES","og_type":"article","og_title":"Un barrendero representa a Argentina en un campeonato internacional de boxeo","og_description":"Sent\u00ed muchas emociones al finalizar la pelea, me quebr\u00e9 en llanto y record\u00e9 todo el esfuerzo que me llev\u00f3 llegar hasta all\u00ed. Record\u00e9 a mi familia, mi padre, mis tiempos en la calle buscando encontrar una actividad que me apasione y mis a\u00f1os de sobrepeso que fueron complicados para m\u00ed.","og_url":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2022-10-23T12:00:00+00:00","article_modified_time":"2023-01-24T11:17:47+00:00","og_image":[{"width":643,"height":482,"url":"https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp","type":"image\/webp"}],"author":"Mariano Junco","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariano Junco","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/"},"author":{"name":"Mariano Junco","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/79142d42b64e887a09c4f86e2baefd45"},"headline":"Un barrendero representa a Argentina en un campeonato internacional de boxeo","datePublished":"2022-10-23T12:00:00+00:00","dateModified":"2023-01-24T11:17:47+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp","keywords":["Argentina","barrendero","Boxeo","Francia","Latinoam\u00e9rica","Miguel Acosta","Organizaci\u00f3n Internacional de Boxeo"],"articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/","url":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/","name":"Un barrendero representa a Argentina en un campeonato de boxeo","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp","datePublished":"2022-10-23T12:00:00+00:00","dateModified":"2023-01-24T11:17:47+00:00","description":"Miguel Acosta trabaja como barrendero en Argentina mientras persigue su pasi\u00f3n por el boxeo; pele\u00f3 en el campeonato de la IBO en Francia","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp","width":643,"height":482,"caption":"Miguel Acosta, a street sweeper in Argentina, fights at the IBO Championships in France | Photo courtesy of"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2022\/10\/23\/un-barrendero-representa-a-argentina-en-un-campeonato-internacional-de-boxeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Un barrendero representa a Argentina en un campeonato internacional de boxeo"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/79142d42b64e887a09c4f86e2baefd45","name":"Mariano Junco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariano Junco"},"description":"Mariano Junco serves as a communicator and content manager. he began experimenting in 2004 at the age of 17. Between 2007 and today, he developed a national and international career in sports while training in journalism, communications, and politics. He currently works in digital, audiovisual, and graphic media. He is passionate about the world of amateur sports and the institutions that comprise it.","url":"https:\/\/orato.world\/es\/author\/mariano-junco\/"}]}},"modified_by":"Aurelie Msiza","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",643,482,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero-100x100.webp",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero-300x225.webp",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",640,480,false],"large":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",640,480,false],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",643,482,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",643,482,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero-534x400.webp",534,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero-360x240.webp",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero.webp",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Historia-Barrendero-500x482.webp",500,482,true]},"uagb_author_info":{"display_name":"Mariano Junco","author_link":"https:\/\/orato.world\/es\/author\/mariano-junco\/"},"uagb_comment_info":0,"uagb_excerpt":"Sent\u00ed muchas emociones al finalizar la pelea, me quebr\u00e9 en llanto y record\u00e9 todo el esfuerzo que me llev\u00f3 llegar hasta all\u00ed. Record\u00e9 a mi familia, mi padre, mis tiempos en la calle buscando encontrar una actividad que me apasione y mis a\u00f1os de sobrepeso que fueron complicados para m\u00ed.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/56406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=56406"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/56406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/66389"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=56406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=56406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=56406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}