{"id":68847,"date":"2023-01-31T05:28:02","date_gmt":"2023-01-31T13:28:02","guid":{"rendered":"https:\/\/orato.world\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/"},"modified":"2023-02-08T05:03:27","modified_gmt":"2023-02-08T13:03:27","slug":"un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/","title":{"rendered":"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-500x500.webp\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-500x500.webp 500w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-300x300.webp 300w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-100x100.webp 100w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-400x400.webp 400w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-150x150.webp 150w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-70x70.webp 70w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1-293x293.webp 293w, https:\/\/orato.world\/wp-content\/uploads\/FjP5_WzUoAANeDz-1.webp 594w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Interview Subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Roan Carr-Hartley is a conservationist and pilot with the Sheldrick Wildlife Trust in Kenya, which is one of Africa\u2019s oldest wildlife charities and a leading conservation organization. He was involved in the search for the 4-year-old boy who was missing in the wild for six days. He has been involved in many wild animal rescue missions.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Background Information<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Tsavo National Park, established in 1948. is the largest of Kenya&#8217;s national parks. In it, live the big five: lions, leopards, elephants, buffalo, and Rhinos. It is among the few national parks in Kenya where you can see both Black and White Rhinos.\u00a0Huge parts of the park remain unfenced and human-wildlife conflicts are common. <a href=\"https:\/\/www.businessdailyafrica.com\/bd\/economy\/unpaid-compensation-claims-for-wildlife-victims-hits-sh2-6bn-3719310#:~:text=Victims%20have%2C%20in%20the%20past,human%20injury%20and%20human%20death.\" target=\"_blank\" rel=\"noreferrer noopener\">Victims are compensated for crop destruction, livestock predation (where livestock is attacked and killed by wildlife), human injury, and human death.<\/a><br>Between 2017 and 2020, more than 380 Kenyans died after being attacked by wild animals, while 2,080 were left nursing various injuries, according to KWS statistics.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">PARQUE NACIONAL DE TSAVO, Kenia \ua7f7 Durante cinco d\u00edas, busqu\u00e9 a un ni\u00f1o desaparecido de cuatro a\u00f1os llamado Ayub en el Parque Nacional de Tsavo, en Kenia. En el sexto d\u00eda de b\u00fasqueda, contuve la respiraci\u00f3n al ver una criatura diminuta en movimiento desde mi punto de vista en el avi\u00f3n. Parec\u00eda aterrorizado, intentando esconderse entre los arbustos o bajo los grandes \u00e1rboles. Mantuve la mirada fija en \u00e9l. Si lo perd\u00eda, las posibilidades de volver a verlo eran escasas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser el <a href=\"https:\/\/www.tsavopark.com\/\">parque nacional m\u00e1s grande de Kenia<\/a>, la inmensidad del paisaje de Tsavo parece la misma desde arriba, vuele donde vuele. A veces es dif\u00edcil no perder de vista a un elefante abajo, por no hablar de un ni\u00f1o peque\u00f1o. Durante 30 minutos estrech\u00e9 cada vez m\u00e1s mi c\u00edrculo manteniendo la altitud perfecta. No ten\u00eda medios para comunicarme con nadie. El pueblo m\u00e1s cercano estaba a 18 kil\u00f3metros. De repente, unos aldeanos de un grupo de b\u00fasqueda vieron mi avi\u00f3n volando bajo y entramos en acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong><a href=\"https:\/\/orato.world\/?s=kenya\">M\u00e1s reportajes sobre Kenia en Orato World Media.<\/a><\/strong><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-child-survives-kenya-s-big-five-elephants-lions-buffalo-leopards-and-rhinos\"><h2>Un ni\u00f1o sobrevive a los cinco grandes de Kenia: elefantes, leones, b\u00fafalos, leopardos y rinocerontes<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Abr\u00ed la puerta del avi\u00f3n y empec\u00e9 a se\u00f1alar al chico. El grupo de b\u00fasqueda se dirigi\u00f3 en la direcci\u00f3n que les indiqu\u00e9 y finalmente dieron con \u00e9l. All\u00ed estaba, en la inmensidad hasta donde alcanzaba la vista, vivo y congelado. Apenas pod\u00eda creer lo que ve\u00edan mis ojos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando miro hacia atr\u00e1s y veo las fotos que tom\u00e9, puedo ver su alivio total. Para este ni\u00f1o, y para todos los que participaron en su b\u00fasqueda, fue como un milagro: una segunda oportunidad de vivir. Super\u00f3 una situaci\u00f3n en la que las posibilidades de supervivencia eran casi nulas. El Parque Nacional de Tsavo no s\u00f3lo es el mayor parque nacional del pa\u00eds, sino que sigue siendo el hogar de los \u00abcinco grandes\u00bb: elefantes, leones, b\u00fafalos, leopardos y rinocerontes. Tambi\u00e9n llov\u00eda mucho durante su desaparici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayub ten\u00eda un aspecto fr\u00e1gil y el cuerpo cubierto de picaduras de mosquito y ara\u00f1azos de arbustos espinosos. Cuando el equipo de b\u00fasqueda lo tuvo a salvo, aterric\u00e9 en una carretera cercana al pueblo. Me recibi\u00f3 un grupo de ancianos y funcionarios del gobierno local encabezados por el jefe. El jefe me llev\u00f3 con los padres del ni\u00f1o.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"621\" src=\"https:\/\/orato.world\/wp-content\/uploads\/boy-survives-days-alone-african-wilderness-zz-221206-02-4eeafc-1-1024x621-1.webp\" alt=\"\" class=\"wp-image-69284\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/boy-survives-days-alone-african-wilderness-zz-221206-02-4eeafc-1-1024x621-1.webp 1024w, https:\/\/orato.world\/wp-content\/uploads\/boy-survives-days-alone-african-wilderness-zz-221206-02-4eeafc-1-1024x621-1-300x182.webp 300w, https:\/\/orato.world\/wp-content\/uploads\/boy-survives-days-alone-african-wilderness-zz-221206-02-4eeafc-1-1024x621-1-770x467.webp 770w, https:\/\/orato.world\/wp-content\/uploads\/boy-survives-days-alone-african-wilderness-zz-221206-02-4eeafc-1-1024x621-1-660x400.webp 660w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Piloto ve a ni\u00f1o desde su avi\u00f3n | <strong>Foto cortes\u00eda de Sheldrick Wildlife Trust<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Su madre conten\u00eda las l\u00e1grimas de incredulidad. Le ense\u00f1\u00e9 las fotos de su hijo para confirmar que lo hab\u00edan encontrado sano y salvo. La emoci\u00f3n inund\u00f3 a todos, que se arremolinaron alrededor de la c\u00e1mara para ver las fotos. El equipo de b\u00fasqueda traslad\u00f3 a Ayub 18 kil\u00f3metros hasta su casa y, cuando lleg\u00f3, la gente rompi\u00f3 a cantar. Bailaron y corearon. &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><h2>La familia le da un nuevo nombre<\/h2><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al final supimos lo que hab\u00eda pasado antes de mi agotadora b\u00fasqueda desde el cielo. El ni\u00f1o viv\u00eda en el pueblo de Asa, en el condado de Makueni, y se dirig\u00eda con sus hermanos a cuidar el ganado de la familia cuando desapareci\u00f3. [Para los ganaderos que viven cerca del parque, el ganado puede pastar cerca o dentro del propio parque]. Debido a la estaci\u00f3n de lluvias, no pudieron encontrar ning\u00fan rastro de huellas. El jefe local moviliz\u00f3 r\u00e1pidamente un grupo de b\u00fasqueda sobre el terreno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin \u00e9xito el primer d\u00eda, el jefe de zona llam\u00f3 al Sheldrick Wildlife Trust. Pidi\u00f3 ayuda para la vigilancia a\u00e9rea. El segundo d\u00eda de b\u00fasqueda, sal\u00ed del cuartel general de Kaluku por la ma\u00f1ana y vol\u00e9 hasta el pueblo, donde ya hab\u00eda 70 hombres repartidos por todo el parque. Ese d\u00eda vol\u00e9 durante cuatro horas antes de quedarme sin combustible, y s\u00f3lo vi animales salvajes en tierra.&nbsp;Encontrar al ni\u00f1o al sexto d\u00eda fue realmente un milagro. Si no hubiera sido por las fuertes lluvias, probablemente habr\u00eda muerto de sed.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"433\" src=\"https:\/\/orato.world\/wp-content\/uploads\/2Z3A7148.webp\" alt=\"\" class=\"wp-image-69286\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/2Z3A7148.webp 650w, https:\/\/orato.world\/wp-content\/uploads\/2Z3A7148-300x200.webp 300w, https:\/\/orato.world\/wp-content\/uploads\/2Z3A7148-600x400.webp 600w, https:\/\/orato.world\/wp-content\/uploads\/2Z3A7148-360x240.webp 360w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><figcaption class=\"wp-element-caption\">El pueblo celebra la vuelta a casa de Ayub | <strong>Foto cortes\u00eda de Sheldrick Wildlife Trust<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cuando devolvimos al ni\u00f1o a casa, todos quer\u00edan levantarlo mientras la familia derramaba l\u00e1grimas de alegr\u00eda. Todav\u00eda conmocionado, el ni\u00f1o apenas pod\u00eda hablar y mucho menos contar lo que le hab\u00eda ocurrido. Mirando atr\u00e1s, siento un gran alivio por haber ayudado a salvar una vida, incluso cuando pocos ten\u00edan esperanzas de que Ayub volviera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del incidente, los padres lo rebautizaron Roan en mi honor. La familia y los ancianos del pueblo me dieron una cabra como muestra de agradecimiento. Me sent\u00ed muy honrado. Tras recibir la atenci\u00f3n m\u00e9dica que tanto necesitaba, Roan recuper\u00f3 la salud y volvi\u00f3 a jugar al aire libre con sus compa\u00f1eros como cualquier otro ni\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abr\u00ed la puerta del avi\u00f3n y empec\u00e9 a se\u00f1alar al chico. El grupo de b\u00fasqueda se dirigi\u00f3 en la direcci\u00f3n que les indiqu\u00e9 y finalmente dieron con \u00e9l. All\u00ed estaba, en la inmensidad hasta donde alcanzaba la vista, vivo y congelado. Apenas pod\u00eda creer lo que ve\u00edan mis ojos.<\/p>\n","protected":false},"author":77,"featured_media":68966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[319,188],"tags":[613,5267,5265,512,5266,5264],"class_list":["post-68847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente","category-salud","tag-africa-es","tag-busqueda-y-rescate-es","tag-cuatro-anos-de-edad-es","tag-kenya-es","tag-nino-desaparecido-es","tag-parque-nacional-tsavo-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Parque Nacional de Tsavo se trag\u00f3 a un ni\u00f1o de 4 a\u00f1os durante seis d\u00edas<\/title>\n<meta name=\"description\" content=\"En el Parque Nacional de Tsavo, un ni\u00f1o deambul\u00f3 durante seis d\u00edas antes de que un piloto lo localizara durante una b\u00fasqueda a\u00e9rea.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza\" \/>\n<meta property=\"og:description\" content=\"Abr\u00ed la puerta del avi\u00f3n y empec\u00e9 a se\u00f1alar al chico. El grupo de b\u00fasqueda se dirigi\u00f3 en la direcci\u00f3n que les indiqu\u00e9 y finalmente dieron con \u00e9l. All\u00ed estaba, en la inmensidad hasta donde alcanzaba la vista, vivo y congelado. Apenas pod\u00eda creer lo que ve\u00edan mis ojos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-31T13:28:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T13:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ronald Muya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ronaldmuya2020\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ronald Muya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/\"},\"author\":{\"name\":\"Ronald Muya\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/a79bdd6d15a8b749b755e724d7da4eb6\"},\"headline\":\"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza\",\"datePublished\":\"2023-01-31T13:28:02+00:00\",\"dateModified\":\"2023-02-08T13:03:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/\"},\"wordCount\":875,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/120722-kenya-1280x720.jpeg.webp\",\"keywords\":[\"Africa\",\"b\u00fasqueda y rescate\",\"cuatro a\u00f1os de edad\",\"Kenya\",\"ni\u00f1o desaparecido\",\"Parque Nacional Tsavo\"],\"articleSection\":[\"Medio ambiente\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/\",\"name\":\"El Parque Nacional de Tsavo se trag\u00f3 a un ni\u00f1o de 4 a\u00f1os durante seis d\u00edas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/120722-kenya-1280x720.jpeg.webp\",\"datePublished\":\"2023-01-31T13:28:02+00:00\",\"dateModified\":\"2023-02-08T13:03:27+00:00\",\"description\":\"En el Parque Nacional de Tsavo, un ni\u00f1o deambul\u00f3 durante seis d\u00edas antes de que un piloto lo localizara durante una b\u00fasqueda a\u00e9rea.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/120722-kenya-1280x720.jpeg.webp\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/120722-kenya-1280x720.jpeg.webp\",\"width\":1280,\"height\":960,\"caption\":\"Four-year-old Ayub went missing in the Tsavo National Forest for six days, discovered by a pilot doing an aerial search. | Photo Courtesy of Sheldrick Wildlife Trust\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/31\\\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/a79bdd6d15a8b749b755e724d7da4eb6\",\"name\":\"Ronald Muya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Ronald Muya\"},\"description\":\"Ronald Muya is a freelance professional journalist working in Kenya covering mostly topical issues and human interest stories affecting the society in his home country and East Africa.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/Ronaldmuya2020\"],\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/ronald-muya\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Parque Nacional de Tsavo se trag\u00f3 a un ni\u00f1o de 4 a\u00f1os durante seis d\u00edas","description":"En el Parque Nacional de Tsavo, un ni\u00f1o deambul\u00f3 durante seis d\u00edas antes de que un piloto lo localizara durante una b\u00fasqueda a\u00e9rea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/","og_locale":"es_ES","og_type":"article","og_title":"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza","og_description":"Abr\u00ed la puerta del avi\u00f3n y empec\u00e9 a se\u00f1alar al chico. El grupo de b\u00fasqueda se dirigi\u00f3 en la direcci\u00f3n que les indiqu\u00e9 y finalmente dieron con \u00e9l. All\u00ed estaba, en la inmensidad hasta donde alcanzaba la vista, vivo y congelado. Apenas pod\u00eda creer lo que ve\u00edan mis ojos.","og_url":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-01-31T13:28:02+00:00","article_modified_time":"2023-02-08T13:03:27+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp","type":"image\/webp"}],"author":"Ronald Muya","twitter_card":"summary_large_image","twitter_creator":"@Ronaldmuya2020","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Ronald Muya","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/"},"author":{"name":"Ronald Muya","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/a79bdd6d15a8b749b755e724d7da4eb6"},"headline":"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza","datePublished":"2023-01-31T13:28:02+00:00","dateModified":"2023-02-08T13:03:27+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/"},"wordCount":875,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp","keywords":["Africa","b\u00fasqueda y rescate","cuatro a\u00f1os de edad","Kenya","ni\u00f1o desaparecido","Parque Nacional Tsavo"],"articleSection":["Medio ambiente","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/","url":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/","name":"El Parque Nacional de Tsavo se trag\u00f3 a un ni\u00f1o de 4 a\u00f1os durante seis d\u00edas","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp","datePublished":"2023-01-31T13:28:02+00:00","dateModified":"2023-02-08T13:03:27+00:00","description":"En el Parque Nacional de Tsavo, un ni\u00f1o deambul\u00f3 durante seis d\u00edas antes de que un piloto lo localizara durante una b\u00fasqueda a\u00e9rea.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp","width":1280,"height":960,"caption":"Four-year-old Ayub went missing in the Tsavo National Forest for six days, discovered by a pilot doing an aerial search. | Photo Courtesy of Sheldrick Wildlife Trust"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/01\/31\/un-nino-de-cuatro-anos-perdido-en-el-parque-nacional-de-tsavo-sobrevive-seis-dias-en-la-naturaleza-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Un ni\u00f1o de cuatro a\u00f1os perdido en el Parque Nacional de Tsavo sobrevive seis d\u00edas en la naturaleza"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/a79bdd6d15a8b749b755e724d7da4eb6","name":"Ronald Muya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Ronald Muya"},"description":"Ronald Muya is a freelance professional journalist working in Kenya covering mostly topical issues and human interest stories affecting the society in his home country and East Africa.","sameAs":["https:\/\/x.com\/Ronaldmuya2020"],"url":"https:\/\/orato.world\/es\/author\/ronald-muya\/"}]}},"modified_by":"Aurelie Msiza","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-100x100.webp",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-300x225.webp",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-770x578.webp",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-1024x768.webp",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-533x400.webp",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-360x240.webp",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg.webp",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/120722-kenya-1280x720.jpeg-500x500.webp",500,500,true]},"uagb_author_info":{"display_name":"Ronald Muya","author_link":"https:\/\/orato.world\/es\/author\/ronald-muya\/"},"uagb_comment_info":0,"uagb_excerpt":"Abr\u00ed la puerta del avi\u00f3n y empec\u00e9 a se\u00f1alar al chico. El grupo de b\u00fasqueda se dirigi\u00f3 en la direcci\u00f3n que les indiqu\u00e9 y finalmente dieron con \u00e9l. All\u00ed estaba, en la inmensidad hasta donde alcanzaba la vista, vivo y congelado. Apenas pod\u00eda creer lo que ve\u00edan mis ojos.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/68847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=68847"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/68847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/68966"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=68847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=68847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=68847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}