{"id":68891,"date":"2023-01-22T05:35:31","date_gmt":"2023-01-22T13:35:31","guid":{"rendered":"https:\/\/orato.world\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/"},"modified":"2023-02-05T14:47:03","modified_gmt":"2023-02-05T22:47:03","slug":"la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/","title":{"rendered":"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1.webp\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1.webp 500w, https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1-300x300.webp 300w, https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1-100x100.webp 100w, https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1-400x400.webp 400w, https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1-150x150.webp 150w, https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1-70x70.webp 70w, https:\/\/orato.world\/wp-content\/uploads\/Andrea-y-jasmin-1-500x500-1-293x293.webp 293w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Interview Subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Lorllys Andrea Palacios (left) is a Venezuelan who made history by becoming the youngest next-generation aircraft captain in Latin America, as well as captain for the first all-female flight crew in Venezuela. Born on February 12, 1992, she is the daughter of Major General Lorllys Ramos Acevedo and Captain Hugo Richard Palacios Betancourt. Both are former members of the Venezuelan Air Force. Nearly everyone in her family is involved with aviation in some way.<br><br>She underwent pilot training at the <a href=\"https:\/\/centreforaviation.com\/data\/profiles\/government-bodies\/venezuela-instituto-nacional-de-aeronautica-civil-venezuela-inac\" target=\"_blank\" rel=\"noreferrer noopener\">Civil Aeronautical Instruction Center (CIAC) located in Maracay<\/a>. It was at the <a href=\"https:\/\/www.aviacioncivil.com.ve\/category\/ciac-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">CIAC<\/a> where she flew her first plane, a Cessna 150. Later, she started working as a commercial pilot at the state airline Conviasa. There she was chosen to train in the Embraer E190 plane, a 100-passenger aircraft. She has done numerous simulators in various countries around the world, including the United States, Russia, France, Argentina, and Finland. Andrea has a degree in International Trade from the University of Alejandro Humboldt University. She has traveled as a captain to every destination offered by Conviasa including Cuba, Mexico, Panama, Nicaragua, Bolivia, and Saint Martin. She aspires to be a mother in the future and when she is not flying, she spends time with her family, friends, and partner.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Background Information<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.skytough.com\/post\/how-many-pilots-are-there\" target=\"_blank\" rel=\"noreferrer noopener\">According to SkyTough<\/a>, there are between 1.5 and 2.3 million pilots around the world in all industries including private, commercial, and military. The United States boasts about 734,911 pilots across categories. Of that, 58,541 or about 8 percent are female. Multiple articles cite India as having the greatest percentage of female pilots in the world.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">CARACAS, Venezuela. El 16 de septiembre de 2022 decid\u00ed compartir con los pasajeros del vuelo Maiquet\u00eda-Margarita que toda la tripulaci\u00f3n con la que estaban viajando ese d\u00eda estaba conformada por mujeres, tanto las tripulantes de cabina, como la primera oficial y yo, su capit\u00e1n. Jam\u00e1s imagin\u00e9 el alcance que esto tendr\u00eda.<\/p>\n\n<p class=\"wp-block-paragraph\"><em><strong><a href=\"https:\/\/orato.world\/category\/visionaries\/\">Lee m\u00e1s historias sobre visionarios que marcan la diferencia en Orato World Media.<\/a><\/strong><\/em><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-venezuela-s-minister-of-tourism-intervenes-gives-me-a-fair-chance-at-becoming-captain\"><h2>El Ministro de Turismo de Venezuela interviene y me da una oportunidad justa de ser capit\u00e1n<\/h2><\/h2>\n\n<p class=\"wp-block-paragraph\">Vol\u00e9 para la aerol\u00ednea venezolana Conviasa durante seis a\u00f1os como primer oficial en un avi\u00f3n Embraer. Vi c\u00f3mo compa\u00f1eros que entraron en la compa\u00f1\u00eda al mismo tiempo que yo alcanzaban el rango de capit\u00e1n. Para ser capit\u00e1n en Venezuela hay que tener 1.500 horas de vuelo y m\u00e1s de 21 a\u00f1os. Yo superaba los requisitos. Pas\u00f3 el tiempo y el ascenso nunca lleg\u00f3.<\/p>\n\n<p class=\"wp-block-paragraph\">Me di cuenta de algo durante ese tiempo. Muchos hombres actuaban como si apoyaran a las mujeres. Dec\u00edan que quer\u00edan vernos desarrollarnos, pero practicaban lo que yo llamo \u00abmachismo de closet\u00bb. [En Am\u00e9rica Latina, el machismo es una forma de orgullo masculino fuerte o agresivo] Cuando lleg\u00f3 el momento de hacer algo para apoyarnos, se negaron. Ocultaban su machismo tras una fachada. Peor a\u00fan, algunos intentar\u00edan hundir a una mujer si pudieran.<\/p>\n\n<p class=\"wp-block-paragraph\">En 2019, frustrada por la situaci\u00f3n, busqu\u00e9 una intervenci\u00f3n. El general Ram\u00f3n Vel\u00e1zquez Araujo lleg\u00f3 como nuevo ministro de Turismo. Tuve la oportunidad de hablar con \u00e9l y explicarle mi situaci\u00f3n. \u00c9l intervino.<\/p>\n\n<p class=\"wp-block-paragraph\">El general solicit\u00f3 mis expedientes y vio los resultados de mis simulaciones y la ausencia de comentarios negativos. Me autoriz\u00f3 a ser evaluada para el estatus de capit\u00e1n. Despu\u00e9s de haber esperado tanto tiempo este momento, me presion\u00e9 mucho. Me hicieron un nuevo simulador, una prueba oral y me exigieron que completara otras 25 horas de vuelo con un instructor.<\/p>\n\n<p class=\"wp-block-paragraph\">Recuerdo que el d\u00eda de la \u00faltima prueba, que es un vuelo donde tambi\u00e9n est\u00e1 el instructor y un inspector del Instituto Nacional de Aeron\u00e1utica (INAC), estaba realmente nerviosa porque te van preguntando y adem\u00e1s debes estar pendiente de todo operacionalmente. Ese d\u00eda me convert\u00ed en la capit\u00e1n de aviones de \u00faltima generaci\u00f3n m\u00e1s joven de Latinoam\u00e9rica con 27 a\u00f1os.<\/p>\n\n<h2 class=\"wp-block-heading\"><h2>Una tripulaci\u00f3n femenina y un sue\u00f1o hecho realidad<\/h2><\/h2>\n\n<p class=\"wp-block-paragraph\">Por mucho tiempo fui la \u00fanica mujer piloto en Conviasa. Deseaba que m\u00e1s mujeres se preparan y entraran a trabajar a la aerol\u00ednea. Hace algunos a\u00f1os, mi deseo se hizo realidad cuando entran dos colegas, entre ellas Jasm\u00edn Acosta, mi actual compa\u00f1era de aviones Embraer.<\/p>\n\n<p class=\"wp-block-paragraph\">A inicios de septiembre de 2022, revisando la programaci\u00f3n de vuelos, me doy cuenta de que volar\u00e9 con Jasm\u00edn y le escribo inmediatamente. <a href=\"https:\/\/aviacionaldia.com\/en\/2022\/09\/conviasa-first-flight-operated-by-women-in-venezuela.html\">Sin embargo, a\u00fan no sab\u00edamos que el 16 de septiembre har\u00edamos historia en la aviaci\u00f3n venezolana. \u00a0<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Un tripulante de cabina no pudo asistir, por lo que asignaron a otra chica y el equipo del vuelo Maiquet\u00eda-Margarita qued\u00f3 integrado totalmente por mujeres. Decid\u00ed compartir la informaci\u00f3n con los pasajeros y el momento en mis redes sociales sin imaginarme el alcance que tendr\u00eda.<\/p>\n\n<p class=\"wp-block-paragraph\">En ese hermoso y soleado d\u00eda, muchas personas, incluidos hombres, celebraron este hito en la historia de la aviaci\u00f3n femenina en Venezuela. Su respuesta reflejaba el orgullo que sent\u00edan por nosotras. Me sent\u00ed incre\u00edblemente feliz. Desde los dos a\u00f1os, he viajado en avi\u00f3n. Mis padres sirvieron como soldados en la Fuerza A\u00e9rea Venezolana y se convirtieron en expertos en seguridad a\u00e9rea. Mi padre pas\u00f3 a volar en la industria comercial. T\u00edos, primos y familiares se convirtieron en ingenieros, pilotos y miembros de la tripulaci\u00f3n de cabina. A los 17 a\u00f1os sab\u00eda exactamente lo que quer\u00eda hacer.<\/p>\n\n<h2 class=\"wp-block-heading\"><h2>En una encrucijada, segu\u00ed mi sue\u00f1o infantil de ser piloto.<\/h2><\/h2>\n\n<p class=\"wp-block-paragraph\">La primera vez que entr\u00e9 en la cabina de un avi\u00f3n ten\u00eda siete a\u00f1os. Fue como ir a un parque de atracciones que siempre hab\u00eda querido visitar. All\u00ed estaba, viviendo mi sue\u00f1o. En ese momento supe que quer\u00eda pasar mi vida all\u00ed. Me asombraba la acci\u00f3n que ten\u00eda lugar antes, durante y despu\u00e9s del despegue. Al ver a todo el equipo realizar un vuelo, decid\u00ed hacerme piloto.<\/p>\n\n<p class=\"wp-block-paragraph\">No obstante, la carrera de aviaci\u00f3n es costosa a nivel mundial y aunque mis padres me apoyaban al cien por cien cuando a los 17 a\u00f1os dije que quer\u00eda estar en la aviaci\u00f3n, mi mam\u00e1 siempre me incentiv\u00f3 a estudiar otra carrera. Prestando atenci\u00f3n a esta sugerencia de mi mam\u00e1, empec\u00e9 a estudiar Ciencias Pol\u00edticas en la Universidad Central de Venezuela (UCV) que se encuentra en la capital, Caracas. Adem\u00e1s, inici\u00e9 mis estudios de aviaci\u00f3n en el Centro Aeron\u00e1utico PAC, ubicado en un centro comercial de la ciudad.&#13;\n <\/p>\n\n<p class=\"wp-block-paragraph\">En todo el mundo, estudiar aviaci\u00f3n lleva un enorme n\u00famero de horas y sigue siendo muy caro. Hice el curso de tierra en una escuela propiedad de los padres de mis amigos. Aun as\u00ed, no pod\u00eda permit\u00edrmelo. Cuando o\u00ed hablar de una beca que ofrec\u00eda el Instituto Nacional de Aeron\u00e1utica Civil (INAC), decid\u00ed solicitarla. Me somet\u00ed a ex\u00e1menes t\u00e9cnicos, psicol\u00f3gicos y m\u00e9dicos. De cien personas, s\u00f3lo aprobaron veinte. Gan\u00e9 la beca para estudiar en la Escuela Miguel Rodr\u00edguez de Maracay, a una hora de distancia.<\/p>\n\n<p class=\"wp-block-paragraph\">Todos los d\u00edas me levantaba a las 4.30 de la ma\u00f1ana para asistir a la escuela de vuelo en Maracay, y luego volv\u00eda a Caracas para mis cursos de Ciencias Pol\u00edticas. Mi jornada terminaba a las 11:00 p.m. Me cansaba y mi rendimiento se resent\u00eda. En ese momento, tuve que decidir. \u00bfSegu\u00eda estudiando aviaci\u00f3n o continuaba con mi carrera universitaria? Volv\u00ed a pensar en la ni\u00f1a de siete a\u00f1os que, de pie en la cabina del avi\u00f3n, so\u00f1aba con ser piloto. Gracias a Dios, hice caso a esa voz interior.<\/p>\n\n<h2 class=\"wp-block-heading\"><h2>En lugar de reflejar la cultura machista que nos rodea, las mujeres deben apoyar a las mujeres<\/h2><\/h2>\n\n<p class=\"wp-block-paragraph\">Comenzar mi formaci\u00f3n en el Centro de Instrucci\u00f3n de Aeron\u00e1utica Civil (CIAC) result\u00f3 muy diferente de las escuelas privadas de aviaci\u00f3n. Estudi\u00e9 a las \u00f3rdenes de militares retirados. Adem\u00e1s de estudiar, ten\u00eda que cortar hierba, limpiar el aula y realizar diversas actividades laborales. Me centr\u00e9 en el objetivo y en mantener mi beca.<\/p>\n\n<p class=\"wp-block-paragraph\">Al salir del CIAC en el 2012, entr\u00f3 a trabajar en Conviasa, la aerol\u00ednea del estado venezolano. Esto como parte del programa para pagar la beca que me hab\u00edan dado. Para ese entonces, el presidente de la empresa era el general C\u00e9sar Mart\u00ednez, que ten\u00eda el proyecto de traer a los aviones brasileros, Embraer.<\/p>\n\n<p class=\"wp-block-paragraph\">Estos aviones son de nueva generaci\u00f3n, aunque son muy parecidos a todas las aeronaves, son de tecnolog\u00eda avanzada. Son equipos que se manejan muy f\u00e1cilmente por computadora y son automatizados.<\/p>\n\n<p class=\"wp-block-paragraph\">A partir de ese momento, trabaj\u00e9 duro para impulsar mi carrera. Nunca fue f\u00e1cil, pero persever\u00e9. Hoy creo que el principal obst\u00e1culo para las mujeres trabajadoras siguen siendo las dem\u00e1s mujeres. En lugar de animarse unas a otras, con demasiada frecuencia ven a otras mujeres como competencia.<\/p>\n\n<p class=\"wp-block-paragraph\">Debemos creer las unas en las otras y apoyar a otras mujeres en lugar de pelearnos. Si no tienes mujeres en tu equipo, crea un equipo. La misma cultura machista que pretend\u00eda frenarnos nos enfrenta entre nosotras. Deber\u00edamos hacer algo diferente y crecer juntas.<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando a los siete a\u00f1os me sub\u00ed por primera vez a la cabina de un avi\u00f3n, sab\u00eda exactamente lo que quer\u00eda hacer. Hoy me siento orgullosa de haber sido la capitana de la primera tripulaci\u00f3n de vuelo exclusivamente femenina de Venezuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera vez que entr\u00e9 en la cabina de un avi\u00f3n ten\u00eda siete a\u00f1os. Fue como ir a un parque de atracciones que siempre hab\u00eda querido visitar. All\u00ed estaba, viviendo mi sue\u00f1o. En ese momento supe que quer\u00eda pasar mi vida all\u00ed. Me asombraba la acci\u00f3n que ten\u00eda lugar antes, durante y despu\u00e9s del despegue. Al ver a todo el equipo realizar un vuelo, decid\u00ed hacerme piloto.<\/p>\n","protected":false},"author":153,"featured_media":67993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[772,261],"tags":[5306,5309,5311,2214,5307,197,5310,5308],"class_list":["post-68891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreras","category-sexo-y-genero","tag-aviacion-es","tag-capitan-de-vuelo-es","tag-la-capitana-de-vuelo-mas-joven-es","tag-latinoamerica","tag-tripulacion-femenina-es","tag-venezuela-es","tag-volar-es","tag-vuelo-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El capit\u00e1n Palacios se convierte en el capit\u00e1n de vuelo m\u00e1s joven de Latinoam\u00e9rica<\/title>\n<meta name=\"description\" content=\"Lorllys Andrea Palacios no s\u00f3lo se convirti\u00f3 en la capitana de vuelo m\u00e1s joven de Am\u00e9rica Latina, sino que dirigi\u00f3 la primera tripulaci\u00f3n femenina de Venezuela.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds\" \/>\n<meta property=\"og:description\" content=\"La primera vez que entr\u00e9 en la cabina de un avi\u00f3n ten\u00eda siete a\u00f1os. Fue como ir a un parque de atracciones que siempre hab\u00eda querido visitar. All\u00ed estaba, viviendo mi sue\u00f1o. En ese momento supe que quer\u00eda pasar mi vida all\u00ed. Me asombraba la acci\u00f3n que ten\u00eda lugar antes, durante y despu\u00e9s del despegue. Al ver a todo el equipo realizar un vuelo, decid\u00ed hacerme piloto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-22T13:35:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-05T22:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ariana Berroteran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ariana Berroteran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/\"},\"author\":{\"name\":\"Ariana Berroteran\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/2c8655aa1fbeed52301bcc1dec9ca6f8\"},\"headline\":\"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds\",\"datePublished\":\"2023-01-22T13:35:31+00:00\",\"dateModified\":\"2023-02-05T22:47:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/\"},\"wordCount\":1369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Andrea-palacios.webp\",\"keywords\":[\"aviaci\u00f3n\",\"capit\u00e1n de vuelo\",\"La capitana de vuelo m\u00e1s joven\",\"Latinoam\u00e9rica\",\"tripulaci\u00f3n femenina\",\"Venezuela\",\"volar\",\"vuelo\"],\"articleSection\":[\"Carreras\",\"Sexo y g\u00e9nero\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/\",\"name\":\"El capit\u00e1n Palacios se convierte en el capit\u00e1n de vuelo m\u00e1s joven de Latinoam\u00e9rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Andrea-palacios.webp\",\"datePublished\":\"2023-01-22T13:35:31+00:00\",\"dateModified\":\"2023-02-05T22:47:03+00:00\",\"description\":\"Lorllys Andrea Palacios no s\u00f3lo se convirti\u00f3 en la capitana de vuelo m\u00e1s joven de Am\u00e9rica Latina, sino que dirigi\u00f3 la primera tripulaci\u00f3n femenina de Venezuela.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Andrea-palacios.webp\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Andrea-palacios.webp\",\"width\":1280,\"height\":960,\"caption\":\"Andrea Palacios made history as the youngest pilot to become a flight chief in Latin American and the first to fly with an all-female crew in Venezuela | Photo courtesy of Andrea Palacios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/01\\\/22\\\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/2c8655aa1fbeed52301bcc1dec9ca6f8\",\"name\":\"Ariana Berroteran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Ariana Berroteran\"},\"description\":\"Ariana is a Venezuelan journalist with more than 10 years of experience in the media. She graduated from Santa Maria University and has worked in different digital and print media. Her passion is to seek truth and justice always.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/ariana-berroteran\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El capit\u00e1n Palacios se convierte en el capit\u00e1n de vuelo m\u00e1s joven de Latinoam\u00e9rica","description":"Lorllys Andrea Palacios no s\u00f3lo se convirti\u00f3 en la capitana de vuelo m\u00e1s joven de Am\u00e9rica Latina, sino que dirigi\u00f3 la primera tripulaci\u00f3n femenina de Venezuela.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/","og_locale":"es_ES","og_type":"article","og_title":"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds","og_description":"La primera vez que entr\u00e9 en la cabina de un avi\u00f3n ten\u00eda siete a\u00f1os. Fue como ir a un parque de atracciones que siempre hab\u00eda querido visitar. All\u00ed estaba, viviendo mi sue\u00f1o. En ese momento supe que quer\u00eda pasar mi vida all\u00ed. Me asombraba la acci\u00f3n que ten\u00eda lugar antes, durante y despu\u00e9s del despegue. Al ver a todo el equipo realizar un vuelo, decid\u00ed hacerme piloto.","og_url":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-01-22T13:35:31+00:00","article_modified_time":"2023-02-05T22:47:03+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp","type":"image\/webp"}],"author":"Ariana Berroteran","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Ariana Berroteran","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/"},"author":{"name":"Ariana Berroteran","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/2c8655aa1fbeed52301bcc1dec9ca6f8"},"headline":"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds","datePublished":"2023-01-22T13:35:31+00:00","dateModified":"2023-02-05T22:47:03+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/"},"wordCount":1369,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp","keywords":["aviaci\u00f3n","capit\u00e1n de vuelo","La capitana de vuelo m\u00e1s joven","Latinoam\u00e9rica","tripulaci\u00f3n femenina","Venezuela","volar","vuelo"],"articleSection":["Carreras","Sexo y g\u00e9nero"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/","url":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/","name":"El capit\u00e1n Palacios se convierte en el capit\u00e1n de vuelo m\u00e1s joven de Latinoam\u00e9rica","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp","datePublished":"2023-01-22T13:35:31+00:00","dateModified":"2023-02-05T22:47:03+00:00","description":"Lorllys Andrea Palacios no s\u00f3lo se convirti\u00f3 en la capitana de vuelo m\u00e1s joven de Am\u00e9rica Latina, sino que dirigi\u00f3 la primera tripulaci\u00f3n femenina de Venezuela.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp","width":1280,"height":960,"caption":"Andrea Palacios made history as the youngest pilot to become a flight chief in Latin American and the first to fly with an all-female crew in Venezuela | Photo courtesy of Andrea Palacios"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/01\/22\/la-capitana-mas-joven-de-latinoamerica-lidera-la-primera-tripulacion-de-vuelo-integramente-femenina-del-pais-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"La capitana m\u00e1s joven de Latinoam\u00e9rica lidera la primera tripulaci\u00f3n de vuelo \u00edntegramente femenina del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/2c8655aa1fbeed52301bcc1dec9ca6f8","name":"Ariana Berroteran","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Ariana Berroteran"},"description":"Ariana is a Venezuelan journalist with more than 10 years of experience in the media. She graduated from Santa Maria University and has worked in different digital and print media. Her passion is to seek truth and justice always.","url":"https:\/\/orato.world\/es\/author\/ariana-berroteran\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-100x100.webp",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-300x225.webp",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-770x578.webp",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-1024x768.webp",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-533x400.webp",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-360x240.webp",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios.webp",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Andrea-palacios-500x500.webp",500,500,true]},"uagb_author_info":{"display_name":"Ariana Berroteran","author_link":"https:\/\/orato.world\/es\/author\/ariana-berroteran\/"},"uagb_comment_info":0,"uagb_excerpt":"La primera vez que entr\u00e9 en la cabina de un avi\u00f3n ten\u00eda siete a\u00f1os. Fue como ir a un parque de atracciones que siempre hab\u00eda querido visitar. All\u00ed estaba, viviendo mi sue\u00f1o. En ese momento supe que quer\u00eda pasar mi vida all\u00ed. Me asombraba la acci\u00f3n que ten\u00eda lugar antes, durante y despu\u00e9s del despegue.&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/68891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/153"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=68891"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/68891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/67993"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=68891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=68891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=68891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}