{"id":71261,"date":"2023-03-26T07:38:48","date_gmt":"2023-03-26T14:38:48","guid":{"rendered":"https:\/\/orato.world\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/"},"modified":"2023-03-27T04:48:35","modified_gmt":"2023-03-27T11:48:35","slug":"la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/","title":{"rendered":"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">CIUDAD DE QUEZON, Filipinas &#8211; Hace 37 a\u00f1os, la <a href=\"https:\/\/www.outlookindia.com\/international\/philippines-commemorates-37th-anniversary-of-people-power-revolution-photos-265493\">Revoluci\u00f3n del Poder Popular<\/a> del 25 de febrero de 1986 derroc\u00f3 al presidente Ferdinand E. Marcos, padre, de su dictadura de dos d\u00e9cadas. En la actualidad, su \u00fanico hijo, Ferdinand \u00abBong Bong\u00bb R. Marcos, Jr. es el presidente de Filipinas.<\/p>\n\n<p class=\"wp-block-paragraph\">Ir\u00f3nicamente, Marcos Jr. declar\u00f3 el d\u00eda del levantamiento fiesta laboral especial para conmemorar el acontecimiento hist\u00f3rico. Los manifestantes consideran ofensivo este gesto. Creen que sirve como estrategia para confundir y desinformar al pueblo filipino sobre lo que significa la Revoluci\u00f3n de <a href=\"https:\/\/www.officialgazette.gov.ph\/edsa\/the-ph-protest\/\">EDSA<\/a>. Dicen que el presidente Marcos, hijo, utiliz\u00f3 esta misma estrategia para ganar las elecciones filipinas de mayo de 2022. Muchos creen que manipul\u00f3 los resultados de las elecciones, unos 31.629.783 votos, lo que condujo a su arrollador \u00e9xito.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/orato.world\/?s=philippines\">Ver m\u00e1s art\u00edculos de Filipinas en Orato World Media<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">La Revoluci\u00f3n EDSA o Revoluci\u00f3n del Poder del Pueblo surgi\u00f3 debido a los abusos de los derechos humanos y al r\u00e9gimen autoritario. El pueblo filipino se levant\u00f3 contra la corrupci\u00f3n y el saqueo de la <a href=\"https:\/\/www.bbc.com\/news\/world-asia-61379915\">familia Marcos.<\/a> Durante sus 20 a\u00f1os de reinado, la familia Marcos saque\u00f3 los recursos del pa\u00eds y lo endeud\u00f3 hasta que fueron exiliados. La revoluci\u00f3n no violenta acab\u00f3 con su poder pol\u00edtico e inspir\u00f3 el levantamiento prodemocr\u00e1tico en distintas partes del mundo.<\/p>\n\n<p class=\"wp-block-paragraph\">Varios grupos y organizaciones se reunieron este a\u00f1o en el monumento al Poder Popular para honrar a las v\u00edctimas de los abusos contra los derechos humanos y concientizar sobre el acontecimiento que cambi\u00f3 la historia. En el levantamiento original, filipinos de todo el pa\u00eds protestaron contra el gobierno autoritario y el ej\u00e9rcito del 22 al 25 de febrero de 1986. Considerada la mayor manifestaci\u00f3n no violenta celebrada en Manila, este acontecimiento hist\u00f3rico impuls\u00f3 el cambio en todo el mundo, ya que ciudadanos de todo el planeta observaron c\u00f3mo se desarrollaban los acontecimientos.<\/p>\n\n<p class=\"wp-block-paragraph\">Todas las fotos son cortes\u00eda de George Buid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Revoluci\u00f3n EDSA, o Revoluci\u00f3n del Poder del Pueblo, surgi\u00f3 debido a los abusos contra los derechos humanos, el gobierno autoritario y la corrupci\u00f3n y el saqueo de la familia Marcos durante sus 20 a\u00f1os de reinado. La familia Marcos saque\u00f3 los recursos del pa\u00eds, endeud\u00e1ndolo, hasta que fueron exiliados. <\/p>\n","protected":false},"author":160,"featured_media":71192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[874,725,534],"tags":[3498,3637,4069,5375,4147,3641,760,2672,5812],"class_list":["post-71261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crimen-y-corrupcion-es","category-educacion","category-galeria-de-fotos","tag-asia-es","tag-asia-russia-es","tag-dictadura","tag-dictadura-militar-es","tag-ferdinand-marcos-es","tag-ferdinand-marcos-jr-es","tag-philippines-es","tag-protesta-es-2","tag-revolucion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Recordando la revoluci\u00f3n popular filipina de 1986<\/title>\n<meta name=\"description\" content=\"Han pasado 37 a\u00f1os desde la Revoluci\u00f3n del Poder Popular que derroc\u00f3 al dictador Ferdinand E. Marcos padre e inspir\u00f3 al mundo hacia el cambio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos\" \/>\n<meta property=\"og:description\" content=\"La Revoluci\u00f3n EDSA, o Revoluci\u00f3n del Poder del Pueblo, surgi\u00f3 debido a los abusos contra los derechos humanos, el gobierno autoritario y la corrupci\u00f3n y el saqueo de la familia Marcos durante sus 20 a\u00f1os de reinado. La familia Marcos saque\u00f3 los recursos del pa\u00eds, endeud\u00e1ndolo, hasta que fueron exiliados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-26T14:38:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T11:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"George Buid\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"George Buid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/\"},\"author\":{\"name\":\"George Buid\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/f07397c3ec376a290b2c9f04481d2802\"},\"headline\":\"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos\",\"datePublished\":\"2023-03-26T14:38:48+00:00\",\"dateModified\":\"2023-03-27T11:48:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/\"},\"wordCount\":354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-8.jpg\",\"keywords\":[\"Asia\",\"Asia &amp; Russia\",\"Dictadura\",\"Dictadura Militar\",\"Ferdinand Marcos\",\"Ferdinand Marcos Jr\",\"Philippines\",\"Protesta\",\"revoluci\u00f3n\"],\"articleSection\":[\"Crimen y corrupci\u00f3n\",\"Educaci\u00f3n\",\"Galer\u00eda de fotos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/\",\"name\":\"Recordando la revoluci\u00f3n popular filipina de 1986\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-8.jpg\",\"datePublished\":\"2023-03-26T14:38:48+00:00\",\"dateModified\":\"2023-03-27T11:48:35+00:00\",\"description\":\"Han pasado 37 a\u00f1os desde la Revoluci\u00f3n del Poder Popular que derroc\u00f3 al dictador Ferdinand E. Marcos padre e inspir\u00f3 al mundo hacia el cambio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-8.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-8.jpg\",\"width\":1280,\"height\":854,\"caption\":\"Protesters hold a banner at the People Power Revolution Monument at EDSA that says \\\"Marcos is a Thief\\\" and campaign against the return of the Marcos family and possible authoritarian rule with the use of Marital Law. | Photo courtesy of George Buid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/03\\\/26\\\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/f07397c3ec376a290b2c9f04481d2802\",\"name\":\"George Buid\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"George Buid\"},\"description\":\"George Buid is an independent photographer and journalist based in Metro Manila, Philippines. His work has been published in Stern Crime, Transcontinental Times, InterAksyon, and Deutsche Welle news. He also contributes to the news wire Zuma Press. In addition to writing journalism, George is a self-taught photographer who started his photojournalism career and visual documentary storytelling in 2014. He focuses on capturing stories of everyday individuals, communities, and culture. Occassionally, he also covers science, history, sports, politics, art, and human interest.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/george-buid\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Recordando la revoluci\u00f3n popular filipina de 1986","description":"Han pasado 37 a\u00f1os desde la Revoluci\u00f3n del Poder Popular que derroc\u00f3 al dictador Ferdinand E. Marcos padre e inspir\u00f3 al mundo hacia el cambio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/","og_locale":"es_ES","og_type":"article","og_title":"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos","og_description":"La Revoluci\u00f3n EDSA, o Revoluci\u00f3n del Poder del Pueblo, surgi\u00f3 debido a los abusos contra los derechos humanos, el gobierno autoritario y la corrupci\u00f3n y el saqueo de la familia Marcos durante sus 20 a\u00f1os de reinado. La familia Marcos saque\u00f3 los recursos del pa\u00eds, endeud\u00e1ndolo, hasta que fueron exiliados.","og_url":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-03-26T14:38:48+00:00","article_modified_time":"2023-03-27T11:48:35+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg","type":"image\/jpeg"}],"author":"George Buid","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"George Buid","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/"},"author":{"name":"George Buid","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/f07397c3ec376a290b2c9f04481d2802"},"headline":"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos","datePublished":"2023-03-26T14:38:48+00:00","dateModified":"2023-03-27T11:48:35+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/"},"wordCount":354,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg","keywords":["Asia","Asia &amp; Russia","Dictadura","Dictadura Militar","Ferdinand Marcos","Ferdinand Marcos Jr","Philippines","Protesta","revoluci\u00f3n"],"articleSection":["Crimen y corrupci\u00f3n","Educaci\u00f3n","Galer\u00eda de fotos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/","url":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/","name":"Recordando la revoluci\u00f3n popular filipina de 1986","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg","datePublished":"2023-03-26T14:38:48+00:00","dateModified":"2023-03-27T11:48:35+00:00","description":"Han pasado 37 a\u00f1os desde la Revoluci\u00f3n del Poder Popular que derroc\u00f3 al dictador Ferdinand E. Marcos padre e inspir\u00f3 al mundo hacia el cambio.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg","width":1280,"height":854,"caption":"Protesters hold a banner at the People Power Revolution Monument at EDSA that says \"Marcos is a Thief\" and campaign against the return of the Marcos family and possible authoritarian rule with the use of Marital Law. | Photo courtesy of George Buid"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/03\/26\/la-revolucion-del-poder-popular-de-filipinas-conmemorada-como-uno-de-los-mayores-esfuerzos-activistas-no-violentos-de-todos-los-tiempos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"La Revoluci\u00f3n del Poder Popular de Filipinas conmemorada como uno de los mayores esfuerzos activistas no violentos de todos los tiempos"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/f07397c3ec376a290b2c9f04481d2802","name":"George Buid","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"George Buid"},"description":"George Buid is an independent photographer and journalist based in Metro Manila, Philippines. His work has been published in Stern Crime, Transcontinental Times, InterAksyon, and Deutsche Welle news. He also contributes to the news wire Zuma Press. In addition to writing journalism, George is a self-taught photographer who started his photojournalism career and visual documentary storytelling in 2014. He focuses on capturing stories of everyday individuals, communities, and culture. Occassionally, he also covers science, history, sports, politics, art, and human interest.","url":"https:\/\/orato.world\/es\/author\/george-buid\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg",1280,854,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-300x200.jpg",300,200,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-770x514.jpg",640,427,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg",1280,854,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg",1280,854,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-600x400.jpg",600,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg",300,200,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg",400,267,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/feature-8.jpg",600,400,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/feature-8-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"George Buid","author_link":"https:\/\/orato.world\/es\/author\/george-buid\/"},"uagb_comment_info":0,"uagb_excerpt":"La Revoluci\u00f3n EDSA, o Revoluci\u00f3n del Poder del Pueblo, surgi\u00f3 debido a los abusos contra los derechos humanos, el gobierno autoritario y la corrupci\u00f3n y el saqueo de la familia Marcos durante sus 20 a\u00f1os de reinado. La familia Marcos saque\u00f3 los recursos del pa\u00eds, endeud\u00e1ndolo, hasta que fueron exiliados.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/71261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=71261"}],"version-history":[{"count":0,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/71261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/71192"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=71261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=71261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=71261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}