{"id":74346,"date":"2023-06-21T05:00:00","date_gmt":"2023-06-21T12:00:00","guid":{"rendered":"https:\/\/orato.world\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/"},"modified":"2023-07-02T12:18:39","modified_gmt":"2023-07-02T19:18:39","slug":"una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/","title":{"rendered":"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/subject-33-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-400x400.jpg 400w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-33.jpg 585w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">INTERVIEW SUBJECT<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.instagram.com\/ariasuriburu\/?hl=en\" target=\"_blank\" rel=\"noreferrer noopener\">Gabriela Arias Uriburu<\/a> is an Argentine writer and human rights activist, renowned for her fight to regain contact with her children after her ex-husband, Imad Shaban, illegally took their children to Jordan. She became a public and international figure for Human Rights after starting <a href=\"https:\/\/www.idealist.org\/en\/nonprofit\/66130bd1925f469e8535b9f7262791f1-foundchild-buenos-aires\" target=\"_blank\" rel=\"noreferrer noopener\">FoundChild<\/a>, the first NGO that acts as a mediator during these legal battles to ensure the child&#8217;s safety first. She received recognition from the Honorable Senate of the Nation (2014) as a leading figure for Human Rights in the Buenos Aires Legislature. She currently produces and coordinates the \u00ab<a href=\"https:\/\/www.facebook.com\/GabrielaAriasUriburuOficial\/videos\/taller-pap%C3%A1-mam%C3%A1est%C3%A1s-sin-fuerzas-est%C3%A1s-en-carencia-no-hay-prosperidad-en-tu-vid\/541877654145076\/\" target=\"_blank\" rel=\"noreferrer noopener\">Encounter and Healing<\/a> Workshops\u00bb through which she carries out intense work as a lecturer addressing different topics such as familial bonds, resilience, women, and multiculturalism, among others.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">BACKGROUND INFORMATION<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.idealist.org\/en\/nonprofit\/66130bd1925f469e8535b9f7262791f1-foundchild-buenos-aires\">Foundchild<\/a> is a Children&#8217;s Institution, acting as a mediator between parents, as well as providing the necessary support and containment to safeguard the rights of children to develop fully. It is an NGO that addresses the issue of family restitution by and for the child, prioritizing their place in the family, and in the world.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">BUENOS AIRES, Argentina &#8211; Cuando mi ex marido y yo nos enamoramos por primera vez, est\u00e1bamos decididos a superar cualquier obst\u00e1culo que se nos presentara y a emprender un viaje juntos. Sin embargo, la realidad result\u00f3 ser mucho m\u00e1s dif\u00edcil, y nuestra relaci\u00f3n acab\u00f3 por desmoronarse. En medio del doloroso proceso de divorcio, se llev\u00f3 ilegalmente a Jordania a nuestros tres preciosos hijos. <\/p>\n\n<p class=\"wp-block-paragraph\">Los a\u00f1os siguientes se convirtieron en una lucha constante por recuperar mi presencia en sus vidas. Durante los primeros tres largos meses, no tuve ni idea de su paradero. Las autoridades acabaron descubriendo su paradero, y el gobierno argentino confirm\u00f3 que se encontraban en Jordania. Marc\u00f3 el comienzo de un nuevo cap\u00edtulo y un nuevo camino en mi vida.<\/p>\n\n<p class=\"wp-block-paragraph\">El calvario de que me quitaran a mis hijos y no poder criarlos durante tanto tiempo sigue siendo una carga inmensa que llevo. A pesar de todo, nunca quise ser una v\u00edctima. En lugar de eso, intent\u00e9 encontrar un sentido a las circunstancias y dar prioridad a mis hijos por encima de todo. Tengo profundas cicatrices grabadas en mi ser y, a\u00fan hoy, me despierto por la ma\u00f1ana, agradecida por estar viva, pero sintiendo una profunda contradicci\u00f3n en mi interior, un recordatorio de que a\u00fan queda mucho por curar.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/orato.world\/es\/2023\/06\/03\/una-mujer-que-tenia-la-custodia-total-de-sus-hijos-presenta-una-demanda-por-sustraccion-contra-su-ex-el-frente-nacional-de-mujeres-se-implica\/\"><strong><em>Related: Woman who had full custody of her children files abduction suit against ex, National Women\u2019s Front gets involved<\/em><\/strong><\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-when-he-took-my-children-away-i-felt-the-world-open-up-and-swallow-me-whole\"><strong>Cuando se llev\u00f3 a mis hijos, sent\u00ed que el mundo se abr\u00eda y me tragaba entera. <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cuando era muy joven, mis padres atravesaron una separaci\u00f3n que me sumi\u00f3 en una batalla constante entre su ira, su frustraci\u00f3n y su tristeza. Me encontr\u00e9 atrapada entre dos fuegos, enfrent\u00e1ndome a dolorosas lecciones que ning\u00fan ni\u00f1o deber\u00eda soportar. La experiencia me marc\u00f3. Decid\u00ed muy pronto que ninguno de mis hijos conocer\u00eda jam\u00e1s este tipo de angustia. Cuando conoc\u00ed a Im\u00e1n, al principio todo parec\u00eda un cuento de hadas. Poco despu\u00e9s decidimos casarnos y formar nuestra propia familia. Sin embargo, nos enfrentamos a crisis matrimoniales que resultaron irresolubles, lo que nos llev\u00f3 a separarnos. A pesar de esa profunda tragedia familiar, segu\u00ed decidida a no infligir ning\u00fan da\u00f1o a mis hijos. Ese se convirti\u00f3 en mi principio rector.<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando descubr\u00ed por primera vez que Im\u00e1n se hab\u00eda llevado a mis hijos a Jordania sin mi conocimiento, sent\u00ed que mi pecho apenas pod\u00eda contener los latidos de mi coraz\u00f3n. Una horrible ansiedad recorri\u00f3 mi cuerpo. Durante d\u00edas, llor\u00e9 sin parar, sinti\u00e9ndome completamente perdida. Experiment\u00e9 mucho insomnio, incapaz de pensar en otra cosa. Aun as\u00ed, segu\u00eda decidida a encontrarlos a cualquier precio. En cuanto descubr\u00ed su paradero en Jordania, me embarqu\u00e9 en la misi\u00f3n de reconstruir el v\u00ednculo con mis hijos. <\/p>\n\n<p class=\"wp-block-paragraph\">Me aterrorizaba que pensaran que les hab\u00eda abandonado. A\u00fan eran muy peque\u00f1os y mi \u00fanica preocupaci\u00f3n era ser la mejor madre posible para ellos. Decid\u00ed conscientemente abordar la situaci\u00f3n con calma y no con ira. Incluso cuando me ofrecieron los medios para recuperarlos por la fuerza, me negu\u00e9, sabiendo en el fondo que mi camino ten\u00eda que venir de otra direcci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Despu\u00e9s de cuatro largos a\u00f1os, por fin pude ver el interior de su casa<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Con el tiempo, empec\u00e9 a recibir visitas programadas para ver a mis hijos. Tuvieron lugar en una habitaci\u00f3n muy peque\u00f1a de una residencia porque no se me permiti\u00f3 ver su casa. Tuvieron lugar en una habitaci\u00f3n peque\u00f1a de una residencia porque no se me permiti\u00f3 ver su casa. Cada vez que ven\u00eda a verlos, corr\u00edan emocionados a mis brazos, gritando \u00abmam\u00e1\u00bb a todo pulm\u00f3n. Significaba todo para m\u00ed. A pesar de todo, nunca dej\u00e9 de estar con mis hijos, incluso cuando est\u00e1bamos f\u00edsicamente separados. <\/p>\n\n<p class=\"wp-block-paragraph\">Ten\u00eda tantas ganas de encontrar las palabras adecuadas para decirles lo mucho que les quer\u00eda a pesar de todo lo que nos separaba. En cuanto est\u00e1bamos en la misma habitaci\u00f3n, se pod\u00eda sentir el amor por todas partes. No hubo necesidad de explicaciones ni de restablecer nuestra conexi\u00f3n; simplemente volvimos a ser nosotros. Las palabras quedaron obsoletas, sustituidas por colores vibrantes y sentidos intensificados. Recuerdo perfectamente que, mientras caminaba hacia ellos, todo a nuestro alrededor parec\u00eda iluminarse con un resplandor radiante.<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando me divorci\u00e9, mi hijo menor ten\u00eda s\u00f3lo un a\u00f1o y ocho meses, todav\u00eda era un beb\u00e9. Mi hija Sahira ten\u00eda cuatro a\u00f1os y mi hijo Karim cinco. En 2004, entr\u00e9 en su casa por primera vez tras a\u00f1os de separaci\u00f3n. Las l\u00e1grimas corr\u00edan por mi rostro mientras avanzaba lentamente por las habitaciones. Se agarraron a mis piernas, nuestros ojos se fijaron y nos abrazamos. Las paredes estaban adornadas con todo lo que les hab\u00eda enviado a lo largo de esos a\u00f1os. Recuerdo el bander\u00edn de Boca Juniors, los posters que hab\u00eda hecho con fotos desde su nacimiento hasta ese d\u00eda, y las figuritas. Las despedidas durante esas visitas parec\u00edan eternas.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Las visitas que tuve con ellos son lo \u00fanico que me hizo seguir adelante <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Las visitas que ten\u00edamos eran muy escasas, as\u00ed que me asegur\u00e9 de aprovechar al m\u00e1ximo cada momento. Llevaba un mont\u00f3n de regalos en la valija, como Mary Poppins. Les llev\u00e9 pelotas de f\u00fatbol firmadas, camisetas, juegos y alfajores (dulces argentinos rellenos de dulce de leche). Siempre que est\u00e1bamos separados les extra\u00f1aba much\u00edsimo y empezaba a preparar la valija para nuestra pr\u00f3xima visita. Me tom\u00e9 mi tiempo para organizarlo, cada vez con nuevas sorpresas para ellos. <\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, estas visitas no fueron decisi\u00f3n \u00fanicamente m\u00eda. <a href=\"https:\/\/www.arabnews.com\/node\/401246\">Necesitaba el permiso<\/a> del padre de mis hijos y de toda su familia. No importaba si quer\u00eda o no. Mi abogado me advirti\u00f3 una vez: \u00abSi tengo que atarte a una silla, lo voy a hacer, porque no pod\u00e9s poner un pie ah\u00ed sin inmunidad diplom\u00e1tica. Una vez que entras en Jordania, est\u00e1s bajo su propiedad y la de su familia. Esa es la triste realidad\u00bb. Este viaje me llev\u00f3 muchos a\u00f1os. Mientras trabajaba incansablemente por el bien de mis hijos, empec\u00e9 a darme cuenta del inmenso n\u00famero de otros ni\u00f1os que se encontraban en circunstancias similares. <\/p>\n\n<p class=\"wp-block-paragraph\">Como madre, tuve que dejar a un lado mi angustia y enfrentarme a la colosal complejidad de la situaci\u00f3n de mis hijos. El primer a\u00f1o fue agonizante. Por las ma\u00f1anas, me despertaba sinti\u00e9ndome totalmente agobiada, convencida de que ya no podr\u00eda soportar el peso. La lucha interna en mi interior era feroz. Sent\u00eda como si me estuviera muriendo lentamente. Segu\u00eda viendo sus sonrisas, oyendo sus risitas a mi alrededor. Muchas veces me parec\u00eda demasiado, pero luchaba con todas mis fuerzas para seguir adelante.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Mi viaje me llev\u00f3 a fundar mi propia organizaci\u00f3n <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Su padre y yo experimentamos muchos altibajos en nuestra relaci\u00f3n a lo largo de los a\u00f1os. Cada vez que nos encontr\u00e1bamos reunidos por los ni\u00f1os, se convert\u00eda en un proceso de inmenso crecimiento para ambos. Hemos aprendido y evolucionado mucho desde nuestra separaci\u00f3n. Nuestra relaci\u00f3n mejor\u00f3 con el tiempo y nos esforzamos por crear un entorno positivo por el bien de nuestros hijos. Sol\u00eda dejar que la rabia que sent\u00eda me consumiera cada d\u00eda que mis hijos no estaban conmigo. Poco a poco, tom\u00e9 la decisi\u00f3n de dejarlo pasar y vivir el momento presente. Mientras navego por esta extra\u00f1a situaci\u00f3n, hoy me siento agradecida de que mis hijos y yo compartamos una relaci\u00f3n maravillosa. Casos como el m\u00edo, en el que uno de los progenitores se ve incapaz de ver a sus hijos y debe iniciar una batalla legal para poder verlos, siguen siendo extremadamente frecuentes.<\/p>\n\n<p class=\"wp-block-paragraph\"> Requiere mucho valor y mucha lucha. Me entristecen todos los padres que han sido separados de sus hijos en contra de su voluntad. S\u00e9 muy bien lo doloroso que es. Tiene que haber m\u00e1s ayuda disponible para que puedan emprender una batalla legal. En los \u00faltimos a\u00f1os, he realizado un trabajo interior para buscar la paz y la reconciliaci\u00f3n con la dram\u00e1tica historia de mi vida. Fund\u00e9 <a href=\"https:\/\/www.idealist.org\/en\/nonprofit\/66130bd1925f469e8535b9f7262791f1-foundchild-buenos-aires\">FoundChild<\/a>, una organizaci\u00f3n destinada a dar voz a personas en situaciones similares y a proteger a los ni\u00f1os. Actuamos como mediadores en batallas legales para garantizar el compromiso entre ambas partes, dando prioridad al menor. Es importante superar las dificultades con fuerza interior. Si todav\u00eda est\u00e1s vivo, significa que pod\u00e9s hacerlo. Debemos aprovechar la sabidur\u00eda de la resiliencia. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando descubr\u00ed por primera vez que se los hab\u00eda llevado a Jordania sin que yo lo supiera, sent\u00ed que mi pecho apenas pod\u00eda contener los latidos de mi coraz\u00f3n. Una horrible ansiedad recorri\u00f3 mi cuerpo. Durante d\u00edas, llor\u00e9 sin parar, sinti\u00e9ndome completamente perdida. <\/p>\n","protected":false},"author":28,"featured_media":74108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[874,261],"tags":[701,193,6446,1976,1714,6447,2214,3761,3281],"class_list":["post-74346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crimen-y-corrupcion-es","category-sexo-y-genero","tag-abduction-es","tag-argentina-es","tag-batalla-legal","tag-buenos-aires-es","tag-divorcio","tag-jordania","tag-latinoamerica","tag-ninos","tag-secuestro-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una madre relata el d\u00eda en que su ex le quit\u00f3 a sus hijos<\/title>\n<meta name=\"description\" content=\"Durante cuatro largos a\u00f1os, Gabriela Arias se vio separada de sus hijos tras divorciarse de su padre, y s\u00f3lo los ve\u00eda en breves visitas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Cuando descubr\u00ed por primera vez que se los hab\u00eda llevado a Jordania sin que yo lo supiera, sent\u00ed que mi pecho apenas pod\u00eda contener los latidos de mi coraz\u00f3n. Una horrible ansiedad recorri\u00f3 mi cuerpo. Durante d\u00edas, llor\u00e9 sin parar, sinti\u00e9ndome completamente perdida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-02T19:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariela Laksman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariela Laksman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/\"},\"author\":{\"name\":\"Mariela Laksman\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\"},\"headline\":\"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os\",\"datePublished\":\"2023-06-21T12:00:00+00:00\",\"dateModified\":\"2023-07-02T19:18:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/\"},\"wordCount\":1505,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-63.jpg\",\"keywords\":[\"abduction\",\"Argentina\",\"batalla legal\",\"Buenos Aires\",\"Divorcio\",\"jordania\",\"Latinoam\u00e9rica\",\"ni\u00f1os\",\"Secuestro\"],\"articleSection\":[\"Crimen y corrupci\u00f3n\",\"Sexo y g\u00e9nero\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/\",\"name\":\"Una madre relata el d\u00eda en que su ex le quit\u00f3 a sus hijos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-63.jpg\",\"datePublished\":\"2023-06-21T12:00:00+00:00\",\"dateModified\":\"2023-07-02T19:18:39+00:00\",\"description\":\"Durante cuatro largos a\u00f1os, Gabriela Arias se vio separada de sus hijos tras divorciarse de su padre, y s\u00f3lo los ve\u00eda en breves visitas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-63.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-63.jpg\",\"width\":1280,\"height\":960,\"caption\":\"It took four long years for Gabriela Arias Uriburu to be reunited with her children and get to see the inside of the house they grew up in whilst being separated from her. While she still holds on to a lot of trauma, she chooses to only focus on the positive as she slowly rebuilds herself. | Photo courtesy of Gabriela Arias Uriburu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/06\\\/21\\\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\",\"name\":\"Mariela Laksman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariela Laksman\"},\"description\":\"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \\\"Nuevo Sudaca Border\\\" with the microfiction book \\\"Un Tigre con la Boca Abierta\\\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariela-laksman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una madre relata el d\u00eda en que su ex le quit\u00f3 a sus hijos","description":"Durante cuatro largos a\u00f1os, Gabriela Arias se vio separada de sus hijos tras divorciarse de su padre, y s\u00f3lo los ve\u00eda en breves visitas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os","og_description":"Cuando descubr\u00ed por primera vez que se los hab\u00eda llevado a Jordania sin que yo lo supiera, sent\u00ed que mi pecho apenas pod\u00eda contener los latidos de mi coraz\u00f3n. Una horrible ansiedad recorri\u00f3 mi cuerpo. Durante d\u00edas, llor\u00e9 sin parar, sinti\u00e9ndome completamente perdida.","og_url":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-06-21T12:00:00+00:00","article_modified_time":"2023-07-02T19:18:39+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg","type":"image\/jpeg"}],"author":"Mariela Laksman","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariela Laksman","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/"},"author":{"name":"Mariela Laksman","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90"},"headline":"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os","datePublished":"2023-06-21T12:00:00+00:00","dateModified":"2023-07-02T19:18:39+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/"},"wordCount":1505,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg","keywords":["abduction","Argentina","batalla legal","Buenos Aires","Divorcio","jordania","Latinoam\u00e9rica","ni\u00f1os","Secuestro"],"articleSection":["Crimen y corrupci\u00f3n","Sexo y g\u00e9nero"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/","url":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/","name":"Una madre relata el d\u00eda en que su ex le quit\u00f3 a sus hijos","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg","datePublished":"2023-06-21T12:00:00+00:00","dateModified":"2023-07-02T19:18:39+00:00","description":"Durante cuatro largos a\u00f1os, Gabriela Arias se vio separada de sus hijos tras divorciarse de su padre, y s\u00f3lo los ve\u00eda en breves visitas.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg","width":1280,"height":960,"caption":"It took four long years for Gabriela Arias Uriburu to be reunited with her children and get to see the inside of the house they grew up in whilst being separated from her. While she still holds on to a lot of trauma, she chooses to only focus on the positive as she slowly rebuilds herself. | Photo courtesy of Gabriela Arias Uriburu"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/06\/21\/una-madre-relata-el-tragico-dia-en-que-su-ex-se-llevo-a-sus-hijos-y-desaparecio-durante-cuatro-largos-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Una madre relata el tr\u00e1gico d\u00eda en que su ex se llev\u00f3 a sus hijos y desapareci\u00f3 durante cuatro largos a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90","name":"Mariela Laksman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariela Laksman"},"description":"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \"Nuevo Sudaca Border\" with the microfiction book \"Un Tigre con la Boca Abierta\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.","url":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"}]}},"modified_by":"Titu","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/feature-63.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/feature-63-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Mariela Laksman","author_link":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"},"uagb_comment_info":0,"uagb_excerpt":"Cuando descubr\u00ed por primera vez que se los hab\u00eda llevado a Jordania sin que yo lo supiera, sent\u00ed que mi pecho apenas pod\u00eda contener los latidos de mi coraz\u00f3n. Una horrible ansiedad recorri\u00f3 mi cuerpo. Durante d\u00edas, llor\u00e9 sin parar, sinti\u00e9ndome completamente perdida.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/74346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=74346"}],"version-history":[{"count":3,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/74346\/revisions"}],"predecessor-version":[{"id":74512,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/74346\/revisions\/74512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/74108"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=74346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=74346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=74346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}