{"id":74971,"date":"2023-07-12T06:49:19","date_gmt":"2023-07-12T13:49:19","guid":{"rendered":"https:\/\/orato.world\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/"},"modified":"2023-07-16T11:56:43","modified_gmt":"2023-07-16T18:56:43","slug":"cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/","title":{"rendered":"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra."},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/subject-44-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-770x770.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-400x400.jpg 400w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-44.jpg 800w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">INTERVIEW SUBJECT<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.instagram.com\/pabloborboroglu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pablo Garc\u00eda Borboroglu<\/a> is the founder and president of the Global Penguin Society, an international conservation coalition that protects the world&#8217;s penguin species. He is also the founder and co-chair of the <a href=\"https:\/\/www.penguinsg.org\/about-us#:~:text=Like%20other%20Specialist%20Groups%2C%20the,global%20penguin%20issues%20and%20conservation.\" target=\"_blank\" rel=\"noreferrer noopener\">IUCN SSC Penguin Specialist Group<\/a>, a researcher at the National Research Council of Argentina, and an affiliated associate professor at the University of Washington. Borboroglu has been in the field of marine conservation for 32 years and focuses on different ecological aspects of seabird conservation, with a special emphasis on penguins. His work has helped protect 32 million acres of ocean and coastal habitat. Borboroglu also coordinates an educational program targeting global international audiences, local communities, and schools near penguin colonies in developing countries. He become the first Latin American to receive the world\u2019s leading animal conservation award, the <a href=\"https:\/\/www.indianapoliszoo.com\/prize\/\">2023 The Indianapolis Prize<\/a>.\u00a0<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">BACKGROUND INFORMATION<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.globalpenguinsociety.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">The Global Penguin Society<\/a> is an internationally recognized, leading organization dedicated to the conservation of penguins, the coasts, and the oceans they inhabit. The Global Penguin Society fosters the conservation of all penguin species and their associated ecosystems, generating science, management guidelines, and education.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">CHUBUT, Argentina &#8211; Mientras exploraba una franja de vegetaci\u00f3n aut\u00f3ctona, mi grupo tropez\u00f3 con una colonia de 12 ping\u00fcinos. Sent\u00ed una oleada de adrenalina recorriendo mi cuerpo mientras los observaba desde lejos. La visi\u00f3n inicial de las primeras parejas y los nidos dej\u00f3 entrever el potencial de una colonia emergente. Sin embargo, factores perjudiciales amenazaban sus posibilidades de prosperar. En la misma zona, la gente llevaba perros, prend\u00eda fogatas, tiraba basura y cazaba. Ten\u00edamos que intervenir y crear un entorno sano y seguro para los ping\u00fcinos.<\/p>\n\n<p class=\"wp-block-paragraph\">Trabajando incansablemente para garantizar su seguridad, obligamos a las autoridades a declarar la playa de El Pedral Refugio de Vida Silvestre. Siguieron estudios de investigaci\u00f3n y campa\u00f1as de limpieza de residuos pl\u00e1sticos, con la participaci\u00f3n de cientos de ni\u00f1os a la vez. Tambi\u00e9n organizamos festivales educativos. Poco a poco, la playa de El Pedral pas\u00f3 a ser reconocida como un lugar dedicado a la conservaci\u00f3n, el cuidado y las acciones de concientizaci\u00f3n. <\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/orato.world\/?s=argentina\"><strong><em>Lee m\u00e1s historias de Argentina en Orato World Media <\/em><\/strong><\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-meeting-clarita-the-penguin-colony-s-founding-mother\"><strong>Conocer a Clarita, la madre fundadora de la colonia de ping\u00fcinos <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Mientras continuaba el viaje para preservar la colonia de ping\u00fcinos de El Pedral, el equipo tuvo la extraordinaria oportunidad de identificar a la madre del primer polluelo nacido en los nidos iniciales en 2009. La llamamos Clarita. Calculamos que Clarita ten\u00eda al menos cinco a\u00f1os cuando empez\u00f3 a reproducirse, lo que significa que hoy tiene al menos 20 a\u00f1os. Los ping\u00fcinos suelen vivir entre 30 y 35 a\u00f1os. <\/p>\n\n<p class=\"wp-block-paragraph\">Clarita mostr\u00f3 un comportamiento tranquilo y relajado y no nos dio ninguna preocupaci\u00f3n cuando nos acercamos a ella para el estudio. Su personalidad segura de s\u00ed misma la distingu\u00eda del resto de los ping\u00fcinos. Estar cerca de ella resultaba emocionante y generaba una sensaci\u00f3n de amor y respeto. Pronto descubrimos que Clarita hab\u00eda creado un v\u00ednculo con un ping\u00fcino llamado Eduardo. Su relaci\u00f3n segu\u00eda el patr\u00f3n t\u00edpico de las parejas de ping\u00fcinos: se re\u00fanen cada a\u00f1o en el mismo nido y pasan juntos la temporada. <\/p>\n\n<p class=\"wp-block-paragraph\">La pareja sincroniza sus actividades. Cuando Clarita est\u00e1 en el nido, Eduardo va a alimentar y trae comida para los polluelos. Este patr\u00f3n contin\u00faa durante tres meses seguidos. Cuando concluye la temporada de cr\u00eda, cada ping\u00fcino emigra de forma independiente. Algunos recorren hasta 6.000 kil\u00f3metros, se aventuran hasta la regi\u00f3n meridional de Brasil y luego regresan. <\/p>\n\n<p class=\"wp-block-paragraph\">Los ping\u00fcinos no pueden criar solos a sus polluelos; se requiere el esfuerzo conjunto de ambos progenitores. Por eso adoptan una estrategia mon\u00f3gama durante la \u00e9poca de reproducci\u00f3n. Presenciar este comportamiento por primera vez me provoc\u00f3 emociones tan fuertes que me encontr\u00e9 sec\u00e1ndome las l\u00e1grimas mientras trabajaba. Fue m\u00e1gico verlos interactuar entre s\u00ed de una forma tan delicada. <\/p>\n\n<h2 class=\"wp-block-heading\"><strong>La educaci\u00f3n de los ni\u00f1os de todo el mundo y la creaci\u00f3n de Club Penguin<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Desde mi adolescencia, la naturaleza me influy\u00f3 notablemente. Ayudaba a mi abuela cuando visitaba las colonias de ping\u00fcinos para cuidarlos. Con el tiempo, quise hacer m\u00e1s, y necesitaba una educaci\u00f3n superior para ello. Me inscrib\u00ed en la carrera de Ciencias Biol\u00f3gicas de la Universidad de la Patagonia y durante todos mis estudios so\u00f1\u00e9 con contribuir m\u00e1s eficazmente a solucionar las injusticias contra estos animales.<\/p>\n\n<p class=\"wp-block-paragraph\">Con el tiempo, me di cuenta de que las comunidades cercanas a los h\u00e1bitats de los ping\u00fcinos ten\u00edan escasos conocimientos sobre la especie. Con mi grupo, tomamos una decisi\u00f3n estrat\u00e9gica. Quer\u00edamos centrarnos primero en educar a los ni\u00f1os. Tras realizar una evaluaci\u00f3n exhaustiva y descubrir que la gente de pueblos situados a media hora de las colonias de ping\u00fcinos nunca las visitaba, nos pusimos en marcha. Gracias al programa que creamos, casi 8.000 ni\u00f1os de pa\u00edses en desarrollo han conocido personalmente a los ping\u00fcinos locales. <\/p>\n\n<p class=\"wp-block-paragraph\">Al ver el amor genuino y la emoci\u00f3n que muestran los ni\u00f1os al interactuar con los ping\u00fcinos, se me encogi\u00f3 el coraz\u00f3n y supe que hab\u00edamos marcado la diferencia. El trabajo les sensibiliz\u00f3 y les dio una nueva conciencia y aprecio por los ping\u00fcinos y por la naturaleza. Cuando lleg\u00f3 el momento de crear zonas protegidas, la Global Penguin Society y Disney se unieron a nosotros. Colaboramos en el popular juego <a href=\"https:\/\/newcp.net\/en\/\">Club Penguin<\/a>, incorporando contenidos educativos para enriquecer los conocimientos de los jugadores sobre la conservaci\u00f3n de los ping\u00fcinos. La popularidad de esa asociaci\u00f3n y el apoyo que obtuvimos nos permitieron hacer realidad nuestro incre\u00edble sue\u00f1o de conservaci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Ganar el premio m\u00e1s importante de mi carrera y sensibilizar a la opini\u00f3n p\u00fablica <\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cuando gan\u00e9 el Premio Indian\u00e1polis 2023, sent\u00ed una gran gratitud y un gran honor. Me sent\u00e9 entre los seis finalistas y lleg\u00f3 el anuncio. Pronunciaron mi nombre y sent\u00ed que me invad\u00eda una oleada de emociones. Mi mente se traslad\u00f3 inmediatamente a mi abuela, y las piernas me temblaron cuando me recorri\u00f3 una oleada de sentimientos. Cuando entr\u00e9 en el escenario, me sent\u00ed como flotando. Una sonrisa inund\u00f3 mi rostro al experimentar una felicidad incre\u00edble. Me sent\u00ed como si hubiera ganado la Copa Mundial de la FIFA.<\/p>\n\n<p class=\"wp-block-paragraph\">El premio me ha dado algo importante: m\u00e1s visibilidad para apoyar iniciativas que protegen a los ping\u00fcinos y sus h\u00e1bitats. Cada d\u00eda me propongo inspirar y motivar a personas de todo el mundo para que tomen medidas decisivas para salvaguardar el medio ambiente. <\/p>\n\n<p class=\"wp-block-paragraph\">Me fijo en los efectos de la colonizaci\u00f3n humana y el cambio clim\u00e1tico. En cierto sentido, nos convertimos en depredadores, interfiriendo en el h\u00e1bitat de los ping\u00fcinos y causando destrucci\u00f3n a su alrededor. Veo c\u00f3mo los incendios de vegetaci\u00f3n, por ejemplo, provocados por los cambios medioambientales, suponen una importante amenaza para su supervivencia. Lamentablemente, los ping\u00fcinos no reconocen el fuego como un peligro directo y, a menudo, permanecen inm\u00f3viles ante las llamas envolventes. Me entristece.<\/p>\n\n<p class=\"wp-block-paragraph\">Actualmente, nuestro objetivo es crear una zona protegida para 600.000 ping\u00fcinos. Cuando te dedicas a influir positivamente en los dem\u00e1s, sean humanos o animales, se abre un mundo de posibilidades. Te permite crear un cambio significativo. El ingrediente esencial es abordar estas tareas con pasi\u00f3n, desde lo m\u00e1s profundo del coraz\u00f3n. Esa fuerza puede mover monta\u00f1as.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>Todas las fotos son cortes\u00eda de la Global Penguin Society.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clarita mostr\u00f3 un comportamiento tranquilo y relajado y no nos dio ninguna preocupaci\u00f3n cuando nos acercamos a ella para el estudio. Su personalidad segura de s\u00ed misma la distingu\u00eda del resto de los ping\u00fcinos. Estar cerca de ella resultaba emocionante y generaba una sensaci\u00f3n de amor y respeto. Pronto descubrimos que Clarita hab\u00eda creado un v\u00ednculo con un ping\u00fcino llamado Eduardo. <\/p>\n","protected":false},"author":28,"featured_media":74767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[772,319,416],"tags":[193,6551,4235,2214,6090,6550,5895,4237],"class_list":["post-74971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carreras","category-medio-ambiente","category-viajes-y-aventuras","tag-argentina-es","tag-biologist-es","tag-derechos-de-los-animales","tag-latinoamerica","tag-pinguinos","tag-premio-es","tag-preservacion-animal","tag-rescate-de-animales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un bi\u00f3logo argentino ayud\u00f3 a preservar cientos de colonias de ping\u00fcinos<\/title>\n<meta name=\"description\" content=\"Un d\u00eda, tropezamos con una colonia de 12 ping\u00fcinos. Sent\u00ed una oleada de adrenalina recorriendo mi cuerpo mientras los observaba desde lejos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra.\" \/>\n<meta property=\"og:description\" content=\"Clarita mostr\u00f3 un comportamiento tranquilo y relajado y no nos dio ninguna preocupaci\u00f3n cuando nos acercamos a ella para el estudio. Su personalidad segura de s\u00ed misma la distingu\u00eda del resto de los ping\u00fcinos. Estar cerca de ella resultaba emocionante y generaba una sensaci\u00f3n de amor y respeto. Pronto descubrimos que Clarita hab\u00eda creado un v\u00ednculo con un ping\u00fcino llamado Eduardo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-12T13:49:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-16T18:56:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariela Laksman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariela Laksman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/\"},\"author\":{\"name\":\"Mariela Laksman\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\"},\"headline\":\"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra.\",\"datePublished\":\"2023-07-12T13:49:19+00:00\",\"dateModified\":\"2023-07-16T18:56:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/\"},\"wordCount\":1119,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-79.jpg\",\"keywords\":[\"Argentina\",\"biologist\",\"Derechos de los animales\",\"Latinoam\u00e9rica\",\"ping\u00fcinos\",\"premio\",\"preservaci\u00f3n animal\",\"rescate de animales\"],\"articleSection\":[\"Carreras\",\"Medio ambiente\",\"Viajes y aventuras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/\",\"name\":\"Un bi\u00f3logo argentino ayud\u00f3 a preservar cientos de colonias de ping\u00fcinos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-79.jpg\",\"datePublished\":\"2023-07-12T13:49:19+00:00\",\"dateModified\":\"2023-07-16T18:56:43+00:00\",\"description\":\"Un d\u00eda, tropezamos con una colonia de 12 ping\u00fcinos. Sent\u00ed una oleada de adrenalina recorriendo mi cuerpo mientras los observaba desde lejos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-79.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-79.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Two thirds of the world\u2019s seabirds have vanished since 1960, and among the most critically endangered are penguins. Their alarming decline has spurred Argentinian conservationist Pablo Garc\u00eda Borboroglu to carry out a worldwide campaign to address the main threats facing them. | Photo courtesy of the Global Penguin Society\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/12\\\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\",\"name\":\"Mariela Laksman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariela Laksman\"},\"description\":\"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \\\"Nuevo Sudaca Border\\\" with the microfiction book \\\"Un Tigre con la Boca Abierta\\\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariela-laksman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un bi\u00f3logo argentino ayud\u00f3 a preservar cientos de colonias de ping\u00fcinos","description":"Un d\u00eda, tropezamos con una colonia de 12 ping\u00fcinos. Sent\u00ed una oleada de adrenalina recorriendo mi cuerpo mientras los observaba desde lejos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/","og_locale":"es_ES","og_type":"article","og_title":"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra.","og_description":"Clarita mostr\u00f3 un comportamiento tranquilo y relajado y no nos dio ninguna preocupaci\u00f3n cuando nos acercamos a ella para el estudio. Su personalidad segura de s\u00ed misma la distingu\u00eda del resto de los ping\u00fcinos. Estar cerca de ella resultaba emocionante y generaba una sensaci\u00f3n de amor y respeto. Pronto descubrimos que Clarita hab\u00eda creado un v\u00ednculo con un ping\u00fcino llamado Eduardo.","og_url":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-07-12T13:49:19+00:00","article_modified_time":"2023-07-16T18:56:43+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg","type":"image\/jpeg"}],"author":"Mariela Laksman","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariela Laksman","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/"},"author":{"name":"Mariela Laksman","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90"},"headline":"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra.","datePublished":"2023-07-12T13:49:19+00:00","dateModified":"2023-07-16T18:56:43+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/"},"wordCount":1119,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg","keywords":["Argentina","biologist","Derechos de los animales","Latinoam\u00e9rica","ping\u00fcinos","premio","preservaci\u00f3n animal","rescate de animales"],"articleSection":["Carreras","Medio ambiente","Viajes y aventuras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/","url":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/","name":"Un bi\u00f3logo argentino ayud\u00f3 a preservar cientos de colonias de ping\u00fcinos","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg","datePublished":"2023-07-12T13:49:19+00:00","dateModified":"2023-07-16T18:56:43+00:00","description":"Un d\u00eda, tropezamos con una colonia de 12 ping\u00fcinos. Sent\u00ed una oleada de adrenalina recorriendo mi cuerpo mientras los observaba desde lejos.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg","width":1280,"height":960,"caption":"Two thirds of the world\u2019s seabirds have vanished since 1960, and among the most critically endangered are penguins. Their alarming decline has spurred Argentinian conservationist Pablo Garc\u00eda Borboroglu to carry out a worldwide campaign to address the main threats facing them. | Photo courtesy of the Global Penguin Society"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/07\/12\/cuando-vi-a-los-pinguinos-rodeados-de-contaminacion-y-amenazas-inminentes-me-puse-manos-a-la-obra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Cuando vi a los ping\u00fcinos rodeados de contaminaci\u00f3n y amenazas inminentes, me puse manos a la obra."}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90","name":"Mariela Laksman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariela Laksman"},"description":"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \"Nuevo Sudaca Border\" with the microfiction book \"Un Tigre con la Boca Abierta\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.","url":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/feature-79.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/feature-79-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Mariela Laksman","author_link":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"},"uagb_comment_info":0,"uagb_excerpt":"Clarita mostr\u00f3 un comportamiento tranquilo y relajado y no nos dio ninguna preocupaci\u00f3n cuando nos acercamos a ella para el estudio. Su personalidad segura de s\u00ed misma la distingu\u00eda del resto de los ping\u00fcinos. Estar cerca de ella resultaba emocionante y generaba una sensaci\u00f3n de amor y respeto. Pronto descubrimos que Clarita hab\u00eda creado un&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/74971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=74971"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/74971\/revisions"}],"predecessor-version":[{"id":74972,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/74971\/revisions\/74972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/74767"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=74971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=74971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=74971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}