{"id":75319,"date":"2023-07-26T04:58:56","date_gmt":"2023-07-26T11:58:56","guid":{"rendered":"https:\/\/orato.world\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/"},"modified":"2023-07-27T07:13:11","modified_gmt":"2023-07-27T14:13:11","slug":"la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/","title":{"rendered":"La \u00abpareja KFC\u00bb de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"341\" height=\"341\" src=\"https:\/\/orato.world\/wp-content\/uploads\/subject-15.jpeg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/subject-15.jpeg 341w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-15-300x300.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-15-100x100.jpeg 100w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-15-150x150.jpeg 150w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-15-70x70.jpeg 70w, https:\/\/orato.world\/wp-content\/uploads\/\/subject-15-293x293.jpeg 293w\" sizes=\"auto, (max-width: 341px) 100vw, 341px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">INTERVIEW SUBJECT<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Nonhlanhla Soldaat married Hector Mkansi<em> <\/em>a month after their proposal went viral online. The South African couple, nicknamed the KFC couple, became an internet sensation after online trolls left mean comments on their proposal video, which took place in a fast-food restaurant. Strangers and brands from all over the country were so moved by the proposal that they tracked down the couple and offered to help them plan their wedding. Today, they remain married, with three children, and reside in Gauteng Vereeniging, South Africa.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">BACKGROUND INFORMATION<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">The rapid growth of internet access and social media platforms across the continent has amplified bullying. <a href=\"https:\/\/anti-bullyingalliance.org.uk\/tools-information\/all-about-bullying\/bullying-and-law\/online-bullying-and-law\" target=\"_blank\" rel=\"noreferrer noopener\">Online trolls, cyberbullying, and harassment are prevalent issues worldwide.<\/a> Combating all of it requires a comprehensive and collaborative approach involving stakeholders.\u00a0Governments, technology companies, and individuals are trying to create laws that will help provide a safer and more inclusive online media space.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">GAUTENG VEREENIGING, Sud\u00e1frica &#8211; Nunca olvidar\u00e9 el m\u00e1gico momento en que mi marido me sorprendi\u00f3 con una espont\u00e1nea proposici\u00f3n de matrimonio delante de una multitud en uno de nuestros restaurantes de comida r\u00e1pida favoritos: Kentucky Fried Chicken (KFC).<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando le vi bajar al suelo y arrodillarse, casi se me sale el coraz\u00f3n del pecho. Una oleada de felicidad y emoci\u00f3n me invadi\u00f3 mientras procesaba el momento. Se me llenaron los ojos de l\u00e1grimas y respond\u00ed con un rotundo: \u00ab\u00a1S\u00ed!\u00bb. Cuando se levant\u00f3 para abrazarme, sent\u00ed como si fu\u00e9ramos las dos \u00fanicas personas del mundo. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/orato.world\/es\/\">Lee m\u00e1s art\u00edculos de Orato World Media.<\/a><\/em><\/strong><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-our-proposal-went-viral\"><strong>Nuestra propuesta se hizo viral<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, mi primo me dijo que nuestra propuesta era tendencia en Internet. Me sent\u00ed confundida. \u00ab\u00bfC\u00f3mo puede ser?\u00bb, me pregunt\u00e9. Hice clic en el enlace y descubr\u00ed que un espectador hab\u00eda filmado la pedida de mano de mi marido y la hab\u00eda compartido con el mundo.<\/p>\n\n<p class=\"wp-block-paragraph\">De repente, nuestra historia de amor se convirti\u00f3 en un tema candente de debate. Algunos se burlaron de su elecci\u00f3n del lugar y nos llamaron taca\u00f1os. Me entristeci\u00f3 que un momento tan especial pudiera convertirse en el hazmerre\u00edr de unos desconocidos en Internet. Nuestro momento \u00edntimo se sinti\u00f3 invadido por el mundo entero. Intentamos no leer demasiados comentarios. Despu\u00e9s de todo, para m\u00ed, la propuesta fue perfecta.<\/p>\n\n<p class=\"wp-block-paragraph\">Nunca nos han importado los lugares lujosos ni los grandes gestos caros. Mi experiencia fue personal, espont\u00e1nea e \u00edntima a nuestra manera. Ver a tanta gente decir lo contrario me pareci\u00f3 invasivo y triste. Pas\u00f3 poco tiempo antes de que recibiera una llamada de una emisora local. Quer\u00edan <a href=\"https:\/\/www.youtube.com\/watch?v=l41yP9anLG8&amp;ab_channel=SABCNews\">entrevistarnos<\/a> sobre nuestra nueva fama. Nunca previmos que la historia llegar\u00eda tan lejos. Al principio, nos sentimos inseguros ante la entrevista, temiendo que se burlaran de nosotros. <\/p>\n\n<p class=\"wp-block-paragraph\">Esperamos un tiempo, pero al cabo de unos d\u00edas lleg\u00f3 otro mensaje. Esta vez, el personal del Kentucky Fried Chicken (KFC) donde mi marido me propuso matrimonio, nos hizo una oferta que no pod\u00edamos rechazar. Vieron que los videos eran tendencia en las redes sociales y quisieron ofrecernos la boda de nuestros sue\u00f1os.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Kentucky Fried Chicken (KFC) nos regala la boda de nuestros sue\u00f1os<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Nuestros corazones se llenaron de gratitud al aceptar su incre\u00edble oferta. Mi marido y yo saltamos de un lado a otro de nuestro sal\u00f3n. A partir de ese momento, nuestras vidas se convirtieron en un torbellino de c\u00e1maras y atenci\u00f3n. Organizaciones y particulares se apresuraron a participar en nuestro gran d\u00eda, brind\u00e1ndonos su apoyo y ayuda. Todo lo que tuvimos que hacer fue presentarnos y ellos se encargaron de todo. <\/p>\n\n<p class=\"wp-block-paragraph\">Pasamos de no poder permitirnos un organizador de bodas a tener de repente garantizada la <a href=\"https:\/\/www.instagram.com\/p\/B6x2aKSAa-0\/\">boda que siempre quisimos.<\/a> Se sent\u00eda irreal. Aquella terrible experiencia nos dej\u00f3 profundamente afectados por la incre\u00edble humanidad y bondad que puede mostrar la gente.<\/p>\n\n<p class=\"wp-block-paragraph\">Hoy, all\u00e1 donde vamos, la gente nos sigue reconociendo. Preguntan: \u00ab\u00bfC\u00f3mo te va?\u00bb y \u00ab<a href=\"https:\/\/www.timeslive.co.za\/news\/south-africa\/2021-12-22-kfc-couple-still-madly-in-love-and-still-longing-for-dream-honeymoon-that-was-halted-by-covid-19\/\">\u00bfC\u00f3mo va tu matrimonio?\u00bb.<\/a> Todo el viaje puso de manifiesto el incre\u00edble poder del amor y el abrumador apoyo de la gente de buen coraz\u00f3n. Es un testimonio de que el amor triunfa sobre todo lo dem\u00e1s, incluso en medio de juicios severos.<\/p>\n\n<p class=\"wp-block-paragraph\">Esta historia tambi\u00e9n encierra una lecci\u00f3n vital. Revela la naturaleza enga\u00f1osa de las redes sociales. La realidad sigue siendo m\u00e1s matizada de lo que nunca podremos saber. Puede que algunos utilicen las redes sociales para pintar una fachada, pero nosotros aprendimos la importancia de abrazar nuestro yo aut\u00e9ntico y apreciar el amor que de verdad importa. <\/p>\n\n<p class=\"wp-block-paragraph\">Creo que la autoestima y la percepci\u00f3n de la realidad de muchas personas corren el riesgo de verse afectadas negativamente por las fotograf\u00edas impecables que ven a diario en las plataformas sociales. Resulta demasiado f\u00e1cil juzgar duramente a los dem\u00e1s y a nosotros mismos. Al final, ese comentario negativo que pretend\u00eda ensombrecer nuestro d\u00eda especial provoc\u00f3 sin querer un incendio de positividad. Nuestros corazones rebosan felicidad y gratitud, incluso ahora. S\u00f3lo deseo que los dem\u00e1s dejen de lado esa presi\u00f3n por ser perfectos y acepten la belleza de las cosas sencillas que est\u00e1n por venir.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"#KFCProposal: I asked her to love me because I love her\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/fTWsOJJWqgs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros corazones se llenaron de gratitud al aceptar [the incredible offer from KFC to fund our dream wedding] Mi marido y yo saltamos de un lado a otro de nuestro sal\u00f3n. A partir de ese momento, nuestras vidas se convirtieron en un torbellino de c\u00e1maras y atenci\u00f3n. <\/p>\n","protected":false},"author":50,"featured_media":75236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1617],"tags":[3921,613,5850,6614,6617,6613,6615,767,6612,6616],"class_list":["post-75319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-cultura-es","tag-acoso","tag-africa-es","tag-amor","tag-boda","tag-humanidad","tag-internet-es","tag-propuesta","tag-south-africa-es","tag-video-es","tag-viral-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La &quot;pareja KFC&quot; consigue una boda de ensue\u00f1o tras hacerse viral un v\u00eddeo de su propuesta de matrimonio<\/title>\n<meta name=\"description\" content=\"Todo comenz\u00f3 con un momento m\u00e1gico el 19 de noviembre de 2019. Mi marido me sorprendi\u00f3 con una proposici\u00f3n de matrimonio en uno de nuestros sitios favoritos para comer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La &quot;pareja KFC&quot; de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio\" \/>\n<meta property=\"og:description\" content=\"Nuestros corazones se llenaron de gratitud al aceptar Mi marido y yo saltamos de un lado a otro de nuestro sal\u00f3n. A partir de ese momento, nuestras vidas se convirtieron en un torbellino de c\u00e1maras y atenci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-26T11:58:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-27T14:13:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola Wanyonyi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola Wanyonyi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/\"},\"author\":{\"name\":\"Lola Wanyonyi\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/9dc47b64e8bf2958b15186bef661d9bb\"},\"headline\":\"La \u00abpareja KFC\u00bb de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio\",\"datePublished\":\"2023-07-26T11:58:56+00:00\",\"dateModified\":\"2023-07-27T14:13:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/\"},\"wordCount\":758,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-94.jpg\",\"keywords\":[\"Acoso\",\"Africa\",\"amor\",\"boda\",\"humanidad\",\"Internet\",\"propuesta\",\"South Africa\",\"Video\",\"viral\"],\"articleSection\":[\"Arte y Cultura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/\",\"name\":\"La \\\"pareja KFC\\\" consigue una boda de ensue\u00f1o tras hacerse viral un v\u00eddeo de su propuesta de matrimonio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-94.jpg\",\"datePublished\":\"2023-07-26T11:58:56+00:00\",\"dateModified\":\"2023-07-27T14:13:11+00:00\",\"description\":\"Todo comenz\u00f3 con un momento m\u00e1gico el 19 de noviembre de 2019. Mi marido me sorprendi\u00f3 con una proposici\u00f3n de matrimonio en uno de nuestros sitios favoritos para comer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-94.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/feature-94.jpg\",\"width\":1280,\"height\":960,\"caption\":\"nhlanhla Mkansi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/07\\\/26\\\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La \u00abpareja KFC\u00bb de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/9dc47b64e8bf2958b15186bef661d9bb\",\"name\":\"Lola Wanyonyi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Lola Wanyonyi\"},\"description\":\"Lola Wanyonyi is an experienced Multi-media Journalist based in Nairobi, Kenya, and holds a Bachelors of Science degree in Communication and Journalism from Moi University. She is Skilled in headline writing, breaking news, media relations, Online News, and News Writing. She is a contributing editor to various international media news outlets.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/lola-wanyonyi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La \"pareja KFC\" consigue una boda de ensue\u00f1o tras hacerse viral un v\u00eddeo de su propuesta de matrimonio","description":"Todo comenz\u00f3 con un momento m\u00e1gico el 19 de noviembre de 2019. Mi marido me sorprendi\u00f3 con una proposici\u00f3n de matrimonio en uno de nuestros sitios favoritos para comer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/","og_locale":"es_ES","og_type":"article","og_title":"La \"pareja KFC\" de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio","og_description":"Nuestros corazones se llenaron de gratitud al aceptar Mi marido y yo saltamos de un lado a otro de nuestro sal\u00f3n. A partir de ese momento, nuestras vidas se convirtieron en un torbellino de c\u00e1maras y atenci\u00f3n.","og_url":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-07-26T11:58:56+00:00","article_modified_time":"2023-07-27T14:13:11+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg","type":"image\/jpeg"}],"author":"Lola Wanyonyi","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Lola Wanyonyi","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/"},"author":{"name":"Lola Wanyonyi","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/9dc47b64e8bf2958b15186bef661d9bb"},"headline":"La \u00abpareja KFC\u00bb de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio","datePublished":"2023-07-26T11:58:56+00:00","dateModified":"2023-07-27T14:13:11+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/"},"wordCount":758,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg","keywords":["Acoso","Africa","amor","boda","humanidad","Internet","propuesta","South Africa","Video","viral"],"articleSection":["Arte y Cultura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/","url":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/","name":"La \"pareja KFC\" consigue una boda de ensue\u00f1o tras hacerse viral un v\u00eddeo de su propuesta de matrimonio","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg","datePublished":"2023-07-26T11:58:56+00:00","dateModified":"2023-07-27T14:13:11+00:00","description":"Todo comenz\u00f3 con un momento m\u00e1gico el 19 de noviembre de 2019. Mi marido me sorprendi\u00f3 con una proposici\u00f3n de matrimonio en uno de nuestros sitios favoritos para comer.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg","width":1280,"height":960,"caption":"nhlanhla Mkansi"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/07\/26\/la-pareja-kfc-de-internet-consigue-una-boda-de-ensueno-tras-hacerse-viral-el-video-de-su-propuesta-de-matrimonio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"La \u00abpareja KFC\u00bb de Internet consigue una boda de ensue\u00f1o tras hacerse viral el v\u00eddeo de su propuesta de matrimonio"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/9dc47b64e8bf2958b15186bef661d9bb","name":"Lola Wanyonyi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Lola Wanyonyi"},"description":"Lola Wanyonyi is an experienced Multi-media Journalist based in Nairobi, Kenya, and holds a Bachelors of Science degree in Communication and Journalism from Moi University. She is Skilled in headline writing, breaking news, media relations, Online News, and News Writing. She is a contributing editor to various international media news outlets.","url":"https:\/\/orato.world\/es\/author\/lola-wanyonyi\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/feature-94.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/feature-94-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Lola Wanyonyi","author_link":"https:\/\/orato.world\/es\/author\/lola-wanyonyi\/"},"uagb_comment_info":0,"uagb_excerpt":"Nuestros corazones se llenaron de gratitud al aceptar [the incredible offer from KFC to fund our dream wedding] Mi marido y yo saltamos de un lado a otro de nuestro sal\u00f3n. A partir de ese momento, nuestras vidas se convirtieron en un torbellino de c\u00e1maras y atenci\u00f3n.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/75319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=75319"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/75319\/revisions"}],"predecessor-version":[{"id":75320,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/75319\/revisions\/75320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/75236"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=75319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=75319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=75319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}