{"id":77351,"date":"2023-08-21T14:07:51","date_gmt":"2023-08-21T21:07:51","guid":{"rendered":"https:\/\/orato.world\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/"},"modified":"2023-08-28T12:16:22","modified_gmt":"2023-08-28T19:16:22","slug":"lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/","title":{"rendered":"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-39-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-39.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/www.instagram.com\/tephyluv\/?hl=en\">Stephanie Evans<\/a>, de 37 a\u00f1os, madre soltera de dos ni\u00f1os preciosos, Romeo (5) y Oliver (9), es una orgullosa residente de Lahaina y ama profundamente a su comunidad, su familia y sus amigos. Tr\u00e1gicamente, Stephanie y su familia perdieron su casa en los recientes incendios de Lahaina.<br>Stephanie es m\u00e9dico-est\u00e9tica y recientemente hab\u00eda aportado su talento a la galer\u00eda de arte 505 \u00abGallerie Behl\u00bb, que tambi\u00e9n se quem\u00f3 en los recientes incendios de Lahaina. Tras estas devastadoras p\u00e9rdidas, se agradecen profundamente todas las muestras de cari\u00f1o, apoyo y ayuda econ\u00f3mica. Las contribuciones pueden hacerse a trav\u00e9s de su p\u00e1gina de GoFundMe, titulada \u00ab<a href=\"https:\/\/www.gofundme.com\/f\/family-lost-everything-in-maui-fires?utm_medium=email&amp;utm_source=product&amp;utm_campaign=p_email_m_pd-5332-donation-receipt-adyen&amp;utm_content=internal\">Familia lo perdi\u00f3 todo en los incendios de Maui\u00bb<\/a>.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">La hist\u00f3rica ciudad costera de <a href=\"https:\/\/www.gohawaii.com\/islands\/maui\/regions\/west-maui\/Lahaina\">Lahaina<\/a> a\u00fan no ha superado el alcance de la destrucci\u00f3n. Desde la noche del 8 de agosto de 2023, varios incendios forestales han arrasado el oeste de Maui, siendo Lahaina, capital original del reino hawaiano y monumento hist\u00f3rico nacional, la m\u00e1s afectada. Esta ciudad del siglo XVIII tiene una inmensa importancia para los nativos hawaianos, ya que fue la residencia real del rey Kamehameha I durante tres d\u00e9cadas tras unificar las islas en 1810. Los incendios han dejado en ruinas miles de casas, negocios y lugares de importancia cultural, como una iglesia con enterramientos reales y un baniano de 150 a\u00f1os que se cree es el m\u00e1s grande de Estados Unidos. El coste estimado de la reconstrucci\u00f3n de Lahaina <a href=\"https:\/\/mauinow.com\/2023\/08\/12\/fema-map-shows-2207-structures-damaged-or-destroyed-in-west-maui-wildfire-5-52-billion-price-to-to-rebuild\/\">supera los 5.500 millones de d\u00f3lares, <\/a>seg\u00fan la Agencia Federal de Gesti\u00f3n de Emergencias.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">LAHAINA, Maui &#8211; Alrededor de las 7 de la ma\u00f1ana del 8 de agosto de 2023, un incendio arras\u00f3 Kula, al otro lado de la isla. Sal\u00ed, ol\u00ed el humo y consult\u00e9 con mi vecino, que vio el fuego desde la l\u00ednea de circunvalaci\u00f3n. Las autoridades informaron de que estaba controlado al 100%, as\u00ed que nos quedamos en casa a pesar de los vientos huracanados y los cortes de electricidad. Mi madre se llev\u00f3 a los ni\u00f1os a comer y a tomar un helado mientras yo dorm\u00eda la siesta en casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacia las tres de la tarde, mi madre not\u00f3 que el humo se acercaba y me despert\u00f3. Pens\u00e9 que todo iba bien hasta que olimos el humo, ahora peor que antes. En 10 minutos, el humo invadi\u00f3 nuestro barrio y se desat\u00f3 el p\u00e1nico. Actuamos con rapidez y evacuamos para proteger a mi hijo mayor, que tiene asma. Dejamos todo atr\u00e1s, incluidos nuestros gatos, sin pensar que el fuego nos alcanzar\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/orato.world\/?s=wildfires\"><em>Lee m\u00e1s sobre los incendios forestales en Orato World Media<\/em><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-contencion-fallida-y-las-carreteras-bloqueadas-se-convierten-en-un-calvario-aterrador\">La contenci\u00f3n fallida y las carreteras bloqueadas se convierten en un calvario aterrador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra huida result\u00f3 dif\u00edcil, ya que intentamos conducir hacia el norte, pero la polic\u00eda nos hizo retroceder. Pasamos por un peque\u00f1o incendio de desv\u00edo y nos enteramos de que la contenci\u00f3n hab\u00eda fallado. Las carreteras bloqueadas a ambos lados frustraron nuestros intentos de llegar al barrio de mi madre, as\u00ed que condujimos hacia Launiupoko.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La salida anticipada result\u00f3 ser un milagro. Si hubi\u00e9ramos esperado, el embotellamiento podr\u00eda habernos atrapado, cost\u00e1ndonos la vida. Di gracias a Dios por despertarme en el momento adecuado y por todo lo que funcion\u00f3 a nuestro favor. De lo contrario, podr\u00eda haberme despertado con la casa en llamas. Mientras continu\u00e1bamos nuestra huida, el fuego se extendi\u00f3 por la ciudad. Finalmente llegamos a Launiupoko, agradecidos por haber salido temprano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca olvidar\u00e9 el humo volvi\u00e9ndose negro como el carb\u00f3n. De pie en la subdivisi\u00f3n cercana, mi coraz\u00f3n se aceler\u00f3 mientras las llamas envolv\u00edan Lahaina. El humo que se oscurec\u00eda y que yo cre\u00eda ingenuamente que significaba control era el presagio de la destrucci\u00f3n. El fuego lo consumi\u00f3 todo en toda la ciudad: Lahaina ardi\u00f3 por completo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante 30 aterradores minutos, me qued\u00e9 paralizada de miedo e incredulidad. Sin embargo, me aferr\u00e9 a un \u00e1pice de esperanza: tal vez s\u00f3lo sufrir\u00edan algunos lados de la calle. A medida que avanzaba la noche, mi esperanza se desmoronaba. Instagram llen\u00f3 mi pantalla de v\u00eddeos de llamas abrasadoras, incluida una que asol\u00f3 mi barrio. El post de mi amigo insinuaba mi peor temor: que el fuego consumiera mi casa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A las nueve de la noche, un mensaje de texto de mi vecino, que es bombero, me cont\u00f3 la horrible verdad: no s\u00f3lo mi casa, sino todo el pueblo ard\u00eda en llamas. Mientras abrazaba a mis hijos aquella noche de insomnio, los recuerdos de mi difunto padre, nuestra herencia y todas nuestras experiencias en aquel hogar familiar de 40 a\u00f1os se redujeron a cenizas. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-comunidad-se-moviliza-mientras-lahaina-yace-en-ruinas-el-fracaso-del-gobierno-es-una-amarga-decepcion\">La comunidad se moviliza mientras Lahaina yace en ruinas, el fracaso del gobierno es una amarga decepci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mis hijos y yo nos fuimos s\u00f3lo con lo puesto. Afortunadamente, encontramos refugio en un Airbnb en Kihei. Han llegado donaciones para ayudarnos a comprar art\u00edculos de primera necesidad, como medicamentos. Muchas familias siguen en situaci\u00f3n de extrema necesidad. La ciudad est\u00e1 en ruinas; los monumentos, los bancos y las tiendas han desaparecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desaparecieron m\u00e1s de 1.000 personas, entre ellas muchas de mi barrio. Debido a las normas culturales y al elevado coste de la vida, la gente se fue a trabajar ese d\u00eda y dej\u00f3 a sus hijos solos en casa o con parientes ancianos. Si hubiera sabido cu\u00e1ntos ni\u00f1os hab\u00eda solos, habr\u00eda intentado rescatarlos, pero no hubo avisos. Algunos ni siquiera recibieron las alertas telef\u00f3nicas debido a la mala recepci\u00f3n de los m\u00f3viles. Mis hijos perdieron una docena de amigos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-43-1024x768.png\" alt=\"\" class=\"wp-image-76909\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-43-1024x768.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-43-300x225.png 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-43-770x578.png 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-43-533x400.png 533w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-43.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Los hijos de Stephanie sobrevivieron a los incendios. En la foto, Oliver (izquierda) y Romeo (derecha).<strong> | Foto cortes\u00eda de Stephanie Evans<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si hubieran sonado las alarmas de tsunami, se podr\u00edan haber salvado vidas. Si la polic\u00eda hubiera abierto las carreteras antes, podr\u00edan haber despejado el tr\u00e1fico, pero parece que s\u00f3lo actuaron cuando los incendios se les fueron de las manos. Las im\u00e1genes de video muestran a personas dirigidas hacia el oc\u00e9ano, atrapadas en Front Street. El fuego descendi\u00f3 r\u00e1pidamente, obligando a tomar la decisi\u00f3n de permanecer en los coches o saltar al agua. Estoy agradecida por los que eligieron el agua y pueden haber sobrevivido. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siento que el fracaso del Gobierno es una amarga decepci\u00f3n. Con una base militar a s\u00f3lo 30 minutos, deber\u00edan haber ayudado, pero la respuesta recay\u00f3 en la comunidad. La polic\u00eda dirigi\u00f3 el tr\u00e1fico y los amigos recuperaron cad\u00e1veres, pero la Guardia Nacional y los militares parec\u00edan ausentes. La unidad de la comunidad contrasta fuertemente con este abandono oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del fracaso de nuestro gobierno, brilla el esp\u00edritu de nuestra comunidad. Incluso los que lo perdieron todo tienden la mano para ayudar. Las muestras de cari\u00f1o y apoyo siguen siendo vitales, y la comunidad se moviliza para proporcionar alimentos, agua, suministros y art\u00edculos de aseo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-una-familia-de-lahaina-pierde-su-casa-en-un-incendio-un-texto-devastador-confirmo-lo-impensable\">Una familia de Lahaina pierde su casa en un incendio, un texto devastador confirm\u00f3 lo impensable<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aquella terrible noche, cuando recib\u00ed el devastador mensaje de texto de mi vecino confirmando la p\u00e9rdida de nuestra casa familiar y el impacto masivo en Lahaina, me invadi\u00f3 un dolor agudo y desgarrador. Ca\u00ed de rodillas, sollozando. Mi hijo mayor expres\u00f3 su angustia arremetiendo contra m\u00ed, mientras que el peque\u00f1o me abrazaba con ternura. Sus emociones crudas reforzaron mi determinaci\u00f3n y me recordaron que seguimos siendo una familia, que estamos en casa cuando estamos juntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No he vuelto a Lahaina desde que reabrieron las carreteras. Antes, el \u00fanico acceso era a trav\u00e9s de una ruta peligrosa, e incluso ahora, la Guardia Nacional bloquea la entrada a nuestras calles mientras buscan cad\u00e1veres. Cuando terminen los perros rastreadores, nos dejar\u00e1n volver para enfrentarnos a las cenizas y a lo que queda de nuestras vidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-42-1-1024x768.png\" alt=\"\" class=\"wp-image-76914\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-42-1-1024x768.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-42-1-300x225.png 300w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-42-1-770x578.png 770w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-42-1-533x400.png 533w, https:\/\/orato.world\/wp-content\/uploads\/\/Untitled-design-42-1.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La casa de Stephanie en Lahaina antes del incendio.<strong> | Foto cortes\u00eda de Stephanie Evans<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace d\u00edas que s\u00e9 que mi hogar ha desaparecido, una cruda realidad captada en la imagen de un dron en las noticias que no mostraba m\u00e1s que cenizas. Necesito buscar un cierre y anhelo encontrar a mis gatos para dar a mis hijos una sensaci\u00f3n de continuidad y una conexi\u00f3n con lo que fue. Estas mascotas son de la familia, y su regreso supondr\u00eda un gran alivio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La adaptaci\u00f3n de mis hijos a su nueva escuela en Kihei y el esfuerzo de la comunidad por reponer sus pertenencias perdidas me reconfortan. La p\u00e9rdida es inmensa, tanto en bienes como en vidas, pero el apoyo que recibimos lo es todo mientras gestiono una creciente lista de tareas pendientes e intento encontrar tiempo para llorar. La vida ense\u00f1a lecciones a trav\u00e9s de las dificultades. Hemos encontrado fuerza los unos en los otros y amabilidad en los extra\u00f1os. La humanidad y la voluntad de los dem\u00e1s de ayudar a la comunidad significan mucho para nosotros, y no puedo agradec\u00e9rselo lo suficiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nunca olvidar\u00e9 el humo volvi\u00e9ndose negro como el carb\u00f3n. De pie en la subdivisi\u00f3n cercana, mi coraz\u00f3n se aceler\u00f3 mientras las llamas envolv\u00edan Lahaina. El humo que se oscurec\u00eda y que yo cre\u00eda ingenuamente que significaba control era el presagio de la destrucci\u00f3n. El fuego lo consumi\u00f3 todo en toda la ciudad: Lahaina ardi\u00f3 por completo. <\/p>\n","protected":false},"author":112,"featured_media":76905,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[319],"tags":[6820,6823,6681,6821,6822,3023],"class_list":["post-77351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente","tag-hawaii-es","tag-incendios","tag-incendios-forestales","tag-lahaina-es","tag-maui-es","tag-norteamerica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lahaina, arrasada por los incendios de Maui<\/title>\n<meta name=\"description\" content=\"Una situaci\u00f3n catastr\u00f3fica se desencaden\u00f3 cuando m\u00faltiples incendios forestales asolaron la hist\u00f3rica ciudad de Lahaina, en Maui, y la polic\u00eda bloque\u00f3 las salidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo\" \/>\n<meta property=\"og:description\" content=\"Nunca olvidar\u00e9 el humo volvi\u00e9ndose negro como el carb\u00f3n. De pie en la subdivisi\u00f3n cercana, mi coraz\u00f3n se aceler\u00f3 mientras las llamas envolv\u00edan Lahaina. El humo que se oscurec\u00eda y que yo cre\u00eda ingenuamente que significaba control era el presagio de la destrucci\u00f3n. El fuego lo consumi\u00f3 todo en toda la ciudad: Lahaina ardi\u00f3 por completo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-21T21:07:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-28T19:16:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniella Mejia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniella Mejia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/\"},\"author\":{\"name\":\"Daniella Mejia\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/15dc70811c2e3c836b0aeda25165ec9a\"},\"headline\":\"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo\",\"datePublished\":\"2023-08-21T21:07:51+00:00\",\"dateModified\":\"2023-08-28T19:16:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/\"},\"wordCount\":1283,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-41.png\",\"keywords\":[\"Hawaii\",\"Incendios\",\"Incendios forestales\",\"Lahaina\",\"Maui\",\"Norteam\u00e9rica\"],\"articleSection\":[\"Medio ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/\",\"name\":\"Lahaina, arrasada por los incendios de Maui\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-41.png\",\"datePublished\":\"2023-08-21T21:07:51+00:00\",\"dateModified\":\"2023-08-28T19:16:22+00:00\",\"description\":\"Una situaci\u00f3n catastr\u00f3fica se desencaden\u00f3 cuando m\u00faltiples incendios forestales asolaron la hist\u00f3rica ciudad de Lahaina, en Maui, y la polic\u00eda bloque\u00f3 las salidas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-41.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-41.png\",\"width\":1280,\"height\":960,\"caption\":\"Stephanie's home consumed by the Maui fires | Photo courtesy Stephanie Evans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/08\\\/21\\\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/15dc70811c2e3c836b0aeda25165ec9a\",\"name\":\"Daniella Mejia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Daniella Mejia\"},\"description\":\"Daniella Mejia, a business administration graduate with dual specializations in international business and digital marketing, boasts over five years of experience in design, editing, and translation. Her time as an interpreter for Habitat for Humanity in El Salvador ignited a profound passion for social work and honed her expertise in cross-cultural communication. &nbsp; In Canada, Daniella sharpened her design skills as a design specialist for a risk management and child safety consultancy while freelancing social media design for a Vancouver-based Latin American magazine. Ascending through the ranks at Orato, she journeyed from a marketing intern to an editorial lead to her present-day position as a senior editor. &nbsp; As senior editor for Orato World Media, Daniella produces weekly compelling first-person news for global audiences. Her knack for storytelling and editing contributes to the continual elevation of the publication\u2019s content quality.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/daniella-mejiaorato-world\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lahaina, arrasada por los incendios de Maui","description":"Una situaci\u00f3n catastr\u00f3fica se desencaden\u00f3 cuando m\u00faltiples incendios forestales asolaron la hist\u00f3rica ciudad de Lahaina, en Maui, y la polic\u00eda bloque\u00f3 las salidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/","og_locale":"es_ES","og_type":"article","og_title":"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo","og_description":"Nunca olvidar\u00e9 el humo volvi\u00e9ndose negro como el carb\u00f3n. De pie en la subdivisi\u00f3n cercana, mi coraz\u00f3n se aceler\u00f3 mientras las llamas envolv\u00edan Lahaina. El humo que se oscurec\u00eda y que yo cre\u00eda ingenuamente que significaba control era el presagio de la destrucci\u00f3n. El fuego lo consumi\u00f3 todo en toda la ciudad: Lahaina ardi\u00f3 por completo.","og_url":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-08-21T21:07:51+00:00","article_modified_time":"2023-08-28T19:16:22+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png","type":"image\/png"}],"author":"Daniella Mejia","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Daniella Mejia","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/"},"author":{"name":"Daniella Mejia","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/15dc70811c2e3c836b0aeda25165ec9a"},"headline":"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo","datePublished":"2023-08-21T21:07:51+00:00","dateModified":"2023-08-28T19:16:22+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/"},"wordCount":1283,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png","keywords":["Hawaii","Incendios","Incendios forestales","Lahaina","Maui","Norteam\u00e9rica"],"articleSection":["Medio ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/","url":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/","name":"Lahaina, arrasada por los incendios de Maui","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png","datePublished":"2023-08-21T21:07:51+00:00","dateModified":"2023-08-28T19:16:22+00:00","description":"Una situaci\u00f3n catastr\u00f3fica se desencaden\u00f3 cuando m\u00faltiples incendios forestales asolaron la hist\u00f3rica ciudad de Lahaina, en Maui, y la polic\u00eda bloque\u00f3 las salidas.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png","width":1280,"height":960,"caption":"Stephanie's home consumed by the Maui fires | Photo courtesy Stephanie Evans"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/08\/21\/lahaina-arrasada-por-los-incendios-de-maui-la-policia-bloquea-las-salidas-y-una-familia-evacua-antes-de-tiempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Lahaina arrasada por los incendios de Maui: la polic\u00eda bloquea las salidas y una familia evacua antes de tiempo"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/15dc70811c2e3c836b0aeda25165ec9a","name":"Daniella Mejia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Daniella Mejia"},"description":"Daniella Mejia, a business administration graduate with dual specializations in international business and digital marketing, boasts over five years of experience in design, editing, and translation. Her time as an interpreter for Habitat for Humanity in El Salvador ignited a profound passion for social work and honed her expertise in cross-cultural communication. &nbsp; In Canada, Daniella sharpened her design skills as a design specialist for a risk management and child safety consultancy while freelancing social media design for a Vancouver-based Latin American magazine. Ascending through the ranks at Orato, she journeyed from a marketing intern to an editorial lead to her present-day position as a senior editor. &nbsp; As senior editor for Orato World Media, Daniella produces weekly compelling first-person news for global audiences. Her knack for storytelling and editing contributes to the continual elevation of the publication\u2019s content quality.","url":"https:\/\/orato.world\/es\/author\/daniella-mejiaorato-world\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-41-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Daniella Mejia","author_link":"https:\/\/orato.world\/es\/author\/daniella-mejiaorato-world\/"},"uagb_comment_info":0,"uagb_excerpt":"Nunca olvidar\u00e9 el humo volvi\u00e9ndose negro como el carb\u00f3n. De pie en la subdivisi\u00f3n cercana, mi coraz\u00f3n se aceler\u00f3 mientras las llamas envolv\u00edan Lahaina. El humo que se oscurec\u00eda y que yo cre\u00eda ingenuamente que significaba control era el presagio de la destrucci\u00f3n. El fuego lo consumi\u00f3 todo en toda la ciudad: Lahaina ardi\u00f3 por&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/77351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/112"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=77351"}],"version-history":[{"count":4,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/77351\/revisions"}],"predecessor-version":[{"id":77910,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/77351\/revisions\/77910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/76905"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=77351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=77351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=77351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}