{"id":85556,"date":"2023-12-13T06:16:57","date_gmt":"2023-12-13T14:16:57","guid":{"rendered":"https:\/\/orato.world\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/"},"modified":"2023-12-17T13:44:50","modified_gmt":"2023-12-17T21:44:50","slug":"estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/","title":{"rendered":"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-12T083309.276.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">journalist&#8217;s notes<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Melina Fosatti, de 34 a\u00f1os, es una destacada dise\u00f1adora de interiores y emprendedora que dirige su propia empresa de decoraci\u00f3n. Casada con Ezequiel, tambi\u00e9n es una madre devota de su hijo Enzo, de 2 a\u00f1os. Apasionados por el f\u00fatbol, \u200b\u200bMelina y su familia son fervientes seguidores de la Selecci\u00f3n Argentina de F\u00fatbol, \u200b\u200bhabiendo asistido a los siete partidos del Mundial de Qatar 2022, donde Argentina triunf\u00f3 como campeona del mundo despu\u00e9s de 36 a\u00f1os.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Los equipos de f\u00fatbol de Argentina y Brasil, entre los m\u00e1s fuertes de Sudam\u00e9rica y del mundo, tienen una rivalidad intensa y de larga data que se extiende m\u00e1s all\u00e1 del campo hasta las gradas. El partido del 21 de noviembre de 2023 fue un momento hist\u00f3rico en esta rivalidad, con Argentina logrando una victoria por 1-0 sobre Brasil. Este partido fue la primera derrota de Brasil en casa en las Eliminatorias para la Copa del Mundo en su historia. Sin embargo, el partido comenz\u00f3 con casi 30 minutos de retraso debido a un disturbio importante. Una pelea general se desat\u00f3 entre los aficionados argentinos, lo que provoc\u00f3 una severa intervenci\u00f3n policial. Los propios jugadores intentaron calmar la situaci\u00f3n y, tras sus infructuosos esfuerzos, se retiraron al vestuario durante 17 minutos hasta que se restableci\u00f3 el orden. Para informaci\u00f3n m\u00e1s detallada, consulte los reportes de <a href=\"https:\/\/www.infobae.com\/deportes\/2023\/11\/21\/la-argentina-de-lionel-messi-enfrentara-a-brasil-en-una-nueva-edicion-del-superclascio-de-las-americas-en-vivo-hora-tv-y-formaciones\/\">Infobae<\/a>, <a href=\"https:\/\/www.swissinfo.ch\/spa\/f%C3%BAtbol-mundial-2026--brasil-argentina_0-1--argentina-gana-el-cl%C3%A1sico-sudamericano-en-el-maracan%C3%A1-y-deja-a-brasil-en-crisis\/48998198\">Swissinfo<\/a>, y <a href=\"https:\/\/www.tycsports.com\/seleccion-argentina\/fotos-escandalo-maracana-brasil-argentina-id549081.html\">TyC Sports<\/a>.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">R\u00cdO DE JANEIRO, Brasil <strong>\u2014<\/strong> En noviembre pasado, mi familia y yo nos embarcamos en un emocionante viaje a Brasil para animar a la Selecci\u00f3n Argentina de f\u00fatbol. Esper\u00e1bamos con ansias un d\u00eda de deporte y energ\u00eda en el ic\u00f3nico Estadio Maracan\u00e1. Sin embargo, nuestra anticipaci\u00f3n r\u00e1pidamente se convirti\u00f3 en una impactante pesadilla momentos antes del tan esperado partido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sumidos en el caos, los aficionados en el estadio se transformaron en adversarios, convirtiendo los asientos en armas improvisadas. La rivalidad entusiasta se convirti\u00f3 en absoluta violencia y la polic\u00eda brasile\u00f1a se neg\u00f3 a calmar la situaci\u00f3n. En cambio, confrontaron agresivamente a los fan\u00e1ticos argentinos, alimentando a\u00fan m\u00e1s el malestar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de esta agitaci\u00f3n, encontr\u00e9 una manera de entrar al campo para escapar del caos. A pesar de la victoria de Argentina, ese d\u00eda de noviembre permanece grabado en mi memoria. La angustia eclips\u00f3 la alegr\u00eda de nuestra victoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/orato.world\/es\/category\/deportes\/\">Lee m\u00e1s art\u00edculos deportivos en Orato World Media<\/a><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-en-el-estadio-maracana-la-rivalidad-dio-paso-a-una-tension-palpable\"><strong>En el estadio Maracan\u00e1 la rivalidad dio paso a una tensi\u00f3n palpable<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mi esposo y yo compartimos un v\u00ednculo \u00fanico. Seguimos con avidez a la Selecci\u00f3n Argentina de f\u00fatbol y viajamos por todo el mundo para apoyarla. En cada aventura llevamos un compa\u00f1ero entusiasta: nuestro hijo de dos a\u00f1os. En esta ocasi\u00f3n nos aventuramos a R\u00edo de Janeiro. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llegar a nuestro hotel, nos instalamos para prepararnos para el tan esperado partido de f\u00fatbol entre Argentina y Brasil el 21 de noviembre de 2023. Sin embargo, al ingresar ese d\u00eda al Estadio Maracan\u00e1, nos encontramos con un desaf\u00edo inesperado. Rodeado por un mar de fan\u00e1ticos brasile\u00f1os vestidos de amarillo vibrante, una tensi\u00f3n palpable llen\u00f3 el aire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tensi\u00f3n aument\u00f3 cuando el estadio estall\u00f3 con silbidos durante el himno argentino. En una muestra de solidaridad, cantamos m\u00e1s fuerte, tratando de superar la falta de respeto. Desafortunadamente, algunos fan\u00e1ticos argentinos reflejaron esa falta de respeto durante el himno de Brasil, exacerbando a\u00fan m\u00e1s la situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al priorizar nuestra seguridad, siempre me aseguro de que mi hijo y yo estemos ubicados cerca de una salida. Cuando escuch\u00e9 el inquietante sonido de los asientos al romperse, inmediatamente tom\u00e9 medidas e inst\u00e9 a seguridad a que nos dejaran entrar al campo. En segundos, esos asientos se convirtieron en proyectiles peligrosos que volaban sobre nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, la polic\u00eda brasile\u00f1a entr\u00f3 en la zona y comenz\u00f3 a usar fuerza excesiva, lo que agrav\u00f3 dram\u00e1ticamente la situaci\u00f3n. En lugar de calmar el caos, comenzaron a agredir brutalmente a los aficionados argentinos. En medio de esta confusi\u00f3n, abrac\u00e9 a mi hijo con fuerza, empujando la puerta de salida y tratando de mantener la calma por su bien. De alguna manera logramos escapar. Una vez que logramos levantarnos de nuestros asientos, fui testigo de una escena horrible. La polic\u00eda estaba atacando a todos, incluso a mujeres, ni\u00f1os y ancianos en un violento frenes\u00ed. Al borde del campo, not\u00e9 un cambio radical en mi hijo. El ni\u00f1o alegre y excitado al que estaba acostumbrado se volvi\u00f3 retra\u00eddo y sin vida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estrellas-del-futbol-argentino-se-convierten-en-salvadores\"><strong>Estrellas del f\u00fatbol argentino se convierten en salvadores<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De pie en el campo, respir\u00e9 profundamente varias veces, tratando de mantener la calma. Sin embargo, comenc\u00e9 a temblar notablemente. La expresi\u00f3n entumecida y confusa de mi hijo me llen\u00f3 de preocupaci\u00f3n. \u00ab\u00bfCu\u00e1les ser\u00e1n los efectos psicol\u00f3gicos a largo plazo?\u00bb, me preocup\u00e9. Presa del p\u00e1nico, comenc\u00e9 a gritar. Me consum\u00eda la preocupaci\u00f3n por mi marido, mi madre y mi padre que permanec\u00edan en las gradas. Mientras observaba a ni\u00f1os aterrorizados tratando de escapar de la violencia, mi angustia se dispar\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Momentos despu\u00e9s, mi esposo y mi madre se unieron a m\u00ed. Abrumada de sentimientos, mi madre grit\u00f3 incontrolablemente. Le entregu\u00e9 a mi hijo a mi marido y comenc\u00e9 a buscar a mi padre. Los periodistas sobre el terreno comenzaron a pedir entrevistas en medio del caos. Los ignor\u00e9 y segu\u00ed buscando a mi pap\u00e1. Entonces vi algo que me sumi\u00f3 en la desesperaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203459.174-1024x768.png\" alt=\"\" class=\"wp-image-85377\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203459.174-1024x768.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203459.174-300x225.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203459.174-770x578.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203459.174-533x400.png 533w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203459.174.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La familia argentina esperaba con ansias el partido de Brasil contra Argentina antes del choque previo al partido en el estadio. <strong><em>| Foto cortes\u00eda de Melina Fosatti.<\/em><\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La polic\u00eda brasile\u00f1a estaba golpeando a mi padre. Gracias a Dios, mi esposo intervino y nos lo trajo. Mientras continuaba la pesadilla, sucedi\u00f3 algo incre\u00edble. Los futbolistas profesionales de la selecci\u00f3n argentina ingresaron al \u00e1rea y comenzaron a defender a la gente en la tribuna, a\u00fan atacada. Normalmente, su presencia me llenar\u00eda de emoci\u00f3n, pero lo \u00fanico en lo que pod\u00eda pensar era en la seguridad de mi familia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">esposo escolt\u00f3 a mi padre lejos del peligro, sent\u00ed un momento de alivio. Mientras tanto, los famosos futbolistas Franco Armani y Dibu Mart\u00ednez le ofrecieron compa\u00f1\u00eda a mi hijo. Su gracia y valent\u00eda me sorprendieron. , aportando gracia y valent\u00eda. Recuerdo al lateral izquierdo Nicol\u00e1s Tagliafico ofreci\u00e9ndonos agua y d\u00e1ndonos un poco de consuelo. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-argentina-gana-pero-la-familia-teme-represalias\"><strong>Argentina gana pero la familia teme represalias<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la situaci\u00f3n se estabiliz\u00f3, insist\u00ed en regresar a nuestros asientos, decidida a no permitir que el caos eclipsara nuestra experiencia. Sin embargo, la atm\u00f3sfera alterada persisti\u00f3. Durante todo el juego, me mantuve alerta, atento a cualquier acci\u00f3n amenazadora por parte de la polic\u00eda. Incapaz de relajarme o celebrar plenamente, la tensi\u00f3n me envolvi\u00f3 y la paz se volvi\u00f3 imposible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el momento en que Argentina anot\u00f3 el gol de la victoria en el segundo tiempo, mis emociones se enredaron en una compleja red. Sent\u00ed alegr\u00eda por mi equipo, pero luch\u00e9 contra el miedo a las represalias brasile\u00f1as. Toda la experiencia apag\u00f3 mi \u00e1nimo. Mientras tanto, las miradas hostiles de los polic\u00edas nos hac\u00edan sentir como delincuentes. Proteger a mi hijo de mayores angustias y garantizar nuestro regreso seguro al hotel se convirti\u00f3 en mi principal objetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando llegamos a la seguridad de nuestro hotel, mi tel\u00e9fono se desbord\u00f3 de notificaciones. La transmisi\u00f3n del evento hab\u00eda capturado mi ansiedad y desesperaci\u00f3n. Esto provoc\u00f3 mensajes de amigos y familiares en todo el mundo. Ver esas im\u00e1genes m\u00edas profundamente angustiada y de mi hijo aturdido, alter\u00f3 a todos mis seres queridos. Cuando vi las fotos de mi beb\u00e9 tan visiblemente afectado, se me rompi\u00f3 el coraz\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche se volvi\u00f3 a\u00fan m\u00e1s dif\u00edcil cuando mi hijo tuvo fiebre y comenz\u00f3 a quejarse mientras dorm\u00eda, atormentado por pesadillas. Durmi\u00f3 mucho al d\u00eda siguiente, claramente afectado por el trauma de lo que hab\u00edamos sufrido. Sin embargo, poco a poco empez\u00f3 a recuperarse y volvi\u00f3 a su comportamiento alegre y habitual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del calvario, nuestro compromiso de apoyar a la Selecci\u00f3n Argentina se mantiene firme. Este incidente no ha atenuado nuestra pasi\u00f3n. Sin embargo, ahora tengo dudas sobre asistir a partidos en Brasil, considerando la excesiva violencia policial y el aparente desprecio por el bienestar de los aficionados. Sin embargo, nos estamos preparando para nuestra pr\u00f3xima aventura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda brasile\u00f1a entr\u00f3 en la zona y comenz\u00f3 a hacer uso excesivo de la fuerza, lo que agrav\u00f3 dram\u00e1ticamente la situaci\u00f3n. En lugar de calmar el caos, comenzaron a agredir brutalmente a los aficionados argentinos. <\/p>\n","protected":false},"author":46,"featured_media":85383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,334],"tags":[7720,193,3308,2408,2214,7719,7721,369,1863],"class_list":["post-85556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-deportes","tag-aficionados-al-futbol","tag-argentina-es","tag-brasil","tag-brutalidad-policial","tag-latinoamerica","tag-rio-de-janeiro-es","tag-seleccion-argentina-de-futbol","tag-soccer-es","tag-violencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La fuga de una familia argentina del alboroto en el estadio Maracan\u00e1<\/title>\n<meta name=\"description\" content=\"La fuga de una familia argentina del estadio Maracan\u00e1 alborota en medio de una hist\u00f3rica victoria de f\u00fatbol en R\u00edo, a pesar de que la tensi\u00f3n persiste\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro\" \/>\n<meta property=\"og:description\" content=\"La polic\u00eda brasile\u00f1a entr\u00f3 en la zona y comenz\u00f3 a hacer uso excesivo de la fuerza, lo que agrav\u00f3 dram\u00e1ticamente la situaci\u00f3n. En lugar de calmar el caos, comenzaron a agredir brutalmente a los aficionados argentinos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T14:16:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-17T21:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Juan Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/\"},\"author\":{\"name\":\"Juan Martinez\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\"},\"headline\":\"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro\",\"datePublished\":\"2023-12-13T14:16:57+00:00\",\"dateModified\":\"2023-12-17T21:44:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/\"},\"wordCount\":1241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2023-12-11T203444.822.png\",\"keywords\":[\"Aficionados al futbol\",\"Argentina\",\"Brasil\",\"Brutalidad policial\",\"Latinoam\u00e9rica\",\"Rio de Janeiro\",\"Selecci\u00f3n Argentina de f\u00fatbol\",\"Soccer\",\"violencia\"],\"articleSection\":[\"Conflicto\",\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/\",\"name\":\"La fuga de una familia argentina del alboroto en el estadio Maracan\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2023-12-11T203444.822.png\",\"datePublished\":\"2023-12-13T14:16:57+00:00\",\"dateModified\":\"2023-12-17T21:44:50+00:00\",\"description\":\"La fuga de una familia argentina del estadio Maracan\u00e1 alborota en medio de una hist\u00f3rica victoria de f\u00fatbol en R\u00edo, a pesar de que la tensi\u00f3n persiste\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2023-12-11T203444.822.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2023-12-11T203444.822.png\",\"width\":1280,\"height\":960,\"caption\":\"Days leading up to the historic match at Maracan\u00e1 stadium | Photo courtesy Melina Fosatti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2023\\\/12\\\/13\\\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\",\"name\":\"Juan Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"caption\":\"Juan Martinez\"},\"description\":\"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/juan-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La fuga de una familia argentina del alboroto en el estadio Maracan\u00e1","description":"La fuga de una familia argentina del estadio Maracan\u00e1 alborota en medio de una hist\u00f3rica victoria de f\u00fatbol en R\u00edo, a pesar de que la tensi\u00f3n persiste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/","og_locale":"es_ES","og_type":"article","og_title":"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro","og_description":"La polic\u00eda brasile\u00f1a entr\u00f3 en la zona y comenz\u00f3 a hacer uso excesivo de la fuerza, lo que agrav\u00f3 dram\u00e1ticamente la situaci\u00f3n. En lugar de calmar el caos, comenzaron a agredir brutalmente a los aficionados argentinos.","og_url":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2023-12-13T14:16:57+00:00","article_modified_time":"2023-12-17T21:44:50+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png","type":"image\/png"}],"author":"Juan Martinez","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Juan Martinez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/"},"author":{"name":"Juan Martinez","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d"},"headline":"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro","datePublished":"2023-12-13T14:16:57+00:00","dateModified":"2023-12-17T21:44:50+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/"},"wordCount":1241,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png","keywords":["Aficionados al futbol","Argentina","Brasil","Brutalidad policial","Latinoam\u00e9rica","Rio de Janeiro","Selecci\u00f3n Argentina de f\u00fatbol","Soccer","violencia"],"articleSection":["Conflicto","Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/","url":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/","name":"La fuga de una familia argentina del alboroto en el estadio Maracan\u00e1","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png","datePublished":"2023-12-13T14:16:57+00:00","dateModified":"2023-12-17T21:44:50+00:00","description":"La fuga de una familia argentina del estadio Maracan\u00e1 alborota en medio de una hist\u00f3rica victoria de f\u00fatbol en R\u00edo, a pesar de que la tensi\u00f3n persiste","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png","width":1280,"height":960,"caption":"Days leading up to the historic match at Maracan\u00e1 stadium | Photo courtesy Melina Fosatti"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2023\/12\/13\/estalla-una-violencia-aterradora-entre-aficionados-al-futbol-argentino-y-brasileno-una-madre-lleva-a-su-hijo-de-2-anos-a-un-lugar-seguro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Estalla una violencia aterradora entre aficionados al f\u00fatbol argentino y brasile\u00f1o: una madre lleva a su hijo de 2 a\u00f1os a un lugar seguro"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d","name":"Juan Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","url":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","caption":"Juan Martinez"},"description":"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.","url":"https:\/\/orato.world\/es\/author\/juan-martinez\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2023-12-11T203444.822-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Juan Martinez","author_link":"https:\/\/orato.world\/es\/author\/juan-martinez\/"},"uagb_comment_info":0,"uagb_excerpt":"La polic\u00eda brasile\u00f1a entr\u00f3 en la zona y comenz\u00f3 a hacer uso excesivo de la fuerza, lo que agrav\u00f3 dram\u00e1ticamente la situaci\u00f3n. En lugar de calmar el caos, comenzaron a agredir brutalmente a los aficionados argentinos.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/85556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=85556"}],"version-history":[{"count":2,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/85556\/revisions"}],"predecessor-version":[{"id":85677,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/85556\/revisions\/85677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/85383"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=85556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=85556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=85556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}