{"id":86576,"date":"2024-01-07T04:00:00","date_gmt":"2024-01-07T12:00:00","guid":{"rendered":"https:\/\/orato.world\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/"},"modified":"2024-01-08T08:17:26","modified_gmt":"2024-01-08T16:17:26","slug":"un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/","title":{"rendered":"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T135455.701.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">journalist&#8217;s notes<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">El Dr. Andr\u00e9s Carot, cirujano de C\u00f3rdoba, Argentina, de 45 a\u00f1os, reside actualmente en Buenos Aires y ha dedicado 14 a\u00f1os a M\u00e9dicos Sin Fronteras, completando su misi\u00f3n n\u00famero 34 a mediados de diciembre de 2023 en la Franja de Gaza. Su amplia experiencia incluye servir en zonas de conflicto como Nigeria, Venezuela, Hait\u00ed, Sierra Leona, Sud\u00e1n del Sur, Etiop\u00eda, Somalia, Camer\u00fan, Siria, Irak, Yemen, Palestina, L\u00edbano, Ucrania, Afganist\u00e1n e India. Su misi\u00f3n m\u00e1s reciente en Gaza lo expuso a graves crisis humanitarias, destacando su compromiso de abordar necesidades cr\u00edticas en entornos desafiantes.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">M\u00e9dicos Sin Fronteras, conocida internacionalmente como M\u00e9dicos Sin Fronteras (MSF), es una organizaci\u00f3n m\u00e9dica humanitaria mundial reconocida por brindar atenci\u00f3n m\u00e9dica cr\u00edtica en zonas de conflicto, desastres naturales y brotes epid\u00e9micos. Establecida a ra\u00edz de la Guerra de Biafra en Nigeria en 1967, la organizaci\u00f3n fue fundada por m\u00e9dicos y periodistas franceses motivados para crear una entidad neutral e imparcial dedicada a brindar ayuda de emergencia independientemente de su raza, religi\u00f3n o afiliaci\u00f3n pol\u00edtica. A lo largo de d\u00e9cadas, MSF ha estado a la vanguardia de las crisis m\u00e9dicas y humanitarias en todo el mundo, ofreciendo servicios que van desde atenci\u00f3n primaria de salud y campa\u00f1as de vacunaci\u00f3n masiva hasta tratamientos de desnutrici\u00f3n e intervenciones quir\u00fargicas. El conflicto de Gaza ha sido un punto central de la intervenci\u00f3n de MSF, donde la organizaci\u00f3n ha sido testigo y ha respondido al extenso sufrimiento humano causado por las hostilidades prolongadas. Tras la escalada de violencia en octubre de 2023, MSF ha informado de graves impactos en la poblaci\u00f3n civil, incluido un coste significativo en salud y derechos humanos. La organizaci\u00f3n contin\u00faa brindando atenci\u00f3n m\u00e9dica vital y apoyo a las comunidades afectadas, abogando por el acceso sin obst\u00e1culos a quienes lo necesitan y pidiendo un cese inmediato de las hostilidades para proteger a los civiles y garantizar la prestaci\u00f3n de asistencia humanitaria. Para obtener m\u00e1s detalles y apoyar su misi\u00f3n, visite <a href=\"https:\/\/www.msf.org.ar\/\">M\u00e9dicos sin Fronteras<\/a>.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">KHAN YUNIS, Franja de Gaza \u2014 Durante los \u00faltimos 14 a\u00f1os, trabaj\u00e9 con M\u00e9dicos Sin Fronteras, embarc\u00e1ndome en misiones anuales en zonas de conflicto en todo el mundo. Sin embargo, ninguna de estas misiones se ha comparado con mi estancia en Gaza. Las bajas civiles sin precedentes presentaron un escenario desolador de sufrimiento y resiliencia humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde mediados de noviembre hasta diciembre de 2023, asist\u00ed en el Hospital Nasser, recorriendo pasillos llenos de heridos y sus familias. El impacto del bloqueo fue palpable, con una grave falta de suministros m\u00e9dicos que provoc\u00f3 tratamientos dolorosos e infecciones rampantes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando sal\u00ed de Gaza a mediados de diciembre, llevaba conmigo una culpa desconocida y una profunda frustraci\u00f3n por los problemas sist\u00e9micos que perpet\u00faan ese sufrimiento. La experiencia subray\u00f3 el poder de los actos individuales de curaci\u00f3n y la necesidad urgente de un compromiso global y una narraci\u00f3n para enfrentar y abordar esta crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong><a href=\"https:\/\/orato.world\/es\/2023\/12\/07\/una-familia-de-cisjordania-vive-en-una-tienda-de-campana-despues-de-que-colonos-israelies-atacaran-una-aldea-palestina-al-sur-de-la-colina-de-hebron\/\">Lea m\u00e1s historias sobre el conflicto palestino-israel\u00ed en Orato World Media.<\/a><\/strong><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-rumbo-al-corazon-del-conflicto-la-inquebrantable-agitacion-en-gaza\"><strong>Rumbo al coraz\u00f3n del conflicto: la inquebrantable agitaci\u00f3n en Gaza<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En octubre, cuando Hamas lanz\u00f3 sus ataques contra Israel, me encontr\u00e9 esperando con impaciencia una visa para una misi\u00f3n en Sud\u00e1n en medio del conflicto armado all\u00ed. Los obst\u00e1culos burocr\u00e1ticos descarrilaron mis planes, pero surgi\u00f3 una oportunidad alternativa: un viaje a Egipto de camino a Gaza. Agarr\u00e9 mi equipo y part\u00ed, lleno de prop\u00f3sito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llegar a Egipto el 19 de octubre de 2023, mi expectativa de ayudar se intensific\u00f3. Los frustrantes retrasos en la autorizaci\u00f3n de mi entrada s\u00f3lo aumentaron mi entusiasmo por entrar en Gaza. Durante esos d\u00edas de espera, pas\u00e9 horas siguiendo a los fotoperiodistas de la Franja de Gaza a trav\u00e9s de las redes sociales, obteniendo un sombr\u00edo adelanto de lo que nos esperaba. Esta vez no estuvo inactiva; permiti\u00f3 a nuestro equipo forjar camarader\u00eda y profundizar nuestra determinaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 14 de noviembre, despu\u00e9s de numerosos reveses, finalmente entramos en Gaza. La vista de su paisaje amurallado, de p\u00faas y de su ruina total parec\u00eda inquietantemente familiar. Sin embargo, en medio de la devastaci\u00f3n, el reencuentro con dos colegas de Gaza provoc\u00f3 una inesperada oleada de alegr\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando nos pusimos a trabajar en Khan Yunis, las secuelas de los bombardeos segu\u00edan siendo visibles en todas partes. La basura se amontonaba sin ser recogida, llenando el aire de un olor nocivo. Las carreteras, antes navegables, ahora eran pistas de obst\u00e1culos llenas de escombros y coches abandonados. A pesar del sombr\u00edo entorno, mi compromiso de ayudar nunca flaque\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llegar al Hospital Nasser, entr\u00e9 en un escenario de caos total. El hospital parec\u00eda un campo de refugiados, repleto de pacientes y sus familias. Navegu\u00e9 por pasillos atestados de viviendas improvisadas en busca de quienes buscaban ayuda. Esta experiencia marc\u00f3 el comienzo de un intenso viaje que pondr\u00eda a prueba mi determinaci\u00f3n y subrayar\u00eda el profundo impacto del conflicto en las vidas humanas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-cruda-realidad-del-hospital-nasser-realizar-tratamientos-dolorosamente-necesarios-sin-un-alivio-adecuado-del-dolor-se-convirtio-en-una-prueba-habitual\"><strong>La cruda realidad del hospital Nasser: realizar tratamientos dolorosamente necesarios sin un alivio adecuado del dolor se convirti\u00f3 en una prueba habitual<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al tercer d\u00eda en el hospital, mientras realizaba la cirug\u00eda, una explosi\u00f3n ensordecedora sacudi\u00f3 el edificio, resonando con los gritos escalofriantes de ni\u00f1os aterrorizados. Me obligu\u00e9 a mantener la concentraci\u00f3n y terminar la cirug\u00eda antes de buscar la causa, que fue un misil que hab\u00eda impactado a un kil\u00f3metro de distancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras me mov\u00eda para consultar con mis colegas, llegaron ambulancias y autom\u00f3viles, transportando un flujo incesante de cuerpos heridos y sin vida. Los padres desesperados, abrazando a sus hijos inm\u00f3viles, se sumaron a la sombr\u00eda angustia y el caos que llenaba cada rinc\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al regresar al quir\u00f3fano, me enfrent\u00e9 a la abrumadora tarea de tratar a los heridos cr\u00edticos. Incluso con mi amplia experiencia, el n\u00famero de v\u00edctimas civiles, en particular ni\u00f1os y mujeres, result\u00f3 desgarrador. En esta zona densamente poblada, las bombas causaron una destrucci\u00f3n indiscriminada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del peso de esta tragedia, mantuve mano firme y un coraz\u00f3n compasivo, comprometido a salvar vidas. Como uno de los primeros equipos internacionales en llegar al terreno, los locales se abrieron ante nosotros con sus historias tr\u00e1gicas y vieron esperanza en nuestros esfuerzos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la violencia no cedi\u00f3. Pronto comprend\u00ed que los bombardeos continuar\u00edan sin cesar y que los llamados ataques de precisi\u00f3n se cobrar\u00edan vidas y destruir\u00edan infraestructura esencial. Esta comprensi\u00f3n profundiz\u00f3 mi resoluci\u00f3n a pesar de la desesperaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El bloqueo limit\u00f3 gravemente los suministros, lo que complic\u00f3 la atenci\u00f3n de los pacientes. Esta escasez provoc\u00f3 infecciones generalizadas. El aire del hospital estaba cargado de sonidos de sufrimiento debido a la grave escasez de antibi\u00f3ticos y analg\u00e9sicos. Realizar tratamientos dolorosamente necesarios sin un alivio adecuado del dolor se convirti\u00f3 en una prueba habitual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-continuan-los-bombardeos-implacables-se-intensifica-la-desesperacion-del-pueblo-de-gaza\"><strong>Contin\u00faan los bombardeos implacables, se intensifica la desesperaci\u00f3n del pueblo de Gaza<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las cirug\u00edas en ni\u00f1os parecieron una de las experiencias m\u00e1s impactantes que encontr\u00e9. Recuerdo a un chico de 16 a\u00f1os que lleg\u00f3 despu\u00e9s de que una bomba destruyera su casa y no me dej\u00f3 m\u00e1s remedio que amputarle ambas piernas y un brazo. Mientras lo cuidaba, sus ojos transmit\u00edan una tristeza extrema, dej\u00e1ndome con un hoyo en el est\u00f3mago. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n trat\u00e9 a un ni\u00f1o de dos a\u00f1os y medio que necesitaba una amputaci\u00f3n. Durante la cirug\u00eda, no pude evitar considerar la cruel aleatoriedad de los lugares de nacimiento y el privilegio inmerecido de mis circunstancias. Estos ni\u00f1os, que encarnaban la inocencia, se enfrentaron a destinos brutales que no merec\u00edan. En ese momento, mi conexi\u00f3n con ellos se profundiz\u00f3 y me record\u00f3 nuestra humanidad compartida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de la sombr\u00eda situaci\u00f3n, me sent\u00ed decidido a brindar alegr\u00eda. Lo hice a trav\u00e9s de una simple broma, un globo hecho con un guante o un partido r\u00e1pido de f\u00fatbol. Estos fugaces momentos de ligereza fueron vitales y enfatizaron la resiliencia de la esperanza y la necesidad de felicidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pueblo de Gaza nos implor\u00f3 que comparti\u00e9ramos su dif\u00edcil situaci\u00f3n con el mundo, sinti\u00e9ndose olvidado y condenado. El siempre presente zumbido de los drones sirvi\u00f3 como recordatorio del asedio en curso, haciendo que las noches se inquietaran ante la amenaza de explosiones cercanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El final de mi misi\u00f3n a mediados de diciembre lleg\u00f3 con una rotaci\u00f3n programada, pero abandonar Gaza me trajo un sentimiento de culpa desconocido. Normalmente, regresar a casa es un alivio, pero esta vez me sent\u00ed c\u00f3mplice de un mundo que permite tanto sufrimiento. Reflexionar sobre los problemas sist\u00e9micos que llevaron a estos horrores me hizo sentir enojado y frustrado al mismo tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De vuelta en Buenos Aires, las comodidades cotidianas contrastaban marcadamente con la realidad de Gaza. Esta disparidad fortaleci\u00f3 mi determinaci\u00f3n de compartir lo que presenci\u00e9. A medida que contin\u00faan los incesantes bombardeos, la desesperaci\u00f3n del pueblo de Gaza no hace m\u00e1s que intensificarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Todas las fotograf\u00edas proporcionadas por Mohammed Abed \/ Cortes\u00eda de M\u00e9dicos Sin Fronteras.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al tercer d\u00eda en el hospital, mientras realizaba la cirug\u00eda, una explosi\u00f3n ensordecedora sacudi\u00f3 el edificio, resonando con los gritos escalofriantes de ni\u00f1os aterrorizados. Me obligu\u00e9 a mantener la concentraci\u00f3n y terminar la cirug\u00eda antes de buscar la causa, que fue un misil que hab\u00eda impactado a un kil\u00f3metro de distancia.<\/p>\n","protected":false},"author":46,"featured_media":86421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,874],"tags":[3637,7888,7539,7334,1321,7652,7889,1261],"class_list":["post-86576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-crimen-y-corrupcion-es","tag-asia-russia-es","tag-conflicto-israel-gaza","tag-conflicto-israeli-palestino","tag-franja-de-gaza","tag-gaza-es","tag-guerra-entre-israel-y-hamas","tag-medicos-sin-fronteras","tag-palestina"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gaza lucha contra las bombas y la escasez<\/title>\n<meta name=\"description\" content=\"M\u00e9dicos sin fronteras luchan contra las bombas y la escasez en el coraz\u00f3n de Gaza, Argentina realiza cirug\u00edas que salvan vidas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Al tercer d\u00eda en el hospital, mientras realizaba la cirug\u00eda, una explosi\u00f3n ensordecedora sacudi\u00f3 el edificio, resonando con los gritos escalofriantes de ni\u00f1os aterrorizados. Me obligu\u00e9 a mantener la concentraci\u00f3n y terminar la cirug\u00eda antes de buscar la causa, que fue un misil que hab\u00eda impactado a un kil\u00f3metro de distancia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-07T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-08T16:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Juan Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/\"},\"author\":{\"name\":\"Juan Martinez\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\"},\"headline\":\"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os\",\"datePublished\":\"2024-01-07T12:00:00+00:00\",\"dateModified\":\"2024-01-08T16:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/\"},\"wordCount\":1246,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-03T140106.271.png\",\"keywords\":[\"Asia &amp; Russia\",\"Conflicto Israel-Gaza\",\"Conflicto israel\u00ed-palestino\",\"Franja de Gaza\",\"Gaza\",\"Guerra entre Israel y Ham\u00e1s\",\"m\u00e9dicos Sin Fronteras\",\"Palestina\"],\"articleSection\":[\"Conflicto\",\"Crimen y corrupci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/\",\"name\":\"Gaza lucha contra las bombas y la escasez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-03T140106.271.png\",\"datePublished\":\"2024-01-07T12:00:00+00:00\",\"dateModified\":\"2024-01-08T16:17:26+00:00\",\"description\":\"M\u00e9dicos sin fronteras luchan contra las bombas y la escasez en el coraz\u00f3n de Gaza, Argentina realiza cirug\u00edas que salvan vidas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-03T140106.271.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-03T140106.271.png\",\"width\":1280,\"height\":960,\"caption\":\"Gazan citizens could be seen in the hallways of Al Aqsa hospital, taking shelter like refugees as they awaited treatment following Israel's bombing of the Strip. | Photo courtesy of Mohammed Abed and Doctors Without Borders\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/07\\\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\",\"name\":\"Juan Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"caption\":\"Juan Martinez\"},\"description\":\"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/juan-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gaza lucha contra las bombas y la escasez","description":"M\u00e9dicos sin fronteras luchan contra las bombas y la escasez en el coraz\u00f3n de Gaza, Argentina realiza cirug\u00edas que salvan vidas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os","og_description":"Al tercer d\u00eda en el hospital, mientras realizaba la cirug\u00eda, una explosi\u00f3n ensordecedora sacudi\u00f3 el edificio, resonando con los gritos escalofriantes de ni\u00f1os aterrorizados. Me obligu\u00e9 a mantener la concentraci\u00f3n y terminar la cirug\u00eda antes de buscar la causa, que fue un misil que hab\u00eda impactado a un kil\u00f3metro de distancia.","og_url":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-01-07T12:00:00+00:00","article_modified_time":"2024-01-08T16:17:26+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png","type":"image\/png"}],"author":"Juan Martinez","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Juan Martinez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/"},"author":{"name":"Juan Martinez","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d"},"headline":"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os","datePublished":"2024-01-07T12:00:00+00:00","dateModified":"2024-01-08T16:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/"},"wordCount":1246,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png","keywords":["Asia &amp; Russia","Conflicto Israel-Gaza","Conflicto israel\u00ed-palestino","Franja de Gaza","Gaza","Guerra entre Israel y Ham\u00e1s","m\u00e9dicos Sin Fronteras","Palestina"],"articleSection":["Conflicto","Crimen y corrupci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/","url":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/","name":"Gaza lucha contra las bombas y la escasez","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png","datePublished":"2024-01-07T12:00:00+00:00","dateModified":"2024-01-08T16:17:26+00:00","description":"M\u00e9dicos sin fronteras luchan contra las bombas y la escasez en el coraz\u00f3n de Gaza, Argentina realiza cirug\u00edas que salvan vidas","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png","width":1280,"height":960,"caption":"Gazan citizens could be seen in the hallways of Al Aqsa hospital, taking shelter like refugees as they awaited treatment following Israel's bombing of the Strip. | Photo courtesy of Mohammed Abed and Doctors Without Borders"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/01\/07\/un-voluntario-de-medicos-sin-fronteras-realiza-cirugias-que-salvan-vidas-en-el-corazon-de-gaza-y-amputa-extremidades-a-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Un voluntario de M\u00e9dicos Sin Fronteras realiza cirug\u00edas que salvan vidas en el coraz\u00f3n de Gaza y amputa extremidades a ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d","name":"Juan Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","url":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","caption":"Juan Martinez"},"description":"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.","url":"https:\/\/orato.world\/es\/author\/juan-martinez\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-03T140106.271-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Juan Martinez","author_link":"https:\/\/orato.world\/es\/author\/juan-martinez\/"},"uagb_comment_info":0,"uagb_excerpt":"Al tercer d\u00eda en el hospital, mientras realizaba la cirug\u00eda, una explosi\u00f3n ensordecedora sacudi\u00f3 el edificio, resonando con los gritos escalofriantes de ni\u00f1os aterrorizados. Me obligu\u00e9 a mantener la concentraci\u00f3n y terminar la cirug\u00eda antes de buscar la causa, que fue un misil que hab\u00eda impactado a un kil\u00f3metro de distancia.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/86576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=86576"}],"version-history":[{"count":4,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/86576\/revisions"}],"predecessor-version":[{"id":86612,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/86576\/revisions\/86612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/86421"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=86576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=86576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=86576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}