{"id":87073,"date":"2024-01-19T04:44:27","date_gmt":"2024-01-19T12:44:27","guid":{"rendered":"https:\/\/orato.world\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/"},"modified":"2024-01-22T06:37:48","modified_gmt":"2024-01-22T14:37:48","slug":"coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/","title":{"rendered":"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081442.442.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">journalist&#8217;s notes<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">interview subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Dr Yoo Young (Dominique) Lee is a consultant radiation oncologist at Princess Alexandra Hospital and Icon Cancer Centre and a senior lecturer at University of Queensland in Brisbane, Australia. Alongside her clinical and academic roles, Dr Lee is a fervent advocate for physicians\u2019 welfare and professional growth. Her passion for this cause led her to establish <a href=\"https:\/\/heyboss.org\/\">HeyBoss!<\/a>, an innovative support company dedicated to empowering doctors through advocacy and resources.<br><br><a href=\"https:\/\/iconcancercentre.com.au\/doctor\/yoo-young-dominique-lee\">Icon Cancer Centre website<\/a>.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">background information<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Dr. Dominique Lee\u2019s legal battle in Australia is a testament to her bravery in confronting a harrowing personal ordeal. She endured a traumatic experience at the hands of Professor Kearsley, who drugged and assaulted her under the guise of offering career advice. This incident marked a significant turning point in Dr. Lee\u2019s life and career. Despite the immense personal and professional risks involved, Dr. Lee reported the assault, leading to Professor Kearsley\u2019s conviction on charges of using an intoxicating substance to commit an indictable offence and assault with an act of indecency. This case was a first in Australia, highlighting the challenges faced by victims of sexual assault in professional environments. Dr. Lee\u2019s courageous actions and the subsequent legal proceedings, although successful, had a profound impact on her career, compelling her to change specialties and relocate her practice. Her story is a powerful reminder of the importance of speaking out against injustice and supporting victims. For more detailed information, please refer to the articles on\u00a0<a href=\"https:\/\/www.ausdoc.com.au\/news\/drugged-and-assaulted-by-her-would-be-supervisor-dr-dominique-lee-tells-her-shocking-story\">AusDoc<\/a>\u00a0and\u00a0<a href=\"https:\/\/tramp-v2.herokuapp.com\/news\/australia-news\/2023_sep_24_the-system-teaches-you-to-be-quiet-doctor-indecently-assaulted-by-senior-colleague-identifies-herself\">PressReader<\/a>.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">SYDNEY, Australia \ua7f7 En noviembre de 2013, mientras completaba con entusiasmo mi \u00faltimo a\u00f1o de formaci\u00f3n m\u00e9dica, un evento traum\u00e1tico cambi\u00f3 mi vida para siempre. Un profesor y consultor principal del Hospital St. George me drog\u00f3 y agredi\u00f3. [El perpetrador, el Dr. John Kearsley, fue finalmente condenado por los cargos de uso de una sustancia intoxicante para cometer un delito procesable y agresi\u00f3n con un acto indecente en los tribunales australianos.]<\/p>\n\n<p class=\"wp-block-paragraph\">Una noche, mientras conduc\u00eda a casa desde el trabajo, el profesor Kearsley me llam\u00f3. Me sugiri\u00f3 que fuera parte de un programa formal de tutor\u00eda en el Hospital St. George y me invit\u00f3 a discutirlo durante una cena en su apartamento. Consider\u00e9 la oportunidad como un gesto amable y nada inusual. Sin ser consciente de los riesgos, lo visit\u00e9 sola un viernes por la noche.<\/p>\n\n<p class=\"wp-block-paragraph\">Una sensaci\u00f3n inquietante surgi\u00f3 cuando llegu\u00e9 y encontr\u00e9 a su esposa notoriamente ausente. Este hombre, conocido por su enfoque hol\u00edstico en la atenci\u00f3n al paciente y sus discursos en conferencias internacionales, comenz\u00f3 a sugerirme que pasara la noche y a tocarme los hombros persistentemente.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/orato.world\/?s=australia\"><em>Descubra m\u00e1s historias de Australia en Orato World Media.<\/em><\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-inside-his-apartment-he-began-massaging-me-and-taking-off-my-clothes\"><strong>Dentro de su departamento comenz\u00f3 a masajearme y a quitarme la ropa.<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Durante la cena, rechac\u00e9 repetidamente la oferta de alcohol del Dr. Kearsley. A medida que avanzaba la noche, sali\u00f3 con una supuesta botella de vino de 800 d\u00f3lares. Acept\u00e9 un vaso por cortes\u00eda, pero despu\u00e9s de unos sorbos, me sent\u00ed extra\u00f1amente somnolienta. Antes de que pudiera reaccionar a lo que estaba sucediendo en mi cuerpo, el Dr. Kearsley me llev\u00f3 a dar un paseo por Centennial Park y me sugiri\u00f3 que necesitaba un poco de aire. <\/p>\n\n<p class=\"wp-block-paragraph\">Recuerdo haber tropezado mientras regres\u00e1bamos a su departamento, y recuerdo que \u00e9l me apoy\u00f3 para mantenerme de pie. Dentro de su departamento, comenz\u00f3 a masajearme y me llev\u00f3 al dormitorio. Me acost\u00f3 y comenz\u00f3 a quitarme la ropa. Ignorando todas mis protestas, me bes\u00f3 y toc\u00f3. En un breve momento de claridad, lo empuj\u00e9 y me puse de pie, me puse la ropa y me dirig\u00ed hacia la puerta.<\/p>\n\n<p class=\"wp-block-paragraph\">Luchando por recuperar la compostura y todav\u00eda somnolienta, me sub\u00ed torpemente la cremallera de las botas y sal\u00ed del apartamento a trompicones. Mientras conduc\u00eda a casa por las calles de Sydney, mi visi\u00f3n se volvi\u00f3 borrosa y no pod\u00eda ver la hora en el reloj de mi auto. De regreso a casa, me desplom\u00e9 en la cama. Mi memoria es vaga, pero a la ma\u00f1ana siguiente lleg\u00f3 una amiga preocupado y me encontr\u00f3 sentada en mi cama. Al parecer, a primera hora de la ma\u00f1ana hab\u00eda hecho varias llamadas, incluso a ella, pero no lo recordaba. <\/p>\n\n<p class=\"wp-block-paragraph\">Mi amiga, una m\u00e9dica respiratoria que viv\u00eda cerca, reconoci\u00f3 que yo parec\u00eda estar en un estado alterado. R\u00e1pidamente me llev\u00f3 a un m\u00e9dico local. Mientras estaba en el consultorio del m\u00e9dico de cabecera, recuerda c\u00f3mo me costaba responder preguntas y no pod\u00eda sentarme sin que mi cuerpo se balanceara. Mi recuerdo del d\u00eda anterior segu\u00eda confuso y me faltaban horas de tiempo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-i-tested-positive-for-benzodiazepine-but-did-i-want-to-be-perceived-as-a-troublemaker\"><strong>Di positivo en benzodiacepinas, pero \u00bfquer\u00eda que me percibieran como problem\u00e1tica?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Mi amigo inform\u00f3 a la doctora sobre lo que pas\u00f3. Sin estar segura de los pr\u00f3ximos pasos, el m\u00e9dico mir\u00f3 a mi amiga en busca de orientaci\u00f3n. Necesitaba pruebas urgentes de agresi\u00f3n sexual, pero la unidad especializada estuvo cerrada durante el fin de semana. Mi amiga insisti\u00f3 en una prueba de orina.<\/p>\n\n<p class=\"wp-block-paragraph\">En el laboratorio, el personal me ayud\u00f3 a recolectar mi muestra porque no pod\u00eda hacerlo sola. Cuando la realidad se impuso, no pod\u00eda creer lo que hab\u00eda sucedido. Permanec\u00eda la sospecha de que me hab\u00edan drogado, pero no pod\u00eda imaginar c\u00f3mo un hombre al que consideraba un mentor me har\u00eda esto. Una gran parte de m\u00ed deseaba que la prueba de drogas diera negativa para poder atribuirlo a un error de borrachera.<\/p>\n\n<p class=\"wp-block-paragraph\">Al d\u00eda siguiente, que era domingo, inform\u00e9 a mi director de entrenamiento en el Hospital de Liverpool que no regresar\u00eda a St. George para trabajar con el Dr. Kearsley. Aconsej\u00f3 documentar todo, lo que result\u00f3 ser un consejo invaluable. Fijamos una reuni\u00f3n con el director m\u00e9dico del Liverpool para el viernes siguiente y antes de la reuni\u00f3n, el m\u00e9dico al que hab\u00eda visitado me llam\u00f3 para comunicarme los resultados de mi orina. <\/p>\n\n<p class=\"wp-block-paragraph\">Di positivo a benzodiacepinas. Sent\u00ed como si me hubieran golpeado en la cabeza con un bate. Una profunda sensaci\u00f3n visceral de traici\u00f3n que nunca antes hab\u00eda sentido me provoc\u00f3 n\u00e1useas. Comprender que yo era la presa en la escena del crimen cuidadosamente dise\u00f1ada por Kearsley lo cambi\u00f3 todo. Se demostr\u00f3 una clara intenci\u00f3n criminal. Inmediatamente las preguntas llenaron mi mente. \u00ab\u00bfA cu\u00e1ntas mujeres les hab\u00eda hecho esto antes, por qu\u00e9 me eligi\u00f3 a m\u00ed y c\u00f3mo pude haber sido tan est\u00fapida?\u00bb<\/p>\n\n<p class=\"wp-block-paragraph\">El informe sobre drogas result\u00f3 ser una cruda revelaci\u00f3n. La presencia de benzodiazepinas subray\u00f3 la necesidad de una investigaci\u00f3n exhaustiva. Me preocup\u00e9 incesantemente por lo que pudo haber sucedido en los momentos de la noche que no recuerdo debido al efecto de la droga. La culpa se apoder\u00f3 de mi. En los d\u00edas posteriores al incidente, hice llamadas an\u00f3nimas a l\u00edneas directas de violencia sexual, buscando orientaci\u00f3n mientras ocultaba mi identidad. Mi amiga y yo presentamos la situaci\u00f3n como un escenario hipot\u00e9tico a la polic\u00eda No ten\u00eda idea de por d\u00f3nde empezar, ni qu\u00e9 significar\u00eda la investigaci\u00f3n policial.<\/p>\n\n<p class=\"wp-block-paragraph\">Durante estas llamadas, cada vez que la polic\u00eda buscaba detalles o suger\u00eda contacto directo, terminaba abruptamente la llamada, temiendo que mi identidad quedara expuesta. Me involucr\u00e9 en este proceso durante varios d\u00edas, luchando con una pregunta desafiante. Como m\u00e9dico a punto de completar mi formaci\u00f3n especializada, con la etiqueta de problem\u00e1tica \u00bfcu\u00e1les eran mis posibilidades de sobrevivir en nuestra comunidad tan unida?<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-sexual-assault-victim-couldn-t-bear-this-happening-to-someone-else\"><strong>La v\u00edctima de agresi\u00f3n sexual no pod\u00eda soportar que esto le pasara a otra persona<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Sab\u00eda que denunciar el incidente podr\u00eda poner en riesgo mi carrera, pero \u00bfval\u00eda la pena permanecer en silencio? La insoportable idea de que alguien m\u00e1s sufriera un destino similar impuls\u00f3 mi decisi\u00f3n. Cuando entr\u00e9 a la comisar\u00eda local, acept\u00e9 que mi carrera en oncolog\u00eda radioter\u00e1pica habr\u00eda terminado. Me asegur\u00e9 de que con mi t\u00edtulo de m\u00e9dico y mis habilidades transferibles, podr\u00eda empezar de nuevo en una especialidad diferente.<\/p>\n\n<p class=\"wp-block-paragraph\">En mi declaraci\u00f3n al director m\u00e9dico, inclu\u00ed los resultados de la prueba de drogas y mi intenci\u00f3n de informar. El sistema criminal parec\u00eda un mundo desconocido y, en ese momento, Sydney carec\u00eda de una unidad especializada para manejar agresiones sexuales. Al principio, el detective pareci\u00f3 dudar en aceptar mi caso, refiri\u00e9ndose a \u00e9l como \u00ab\u00e9l dijo, ella dijo\u00bb. Sin embargo, cuando el detective se dio cuenta de que ten\u00edamos pruebas tangibles, su actitud cambi\u00f3.<\/p>\n\n<p class=\"wp-block-paragraph\">Lamentablemente, ante la falta de tales pruebas, las denuncias de muchas mujeres son rechazadas A pesar de tener unos treinta a\u00f1os, ser bien educado y elocuente, el detective no me disuadi\u00f3 de continuar con la investigaci\u00f3n. Ingenuamente pens\u00e9 que una vez que me comprometiera a denunciar el crimen, la polic\u00eda iniciar\u00eda inmediatamente la investigaci\u00f3n. En un momento de realidad aleccionadora, me di cuenta del ambiente intimidante que enfrentan las mujeres si denuncian su agresi\u00f3n a la polic\u00eda.<\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, con las pruebas en mano, el detective se convirti\u00f3 en un incansable defensor de la justicia: un h\u00e9roe a mis ojos. A pesar de varias semanas de silencio e incertidumbre, alrededor de Navidad, me contact\u00f3 para contarme una actualizaci\u00f3n. Estaban trabajando para obtener una orden judicial para una llamada grabada para obtener una admisi\u00f3n de Kearsley.<\/p>\n\n<p class=\"wp-block-paragraph\">Al principio, me sorprendi\u00f3 la petici\u00f3n del detective de que participara en la llamada. Parec\u00eda una t\u00e1ctica sacada de una vieja pel\u00edcula de detectives. La idea de hablar con Kearsley me hizo temblar, especialmente porque no se hab\u00eda acercado a m\u00ed desde el incidente. Su falta de preocupaci\u00f3n por mi seguridad esa noche, sabiendo que me drog\u00f3 y me dej\u00f3 conducir, me pareci\u00f3 imperdonable.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-perpetrator-pleads-guilty-in-court-of-law\"><strong>El perpetrador se declara culpable ante un tribunal de justicia<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La polic\u00eda arregl\u00f3 todo y lleg\u00f3 el d\u00eda de llamar al Dr. Kearsley. En el transcurso de nuestras conversaciones, intent\u00f3 disuadirme de denunciar el incidente. Me propuso un asesoramiento conjunto y me present\u00f3 una oferta de trabajo. Inicialmente neg\u00f3 el incidente, pero luego afirm\u00f3 que pudo haber tenido un \u201capag\u00f3n\u201d y no recuerda lo sucedido.<\/p>\n\n<p class=\"wp-block-paragraph\">En esa primera e intensa llamada telef\u00f3nica, lo inst\u00e9 a reflexionar sobre sus acciones mientras me esforzaba por mantener la compostura. No quer\u00eda darle una ventaja. Sin saber que present\u00e9 un informe policial, envi\u00f3 correos electr\u00f3nicos que revelaban m\u00e1s de lo que pretend\u00eda. Con el tiempo, el Dr. Kearsley divulg\u00f3 informaci\u00f3n importante. Este se convirti\u00f3 en un paso crucial en la construcci\u00f3n del caso. Mientras tanto, sus extra\u00f1as justificaciones me ofendieron profundamente.<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando la polic\u00eda lo acus\u00f3, y allan\u00f3 su casa, no encontraron pruebas de que tuviera drogas en su poder. A los pocos d\u00edas, se ausent\u00f3 del trabajo y meses despu\u00e9s, mientras limpiaba su oficina, la persona que lo reemplazaba encontr\u00f3 Lorazepam, que es la benzodiazepina que encontraron en m\u00e1s pruebas forenses de mi orina. En el caj\u00f3n de su escritorio, este descubrimiento complet\u00f3 el rompecabezas.<\/p>\n\n<p class=\"wp-block-paragraph\">Con el caso en marcha, el fiscal ofreci\u00f3 un acuerdo de culpabilidad, que rechac\u00e9 despu\u00e9s de una deliberaci\u00f3n exhaustiva. Me sent\u00ed decidida a abordar plenamente la naturaleza del delito, en particular la drogaci\u00f3n premeditada. El prolongado proceso judicial me afect\u00f3 profundamente y, en octubre de 2015, estaba luchando.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-we-must-stand-up-for-the-silent-sufferers-and-demand-a-system-change-that-protects-the-victims\"><strong>Debemos defender a los que sufren en silencio y exigir un cambio de sistema que proteja a las v\u00edctimas.<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Casi dos a\u00f1os despu\u00e9s de la agresi\u00f3n, cuando finalmente se acercaba la fecha de la audiencia, recib\u00ed la noticia de que Kearsley deseaba declararse culpable de ambos cargos penales. El equipo del fiscal me tranquiliz\u00f3, esto era lo mejor que pod\u00eda pasar<\/p>\n\n<p class=\"wp-block-paragraph\">Cientos de p\u00e1ginas de resultados de investigaciones recopiladas durante dos a\u00f1os se redujeron a dos p\u00e1ginas de \u00abHechos acordados\u00bb y firmas de ambas partes. El caso atrajo una intensa atenci\u00f3n de los medios y, aunque Kearsley fue sentenciado a prisi\u00f3n, yo me sent\u00ed nuevamente decepcionada con la reducci\u00f3n de la sentencia en la apelaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Quer\u00eda que Kearsley supiera que no estaba de acuerdo con el resultado de la apelaci\u00f3n y finalmente present\u00e9 una demanda civil por da\u00f1os y perjuicios. Kearsley finalmente ofreci\u00f3 un acuerdo en 2018. Para entonces, el impacto de la terrible experiencia me hab\u00eda alejado de Sydney. Me mud\u00e9 a Brisbane, donde busqu\u00e9 un nuevo comienzo. Necesitaba concentrarme en sanarme de los a\u00f1os de trauma y angustia que este hombre caus\u00f3.<\/p>\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la agresi\u00f3n, casi dej\u00e9 mi campo de especializaci\u00f3n, pero durante mi viaje de recuperaci\u00f3n en Brisbane, me compromet\u00ed a brindar tutor\u00eda y apoyo a los m\u00e9dicos j\u00f3venes. Esta iniciativa est\u00e1 impulsada no solo por la prevalencia de casos de abuso sexual en el campo m\u00e9dico, sino tambi\u00e9n por a\u00f1os de observar a m\u00e9dicos j\u00f3venes darse por vencidos despu\u00e9s de luchar por navegar en un sistema jer\u00e1rquico que no tiene una estructura que los proteja. Necesitamos una revisi\u00f3n sist\u00e9mica para proteger a los profesionales m\u00e9dicos, abordar la mala conducta de los pares y desarrollar intervenciones exitosas.<\/p>\n\n<p class=\"wp-block-paragraph\">Mucha gente elogia mi valent\u00eda al enfrentar a mi abusador. Lo veo como una defensa de la justicia y un deber m\u00e9dico de prevenir da\u00f1os. S\u00ed, arriesgar mi reputaci\u00f3n y mi carrera me llev\u00f3 a a\u00f1os de sufrimiento, pero sobreviv\u00ed y me alegro de haber persistido. Denunciar los abusos con los recursos adecuados es la \u00fanica manera de hacer que los perpetradores rindan cuentas. Mientras tanto, hay mucho margen de mejora en el proceso de presentaci\u00f3n de informes para proteger mejor a las v\u00edctimas.<\/p>\n\n<p class=\"wp-block-paragraph\">Mi trayectoria en la comunidad m\u00e9dica destaca la importancia del apoyo y la solidaridad. Despu\u00e9s de ser drogada y agredida por un m\u00e9dico de alto nivel, encabec\u00e9 una victoria legal \u00fanica en Australia. Este caso p\u00fablico hizo a\u00f1icos la percepci\u00f3n de invencibilidad de figuras poderosas de la medicina. Espero que mi historia vaya m\u00e1s all\u00e1 del logro personal y genere esperanza de que podemos luchar contra el abuso de poder. Mi recuperaci\u00f3n ha sido dura y a\u00fan no ha terminado. Durante demasiado tiempo cargu\u00e9 con el peso de la culpa por el ataque que nunca deb\u00ed haber soportado. Ahora s\u00e9 que deber\u00eda haberse informado de inmediato, con o sin drogas. Es sorprendente c\u00f3mo el alcohol nunca ser\u00eda una excusa aceptable para el asesinato y, sin embargo, se utiliza f\u00e1cilmente para justificar la violencia sexual.<\/p>\n\n<p class=\"wp-block-paragraph\">Este no es un incidente aislado y debemos considerar el panorama m\u00e1s amplio. La verdadera tragedia es la multitud de pacientes silenciosos en la medicina, cuyas historias siguen sin contarse. Al compartir mi experiencia, aspiro a crear un futuro en el que esas historias impulsen la transformaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi trayectoria en la comunidad m\u00e9dica destaca la importancia del apoyo y la solidaridad. Despu\u00e9s de ser drogada y agredida por un m\u00e9dico de alto nivel, encabec\u00e9 una victoria legal \u00fanica en Australia. Este caso p\u00fablico hizo a\u00f1icos la percepci\u00f3n de invencibilidad de figuras poderosas de la medicina. Espero que mi historia vaya m\u00e1s all\u00e1 del logro personal y genere esperanza de que podemos luchar contra el abuso de poder.<\/p>\n","protected":false},"author":112,"featured_media":86984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[874,188],"tags":[7982,5648,3477,7983,7985,7986,7984,1055],"class_list":["post-87073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crimen-y-corrupcion-es","category-salud","tag-agresion-sexual","tag-australia-es","tag-australia-nueva-zelanda","tag-comunidad-medica","tag-drogada","tag-john-kearsley-es","tag-victoria-legal","tag-violacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Victoria legal hist\u00f3rica de una m\u00e9dica en un caso de agresi\u00f3n sexual<\/title>\n<meta name=\"description\" content=\"La hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica\" \/>\n<meta property=\"og:description\" content=\"Mi trayectoria en la comunidad m\u00e9dica destaca la importancia del apoyo y la solidaridad. Despu\u00e9s de ser drogada y agredida por un m\u00e9dico de alto nivel, encabec\u00e9 una victoria legal \u00fanica en Australia. Este caso p\u00fablico hizo a\u00f1icos la percepci\u00f3n de invencibilidad de figuras poderosas de la medicina. Espero que mi historia vaya m\u00e1s all\u00e1 del logro personal y genere esperanza de que podemos luchar contra el abuso de poder.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-19T12:44:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T14:37:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniella Mejia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniella Mejia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/\"},\"author\":{\"name\":\"Daniella Mejia\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/11888e72af4b41f6959de279c8c1d4f4\"},\"headline\":\"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica\",\"datePublished\":\"2024-01-19T12:44:27+00:00\",\"dateModified\":\"2024-01-22T14:37:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/\"},\"wordCount\":2335,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-18T081835.586.png\",\"keywords\":[\"agresi\u00f3n sexual\",\"Australia\",\"Australia &amp; Nueva Zelanda\",\"Comunidad m\u00e9dica\",\"drogada\",\"John Kearsley\",\"victoria legal\",\"violaci\u00f3n\"],\"articleSection\":[\"Crimen y corrupci\u00f3n\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/\",\"name\":\"Victoria legal hist\u00f3rica de una m\u00e9dica en un caso de agresi\u00f3n sexual\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-18T081835.586.png\",\"datePublished\":\"2024-01-19T12:44:27+00:00\",\"dateModified\":\"2024-01-22T14:37:48+00:00\",\"description\":\"La hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-18T081835.586.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-01-18T081835.586.png\",\"width\":1280,\"height\":960,\"caption\":\"Dominique Lee, medical consultant, exposed Professor Kearsley's use of intoxicants, securing a past legal victory | Photo Courtesy of Dominique Lee\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/01\\\/19\\\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/11888e72af4b41f6959de279c8c1d4f4\",\"name\":\"Daniella Mejia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Daniella Mejia\"},\"description\":\"Daniella Mejia, a business administration graduate with dual specializations in international business and digital marketing, boasts over five years of experience in design, editing, and translation. Her time as an interpreter for Habitat for Humanity in El Salvador ignited a profound passion for social work and honed her expertise in cross-cultural communication. &nbsp; In Canada, Daniella sharpened her design skills as a design specialist for a risk management and child safety consultancy while freelancing social media design for a Vancouver-based Latin American magazine. Ascending through the ranks at Orato, she journeyed from a marketing intern to an editorial lead to her present-day position as a senior editor. &nbsp; As senior editor for Orato World Media, Daniella produces weekly compelling first-person news for global audiences. Her knack for storytelling and editing contributes to the continual elevation of the publication\u2019s content quality.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/daniella-mejiaorato-world\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Victoria legal hist\u00f3rica de una m\u00e9dica en un caso de agresi\u00f3n sexual","description":"La hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/","og_locale":"es_ES","og_type":"article","og_title":"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica","og_description":"Mi trayectoria en la comunidad m\u00e9dica destaca la importancia del apoyo y la solidaridad. Despu\u00e9s de ser drogada y agredida por un m\u00e9dico de alto nivel, encabec\u00e9 una victoria legal \u00fanica en Australia. Este caso p\u00fablico hizo a\u00f1icos la percepci\u00f3n de invencibilidad de figuras poderosas de la medicina. Espero que mi historia vaya m\u00e1s all\u00e1 del logro personal y genere esperanza de que podemos luchar contra el abuso de poder.","og_url":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-01-19T12:44:27+00:00","article_modified_time":"2024-01-22T14:37:48+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png","type":"image\/png"}],"author":"Daniella Mejia","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Daniella Mejia","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/"},"author":{"name":"Daniella Mejia","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/11888e72af4b41f6959de279c8c1d4f4"},"headline":"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica","datePublished":"2024-01-19T12:44:27+00:00","dateModified":"2024-01-22T14:37:48+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/"},"wordCount":2335,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png","keywords":["agresi\u00f3n sexual","Australia","Australia &amp; Nueva Zelanda","Comunidad m\u00e9dica","drogada","John Kearsley","victoria legal","violaci\u00f3n"],"articleSection":["Crimen y corrupci\u00f3n","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/","url":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/","name":"Victoria legal hist\u00f3rica de una m\u00e9dica en un caso de agresi\u00f3n sexual","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png","datePublished":"2024-01-19T12:44:27+00:00","dateModified":"2024-01-22T14:37:48+00:00","description":"La hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png","width":1280,"height":960,"caption":"Dominique Lee, medical consultant, exposed Professor Kearsley's use of intoxicants, securing a past legal victory | Photo Courtesy of Dominique Lee"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/01\/19\/coraje-en-la-medicina-la-historica-victoria-legal-de-una-medica-en-un-caso-de-agresion-sexual-contra-un-medico-de-alto-nivel-en-australia-exige-un-cambio-sistemico-en-la-comunidad-medica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Coraje en la medicina: la hist\u00f3rica victoria legal de una m\u00e9dica en un caso de agresi\u00f3n sexual contra un m\u00e9dico de alto nivel en Australia exige un cambio sist\u00e9mico en la comunidad m\u00e9dica"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/11888e72af4b41f6959de279c8c1d4f4","name":"Daniella Mejia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Daniella Mejia"},"description":"Daniella Mejia, a business administration graduate with dual specializations in international business and digital marketing, boasts over five years of experience in design, editing, and translation. Her time as an interpreter for Habitat for Humanity in El Salvador ignited a profound passion for social work and honed her expertise in cross-cultural communication. &nbsp; In Canada, Daniella sharpened her design skills as a design specialist for a risk management and child safety consultancy while freelancing social media design for a Vancouver-based Latin American magazine. Ascending through the ranks at Orato, she journeyed from a marketing intern to an editorial lead to her present-day position as a senior editor. &nbsp; As senior editor for Orato World Media, Daniella produces weekly compelling first-person news for global audiences. Her knack for storytelling and editing contributes to the continual elevation of the publication\u2019s content quality.","url":"https:\/\/orato.world\/es\/author\/daniella-mejiaorato-world\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-01-18T081835.586-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Daniella Mejia","author_link":"https:\/\/orato.world\/es\/author\/daniella-mejiaorato-world\/"},"uagb_comment_info":0,"uagb_excerpt":"Mi trayectoria en la comunidad m\u00e9dica destaca la importancia del apoyo y la solidaridad. Despu\u00e9s de ser drogada y agredida por un m\u00e9dico de alto nivel, encabec\u00e9 una victoria legal \u00fanica en Australia. Este caso p\u00fablico hizo a\u00f1icos la percepci\u00f3n de invencibilidad de figuras poderosas de la medicina. Espero que mi historia vaya m\u00e1s all\u00e1&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/87073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/112"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=87073"}],"version-history":[{"count":5,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/87073\/revisions"}],"predecessor-version":[{"id":87155,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/87073\/revisions\/87155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/86984"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=87073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=87073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=87073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}