{"id":89896,"date":"2024-04-03T03:00:00","date_gmt":"2024-04-03T10:00:00","guid":{"rendered":"https:\/\/orato.world\/?p=89896"},"modified":"2024-04-26T17:37:47","modified_gmt":"2024-04-27T00:37:47","slug":"el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/","title":{"rendered":"Airplane crash survivor featured in Oscar-nominated \u00abSociety of the Snow\u00bb on Netflix tells it in his words"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-500x500.jpeg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-500x500.jpeg 500w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-300x300.jpeg 300w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-1024x1024.jpeg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-100x100.jpeg 100w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-770x771.jpeg 770w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-400x400.jpeg 400w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-150x150.jpeg 150w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-70x70.jpeg 70w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1-293x293.jpeg 293w, https:\/\/orato.world\/wp-content\/uploads\/Carlitos1.jpeg 1125w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Journalist&#8217;s Notes<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"><a href=\"https:\/\/carlitospaez.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Carlitos P\u00e1ez<\/a> naci\u00f3 en Montevideo, Uruguay, el 31 de octubre de 1953. M\u00e1s de 50 a\u00f1os despu\u00e9s de sobrevivir al accidente a\u00e9reo en los Andes, Carlitos tiene dos hijos (Mar\u00eda Elena de los Andes \u00abGochi\u00bb y Carlos Diego) y cinco nietos (Justina, M\u00eda, Violeta, Juan Justo y Alexis). Es T\u00e9cnico Agr\u00f3nomo egresado de la Universidad del Trabajo de Uruguay. En 1992 ingres\u00f3 a la publicidad como parte del equipo creativo de Nivel \/ Publicis. Fund\u00f3 su agencia, Rating Publicidad, y fue director de Bates Uruguay Publicidad. Actualmente dirige su empresa de Consultor\u00eda en Comunicaci\u00f3n y Relaciones P\u00fablicas, al tiempo que se desarrolla, desde 2002, como conferencista internacional.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">El 13 de octubre de 1972, un grupo de uruguayos embarc\u00f3 en un avi\u00f3n con destino a Chile para un viaje de rugby. En el avi\u00f3n viajaban 44 pasajeros en total. El avi\u00f3n choc\u00f3 con algunas bolsas de aire severas y se estrell\u00f3 en la cordillera de los Andes. Las autoridades suspendieron la b\u00fasqueda de supervivientes al cabo de 10 d\u00edas. Setenta y dos d\u00edas despu\u00e9s, dos de los supervivientes &#8211; Nando Parrado y Roberto Canessa &#8211; cruzaron los Andes en busca de ayuda y llegaron a la civilizaci\u00f3n. Diecis\u00e9is personas sobrevivieron. Durante el calvario, recurrieron a comer carne humana de los fallecidos para sobrevivir. Toda la experiencia es ahora una pel\u00edcula nominada al Oscar que se estren\u00f3 en cines y ahora est\u00e1 en Netflix.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n\n\n<p class=\"wp-block-paragraph\">LOS ANDES, Chile \ua7f7 Antes de subir al avi\u00f3n aquel fat\u00eddico d\u00eda de 1972, me sent\u00eda como un ni\u00f1o mimado y bueno para nada. Mi ni\u00f1era me hizo la maleta. No hab\u00eda visto un muerto en mi vida y vengo de una familia acomodada. Mi padre, pintor, nos lo dio todo y la sierra donde crec\u00ed me sirvi\u00f3 de mucho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras el avi\u00f3n atravesaba la cordillera de los Andes, pasamos por dos gigantescos agujeros de aire. Gritamos \u00abO-l\u00e9\u00bb como toreros, inconscientes de lo que ocurrir\u00eda. Entonces, de repente, sentimos el golpe. A 400 kil\u00f3metros por hora, nuestro avi\u00f3n se estrell\u00f3 contra la monta\u00f1a. El avi\u00f3n se parti\u00f3 por la mitad y corri\u00f3 como un trineo con tanta suerte que no tocamos ni una piedra. Si el fuselaje hubiera chocado contra una piedra, nos habr\u00eda roto en pedazos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/orato.world\/?s=on+Netflix\">Lee m\u00e1s historias de artistas en Netflix en Orato World Media.<\/a><\/em><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-joven-y-sus-cuatro-amigos-sobreviven-a-un-accidente-aereo-en-la-cordillera-de-los-andes\"><strong>Un joven y sus cuatro amigos sobreviven a un accidente a\u00e9reo en la cordillera de los Andes<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el avi\u00f3n, a medida que se desarrollaba la cat\u00e1strofe, empez\u00f3 a hacer fr\u00edo. Todo el mundo gritaba y el caos era absoluto. Quer\u00eda rezar, pensando: \u00abVoy a empezar con el Padre Nuestro\u00bb. Luego pens\u00e9: \u00abNo, es demasiado largo, no voy a terminarlo\u00bb. En su lugar, recurr\u00ed a Gloria, la oraci\u00f3n cristiana m\u00e1s breve que se me ocurri\u00f3. Luego rec\u00e9 el Ave Mar\u00eda, que es de longitud media. Me dije: \u00abMatar\u00e9 dos p\u00e1jaros de un tiro porque mis oraciones son buenas con Dios y con la Virgen\u00bb. Aunque no era muy cat\u00f3lico, me aferr\u00e9 a Dios en aquellas monta\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los que iban en fila detr\u00e1s de nosotros -el piloto, el copiloto y otros- murieron todos. Ni\u00f1o de mam\u00e1, le dije a Canessa en medio del desorden: \u00ab\u00bfA esto le llamas desastre?\u00bb. Realmente no conoc\u00eda la definici\u00f3n de la palabra; era tan ingenuo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los primeros d\u00edas que sobrevivimos en los Andes, me jact\u00e9 de que mis amigos y yo hab\u00edamos sobrevivido. Es m\u00e1s, escrib\u00ed a mi madre el 23 de octubre, 10 d\u00edas despu\u00e9s. Le dije: \u00abPor suerte estamos vivos\u00bb. Cuando dos de mis amigos murieron en una avalancha, no llor\u00e9. Como ser humano, me encontr\u00e9 luchando por mi vida lejos de la civilizaci\u00f3n. Los llor\u00e9 m\u00e1s tarde, cuando volvimos a casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algo de lo que rara vez se habla es de la altura a la que nos estrellamos. Cuando m\u00e1s tarde volv\u00ed al lugar en los Andes con un productor de Discovery Channel, fui testigo de ello. A 4.200 metros te enfrentas a serios problemas. Hay que bajar m\u00e1s, pero no tuvimos tiempo de ocuparnos de esa cuesti\u00f3n; nos enfrentamos a otros problemas. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pasan-los-dias-y-los-supervivientes-se-toman-la-justicia-por-su-mano\"><strong>Pasan los d\u00edas y los supervivientes se toman la justicia por su mano<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de un fr\u00edo horrible, nos abrazamos y nos abrazamos. Un vaso de agua me habr\u00eda parecido oro. Sigue siendo imposible que la nieve se derrita a 25 grados bajo cero, as\u00ed que inventamos las latas de plata. Cuando sali\u00f3 el sol, utilizamos las latas y empezaron a caer gotas de agua. La sed te golpea m\u00e1s que el hambre. Esa sed se sent\u00eda desesperante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 10 d\u00edas, 26 de nosotros compartimos una lata de marisco, dos cuadrados de chocolate que encontr\u00e9 y unos vasos de cerezas. Un avi\u00f3n militar, no ten\u00eda comida. Para entonces, los aviones pasaban por encima de nosotros y quer\u00edamos saber d\u00f3nde buscaban. Est\u00e1bamos convencidos de que nos hab\u00edan visto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entr\u00f3 el encargado de escuchar la radio, Gustavo Nicolich, y me dijo: \u00abCarlitos, tengo una buena noticia que darte\u00bb. \u00ab\u00bfQu\u00e9 pas\u00f3, Gustavo?\u00bb, pregunt\u00e9. \u00abAcabo de escuchar la radio chilena donde el locutor dijo que dieron por terminada la b\u00fasqueda del avi\u00f3n uruguayo\u00bb. Lo quer\u00eda matar, y le grit\u00e9: \u00ab\u00a1Buenas noticias, hijo de puta!\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me mir\u00f3 a los ojos y me dijo: \u00ab\u00bfSabes por qu\u00e9 es una buena noticia? Porque ahora dependemos de nosotros mismos y no de gente de fuera. Carlitos, tenemos que encontrar nuestros recursos\u00bb. Mirando atr\u00e1s, puedo decir que Nicolich ten\u00eda raz\u00f3n, porque ese d\u00eda dejamos de esperar y empezamos a actuar. Luchamos por nuestra propia historia y fuimos a buscarla.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-desesperadamente-hambriento-carlitos-me-como-al-piloto\"><strong>Desesperadamente hambriento: \u00abCarlitos, me como al piloto\u00bb<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En la vida, todos experimentamos esa clase de hambre que te hace querer comerte un bocadillo. Eso constituye el hambre inicial. Despu\u00e9s viene un hambre que te hace doler el est\u00f3mago. Las paredes de tu est\u00f3mago parecen pegarse y se te mete en la cabeza. De repente sabes que si no comes, morir\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[When the hunger set in] Todos pensaban lo mismo, pero nadie se atrev\u00eda a decirlo, y menos yo, el m\u00e1s joven del grupo. Creo que Nando Parrado mencion\u00f3 la idea primero. Se aventur\u00f3 hacia la cola del avi\u00f3n y le dije: \u00abNando, no queda nada en la despensa\u00bb. [The pantry was a woman\u2019s bag where we found the seafood.]f Nando me mir\u00f3 y me dijo: \u00abCarlitos, yo me como al piloto\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Society of the Snow - Official Trailer | Netflix\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/095pfwMMi8s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal vez el comentario surgi\u00f3 de forma natural. Nando perdi\u00f3 a su madre en el accidente y a su hermana cinco d\u00edas despu\u00e9s. Era el m\u00e1s distante de todos. Ese d\u00eda hicimos una expedici\u00f3n corta y recuerdo que me alej\u00e9 de Adolfo Strauch pensando: \u00abNo me voy a comer a mi mejor amigo\u00bb. Decid\u00ed preguntar qu\u00e9 pensaban los dem\u00e1s y saqu\u00e9 el tema. Entonces, r\u00e1pidamente culp\u00e9 a Nando. \u00abEst\u00e1 completamente loco\u00bb, le dije, \u00abquiere comerse al piloto\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adolfo me mir\u00f3 y me dijo: \u00abNo Carlitos, no est\u00e1 tan loco. Mis primos y yo ya lo pensamos\u00bb. Todos lo hab\u00edan hecho, aunque nadie se atrevi\u00f3 a hablar. Cuando volvimos, el grupo lo discuti\u00f3 sin oponer resistencia. Parec\u00eda sencillo. Nos mor\u00edamos de hambre; nadie nos buscaba; y pose\u00edamos el m\u00e1s sagrado de los derechos: vivir y volver a casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-sepultados-por-una-avalancha\"><strong>Sepultados por una avalancha<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hicimos un pacto solemne: si alguno de nosotros mor\u00eda, estar\u00edamos a disposici\u00f3n de los dem\u00e1s. Confiamos en los estudiantes de medicina de primer a\u00f1o a bordo que hab\u00edan sobrevivido con nosotros. Comer nos dar\u00eda la energ\u00eda para encontrar la salida. Si no com\u00edamos, nuestra hu\u00edda ser\u00eda imposible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La discusi\u00f3n adopt\u00f3 al principio un tono casi filos\u00f3fico. Comparamos nuestro debate con la exigencia del consentimiento para la donaci\u00f3n de \u00f3rganos. Desde una perspectiva cat\u00f3lica, consideramos el alma y el cuerpo, y razonamos que ambos est\u00e1n separados. El cuerpo es simplemente agua y sales minerales. Naturalizamos la perspectiva de comernos a la gente. Aunque cuidadosos al principio, pronto nos acostumbramos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego vino la avalancha que nos sepult\u00f3 durante tres d\u00edas. Cumpl\u00ed 19 a\u00f1os all\u00ed, bajo la nieve. Mi infantilismo me hizo querer celebrar mi cumplea\u00f1os en medio del caos. Como el personaje de La vida es bella, mantuve el humor durante todo el drama.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante todo el calvario, s\u00f3lo hicimos fotos un d\u00eda. No quer\u00edamos fotografiar el desastre que se estaba produciendo. En una de las fotos se ve a un chico sin camiseta que soy yo. Recuerdo que dije: \u00abQuiero llegar a Punta del Este bronceado\u00bb. Quiz\u00e1s mostr\u00e9 un acto de frivolidad, o quiz\u00e1s un acto de esperanza. En un momento dado ced\u00ed mi chaqueta Pierre Cardin -regalo de mi padre- para que Canessa pudiera cubrirse las piernas. Me doli\u00f3 ver la chaqueta rota. Despu\u00e9s de todo, quer\u00eda lucirla en Chile.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-dos-supervivientes-se-marchan-y-pasan-10-dias\"><strong>Dos supervivientes se marchan y pasan 10 d\u00edas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pens\u00e9 mucho en mi madre, en los Andes. Mi madre ten\u00eda un Fiat 850, un coche europeo que ven\u00eda sin cinturones de seguridad, as\u00ed que rob\u00e9 tres del avi\u00f3n para llev\u00e1rselos a casa. Podr\u00eda haber cogido algo m\u00e1s inteligente -una br\u00fajula o un bar\u00f3metro-, pero los cinturones de seguridad me parec\u00edan un s\u00edmbolo. Me uni\u00f3 a mi madre y eso se convirti\u00f3 en lo m\u00e1s importante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aun as\u00ed, en alg\u00fan momento, dejamos de pensar en la familia. Pronto se sinti\u00f3 como una carga m\u00e1s. Mi obsesi\u00f3n por trascender la situaci\u00f3n se volvi\u00f3 incre\u00edble. Simult\u00e1neamente, surgieron pensamientos absurdos sobre la muerte. Si muero, pens\u00e9, quiero que piensen que mor\u00ed en el accidente, as\u00ed que me afeit\u00e9 la barba para que pareciera que nunca me hab\u00eda crecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No s\u00e9 qu\u00e9 fue m\u00e1s duro, si la espera o el camino. Pasaron los d\u00edas y no ocurri\u00f3 nada. Dos de los supervivientes, Fernando Parrado y Roberto Canesa, salieron a caminar. Hab\u00edan pasado 70 d\u00edas desde el accidente y 10 d\u00edas de la partida de Fernando y Roberto, llor\u00e9 desesperado, abrazado a Coche Iniciarte. El llanto se volvi\u00f3 desesperado. Antes hab\u00edamos fijado un plazo arbitrario para estar en casa en Navidad. Ahora las vacaciones estaban a la vuelta de la esquina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por alg\u00fan mecanismo psicol\u00f3gico, mi depresi\u00f3n y angustia cambiaron bruscamente a euforia cuando experiment\u00e9 una premonici\u00f3n. Fernando y Roberto lo consiguieron, pens\u00e9, pero no se lo dije a nadie. Al d\u00eda siguiente, Daniel Fern\u00e1ndez se despert\u00f3 y dijo: \u00abCarlitos, acabo de so\u00f1ar que Fernando y Roberto llegaban a alguna parte\u00bb. Confirm\u00e9 su sensaci\u00f3n y encendimos la radio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-hola-chicos-os-envio-un-helicoptero-como-regalo-de-navidad\"><strong>\u00abHola, chicos, os env\u00edo un helic\u00f3ptero como regalo de Navidad\u00bb.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de la est\u00e1tica o\u00edmos las palabras: \u00abAvi\u00f3n uruguayo\u00bb. Cambiando el dial, escuchamos al embajador uruguayo C\u00e9sar Charlone en el aeropuerto de Pudahuel decir: \u00abSe\u00f1ores, debo decir que es oficial la aparici\u00f3n de Fernando Parrado y Roberto Canessa.\u00bb O\u00edr sus nombres fue como el final de nuestro dolor y nuestra angustia. Dejamos de llorar ante la perspectiva de nuestra libertad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos abrazamos y lo celebramos, con cara de locos alrededor de aquel peque\u00f1o aparato tirado en la nieve. La radio mencion\u00f3 un helic\u00f3ptero, as\u00ed que me pein\u00e9 con gel y met\u00ed los cinturones de seguridad en la maleta. Luego, nos sentamos a esperar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parec\u00eda una larga espera cuando, de repente, sentimos el helic\u00f3ptero a lo lejos y o\u00edmos el maravilloso ruido de las aspas a lo lejos. Me pregunto qu\u00e9 sintieron los pilotos al vernos cuando irrumpieron en el valle. Salieron tres miembros del cuerpo de Socorro Andino Chileno. Uno de ellos, Sergio D\u00edaz, grit\u00f3 mi nombre. \u00abTengo dos cartas para ti\u00bb, dijo. La primera carta dec\u00eda: \u00abQuerido Carlitos Miguel, Como ves nunca te fall\u00e9. Te esper\u00e9 con m\u00e1s fe en Dios que nunca. Tu madre est\u00e1 llegando ahora a Chile. Un abrazo, el viejo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La segunda carta parec\u00eda m\u00e1s bonita que la primera, con un helic\u00f3ptero dibujado en ella. Dec\u00eda: \u00abHola, chicos, os env\u00edo un helic\u00f3ptero como regalo de Navidad\u00bb. Ese d\u00eda era el 22 de diciembre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-superviviente-de-la-sociedad-de-la-nieve-se-vuelve-sobrio-aprendi-que-el-mundo-sigue-en-movimiento\"><strong>El superviviente de la Sociedad de la Nieve se vuelve sobrio: \u00abAprend\u00ed que el mundo sigue en movimiento\u00bb.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s, la fama me hizo tropezar. Es muy atractivo ser famoso. Quien diga lo contrario miente. Aparecimos en la portada de Gente y aquel verano de 1972 todo el mundo hablaba de nosotros. Sin darme cuenta, empec\u00e9 a beber alcohol. Me involucr\u00e9 y entr\u00e9 en un mundo de drogas y alcohol. Cuando fue demasiado, me pregunt\u00e9: \u00abDespu\u00e9s de haber luchado tanto por la vida, \u00bfc\u00f3mo puedo involucrarme en este proyecto mortal?\u00bb. Me un\u00ed a Narc\u00f3ticos An\u00f3nimos y hoy tengo 34 a\u00f1os de sobriedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volv\u00ed al lugar del accidente tres veces. Primero con otros 11 supervivientes, luego con Discovery Channel y finalmente con mis dos hijos, cuatro nietos y unas 100 personas m\u00e1s. Con los supervivientes utilizaba el humor y les hac\u00eda re\u00edr; pero no pod\u00eda hacer payasadas cuando ven\u00edan mis hijos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquella vez, vi realmente el sufrimiento que ten\u00eda lugar en aquellas monta\u00f1as. Hace poco aprend\u00ed una frase maravillosa de San Francisco de As\u00eds: \u00abEmpieza por hacer lo necesario, luego lo posible, y te encontrar\u00e1s haciendo lo imposible\u00bb. Eso es exactamente lo que hicimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo no veo el accidente ni como una tragedia ni como un milagro. Un milagro ser\u00eda que todos sobrevivieran. Algunos murieron tr\u00e1gicamente, mientras que otros triunfaron. Me centro en el lado positivo. Hoy, los j\u00f3venes que sobrevivieron se han multiplicado. Tengo ocho hijos y nietos. El 22 de diciembre, en el <sup>50\u00ba<\/sup> aniversario, los supervivientes contaban con 120 descendientes en total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escrib\u00ed un libro titulado \u00abDespu\u00e9s del <sup>10\u00ba<\/sup>\u00ab. El mundo segu\u00eda girando mientras luch\u00e1bamos contra el fr\u00edo glacial, sobreviviendo en los Andes. La gente jugaba al f\u00fatbol. Montevideo acogi\u00f3 el D\u00eda de la Playa. Los astronautas llegaron a la Luna y nuestro avi\u00f3n se estrell\u00f3. Esta simple verdad puede ser un golpe brutal para la arrogancia humana. Creemos que cuando nos pasa algo, el mundo se detiene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprend\u00ed que el mundo sigue movi\u00e9ndose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde una perspectiva cat\u00f3lica, consideramos el alma y el cuerpo, y razonamos que ambos est\u00e1n separados. El cuerpo es simplemente agua y sales minerales. Naturalizamos la perspectiva de comernos a la gente. Aunque cuidadosos al principio, pronto nos acostumbramos.<\/p>\n","protected":false},"author":216,"featured_media":89822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1617,319],"tags":[2234,555,6332,8484,8483,8482,2214,2341],"class_list":["post-89896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-y-cultura-es","category-medio-ambiente","tag-accidente-de-avion-chapecoense","tag-chile-es","tag-cordillera-de-los-andes","tag-historias-de-sobrevivientes","tag-la-sociedad-de-la-nieve-es-2","tag-la-sociedad-de-la-nieve-es","tag-latinoamerica","tag-netflix-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sobreviviente del accidente a\u00e9reo de &quot;La sociedad de la nieve&quot; en Netflix<\/title>\n<meta name=\"description\" content=\"Airplane crash survivor featured in Oscar-nominated &quot;Society of the Snow&quot; on Netflix tells it in his words\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Airplane crash survivor featured in Oscar-nominated &quot;Society of the Snow&quot; on Netflix tells it in his words\" \/>\n<meta property=\"og:description\" content=\"Desde una perspectiva cat\u00f3lica, consideramos el alma y el cuerpo, y razonamos que ambos est\u00e1n separados. El cuerpo es simplemente agua y sales minerales. Naturalizamos la perspectiva de comernos a la gente. Aunque cuidadosos al principio, pronto nos acostumbramos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-27T00:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cynthia Serebrinsky\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cynthia Serebrinsky\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/\"},\"author\":{\"name\":\"Cynthia Serebrinsky\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/3444267214a232ad7d2068b057f885ad\"},\"headline\":\"Airplane crash survivor featured in Oscar-nominated \u00abSociety of the Snow\u00bb on Netflix tells it in his words\",\"datePublished\":\"2024-04-03T10:00:00+00:00\",\"dateModified\":\"2024-04-27T00:37:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/\"},\"wordCount\":2217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/432080888_828389679123594_9179800832554894054_n.jpg\",\"keywords\":[\"Accidente de avi\u00f3n Chapecoense\",\"Chile\",\"Cordillera de los Andes\",\"historias de sobrevivientes\",\"La sociedad de la nieve\",\"La sociedad de la nieve\",\"Latinoam\u00e9rica\",\"Netflix\"],\"articleSection\":[\"Arte y Cultura\",\"Medio ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/\",\"name\":\"Sobreviviente del accidente a\u00e9reo de \\\"La sociedad de la nieve\\\" en Netflix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/432080888_828389679123594_9179800832554894054_n.jpg\",\"datePublished\":\"2024-04-03T10:00:00+00:00\",\"dateModified\":\"2024-04-27T00:37:47+00:00\",\"description\":\"Airplane crash survivor featured in Oscar-nominated \\\"Society of the Snow\\\" on Netflix tells it in his words\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/432080888_828389679123594_9179800832554894054_n.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/432080888_828389679123594_9179800832554894054_n.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Carlitos and other survivors spent 72 days surviving in the Andes Mountains after their airplane crashed. They resorted to eating human flesh to survive. | Photo courtesy of Carlito P\u00e1ez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/03\\\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Airplane crash survivor featured in Oscar-nominated \u00abSociety of the Snow\u00bb on Netflix tells it in his words\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/3444267214a232ad7d2068b057f885ad\",\"name\":\"Cynthia Serebrinsky\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Cynthia Serebrinsky\"},\"description\":\"Cynthia studied Communication at Virginia Tech. She was an Editor, Cosmopolitan; Editorial Secretary, Women's Health; and Director of Ser Padres Hoy. She currently writes for Infobae and Orato World Media. She plays tennis and sings in choirs.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/cynthia-serebrinsky\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sobreviviente del accidente a\u00e9reo de \"La sociedad de la nieve\" en Netflix","description":"Airplane crash survivor featured in Oscar-nominated \"Society of the Snow\" on Netflix tells it in his words","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/","og_locale":"es_ES","og_type":"article","og_title":"Airplane crash survivor featured in Oscar-nominated \"Society of the Snow\" on Netflix tells it in his words","og_description":"Desde una perspectiva cat\u00f3lica, consideramos el alma y el cuerpo, y razonamos que ambos est\u00e1n separados. El cuerpo es simplemente agua y sales minerales. Naturalizamos la perspectiva de comernos a la gente. Aunque cuidadosos al principio, pronto nos acostumbramos.","og_url":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-04-03T10:00:00+00:00","article_modified_time":"2024-04-27T00:37:47+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg","type":"image\/jpeg"}],"author":"Cynthia Serebrinsky","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Cynthia Serebrinsky","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/"},"author":{"name":"Cynthia Serebrinsky","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/3444267214a232ad7d2068b057f885ad"},"headline":"Airplane crash survivor featured in Oscar-nominated \u00abSociety of the Snow\u00bb on Netflix tells it in his words","datePublished":"2024-04-03T10:00:00+00:00","dateModified":"2024-04-27T00:37:47+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/"},"wordCount":2217,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg","keywords":["Accidente de avi\u00f3n Chapecoense","Chile","Cordillera de los Andes","historias de sobrevivientes","La sociedad de la nieve","La sociedad de la nieve","Latinoam\u00e9rica","Netflix"],"articleSection":["Arte y Cultura","Medio ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/","url":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/","name":"Sobreviviente del accidente a\u00e9reo de \"La sociedad de la nieve\" en Netflix","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg","datePublished":"2024-04-03T10:00:00+00:00","dateModified":"2024-04-27T00:37:47+00:00","description":"Airplane crash survivor featured in Oscar-nominated \"Society of the Snow\" on Netflix tells it in his words","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg","width":1280,"height":960,"caption":"Carlitos and other survivors spent 72 days surviving in the Andes Mountains after their airplane crashed. They resorted to eating human flesh to survive. | Photo courtesy of Carlito P\u00e1ez"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/04\/03\/el-sobreviviente-de-un-accidente-de-avion-que-aparece-en-la-nominada-al-oscar-la-sociedad-de-las-nieves-en-netflix-lo-cuenta-con-sus-palabras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Airplane crash survivor featured in Oscar-nominated \u00abSociety of the Snow\u00bb on Netflix tells it in his words"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/3444267214a232ad7d2068b057f885ad","name":"Cynthia Serebrinsky","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Cynthia Serebrinsky"},"description":"Cynthia studied Communication at Virginia Tech. She was an Editor, Cosmopolitan; Editorial Secretary, Women's Health; and Director of Ser Padres Hoy. She currently writes for Infobae and Orato World Media. She plays tennis and sings in choirs.","url":"https:\/\/orato.world\/es\/author\/cynthia-serebrinsky\/"}]}},"modified_by":"Stephen","uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/432080888_828389679123594_9179800832554894054_n-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Cynthia Serebrinsky","author_link":"https:\/\/orato.world\/es\/author\/cynthia-serebrinsky\/"},"uagb_comment_info":0,"uagb_excerpt":"Desde una perspectiva cat\u00f3lica, consideramos el alma y el cuerpo, y razonamos que ambos est\u00e1n separados. El cuerpo es simplemente agua y sales minerales. Naturalizamos la perspectiva de comernos a la gente. Aunque cuidadosos al principio, pronto nos acostumbramos.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/89896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=89896"}],"version-history":[{"count":5,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/89896\/revisions"}],"predecessor-version":[{"id":91212,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/89896\/revisions\/91212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/89822"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=89896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=89896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=89896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}