{"id":90483,"date":"2024-04-18T03:00:00","date_gmt":"2024-04-18T10:00:00","guid":{"rendered":"https:\/\/orato.world\/?p=90483"},"modified":"2024-04-16T18:04:31","modified_gmt":"2024-04-17T01:04:31","slug":"podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/","title":{"rendered":"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T154949.979.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">journalist&#8217;s notes<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">interview subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Madison McGhee, 28, is an audiovisual producer based in Los Angeles. Originally from Charleston, West Virginia, she earned her Communication degree from the College of Charleston, an arts college in South Carolina. Madison recently launched her first podcast <a href=\"https:\/\/www.icecoldcase.com\/\">Ice Cold Case.<\/a><\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">background information<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">John Cornelius \u00abJ.C.\u00bb McGhee was tragically shot outside his home in Bridgeport, Ohio, on July 11, 2002, and<a href=\"https:\/\/www.youtube.com\/playlist?list=PLQOiA9OnD-4tM8e5nV6NghTvj2OMqirQZ\"> his murder case remains unsolved<\/a>. His daughter, Madison McGhee, delves into her father&#8217;s mysterious death in her podcast Ice Cold Case. The podcast&#8217;s inaugural season began in August 2023, and the first episode of its second season was released in March 2024.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">OHIO, Estados Unidos &#8211; Desde el momento en que supe que alguien hab\u00eda asesinado a mi padre, pienso en lo ocurrido todos los d\u00edas. Hace 22 a\u00f1os, alguien lo mat\u00f3, y yo me enter\u00e9 10 a\u00f1os despu\u00e9s. Mi investigaci\u00f3n me motiv\u00f3 a iniciar un podcast llamado <em>Ice Cold Case<\/em>, donde profundizo en los escalofriantes detalles de este crimen.<\/p>\n\n<p class=\"wp-block-paragraph\">Mi viaje dio un giro dram\u00e1tico cuando conoc\u00ed y entrevist\u00e9 a Daryl Smith, el principal sospechoso del asesinato de mi padre. Sentarme cara a cara con \u00e9l me sacudi\u00f3 hasta la m\u00e9dula. Despu\u00e9s de nuestra conversaci\u00f3n, reflexion\u00e9 sobre sus palabras, tratando de descifrar lo que pod\u00eda o no ser cierto. Abrumada, me sent\u00e9 en un prolongado silencio, luchando con una inquietante avalancha de pensamientos.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/orato.world\/?s=crime\">Lea m\u00e1s art\u00edculos sobre delincuencia en Orato World Media.<\/a><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-at-six-years-old-she-was-told-her-father-died-of-a-heart-attack\"><strong>A los seis a\u00f1os, le dijeron que su padre hab\u00eda muerto de un ataque al coraz\u00f3n.<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Al crecer en una familia marcada por el divorcio, mi padre y yo forjamos un v\u00ednculo especial a pesar de la distancia. Se empe\u00f1\u00f3 en visitarme, y compartimos risas y jugamos al baloncesto. Recuerdo que mi padre ten\u00eda el don de iluminar una habitaci\u00f3n con su humor, haciendo que cada momento que pas\u00e1bamos juntos fuera memorable. <\/p>\n\n<p class=\"wp-block-paragraph\">Sent\u00eda una conexi\u00f3n m\u00e1s profunda con \u00e9l que con mi madre, con quien discut\u00eda de vez en cuando. Mi hermana, en cambio, parec\u00eda m\u00e1s cercana a nuestra madre, y me molestaba cada vez que chocaba con pap\u00e1. Los recuerdos que tengo de \u00e9l son preciosos, quiz\u00e1 a\u00fan m\u00e1s por haberlo perdido tan repentinamente. Es como si mi mente se aferrara con fuerza, record\u00e1ndome: \u00abEsto es todo lo que tienes, as\u00ed que apr\u00e9cialo\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">Ten\u00eda s\u00f3lo seis a\u00f1os, chapoteaba en la piscina de la casa de mis primos en Texas cuando vi a mi abuela caminando hacia m\u00ed. Su rostro mostraba una seriedad que nunca antes hab\u00eda visto. \u00abTenemos que irnos, tu padre ha fallecido\u00bb, dijo. En ese instante, y durante todo el viaje de vuelta en avi\u00f3n, me sent\u00ed como en una pel\u00edcula. Todo a mi alrededor parec\u00eda surrealista.<\/p>\n\n<p class=\"wp-block-paragraph\">En casa de mi abuela, tengo un recuerdo v\u00edvido de estar de pie en el dormitorio, a punto de bajar las escaleras hacia el sal\u00f3n donde estaba reunida la familia, con la plena conciencia de que mi vida estaba a punto de dar un giro completo. Ten\u00eda una fuerte intuici\u00f3n. En ese momento, me dijeron que mi padre hab\u00eda sufrido un infarto. Esa historia me acompa\u00f1\u00f3 durante a\u00f1os.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-after-visiting-father-s-grave-at-16-teen-discovers-her-dad-was-murdered\"><strong>Tras visitar la tumba de su padre a los 16 a\u00f1os, una adolescente descubre que fue asesinado<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Al mes siguiente, cuando empezaron las clases, todo el mundo me preguntaba c\u00f3mo me sent\u00eda, y hoy esos recuerdos est\u00e1n te\u00f1idos por la verdad revelada m\u00e1s tarde. Me pregunto si muchos de los que me preguntaron sab\u00edan que alguien asesin\u00f3 a mi padre. No estoy segua de si pensaban que yo desconoc\u00eda los hechos o si cre\u00edan que intentaba evitar lo que hab\u00eda ocurrido. Intento hurgar en mis recuerdos en busca de reacciones o se\u00f1ales extra\u00f1as, pero no consigo encontrar ninguna.<\/p>\n\n<p class=\"wp-block-paragraph\">A los 16 a\u00f1os, visit\u00e9 el cementerio con mi familia paterna para colocar una placa en la tumba de mi padre. All\u00ed me encontr\u00e9 con mi primo Omar y me invadi\u00f3 una extra\u00f1a sensaci\u00f3n. Por primera vez, sent\u00ed que ocultaba algo, que hab\u00eda m\u00e1s en la historia de mi padre de lo que yo sab\u00eda. Parec\u00eda como si alguna fuerza intentara acercarme la verdad. No me suelen gustar las experiencias espirituales, pero aquella sensaci\u00f3n era innegable.<\/p>\n\n<p class=\"wp-block-paragraph\">En el coche, no pod\u00eda deshacerme de esta sensaci\u00f3n persistente. Me volv\u00ed hacia mi madre y le pregunt\u00e9: \u00ab\u00bfDe verdad muri\u00f3 pap\u00e1 de un infarto?\u00bb. No pudo contener las l\u00e1grimas. Confes\u00f3 que hab\u00eda sido asesinado y, sorprendentemente, mencion\u00f3 que Omar podr\u00eda haber estado all\u00ed cuando ocurri\u00f3. En ese momento, mi mundo cambi\u00f3 irreversiblemente.<\/p>\n\n<p class=\"wp-block-paragraph\">Entiendo que quisieran proteger a una ni\u00f1a de seis a\u00f1os de una realidad tan dura, pero descubrir la verdad tras diez a\u00f1os de enga\u00f1o me puso furiosa. Sent\u00ed que ten\u00eda derecho a saberlo, que podr\u00eda haberlo manejado. Si no hubiera hecho la pregunta concreta, parec\u00eda que la verdad habr\u00eda quedado enterrada para siempre.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-ohio-native-launches-podcast-dedicated-to-unraveling-father-s-unsolved-murder\"><strong>Una nativa de Ohio lanza un podcast dedicado a desentra\u00f1ar el asesinato sin resolver de su padre<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cuando \u00e9ramos peque\u00f1os, mi primo y yo \u00e9ramos muy creativos y nos embarc\u00e1bamos constantemente en proyectos como hacer v\u00eddeos, escribir guiones y dar rienda suelta a nuestra imaginaci\u00f3n con los recursos disponibles en nuestra ciudad. Cuando me fui a la universidad, mantuve vivo el esp\u00edritu creativo produciendo v\u00eddeos caseros con amigos, a menudo inyectando humor a nuestro trabajo. Sin embargo, tras conocer la verdad sobre la muerte de mi padre, mi enfoque creativo cambi\u00f3. Me pregunt\u00e9: \u00ab\u00bfC\u00f3mo puedo utilizar estas habilidades para profundizar en este caso?\u00bb. Eso me llev\u00f3 a combinar mi pasi\u00f3n por la creatividad con mi necesidad de respuestas.<\/p>\n\n<p class=\"wp-block-paragraph\">En 2020, decid\u00ed ponerme en serio a crear un podcast dedicado al caso de mi padre. Obtuve el expediente policial y profundic\u00e9 en la investigaci\u00f3n. Estaba muy nerviosa, sobre todo por compartirlo con los dem\u00e1s. Cuando por fin reun\u00ed el valor para lanzar el podcast, una parte de m\u00ed asumi\u00f3 que nadie lo escuchar\u00eda. Extra\u00f1amente, la idea de tener un p\u00fablico limitado me reconfort\u00f3.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160202.182-2-1024x768.png\" alt=\"\" class=\"wp-image-90387\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160202.182-2-1024x768.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160202.182-2-300x225.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160202.182-2-770x578.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160202.182-2-533x400.png 533w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160202.182-2.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">La joven Madison y su padre antes de su asesinato. <em><strong>| Foto cortes\u00eda de Madison McGhee<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Explorar la vida de mi padre se convirti\u00f3 en un viaje complejo. Tuve que aceptar su implicaci\u00f3n en el tr\u00e1fico de drogas y otras actividades perjudiciales. A pesar de ello, fue un gran amigo, un padre cari\u00f1oso y un vecino amable. Esta dualidad me ense\u00f1\u00f3 que la vida tiene matices, un tema que quer\u00eda destacar en mi podcast.<\/p>\n\n<p class=\"wp-block-paragraph\">La vida no es simplemente blanca o negra. Est\u00e1 lleno de matices grises. Mi padre merec\u00eda ser humanizado. Aunque no apruebo sus actos, comprendo que ten\u00eda sus razones, y aun as\u00ed merec\u00eda justicia. Trascendi\u00f3 la mera etiqueta de traficante de drogas; am\u00f3 y recibi\u00f3 amor, ayud\u00f3 a los necesitados y ofreci\u00f3 cobijo a la gente, encarnando una vida rebosante de contradicciones.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-ice-cold-case-rises-in-popularity\"><strong>La popularidad de Ice Cold Case aumenta<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Este viaje en el que tuve que lidiar con el asesinato de mi padre me ayud\u00f3 a ver a los dem\u00e1s con m\u00e1s empat\u00eda. Cuando leo una historia, me recuerdo a m\u00ed misma que la persona en cuesti\u00f3n es el t\u00edo, el padre o el hermano de alguien, y que su vida probablemente abarca m\u00e1s de lo que cuentan las noticias. Creo que la persona que mat\u00f3 a mi padre no era una buena persona, pero para alguien era importante. Alguien lo quiere y creo que eso est\u00e1 bien. El amor es la lente a trav\u00e9s de la cual vemos el mundo.<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando lanc\u00e9 el podcast, me sorprendi\u00f3 su r\u00e1pida popularidad. Gan\u00f3 tracci\u00f3n r\u00e1pidamente, lo que fue estimulante y a la vez angustioso debido al contenido personal. Como productor, me encant\u00f3 que la gente apreciara mis esfuerzos. Creo que el fin justifica los medios. Si el podcast ayuda a resolver el caso, lo har\u00eda mil veces. Incluso si no conduce a una resoluci\u00f3n, me acerca a la verdad y me ayuda a encontrar un cierre.<\/p>\n\n<p class=\"wp-block-paragraph\">El \u00e9xito de la primera temporada super\u00f3 mis expectativas. Valid\u00f3 mis habilidades y aument\u00f3 mi confianza. La conexi\u00f3n con el p\u00fablico fue tan fuerte que algunos oyentes incluso empezaron a ofrecer consejos para la investigaci\u00f3n. Era exactamente el tipo de compromiso que hab\u00eda esperado, aunque al principio parec\u00eda una posibilidad remota.<\/p>\n\n<p class=\"wp-block-paragraph\">Uno de los momentos m\u00e1s impactantes se produjo cuando Daryl Smith, el principal sospechoso del asesinato de mi padre, se puso en contacto conmigo. La ma\u00f1ana del 13 de diciembre de 2023, me despert\u00e9 con un mensaje suyo en las redes sociales. Mi coraz\u00f3n se aceler\u00f3 al darme cuenta de qui\u00e9n era. Insegura de sus intenciones, me puse r\u00e1pidamente en contacto con mi abogado, temiendo que quisiera emprender acciones legales contra m\u00ed.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-meeting-the-main-suspect-of-my-father-s-murder\"><strong>Conocer al principal sospechoso del asesinato de mi padre<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">A menudo me hab\u00eda preguntado c\u00f3mo reaccionar\u00eda si alguna vez conociera a la persona que podr\u00eda haber matado a mi padre. Cuando lleg\u00f3 el momento, mi respuesta me sorprendi\u00f3. Sent\u00ed empat\u00eda por \u00e9l, lo vi como un ser humano y realmente quise escuchar su historia. Pens\u00e9 que sus palabras podr\u00edan revelarme una parte del mundo de mi padre hasta entonces desconocida para m\u00ed. As\u00ed que acept\u00e9 reunirme con \u00e9l en Ohio.<\/p>\n\n<p class=\"wp-block-paragraph\">Nuestra conversaci\u00f3n result\u00f3 sorprendentemente amistosa y, creo, honesta. Hablamos de mi padre, de los tiempos que compartieron y de la vida en la ciudad donde viv\u00edan. Era surrealista conversar con alguien que podr\u00eda ser el asesino de mi padre. No puedo estar segura, pero es una posibilidad. Me di cuenta de que no albergo odio; simplemente busco justicia. Si Daryl fue realmente el asesino, entonces debe enfrentarse a un juicio justo y recibir una sentencia apropiada. Nada m\u00e1s. <\/p>\n\n<p class=\"wp-block-paragraph\">Mientras habl\u00e1bamos, pens\u00e9: \u00abAqu\u00ed hay una persona que parece dispuesta a ayudarme\u00bb. Hablamos durante horas, hasta las cuatro y media de la tarde, en una biblioteca p\u00fablica. Cuando por fin nos separamos, me sent\u00ed confusa y frustrada, pero de alguna manera m\u00e1s cerca de la verdad. Cuando nos levantamos para despedirnos, le pregunt\u00e9: \u00ab\u00bfEs raro que te d\u00e9 un abrazo?\u00bb. <\/p>\n\n<p class=\"wp-block-paragraph\">Se acerc\u00f3, nos abrazamos y se fue. Me sent\u00e9 en el coche, reflexion\u00e9 sobre el encuentro y tom\u00e9 notas. Me llev\u00f3 un tiempo entenderlo todo. Por un lado, sent\u00ed como si me hubiera quitado un enorme peso de encima; por otro, como si me hubiera hecho cargo de uno nuevo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-striving-to-maintain-her-role-as-producer-amidst-turmoil-experienced-as-a-daughter\"><strong>Esforz\u00e1ndose por mantener su papel de productora en medio de las turbulencias vividas como hija<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Hab\u00eda conseguido hablar con el principal sospechoso. Si no fue \u00e9l, \u00bfqui\u00e9n fue el asesino? Procesar todo y discernir si estaba diciendo la verdad o no era todo un reto. Me sent\u00e9 en silencio durante mucho tiempo, esperando a que mis pensamientos se desenredaran.<\/p>\n\n<p class=\"wp-block-paragraph\">Me enfrento a una tarea dif\u00edcil: compartimentar mis emociones y seguir adelante. A menudo me encuentro disociada, pero me esfuerzo por mantener mi papel de productora, a pesar de la agitaci\u00f3n que experimento como hija. Hay d\u00edas en los que me siento abrumada, con todas las emociones que reprim\u00ed abati\u00e9ndose de repente sobre m\u00ed. No puedo decir que mi enfoque sea del todo saludable, pero por ahora me funciona.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160022.827-1-1024x768.png\" alt=\"\" class=\"wp-image-90389\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160022.827-1-1024x768.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160022.827-1-300x225.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160022.827-1-770x578.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160022.827-1-533x400.png 533w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160022.827-1.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ice Cold Case: Investigando el asesinato de John Cornelius Mcghee. <em><strong>| Foto cortes\u00eda de Madison Mcghee<\/strong><\/em><\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Mi motivaci\u00f3n para crear este podcast no era s\u00f3lo tener una plataforma; realmente quer\u00eda resolver el caso de mi padre. Quiero descubrir la verdad sobre lo que le ocurri\u00f3. Aunque a veces me desv\u00edo, siempre vuelvo a centrarme en la investigaci\u00f3n. Este caso me ha hecho perder tiempo con amigos, otros proyectos y eventos. <\/p>\n\n<p class=\"wp-block-paragraph\">Creo que cuando cierre esta historia, podr\u00e9 dedicarme a otras cosas. Tal vez pueda ayudar a otras personas en situaciones similares, ayud\u00e1ndolas a descubrir la verdad y a encontrar un final para sus propias vidas. Quiz\u00e1 pueda prestar mis conocimientos de producci\u00f3n a quienes carecen de ellos. No estoy segura de lo que me depara el futuro, pero me siento optimista de que voy a estar bien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los momentos m\u00e1s impactantes se produjo cuando Daryl Smith, el principal sospechoso del asesinato de mi padre, se puso en contacto conmigo. La ma\u00f1ana del 13 de diciembre de 2023, me despert\u00e9 con un mensaje suyo en las redes sociales. Mi coraz\u00f3n se aceler\u00f3 al darme cuenta de qui\u00e9n era.<\/p>\n","protected":false},"author":46,"featured_media":90379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,874],"tags":[1489,3058,8572,8574,3023,8571,6186,8573],"class_list":["post-90483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-crimen-y-corrupcion-es","tag-asesino","tag-estados-unidos","tag-ice-cold-case-es","tag-madison-mcghee-es","tag-norteamerica","tag-ohio-es","tag-podcast-es","tag-podcast-sobre-delincuencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El podcast &quot;Ice Cold Case&quot; arroja luz sobre un asesinato sin resolver<\/title>\n<meta name=\"description\" content=\"El podcast &quot;Ice Cold Case&quot; arroja luz sobre un asesinato sin resolver; una hija busca justicia por la misteriosa muerte de su padre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre\" \/>\n<meta property=\"og:description\" content=\"Uno de los momentos m\u00e1s impactantes se produjo cuando Daryl Smith, el principal sospechoso del asesinato de mi padre, se puso en contacto conmigo. La ma\u00f1ana del 13 de diciembre de 2023, me despert\u00e9 con un mensaje suyo en las redes sociales. Mi coraz\u00f3n se aceler\u00f3 al darme cuenta de qui\u00e9n era.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Juan Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/\"},\"author\":{\"name\":\"Juan Martinez\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\"},\"headline\":\"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre\",\"datePublished\":\"2024-04-18T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/\"},\"wordCount\":1999,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-04-12T160032.134.png\",\"keywords\":[\"Asesino\",\"Estados Unidos\",\"Ice Cold Case\",\"Madison McGhee\",\"Norteam\u00e9rica\",\"Ohio\",\"podcast\",\"podcast sobre delincuencia\"],\"articleSection\":[\"Conflicto\",\"Crimen y corrupci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/\",\"name\":\"El podcast \\\"Ice Cold Case\\\" arroja luz sobre un asesinato sin resolver\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-04-12T160032.134.png\",\"datePublished\":\"2024-04-18T10:00:00+00:00\",\"description\":\"El podcast \\\"Ice Cold Case\\\" arroja luz sobre un asesinato sin resolver; una hija busca justicia por la misteriosa muerte de su padre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-04-12T160032.134.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Untitled-design-2024-04-12T160032.134.png\",\"width\":1280,\"height\":960,\"caption\":\"Ice Cold Case billboard showcasing the podcast's rising popularity. | Photo courtesy of Madison McGhee\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/18\\\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\",\"name\":\"Juan Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"caption\":\"Juan Martinez\"},\"description\":\"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/juan-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El podcast \"Ice Cold Case\" arroja luz sobre un asesinato sin resolver","description":"El podcast \"Ice Cold Case\" arroja luz sobre un asesinato sin resolver; una hija busca justicia por la misteriosa muerte de su padre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/","og_locale":"es_ES","og_type":"article","og_title":"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre","og_description":"Uno de los momentos m\u00e1s impactantes se produjo cuando Daryl Smith, el principal sospechoso del asesinato de mi padre, se puso en contacto conmigo. La ma\u00f1ana del 13 de diciembre de 2023, me despert\u00e9 con un mensaje suyo en las redes sociales. Mi coraz\u00f3n se aceler\u00f3 al darme cuenta de qui\u00e9n era.","og_url":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-04-18T10:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png","type":"image\/png"}],"author":"Juan Martinez","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Juan Martinez","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/"},"author":{"name":"Juan Martinez","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d"},"headline":"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre","datePublished":"2024-04-18T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/"},"wordCount":1999,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png","keywords":["Asesino","Estados Unidos","Ice Cold Case","Madison McGhee","Norteam\u00e9rica","Ohio","podcast","podcast sobre delincuencia"],"articleSection":["Conflicto","Crimen y corrupci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/","url":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/","name":"El podcast \"Ice Cold Case\" arroja luz sobre un asesinato sin resolver","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png","datePublished":"2024-04-18T10:00:00+00:00","description":"El podcast \"Ice Cold Case\" arroja luz sobre un asesinato sin resolver; una hija busca justicia por la misteriosa muerte de su padre","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png","width":1280,"height":960,"caption":"Ice Cold Case billboard showcasing the podcast's rising popularity. | Photo courtesy of Madison McGhee"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/04\/18\/podcast-de-ice-cold-case-una-hija-entrevista-al-principal-sospechoso-del-asesinato-de-su-padre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Podcast de Ice Cold Case: una hija entrevista al principal sospechoso del asesinato de su padre"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d","name":"Juan Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","url":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","caption":"Juan Martinez"},"description":"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.","url":"https:\/\/orato.world\/es\/author\/juan-martinez\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-12T160032.134-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Juan Martinez","author_link":"https:\/\/orato.world\/es\/author\/juan-martinez\/"},"uagb_comment_info":0,"uagb_excerpt":"Uno de los momentos m\u00e1s impactantes se produjo cuando Daryl Smith, el principal sospechoso del asesinato de mi padre, se puso en contacto conmigo. La ma\u00f1ana del 13 de diciembre de 2023, me despert\u00e9 con un mensaje suyo en las redes sociales. Mi coraz\u00f3n se aceler\u00f3 al darme cuenta de qui\u00e9n era.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/90483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=90483"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/90483\/revisions"}],"predecessor-version":[{"id":90484,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/90483\/revisions\/90484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/90379"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=90483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=90483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=90483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}