{"id":90942,"date":"2024-04-27T03:00:00","date_gmt":"2024-04-27T10:00:00","guid":{"rendered":"https:\/\/orato.world\/?p=90942"},"modified":"2024-04-23T13:29:19","modified_gmt":"2024-04-23T20:29:19","slug":"petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/","title":{"rendered":"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Untitled-design-2024-04-19T162931.636.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">journalist&#8217;s notes<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">interview subject<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Katiuska Camargo is a dedicated community activist and administrative professional from Caracas, Venezuela. Raised in the San Blas neighborhood, she was educated in Colombia and at a nuns&#8217; school in Guarenas, where she cultivated values like solidarity and teamwork and developed interests in music and theater. Katiuska continued her education at Sim\u00f3n Bol\u00edvar High School in Caracas but paused her studies after becoming a mother at seventeen. She later completed an administrative assistant program sponsored by Chevron of Venezuela and British Petroleum. Today, Katiuska is an active member of the<a href=\"http:\/\/www.uniendovoluntades.org\/\"> Uniendo Voluntades movement<\/a>, contributing to community revitalization projects through mural art with<a href=\"http:\/\/www.uniendovoluntades.org\/\"> Haciendo Ciudad<\/a>. Connect with her on Instagram:<a href=\"http:\/\/instagram.com\/uniendovoluntades19\"> @uniendovoluntades19<\/a>,<a href=\"http:\/\/instagram.com\/camargokgh\"> @camargokgh<\/a>.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">background context<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Art plays a crucial role in the process of democratic transition by serving as a medium for communicating ideas, feelings, and emotions, while also creating spaces for building peace. Its ability to reshape realities and integrate into social dynamics makes art a powerful tool for expressing, understanding, and redefining conflicts. It helps forge common identities and facilitates genuine social cohesion, allowing people to connect without prejudice. Particularly during times of crisis, art not only fosters historical memory and societal reconciliation but also acts as a means of symbolic reparation for victims of human rights violations. For more on the transformative power of art in society, read this detailed exploration on<a href=\"https:\/\/www.elperiodico.com\/es\/entre-todos\/participacion\/la-importancia-del-arte-como-herramienta-para-la-sociedad-191849\"> El Periodico<\/a>.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">PETARE, Venezuela &#8211; Mientras crec\u00eda en el barrio de San Blas de Petare, era habitual ver la basura amontonada en las esquinas de las casas. Los barrenderos, encargados de recoger la basura, aparec\u00edan una vez a la semana, si acaso. El abandono transform\u00f3 San Blas en un paisaje apocal\u00edptico. La basura asfixiaba nuestras calles, amonton\u00e1ndose cerca de escuelas, guarder\u00edas, hogares y comercios.<\/p>\n\n<p class=\"wp-block-paragraph\">Sin una recogida de residuos eficaz, se acumulaban monta\u00f1as de basura esparcidas por el suelo. Emit\u00eda un olor nauseabundo. El hedor putrefacto, unido a la contaminaci\u00f3n ambiental, aumentaba el riesgo de incendios y espoleaba la proliferaci\u00f3n de gusanos, moscas y otras alima\u00f1as, lo que supon\u00eda un grave peligro para nuestra comunidad. <\/p>\n\n<p class=\"wp-block-paragraph\">Hace siete a\u00f1os, mientras estaba en casa con la familia y los amigos, experiment\u00e9 un momento de claridad. \u00abVamos a retirar la basura\u00bb, anunci\u00e9. Las miradas esc\u00e9pticas de mis familiares y amigos revelaban su incredulidad. \u00abEsta basura se ha acumulado durante 40 a\u00f1os\u00bb, dijeron. \u00abEs imposible de limpiar\u00bb. Sal\u00ed, recog\u00ed la primera bolsa de basura y, al levantarla, sent\u00ed un escalofr\u00edo de transformaci\u00f3n. Sent\u00ed que era el comienzo de algo grande, aunque a\u00fan no pudiera definir de qu\u00e9 se trataba.<\/p>\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/orato.world\/es\/category\/medio-ambiente\/\"><strong>Lea m\u00e1s historias medioambientales de todo el mundo en Orato World Media.<\/strong><\/a><\/em><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-as-garbage-piles-up-crime-increases-at-15-years-old-i-witnessed-the-murder-of-my-two-cousins\"><strong>A medida que se acumula la basura, aumenta la delincuencia: \u00abA los 15 a\u00f1os presenci\u00e9 el asesinato de mis dos primos\u00bb<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Durante mi infancia, mi madre y mi abuela fueron la columna vertebral de nuestro hogar, gan\u00e1ndose la vida como amas de casa. Me ense\u00f1aron el valor de la limpieza desde muy joven. Viv\u00edamos en una casa modesta hecha de tablas de madera y s\u00e1banas, enclavada en un barrio que se debat\u00eda bajo el peso de la pobreza extrema. Lo que nos faltaba en riqueza material, lo compens\u00e1bamos con valores ricos y s\u00f3lidos.<\/p>\n\n<p class=\"wp-block-paragraph\">Mi madre pas\u00f3 43 a\u00f1os trabajando para el Sr. Dennis Schmeichler, que se convirti\u00f3 en mi mentor. Dirigi\u00f3 un importante negocio de arte en Venezuela. Gracias a su trabajo, conoc\u00ed el fascinante mundo del arte. El Sr. Schmeichler me ense\u00f1\u00f3 una lecci\u00f3n vital: nunca dejes que nadie te menosprecie por haber crecido en un barrio pobre.<\/p>\n\n<p class=\"wp-block-paragraph\">En algunas zonas de San Blas, los residuos s\u00f3lo dejaban estrechos canales por los que pod\u00edan pasar los veh\u00edculos, obligando a todos a sortear la inmundicia. La gente rebuscaba en la basura, buscando objetos para comer o vender. La desesperaci\u00f3n desemboc\u00f3 en refriegas. Mientras tanto, el agua se acumulaba en los baches, agravando el problema. <\/p>\n\n<p class=\"wp-block-paragraph\">Luch\u00e1bamos contra la falta de servicios esenciales, como la electricidad, y la amenaza constante de la inseguridad se cern\u00eda sobre nosotros. Cada d\u00eda parec\u00eda una lucha por sobrevivir. A los 15 a\u00f1os presenci\u00e9 el asesinato de mis dos primos. Ver c\u00f3mo sus vidas terminaban abruptamente era horrible. Ver c\u00f3mo sus vidas terminaban abruptamente era horrible.<\/p>\n\n<p class=\"wp-block-paragraph\">La tragedia me toc\u00f3 m\u00e1s de cerca cuando mi t\u00edo, que era como un padre para m\u00ed, fue asesinado por lo poco que ten\u00eda en su poder. Lo mataron mientras trabajaba de taxista, dejando su cuerpo tirado en la acera hasta que fuimos a recuperarlo.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-residents-angry-about-the-cleanup-tried-to-burn-down-her-house\"><strong>Los vecinos, enfadados por la limpieza, intentaron quemar su casa<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cuando empec\u00e9 mi proyecto de limpieza, una a una, la gente empez\u00f3 a unirse a m\u00ed. Me emocion\u00f3 ver crecer nuestro n\u00famero mientras intercambi\u00e1bamos sonrisas y compart\u00edamos risas. La limpieza no hizo m\u00e1s que avivar nuestra emoci\u00f3n. Tardamos un a\u00f1o, pero limpiamos la primera zona y desde entonces, cada ma\u00f1ana, junto a mi familia y amigos, vigilaba ese lugar. Nos aseguramos de que nadie arrojara all\u00ed basura nueva, explicando la importancia de mantener limpia la zona e indicando a la gente las zonas designadas para depositarla.<\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, la retirada de la basura provoc\u00f3 una fuerte reacci\u00f3n entre algunos vecinos. Sin embargo, la retirada de la basura provoc\u00f3 una fuerte reacci\u00f3n entre algunos vecinos. Apagamos las llamas con la ayuda de los vecinos que nos arrojaron agua. Apagamos las llamas con la ayuda de los vecinos que nos arrojaron agua. Despu\u00e9s de apagar las llamas, con l\u00e1grimas en los ojos, me sent\u00e9 con mi madre en la puerta. Pregunt\u00e9: \u00ab\u00bfSeguimos con lo que empezamos?\u00bb. Me cogi\u00f3 la cara con las manos, me mir\u00f3 a los ojos y me dijo: \u00abAunque tengamos miedo, tenemos que seguir adelante. Este camino es el correcto\u00bb. <\/p>\n\n<p class=\"wp-block-paragraph\">Cog\u00ed sus manos, asent\u00ed y sent\u00ed que me invad\u00eda una oleada de fuerza. En ese momento, supe que nada podr\u00eda detenernos. Nuestro proyecto evolucion\u00f3 hasta incluir la pintura de murales, dando vida vibrante a calles que antes estaban llenas de basura y paredes desangeladas. Ahora se nos acercan personas de todas las edades para sugerirnos qu\u00e9 paredes necesitan un toque de color. Nos invitan a iluminar callejones, y de repente parece que todo el mundo se da la mano. Me propuse recuperar y transformar al menos 15 espacios p\u00fablicos de nuestro barrio. Recogimos basura y barrimos con escobas hechas de envases de pl\u00e1stico reciclados. Se nos unieron j\u00f3venes curiosos y entusiastas, deseosos de participar en el cambio.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-neighborhood-became-a-vibrant-and-clean-canvas\"><strong>El barrio se convirti\u00f3 en un lienzo vibrante y limpio<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">A medida que recog\u00edamos la basura, la transformaci\u00f3n de nuestra comunidad se hac\u00eda visible y m\u00e1s vecinos se implicaban. Motivados por las mejoras, empezamos a arreglar las calles y, poco a poco, nuestro entorno fue cambiando. Poco a poco, la escoba se convirti\u00f3 en un s\u00edmbolo de nuestra iniciativa, atrayendo a m\u00e1s y m\u00e1s j\u00f3venes a unirse al proyecto. Predicamos con el ejemplo, ense\u00f1ando la importancia de mantener limpios los entornos vitales y los espacios comunes. Mostramos c\u00f3mo deshacerse de la basura correctamente e inspiramos a ni\u00f1os y j\u00f3venes para que participaran en las labores de limpieza de la comunidad.<\/p>\n\n<p class=\"wp-block-paragraph\">La primera vez que decidimos pintar, ten\u00edamos poca experiencia, pero nos hac\u00eda ilusi\u00f3n. Las calles estaban despejadas y mi primo y yo, armados con botes de pintura de colores y pinceles, nos dispusimos a dar vida a la pared de una esquina desangelada. Imagin\u00e1bamos que abr\u00edamos una nueva puerta. Dudamos en pintar los trazos iniciales, pero pronto florecieron en vibrantes flores y la frase \u00abParada el triunfo\u00bb.<\/p>\n\n<p class=\"wp-block-paragraph\">La transformaci\u00f3n fue tan llamativa que los autobuses se detuvieron en esa esquina, un lugar que antes pasaban de largo. Pronto conect\u00e9 con algunos muralistas y fundamos el colectivo de artistas Haciendo Ciudad. Esta colaboraci\u00f3n llev\u00f3 nuestra transformaci\u00f3n al siguiente nivel. El movimiento cobr\u00f3 impulso, atrayendo cada vez a m\u00e1s participantes. Las calles de nuestro barrio se convirtieron en un lienzo vibrante. Los ni\u00f1os se pasaban pinceles y pinturas, retocando meticulosamente los bordes y rellenando las l\u00edneas. Los adultos tambi\u00e9n contribuyeron, repartiendo caf\u00e9 y compartiendo pan para garantizar la participaci\u00f3n de todos: pintores, ayudantes, repartidores y curiosos.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-garbage-cleanup-and-community-transformation-ignite-a-youth-movement\"><strong>La limpieza de basuras y la transformaci\u00f3n de la comunidad encienden un movimiento juvenil<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cuando los conductores redujeron la velocidad para ver las obras, nuestras calles revitalizadas se convirtieron en una exposici\u00f3n comunitaria en movimiento. Nuestros esfuerzos desembocaron finalmente en la formaci\u00f3n de una organizaci\u00f3n llamada \u00abUniendo Voluntades\u00bb. Las calles se convirtieron en el centro de proyectos art\u00edsticos como Comparte el Mundo, orquestado por el artista internacional Dudu, que brind\u00f3 a la juventud local la oportunidad de aprender el arte del muralismo. Observ\u00e9 c\u00f3mo un joven, anteriormente perdido por la adicci\u00f3n, dirig\u00eda un proyecto de murales. Se me llenaron los ojos de l\u00e1grimas al verle pintar, pincel en mano, con una sonrisa que se dibujaba en su rostro. Fue transformado por el prop\u00f3sito. Pronto, el arte se convirti\u00f3 en un punto de inflexi\u00f3n para los j\u00f3venes delincuentes. <\/p>\n\n<p class=\"wp-block-paragraph\">Me encontr\u00e9 con otro joven llamado Esteban Ruiz en una esquina del barrio. A pesar de sus excepcionales dotes para el dibujo y el arte, Esteben dudaba de s\u00ed mismo. Sin apoyo familiar, luch\u00f3 contra la baja autoestima y la vulnerabilidad. Gracias a nuestro apoyo colectivo, empez\u00f3 a ver oportunidades. La belleza y la complejidad de los dibujos de Esteban me asombraron. Admir\u00e9 en silencio su trabajo y elogi\u00e9 su talento. Cuando le pregunt\u00e9 por sus artistas favoritos, nombr\u00f3 a gente que eran amigos m\u00edos, as\u00ed que se lo present\u00e9. Me dio las gracias con una t\u00edmida sonrisa. Hoy, Esteban trabaja junto a Dagor, un muralista de renombre, y va camino de convertirse en uno de los artistas m\u00e1s destacados del pa\u00eds.<\/p>\n\n<p class=\"wp-block-paragraph\">Jhon Dani Salazar represent\u00f3 otra transformaci\u00f3n inspiradora. Jhon naveg\u00f3 por el \u00e1spero terreno de nuestro barrio, creciendo en un hogar disfuncional y violento. Nuestro movimiento le dio nuevas aspiraciones. Hoy es estudiante, rapero y activista medioambiental. Aqu\u00ed, los j\u00f3venes descubren cada d\u00eda la esperanza. Escuchan a su coraz\u00f3n y sue\u00f1an. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-today-the-neighborhood-of-san-blas-is-lit-up-with-community-spirit\"><strong>Hoy, el barrio de San Blas se ilumina de esp\u00edritu comunitario<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Este trabajo, que abarca varios a\u00f1os, puede medirse en colores. Cientos de murales decoran ahora fachadas, escuelas, calles y callejones. En San Blas, medimos el tiempo por la determinaci\u00f3n de la gente, movilizada y unida. Pasamos de la anarqu\u00eda a una vida limpia y armoniosa. Nuestro proyecto m\u00e1s reciente -transformar un solar abandonado y un vertedero en un centro de actividades sociales y culturales- dar\u00e1 a la comunidad un vibrante espacio para eventos. Servir\u00e1 de faro para el activismo, el arte y la comunidad. Para financiarlo, transformamos 41 escobas en obras de arte, s\u00edmbolo de la determinaci\u00f3n de nuestra comunidad. Los expusimos en la galer\u00eda de arte que creamos en casa de mam\u00e1.<\/p>\n\n<p class=\"wp-block-paragraph\">Cuando salgo a la calle y veo a los j\u00f3venes barriendo las calles con sus peque\u00f1as escobas y bolsas, me recorre una emoci\u00f3n. Siento una energ\u00eda indescriptible en mi cuerpo. \u00abActiva el poder de la escoba\u00bb, gritan. Hago una pausa, miro a mi alrededor y me doy cuenta de que lo estamos consiguiendo. Ahora llegan de visita personas que nunca hab\u00edan venido a San Blas. Llegan representantes de la comunidad, deseosos de reproducir nuestra transformaci\u00f3n all\u00ed donde viven. <\/p>\n\n<p class=\"wp-block-paragraph\">Los j\u00f3venes se han convertido en nuestros embajadores, difundiendo nuestra causa por los municipios. Cada mural terminado desata alegr\u00eda, amor y celebraci\u00f3n. Nos deleitamos con la pincelada final, estallando en aplausos, v\u00edtores y risas. Hoy, todo el barrio est\u00e1 iluminado, iluminado por nuestro esp\u00edritu colectivo.<\/p>\n\n<p class=\"wp-block-paragraph\"><em><strong>Todas las fotos son cortes\u00eda de Adrian Naranjo.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin una recogida de residuos eficaz, se acumulaban monta\u00f1as de basura esparcidas por el suelo. Emit\u00eda un olor nauseabundo. El hedor putrefacto, unido a la contaminaci\u00f3n ambiental, aumentaba el riesgo de incendios y espoleaba la proliferaci\u00f3n de gusanos, moscas y otras alima\u00f1as, lo que supon\u00eda un grave peligro para nuestra comunidad. <\/p>\n","protected":false},"author":28,"featured_media":90786,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[725,319],"tags":[8644,8648,2214,7684,8646,4824,8645,197,8647],"class_list":["post-90942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-medio-ambiente","tag-artistas-es","tag-contaminacion-por-residuos","tag-latinoamerica","tag-limpieza","tag-limpieza-comunitaria","tag-murales","tag-petare-es","tag-venezuela-es","tag-vertedero-comunitario"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La comunidad de Petare se une para convertir en arte un vertedero de d\u00e9cadas de antig\u00fcedad<\/title>\n<meta name=\"description\" content=\"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales\" \/>\n<meta property=\"og:description\" content=\"Sin una recogida de residuos eficaz, se acumulaban monta\u00f1as de basura esparcidas por el suelo. Emit\u00eda un olor nauseabundo. El hedor putrefacto, unido a la contaminaci\u00f3n ambiental, aumentaba el riesgo de incendios y espoleaba la proliferaci\u00f3n de gusanos, moscas y otras alima\u00f1as, lo que supon\u00eda un grave peligro para nuestra comunidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-27T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/1-7.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mariela Laksman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariela Laksman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/\"},\"author\":{\"name\":\"Mariela Laksman\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\"},\"headline\":\"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales\",\"datePublished\":\"2024-04-27T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/\"},\"wordCount\":1805,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/1-7.png\",\"keywords\":[\"artistas\",\"contaminaci\u00f3n por residuos\",\"Latinoam\u00e9rica\",\"Limpieza\",\"limpieza comunitaria\",\"Murales\",\"Petare\",\"Venezuela\",\"vertedero comunitario\"],\"articleSection\":[\"Educaci\u00f3n\",\"Medio ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/\",\"name\":\"La comunidad de Petare se une para convertir en arte un vertedero de d\u00e9cadas de antig\u00fcedad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/1-7.png\",\"datePublished\":\"2024-04-27T10:00:00+00:00\",\"description\":\"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/1-7.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/1-7.png\",\"width\":1280,\"height\":960,\"caption\":\"Urban art in San Blas, Patare transformed a once disheveled community into a hub of color and activism. | Photo courtesy of Adrian Naranjo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/04\\\/27\\\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\",\"name\":\"Mariela Laksman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariela Laksman\"},\"description\":\"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \\\"Nuevo Sudaca Border\\\" with the microfiction book \\\"Un Tigre con la Boca Abierta\\\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariela-laksman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La comunidad de Petare se une para convertir en arte un vertedero de d\u00e9cadas de antig\u00fcedad","description":"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/","og_locale":"es_ES","og_type":"article","og_title":"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales","og_description":"Sin una recogida de residuos eficaz, se acumulaban monta\u00f1as de basura esparcidas por el suelo. Emit\u00eda un olor nauseabundo. El hedor putrefacto, unido a la contaminaci\u00f3n ambiental, aumentaba el riesgo de incendios y espoleaba la proliferaci\u00f3n de gusanos, moscas y otras alima\u00f1as, lo que supon\u00eda un grave peligro para nuestra comunidad.","og_url":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-04-27T10:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/1-7.png","type":"image\/png"}],"author":"Mariela Laksman","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariela Laksman","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/"},"author":{"name":"Mariela Laksman","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90"},"headline":"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales","datePublished":"2024-04-27T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/"},"wordCount":1805,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/1-7.png","keywords":["artistas","contaminaci\u00f3n por residuos","Latinoam\u00e9rica","Limpieza","limpieza comunitaria","Murales","Petare","Venezuela","vertedero comunitario"],"articleSection":["Educaci\u00f3n","Medio ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/","url":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/","name":"La comunidad de Petare se une para convertir en arte un vertedero de d\u00e9cadas de antig\u00fcedad","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/1-7.png","datePublished":"2024-04-27T10:00:00+00:00","description":"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/1-7.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/1-7.png","width":1280,"height":960,"caption":"Urban art in San Blas, Patare transformed a once disheveled community into a hub of color and activism. | Photo courtesy of Adrian Naranjo"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/04\/27\/petare-renace-la-comunidad-se-une-para-transformar-un-vertedero-de-decadas-en-una-ciudad-vibrante-de-calles-limpias-y-murales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Petare renace: la comunidad se une para transformar un vertedero de d\u00e9cadas en una ciudad vibrante de calles limpias y murales"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90","name":"Mariela Laksman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariela Laksman"},"description":"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \"Nuevo Sudaca Border\" with the microfiction book \"Un Tigre con la Boca Abierta\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.","url":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/1-7.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/1-7-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/1-7-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/1-7-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/1-7-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/1-7.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/1-7.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/1-7-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/1-7-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/1-7.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/1-7.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/1-7.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/1-7-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Mariela Laksman","author_link":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"},"uagb_comment_info":0,"uagb_excerpt":"Sin una recogida de residuos eficaz, se acumulaban monta\u00f1as de basura esparcidas por el suelo. Emit\u00eda un olor nauseabundo. El hedor putrefacto, unido a la contaminaci\u00f3n ambiental, aumentaba el riesgo de incendios y espoleaba la proliferaci\u00f3n de gusanos, moscas y otras alima\u00f1as, lo que supon\u00eda un grave peligro para nuestra comunidad.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/90942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=90942"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/90942\/revisions"}],"predecessor-version":[{"id":90943,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/90942\/revisions\/90943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/90786"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=90942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=90942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=90942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}