{"id":91241,"date":"2024-05-01T03:00:00","date_gmt":"2024-05-01T10:00:00","guid":{"rendered":"https:\/\/orato.world\/?p=91241"},"modified":"2024-04-28T12:41:22","modified_gmt":"2024-04-28T19:41:22","slug":"un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/","title":{"rendered":"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Elton Takunda Kasawala is a student in Zimbabwe who contracted cholera during the 2023-2024 outbreak. | Photo courtesy of Elton Takunda Kasawala\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-400x400.jpg 400w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/IMG-20231109-WA0022.jpg 573w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">jOURNALIST&#8217;S nOTES<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">iNTERVIEW sUBJECT<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Elton Takunda Kasawala studies at Eden University in Lusaka Zambia. He suffered a bout of diarrhea and vomiting before he was taken to Matero Hospital where they confirmed he had cholera. He was later transferred to the Heroes stadium, normally a venue for soccer matches, where he went into quarantine. He stayed there for two weeks consuming only milk, bananas, and water before he recovered.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">bACKGROUND iNFORMATION<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">The cholera outbreak in Zambia, which was first reported in October 2023 in the peri-urban areas of the Lusaka Province, quickly spread throughout the country. All ten provinces in Zambia have now been affected. Since the onset of the current outbreak, the country has reported a total of 14,900 suspected cholera cases and 560 cholera-related deaths of January 26, 2024. Lusaka continues to represent the most affected province, reporting 89 percent of all suspected cholera cases and 90 of deaths. The most affected age group are those between 25 and 35 years of age. This public health emergency is not restricted to Zambia, as many countries throughout Africa have reported an increase in cholera cases. Since January 2023, approximately 188,000 cholera cases have been reported in eight countries in Southern Africa including six countries with current active outbreaks: Democratic Republic of Congo, Malawi, Mozambique, Tanzania, Zambia and Zimbabwe. Find more information at the <a href=\"https:\/\/www.choleraalliance.org\/fr\" target=\"_blank\" rel=\"noreferrer noopener\">Global Alliance Against Cholera and Other Water Bourne Illnesses.<\/a><\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">BALASTONE PARK, Zambia \ua7f7 Cuando empec\u00e9 a o\u00edr hablar de casos de c\u00f3lera en mi pa\u00eds, no comprend\u00ed que nos enfrent\u00e1bamos a un brote. Recuerdo perfectamente que pensaba que los anuncios de mi barrio y mi colegio eran de ignorantes. No tem\u00eda que mi compa\u00f1ero de piso y yo, con el que compart\u00eda habitaci\u00f3n, nos vi\u00e9ramos afectados.<\/p>\n\n<p class=\"wp-block-paragraph\">Durante ese tiempo, el c\u00f3lera se extendi\u00f3 por la mayor\u00eda de las provincias de Zambia, incluidas Kangwe y Kitwe. Segu\u00edamos creyendo que el brote se detendr\u00eda all\u00ed, acabando en los lugares m\u00e1s afectados. Beb\u00eda agua sin filtrar sin preocupaciones, tomando agua directamente del tanque en lugar de la opci\u00f3n clorada. Entonces, un d\u00eda, me despert\u00e9 mareado y con fuertes dolores de est\u00f3mago, y empec\u00e9 a vomitar.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>Lea m\u00e1s art\u00edculos de las categor\u00edas <a href=\"https:\/\/orato.world\/es\/category\/virus\/\">Virus<\/a> y <a href=\"https:\/\/orato.world\/es\/category\/salud\/\">Salud<\/a> en Orato World Media.<\/em><\/strong><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-after-waking-up-sick-student-ends-up-in-a-makeshift-treatment-arena-in-the-midst-of-the-cholera-outbreak\"><strong>Tras despertarse enfermo, un estudiante acaba en una arena de tratamiento improvisada en pleno brote de c\u00f3lera<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">El d\u00eda que me levant\u00e9 enfermo, sent\u00ed dolor en todo el cuerpo. Mi compa\u00f1ero de piso me miraba mientras luchaba por levantarme de la cama y dirigirme al ba\u00f1o. Despu\u00e9s de vomitar, volv\u00ed a la habitaci\u00f3n y le dije a mi compa\u00f1era que ten\u00eda que ir al hospital. Sent\u00eda que estaba al borde de la muerte. Sin mis padres cerca, mi compa\u00f1ero de piso era la \u00fanica persona que ten\u00eda de casa, y necesitaba ayuda.<\/p>\n\n<p class=\"wp-block-paragraph\">Antes de llevarme al hospital, mi compa\u00f1ero de piso llam\u00f3 a mis padres para informarles de lo mal que me encontraba. Mientras nos dirig\u00edamos al hospital de nivel uno de Matero, en el distrito de Lusaka, empec\u00e9 a echar de menos mi hogar como nunca. No hab\u00eda pegado ojo, esperando el amanecer para pedir ayuda. Cuando llegamos al hospital de Matero, o\u00ed el sonido constante de las sirenas de las ambulancias. They brought in a steady stream of patients and took others away to bury them after succumbing to the virus.<\/p>\n\n<p class=\"wp-block-paragraph\">De repente, la realidad me golpe\u00f3 de lleno y me di cuenta de la ignorancia con la que actu\u00e9, tom\u00e1ndome la vida por mi mano. Pens\u00e9 en el dicho: la ignorancia es un enemigo, incluso para su due\u00f1o. El personal del hospital me atendi\u00f3 inmediatamente y me ingres\u00f3. M\u00e1s tarde, me trasladaron al Estadio de los H\u00e9roes Nacionales [<em>estadio polivalente de Lusaka que acoge partidos de f\u00fatbol y es la sede de la selecci\u00f3n nacional de f\u00fatbol de Zambia. El estadio, inaugurado en 2014, tiene capacidad para 60.000 espectadores<\/em>.] Las autoridades transformaron el Estadio de los H\u00e9roes Nacionales en un enorme centro de tratamiento con unos 800 profesionales m\u00e9dicos atendiendo a pacientes de todo el pa\u00eds.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-a-classmate-dies-of-cholera-but-young-man-makes-it-through-outbreak-grateful-to-god-and-the-nurses\"><strong>Un compa\u00f1ero de clase muere de c\u00f3lera, pero el joven supera el brote: agradecido a Dios y a las enfermeras<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En el estadio, los visitantes se reunieron m\u00e1s all\u00e1 de la barrera met\u00e1lica a la espera de cualquier posible noticia de sus seres queridos. La \u00fanica persona a la que se le permit\u00eda entrar y visitarme era mi compa\u00f1ero de piso. Peri\u00f3dicamente, el equipo del estadio pasaba lista de los nombres para asegurar a la multitud congregada fuera de la barrera que su ser querido infectado segu\u00eda vivo.<\/p>\n\n<p class=\"wp-block-paragraph\">No permit\u00edan la entrada de alimentos del exterior al estadio y sobrevivimos a base de pl\u00e1tanos, leche y agua. Sin mis padres cerca, me result\u00f3 incre\u00edblemente dif\u00edcil soportar mi enfermedad y la cuarentena. S\u00f3lo hab\u00eda pasado un a\u00f1o desde que empec\u00e9 a estudiar en Zambia, y segu\u00eda enfrent\u00e1ndome a la barrera del idioma, lo que dificultaba especialmente la comunicaci\u00f3n con los m\u00e9dicos. Gracias a Dios por mi compa\u00f1ero de piso, que me ayud\u00f3 durante todo el calvario.<\/p>\n\n<p class=\"wp-block-paragraph\">Cada vez que ven\u00eda a visitarme y ve\u00eda su cara, surg\u00eda en m\u00ed un sentimiento de esperanza. Sufri\u00f3 s\u00edntomas leves de infecci\u00f3n de c\u00f3lera, pero recibi\u00f3 una vacuna inmediata y evolucion\u00f3 bien. Estando en un estado tan terrible, me sent\u00eda constantemente agradecido a las enfermeras que me atend\u00edan.<\/p>\n\n<p class=\"wp-block-paragraph\">Mi miedo aument\u00f3 moment\u00e1neamente cuando mi compa\u00f1era de piso me dijo que un compa\u00f1ero de colegio hab\u00eda sucumbido a la enfermedad. Me pareci\u00f3 surrealista. Pas\u00e9 dos largas semanas en el Estadio de los H\u00e9roes Nacionales, enfrent\u00e1ndome a un dif\u00edcil proceso de curaci\u00f3n, pero mi voluntad de mejorar se mantuvo firme. Tomando mi medicaci\u00f3n cinco veces al d\u00eda, acabamos con el virus. Cuando por fin me recuper\u00e9, me dirig\u00ed a casa muy p\u00e1lido, pero sinti\u00e9ndome mejor. Ahora, simplemente doy gracias a Dios por mantenerme con vida.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>[El brote de c\u00f3lera en Zambia comenz\u00f3 alrededor de octubre de 2023 y, seg\u00fan la <a href=\"https:\/\/www.afro.who.int\/sites\/default\/files\/2024-01\/Donor_Alert_Zambia_January_2024_final.pdf\">Organizaci\u00f3n Mundial de la Salud<\/a>, se convirti\u00f3 r\u00e1pidamente en una emergencia de salud p\u00fablica cr\u00edtica, que afect\u00f3 a miles de personas en pr\u00e1cticamente todas las provincias y provoc\u00f3 cientos de muertes].<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando llegamos al hospital de Matero, o\u00ed el sonido constante de las sirenas de las ambulancias. Tra\u00edan un flujo constante de pacientes y se llevaban a otros para enterrarlos tras sucumbir al virus.<\/p>\n","protected":false},"author":218,"featured_media":90986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[188,190],"tags":[613,8715,8714,8712,8713,8711],"class_list":["post-91241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","category-virus","tag-africa-es","tag-brote","tag-colera","tag-crisis-de-salud-publica","tag-organizacion-mundial-de-salud","tag-zambia-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera<\/title>\n<meta name=\"description\" content=\"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera: narra el duro camino hacia la recuperaci\u00f3n en un estadio de f\u00fatbol convertido en centro de tratamiento\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento\" \/>\n<meta property=\"og:description\" content=\"Cuando llegamos al hospital de Matero, o\u00ed el sonido constante de las sirenas de las ambulancias. Tra\u00edan un flujo constante de pacientes y se llevaban a otros para enterrarlos tras sucumbir al virus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pepertua Rojasi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pepertua Rojasi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/\"},\"author\":{\"name\":\"Pepertua Rojasi\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/c4de24790680d47419660f26c6689cef\"},\"headline\":\"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento\",\"datePublished\":\"2024-05-01T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/\"},\"wordCount\":888,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20240422-WA0003.jpg\",\"keywords\":[\"Africa\",\"Brote\",\"C\u00f3lera\",\"Crisis de Salud P\u00fablica\",\"Organizaci\u00f3n Mundial de Salud\",\"Zambia\"],\"articleSection\":[\"Salud\",\"Virus\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/\",\"name\":\"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20240422-WA0003.jpg\",\"datePublished\":\"2024-05-01T10:00:00+00:00\",\"description\":\"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera: narra el duro camino hacia la recuperaci\u00f3n en un estadio de f\u00fatbol convertido en centro de tratamiento\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20240422-WA0003.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/IMG-20240422-WA0003.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Dirty areas like this, in Barlestone, Zambia, proliferate the spread of Cholera which leads to outbreaks. | Photo courtesy of Pepertua Rojasi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/05\\\/01\\\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/c4de24790680d47419660f26c6689cef\",\"name\":\"Pepertua Rojasi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Pepertua Rojasi\"},\"description\":\"Pepertua Rojasi is a broadcast journalist. She works as a producer and a reporter at a state-owned media house in Zimbabwe. In addition to written journalism, Pepertua is a passionate photographer and enjoys creating documentaries.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/pepertua-rojasi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera","description":"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera: narra el duro camino hacia la recuperaci\u00f3n en un estadio de f\u00fatbol convertido en centro de tratamiento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/","og_locale":"es_ES","og_type":"article","og_title":"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento","og_description":"Cuando llegamos al hospital de Matero, o\u00ed el sonido constante de las sirenas de las ambulancias. Tra\u00edan un flujo constante de pacientes y se llevaban a otros para enterrarlos tras sucumbir al virus.","og_url":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-05-01T10:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg","type":"image\/jpeg"}],"author":"Pepertua Rojasi","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Pepertua Rojasi","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/"},"author":{"name":"Pepertua Rojasi","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/c4de24790680d47419660f26c6689cef"},"headline":"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento","datePublished":"2024-05-01T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/"},"wordCount":888,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg","keywords":["Africa","Brote","C\u00f3lera","Crisis de Salud P\u00fablica","Organizaci\u00f3n Mundial de Salud","Zambia"],"articleSection":["Salud","Virus"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/","url":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/","name":"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg","datePublished":"2024-05-01T10:00:00+00:00","description":"Un estudiante de Zambia ignora las advertencias y contrae el c\u00f3lera: narra el duro camino hacia la recuperaci\u00f3n en un estadio de f\u00fatbol convertido en centro de tratamiento","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg","width":1280,"height":960,"caption":"Dirty areas like this, in Barlestone, Zambia, proliferate the spread of Cholera which leads to outbreaks. | Photo courtesy of Pepertua Rojasi"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/05\/01\/un-estudiante-de-zambia-enferma-de-colera-y-es-enviado-a-un-estadio-de-futbol-convertido-en-centro-de-tratamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Un estudiante de Zambia enferma de c\u00f3lera y es enviado a un estadio de f\u00fatbol convertido en centro de tratamiento"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/c4de24790680d47419660f26c6689cef","name":"Pepertua Rojasi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Pepertua Rojasi"},"description":"Pepertua Rojasi is a broadcast journalist. She works as a producer and a reporter at a state-owned media house in Zimbabwe. In addition to written journalism, Pepertua is a passionate photographer and enjoys creating documentaries.","url":"https:\/\/orato.world\/es\/author\/pepertua-rojasi\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/IMG-20240422-WA0003-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Pepertua Rojasi","author_link":"https:\/\/orato.world\/es\/author\/pepertua-rojasi\/"},"uagb_comment_info":0,"uagb_excerpt":"Cuando llegamos al hospital de Matero, o\u00ed el sonido constante de las sirenas de las ambulancias. Tra\u00edan un flujo constante de pacientes y se llevaban a otros para enterrarlos tras sucumbir al virus.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/91241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/218"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=91241"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/91241\/revisions"}],"predecessor-version":[{"id":91242,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/91241\/revisions\/91242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/90986"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=91241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=91241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=91241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}