{"id":93628,"date":"2024-06-30T02:14:47","date_gmt":"2024-06-30T09:14:47","guid":{"rendered":"https:\/\/orato.world\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/"},"modified":"2024-07-02T14:38:23","modified_gmt":"2024-07-02T21:38:23","slug":"explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/","title":{"rendered":"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente"},"content":{"rendered":"\n<div class=\"wp-block-uagb-blockquote uagb-block-48f9a0a2 uagb-blockquote__skin-border uagb-blockquote__with-tweet uagb-blockquote__tweet-style-classic uagb-blockquote__tweet-icon_text uagb-blockquote__stack-img-none\"><blockquote class=\"uagb-blockquote\"><div class=\"uagb-blockquote__content\"><em>Este art\u00edculo de opini\u00f3n<\/em> forma parte de una serie <em>que hace foco en arrojar luz sobre cuestiones mundiales cr\u00edticas que exigen atenci\u00f3n urgente y abordan un espectro de retos que nos afectan a todos, haciendo hincapi\u00e9 en la necesidad de acci\u00f3n y apoyo colectivos. Al fomentar la concienciaci\u00f3n y alentar la colaboraci\u00f3n, el escritor espera inspirar un cambio positivo y contribuir a un mundo m\u00e1s compasivo y equitativo a medida que cubrimos la multitud de temas que afectan a nuestra comunidad global.<\/em><\/div><footer><div class=\"uagb-blockquote__author-wrap uagb-blockquote__author-at-left\"><cite class=\"uagb-blockquote__author\"><strong>Si desea m\u00e1s informaci\u00f3n sobre la <a href=\"https:\/\/orato.world\/es\/category\/op-ed-guest-posts-es\/\">Secci\u00f3n de Opini\u00f3n de Orato World Media<\/a> o contribuir con un art\u00edculo invitado, p\u00f3ngase en contacto con editor@orato.world.<\/strong><\/cite><\/div><a href=\"\/\" class=\"uagb-blockquote__tweet-button\" target=\"_blank\" rel=\"noopener noreferrer\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 512 512\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>Tweet<\/a><\/footer><\/blockquote><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">El asesinato de Om Fahd, influencer iraqu\u00ed en las redes sociales, a las puertas de su casa en Bagdad, conmocion\u00f3 a la naci\u00f3n y provoc\u00f3 una oleada de condena en todo el mundo. Su vibrante presencia en las redes sociales y sus risas resonantes en TikTok fueron silenciadas por las crueles manos de la violencia. Om Fahd fue asesinada a tiros frente a su casa el 26 de abril de 2024. Le arrebataron la vida en un momento de brutalidad sin sentido.<\/p>\n\n<p class=\"wp-block-paragraph\">Tr\u00e1gicamente, la persecuci\u00f3n de Om Fahd continu\u00f3 incluso despu\u00e9s de su muerte. Alguien filtr\u00f3 sus fotos desnuda de la morgue, llevando el caso por un camino mucho m\u00e1s oscuro. Un acto tan despreciable no s\u00f3lo agrava la tragedia, sino que atenta contra la dignidad y los derechos de los fallecidos. Publicar esas im\u00e1genes se convierte en una forma de profanaci\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">[Om Fahd ten\u00eda casi 84.000 seguidores en <a href=\"https:\/\/www.tiktok.com\/discover\/om-fahad-official\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok<\/a> y algunos de sus v\u00eddeos cosecharon millones de visitas].<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-was-om-fahd-s-crime\"><strong>\u00bfCu\u00e1l fue el delito de Om Fahd?<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">El pasado mes de abril, Om Fahd, de 30 a\u00f1os, cuyo verdadero nombre era <a href=\"https:\/\/www.bbc.com\/news\/world-middle-east-68910812\" target=\"_blank\" rel=\"noreferrer noopener\">Ghufran Mahdi Sawadi, muri\u00f3 tiroteada dentro de su coche cerca de su casa, en el centro de Bagdad.<\/a> El asesino desconocido le dispar\u00f3 desde el asiento de una motocicleta. La de Om es la historia de una madre que dej\u00f3 hijos peque\u00f1os. Unos salvajes profanaron su tumba bailando sobre ella y burl\u00e1ndose.<\/p>\n\n<p class=\"wp-block-paragraph\">El camino de Om Fahd estuvo marcado por las dificultades, pero \u00bfcu\u00e1l fue su delito? Om se limitaba a expresarse, bailando al ritmo de la m\u00fasica iraqu\u00ed y vistiendo ropas que la hac\u00edan sentirse segura de s\u00ed misma. Por ello, sufri\u00f3 persecuci\u00f3n, encarcelamiento y, en \u00faltima instancia, un tr\u00e1gico final a manos de un agresor desconocido.<\/p>\n\n<p class=\"wp-block-paragraph\">En febrero de 2023, un tribunal iraqu\u00ed conden\u00f3 a <a href=\"https:\/\/www.france24.com\/en\/live-news\/20230216-tiktokers-jailed-as-iraq-targets-decadent-content\" target=\"_blank\" rel=\"noreferrer noopener\">Om Fahd a seis meses de prisi\u00f3n.<\/a> Los cargos inclu\u00edan \u00abpublicar varias pel\u00edculas y v\u00eddeos con declaraciones obscenas y prendas que atentan contra el pudor y la moral p\u00fablica y exhibirlos al p\u00fablico a trav\u00e9s de las redes sociales\u00bb. No sabemos espec\u00edficamente qu\u00e9 constituye una vestimenta modesta en el mundo \u00e1rabe. Tampoco sabemos por qu\u00e9 las autoridades exigen un c\u00f3digo de vestimenta s\u00f3lo a las mujeres.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/orato.world\/wp-content\/uploads\/&#x623;&#x645;-&#x641;&#x647;&#x62F;.jpg\" alt=\"\" class=\"wp-image-93369\"\/><figcaption class=\"wp-element-caption\">Foto de perfil de Om Fahd en sus cuentas p\u00fablicas de las redes sociales.<\/figcaption><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Las opiniones var\u00edan de una clase social y un grupo religioso a otro. El Ministerio del Interior iraqu\u00ed anunci\u00f3 previamente la formaci\u00f3n de un comit\u00e9 para vigilar los \u00abcontenidos obscenos e insultantes\u00bb en las redes sociales. Dicen que algunos de estos contenidos \u00abofenden el gusto del p\u00fablico y violan la moral y las tradiciones\u00bb de la sociedad iraqu\u00ed, mayoritariamente conservadora.<\/p>\n\n<p class=\"wp-block-paragraph\">El gobierno cre\u00f3 una plataforma para que los internautas denunciaran este tipo de publicaciones. Como consecuencia, activistas de las redes sociales han sido condenados a prisi\u00f3n u obligados a disculparse por los contenidos que publicaban en l\u00ednea, que a veces no eran m\u00e1s que v\u00eddeos humor\u00edsticos o sat\u00edricos.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/news.sky.com\/video\/iraqi-social-media-influencer-om-fahad-shot-dead-by-motorbike-gunman-13124659\" target=\"_blank\" rel=\"noreferrer noopener\">Om Fahd <\/a> ha sido s\u00f3lo el \u00faltimo de una serie de asesinatos de personalidades influyentes en las redes sociales en Irak. La lista incluye muchos nombres, como <a href=\"https:\/\/www.bbc.co.uk\/news\/resources\/idt-sh\/tara_fares\" target=\"_blank\" rel=\"noreferrer noopener\">Tara Fares, <\/a> <a href=\"https:\/\/www.memri.org\/reports\/iraqi-writers-respond-to-murders-of-iraqi-women\" target=\"_blank\" rel=\"noreferrer noopener\">Rafif Al-Yasiri,<\/a> <a href=\"https:\/\/english.alarabiya.net\/variety\/2018\/08\/24\/After-death-of-Iraq-s-Barbie-another-beautician-dies-in-mysterious-circumstances\" target=\"_blank\" rel=\"noreferrer noopener\">Rasha Al-Hassan,<\/a> <a href=\"https:\/\/www.cnn.com\/2023\/09\/27\/middleeast\/iraq-lgbtq-shot-intl\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">Noor BM<\/a> y <a href=\"https:\/\/ekurd.net\/young-kurdish-woman-shot-2024-04-18\" target=\"_blank\" rel=\"noreferrer noopener\">Fayrouz Azad<\/a>.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-publishing-photos-of-om-fahd-s-dead-naked-body-set-a-dangerous-precedent\"><strong>La publicaci\u00f3n de fotos del cad\u00e1ver desnudo de Om Fahd sienta un peligroso precedente<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Para Om Fahd y su familia, la explotaci\u00f3n de su imagen tiene amplias implicaciones sociales. Sienta un peligroso precedente que amenaza los derechos y la dignidad de todas las personas. En particular, amenaza a los marginados y vulnerables. Al aprobar este comportamiento, corremos el riesgo de normalizar una cultura de explotaci\u00f3n y voyeurismo. En esta cultura, la privacidad ya no importa, y hacemos caso omiso del consentimiento.<\/p>\n\n<p class=\"wp-block-paragraph\">Filtrar fotos de Om Fahd desnuda tras su asesinato no s\u00f3lo viola su intimidad. Viola su propia esencia, causando a su alma heridas inconmensurables. Tambi\u00e9n crea un profundo dolor que se suma a la ya insoportable carga que soportan su familia y sus seres queridos.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@omfaahad\/video\/7330005856676875526\" data-video-id=\"7330005856676875526\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@omfaahad\" href=\"https:\/\/www.tiktok.com\/@omfaahad?refer=embed\">@omfaahad<\/a> <p>\u0645\u0634\u062a\u0627\u0642\u064a\u0644\u064a \u0644\u0648 \u0644\u0627 <a title=\"\u0627\u0645_\u0641\u0647\u062f\ud83d\udc06\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/%D8%A7%D9%85_%D9%81%D9%87%D8%AF%F0%9F%90%86?refer=embed\">#\u0627\u0645_\u0641\u0647\u062f\ud83d\udc06<\/a> <\/p> <a target=\"_blank\" title=\"\u266c \u0627\u0644\u0635\u0648\u062a \u0627\u0644\u0623\u0635\u0644\u064a - \u0627\u0645 \u0641\u0647\u062f - OmFahad\" href=\"https:\/\/www.tiktok.com\/music\/\u0627\u0644\u0635\u0648\u062a-\u0627\u0644\u0623\u0635\u0644\u064a-7330005877013138182?refer=embed\">\u266c \u0627\u0644\u0635\u0648\u062a \u0627\u0644\u0623\u0635\u0644\u064a &#8211; \u0627\u0645 \u0641\u0647\u062f &#8211; OmFahad<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Sorprendentemente, las cosas fueron a\u00fan m\u00e1s lejos. La gente iba a su tumba despu\u00e9s del entierro para bailar sobre ella y burlarse. Esta mujer no ten\u00eda forma de defenderse. Mientras la opini\u00f3n p\u00fablica llora la p\u00e9rdida de Om Fahd, nosotros nos solidarizamos con ella, su familia y sus seres queridos. Debemos reafirmar nuestro compromiso de defender los derechos y la dignidad de todas las personas, tanto en la vida como en la muerte.<\/p>\n\n<p class=\"wp-block-paragraph\">Condenemos este deplorable acto en los t\u00e9rminos m\u00e1s en\u00e9rgicos posibles y esforc\u00e9monos por crear una sociedad en la que este tipo de violaciones no s\u00f3lo se denuncien, sino que se prevengan mediante s\u00f3lidas medidas de salvaguarda y rendici\u00f3n de cuentas. Tambi\u00e9n debemos condenar en los t\u00e9rminos m\u00e1s en\u00e9rgicos la explotaci\u00f3n y degradaci\u00f3n de su memoria. Toda persona, independientemente de sus elecciones o creencias, merece dignidad y respeto en la vida y en la muerte.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-om-fahd-serves-as-a-siren-call-for-the-relentless-pursuit-of-freedom-from-oppression\"><strong>Om Fahd sirve de canto de sirena para la b\u00fasqueda incesante de la libertad frente a la opresi\u00f3n<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La historia de Om Fahd se convierte en una aleccionadora llamada de atenci\u00f3n. Pone de relieve los arraigados problemas de opresi\u00f3n sist\u00e9mica que afectan a algunas sociedades conservadoras. Su caso es un poderoso recordatorio de la urgente necesidad de afrontar y abordar de frente estos problemas fundamentales, en lugar de permitir que persistan sin control.<\/p>\n\n<p class=\"wp-block-paragraph\">Esta preocupante situaci\u00f3n subraya la importancia de la vigilancia, la defensa y el compromiso constante para lograr cambios significativos y garantizar la justicia para todos. La historia de Om subraya la necesidad de una mayor responsabilidad y supervisi\u00f3n, especialmente en las instituciones a las que se conf\u00eda el manejo de informaci\u00f3n sensible.<\/p>\n\n<p class=\"wp-block-paragraph\">La publicaci\u00f3n no autorizada de sus fotos de la morgue plantea serias dudas sobre la integridad del sistema sanitario y las medidas establecidas para proteger la intimidad de los fallecidos. Si los profesionales o miembros del personal m\u00e9dico participaron en la difusi\u00f3n de estas im\u00e1genes, deber\u00e1n afrontar graves consecuencias. Violaron la confianza y las normas \u00e9ticas que se esperan de su profesi\u00f3n.<\/p>\n\n<p class=\"wp-block-paragraph\">Es imperativo que las autoridades les exijan responsabilidades por sus actos y tomen medidas para evitar que se produzcan incidentes similares. Puede que la historia de Om Fahd acabara en tragedia, pero su legado sirve de s\u00edmbolo de resistencia, valor y b\u00fasqueda incesante de la libertad. Que descanse en paz y que su alma baile eternamente entre las estrellas.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Om Fahd y su familia, la explotaci\u00f3n de su imagen tiene amplias implicaciones sociales. Sienta un peligroso precedente que amenaza los derechos y la dignidad de todas las personas. En particular, amenaza a los marginados y vulnerables. Al aprobar este comportamiento, corremos el riesgo de normalizar una cultura de explotaci\u00f3n y voyeurismo. En esta cultura, la privacidad ya no importa, y hacemos caso omiso del consentimiento.<\/p>\n","protected":false},"author":205,"featured_media":93375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[874,6175,261],"tags":[1489,9056],"class_list":["post-93628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crimen-y-corrupcion-es","category-op-ed-guest-posts-es","category-sexo-y-genero","tag-asesino","tag-om-fahd-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Se filtran fotos de Om Fahd desnuda en las redes sociales<\/title>\n<meta name=\"description\" content=\"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente\" \/>\n<meta property=\"og:description\" content=\"Para Om Fahd y su familia, la explotaci\u00f3n de su imagen tiene amplias implicaciones sociales. Sienta un peligroso precedente que amenaza los derechos y la dignidad de todas las personas. En particular, amenaza a los marginados y vulnerables. Al aprobar este comportamiento, corremos el riesgo de normalizar una cultura de explotaci\u00f3n y voyeurismo. En esta cultura, la privacidad ya no importa, y hacemos caso omiso del consentimiento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-30T09:14:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T21:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mahasen Hawary\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mahasen Hawary\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/\"},\"author\":{\"name\":\"Mahasen Hawary\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/735a4bf50677849a5f8a14d7902dc170\"},\"headline\":\"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente\",\"datePublished\":\"2024-06-30T09:14:47+00:00\",\"dateModified\":\"2024-07-02T21:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/\"},\"wordCount\":1268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg\",\"keywords\":[\"Asesino\",\"Om Fahd\"],\"articleSection\":[\"Crimen y corrupci\u00f3n\",\"Op-Ed &amp; Guest Posts\",\"Sexo y g\u00e9nero\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/\",\"name\":\"Se filtran fotos de Om Fahd desnuda en las redes sociales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg\",\"datePublished\":\"2024-06-30T09:14:47+00:00\",\"dateModified\":\"2024-07-02T21:38:23+00:00\",\"description\":\"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg\",\"width\":1280,\"height\":960,\"caption\":\"After being murdered, social media influencer Om Fahd's nudge photos from the morgue were leaked publicly. | Morgue photo by Sharon Lawsona courtesy of Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/06\\\/30\\\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/735a4bf50677849a5f8a14d7902dc170\",\"name\":\"Mahasen Hawary\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mahasen Hawary\"},\"description\":\"Mahasen Elhawary\u00a0is an Egyptian seasoned professional in mass communication and journalism, based in London, United Kingdom. With over a decade of experience, Mahasen has contributed significantly to the field, specializing in journalism, translation, and social media. Her career journey has seen her work as a Senior Journalist at Akhbar El Yom Foundation, where she covered international film festivals, interviewed movie stars and filmmakers, and offered valuable insights as a movie critic. Mahasen's expertise extends to content creation, investigative reporting, and documentary production. She is also a skilled translator, having translated news, articles, and current affairs from international press for Alakhbar daily newspaper.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mahasen-hawary\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Se filtran fotos de Om Fahd desnuda en las redes sociales","description":"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/","og_locale":"es_ES","og_type":"article","og_title":"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente","og_description":"Para Om Fahd y su familia, la explotaci\u00f3n de su imagen tiene amplias implicaciones sociales. Sienta un peligroso precedente que amenaza los derechos y la dignidad de todas las personas. En particular, amenaza a los marginados y vulnerables. Al aprobar este comportamiento, corremos el riesgo de normalizar una cultura de explotaci\u00f3n y voyeurismo. En esta cultura, la privacidad ya no importa, y hacemos caso omiso del consentimiento.","og_url":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-06-30T09:14:47+00:00","article_modified_time":"2024-07-02T21:38:23+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg","type":"image\/jpeg"}],"author":"Mahasen Hawary","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mahasen Hawary","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/"},"author":{"name":"Mahasen Hawary","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/735a4bf50677849a5f8a14d7902dc170"},"headline":"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente","datePublished":"2024-06-30T09:14:47+00:00","dateModified":"2024-07-02T21:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/"},"wordCount":1268,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg","keywords":["Asesino","Om Fahd"],"articleSection":["Crimen y corrupci\u00f3n","Op-Ed &amp; Guest Posts","Sexo y g\u00e9nero"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/","url":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/","name":"Se filtran fotos de Om Fahd desnuda en las redes sociales","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg","datePublished":"2024-06-30T09:14:47+00:00","dateModified":"2024-07-02T21:38:23+00:00","description":"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg","width":1280,"height":960,"caption":"After being murdered, social media influencer Om Fahd's nudge photos from the morgue were leaked publicly. | Morgue photo by Sharon Lawsona courtesy of Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/06\/30\/explotacion-de-los-vulnerables-incluso-en-la-muerte-las-fotos-de-om-fahd-desnuda-sientan-un-peligroso-precedente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Explotaci\u00f3n de los vulnerables, incluso en la muerte: las fotos de Om Fahd desnuda sientan un peligroso precedente"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/735a4bf50677849a5f8a14d7902dc170","name":"Mahasen Hawary","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mahasen Hawary"},"description":"Mahasen Elhawary\u00a0is an Egyptian seasoned professional in mass communication and journalism, based in London, United Kingdom. With over a decade of experience, Mahasen has contributed significantly to the field, specializing in journalism, translation, and social media. Her career journey has seen her work as a Senior Journalist at Akhbar El Yom Foundation, where she covered international film festivals, interviewed movie stars and filmmakers, and offered valuable insights as a movie critic. Mahasen's expertise extends to content creation, investigative reporting, and documentary production. She is also a skilled translator, having translated news, articles, and current affairs from international press for Alakhbar daily newspaper.","url":"https:\/\/orato.world\/es\/author\/mahasen-hawary\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Morgue_Photo-by-Sharon-Lawsona-courtesy-of-Unsplash-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Mahasen Hawary","author_link":"https:\/\/orato.world\/es\/author\/mahasen-hawary\/"},"uagb_comment_info":0,"uagb_excerpt":"Para Om Fahd y su familia, la explotaci\u00f3n de su imagen tiene amplias implicaciones sociales. Sienta un peligroso precedente que amenaza los derechos y la dignidad de todas las personas. En particular, amenaza a los marginados y vulnerables. Al aprobar este comportamiento, corremos el riesgo de normalizar una cultura de explotaci\u00f3n y voyeurismo. En esta&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/93628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/205"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=93628"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/93628\/revisions"}],"predecessor-version":[{"id":93629,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/93628\/revisions\/93629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/93375"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=93628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=93628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=93628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}