{"id":94389,"date":"2024-07-08T03:00:00","date_gmt":"2024-07-08T10:00:00","guid":{"rendered":"https:\/\/orato.world\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/"},"modified":"2024-07-19T18:15:48","modified_gmt":"2024-07-20T01:15:48","slug":"cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/","title":{"rendered":"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \u00abagentes extranjeros\u00bb en medio de la represi\u00f3n policial"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Vache demonstrating on Rustaveli Avenue, Tbilisi, Georgia.\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-770x770.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-400x400.jpg 400w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/Georgia-protest-1.jpg 960w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">NOTAS DEL PERIODISTA<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">PROTAGONISTA<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Vache Nikolaishvili es una estudiante de pol\u00edtica de Tiflis (Georgia). Desempe\u00f1\u00f3 un papel fundamental en la organizaci\u00f3n y participaci\u00f3n en las protestas contra la Ley de Agentes Extranjeros. Junto con sus amigos, Vache experiment\u00f3 en carne propia la agresi\u00f3n de la polic\u00eda antidisturbios y las fuerzas especiales desplegadas para reprimir sus manifestaciones pac\u00edficas en la avenida Rustaveli. A pesar de la resistencia, Vache se mantuvo firme en su compromiso con la protesta pac\u00edfica y la defensa de los derechos de los georgianos.<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">CONTEXTO<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">En Georgia, el Parlamento ha aprobado un pol\u00e9mico proyecto de ley sobre \u00abagentes extranjeros\u00bb que ha desencadenado protestas generalizadas en la capital, Tiflis. El proyecto de ley, aprobado con el voto a favor de 84 de los 150 diputados, exige que las organizaciones no gubernamentales y los medios de comunicaci\u00f3n que reciban m\u00e1s del 20% de su financiaci\u00f3n de fuera de Georgia se registren como entidades que \u00ab<a href=\"https:\/\/edition.cnn.com\/2024\/05\/14\/europe\/georgia-foreign-agents-bill-passed-intl\/index.html\">persiguen los intereses de una potencia extranjera\u00bb.<\/a> La ley es similar a la ley rusa sobre agentes extranjeros, y muchos georgianos temen que afecte a su intento de ingresar en la Uni\u00f3n Europea. Esto ha llevado a miles de personas a salir a la calle para oponerse a la ley y expresar su deseo de ver a Georgia alineada con Europa.<\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">TBILISI, Georgia &#8211; Cuando el gobierno anunci\u00f3 la Ley de <a href=\"https:\/\/www.hrw.org\/news\/2023\/03\/07\/georgia-foreign-agents-bill-tramples-rights?gad_source=1&amp;gclid=Cj0KCQjw7ZO0BhDYARIsAFttkCgvbHMswRianCwZsOvwyATsxYWvIfJnciB45bNF8uzETO8746_OlGcaAuN-EALw_wcB\">Agentes Extranjeros en Georgia,<\/a> mis amigos, compa\u00f1eros de estudios y yo nos unimos a las manifestaciones. Intentamos transmitir a Europa y al mundo que somos georgianos; nuestro futuro est\u00e1 en la <a href=\"https:\/\/www.politico.eu\/article\/georgia-foreign-agent-bill-becomes-law-international-outcry-european-union\/\">Uni\u00f3n Europea.<\/a> Organizamos una manifestaci\u00f3n pac\u00edfica en la avenida Rustaveli de Tiflis, donde se reunieron 200.000 personas para expresar la voluntad del pueblo.<\/p>\n\n<p class=\"wp-block-paragraph\">A pesar de nuestro n\u00famero y de nuestros apasionados gritos de libertad, pronto sentimos la fuerza opresiva del gobierno. Desplegaron polic\u00edas antidisturbios y fuerzas especiales para silenciarnos. Frente a nosotros, eran imbatibles. Utilizando ca\u00f1ones de agua, gases lacrim\u00f3genos y detenciones al azar, reprimieron nuestra expresi\u00f3n pac\u00edfica. El uso injusto del poder contra manifestantes pac\u00edficos cre\u00f3 un desequilibrio que nos dej\u00f3 impotentes, enfadados y frustrados.<\/p>\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/orato.world\/es\/category\/conflicto\/\">Lea m\u00e1s historias de conflictos en Orato World Media.<\/a><\/em><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-protesters-in-tbilisi-devise-strategies-to-resist-and-escape-police-oppression\"><strong>Los manifestantes de Tiflis<\/strong> <strong>dise\u00f1an estrategias para resistir y escapar de la opresi\u00f3n policial<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La avenida Rustaveli se encuentra en el coraz\u00f3n de la ciudad de Tiflis. Se extiende a lo largo de m\u00e1s de un kil\u00f3metro, con caf\u00e9s, galer\u00edas, museos y edificios gubernamentales. Lleva a la Plaza de la Libertad, que conecta con el cercano Puente de la Paz. Con las manifestaciones que all\u00ed se celebraban, me sent\u00ed obligado a participar. El lugar resonaba profundamente con los ideales de libertad y paz.<\/p>\n\n<p class=\"wp-block-paragraph\">El primer d\u00eda de la protesta, mis amigos y yo alzamos nuestras voces: una generaci\u00f3n unida colectivamente. Nos presentamos sin estar preparados, pero decididos a ser el coraz\u00f3n del movimiento y a predicar con el ejemplo. Afirmamos que esta legislaci\u00f3n alinea peligrosamente a <a href=\"https:\/\/www.martenscentre.eu\/blog\/georgias-foreign-agent-law-a-russian-strategy-unfolding-across-eurasia\/\">Georgia con Rusia, <\/a> una postura inaceptable para un pa\u00eds libre y democr\u00e1tico. <\/p>\n\n<p class=\"wp-block-paragraph\">Los manifestantes tambi\u00e9n reconocen el papel crucial del patrocinio de Europa y Estados Unidos en el desarrollo de nuestro pa\u00eds. La Ley de Agentes Extranjeros contradice a nuestra propia naci\u00f3n. Socava nuestro progreso y pone en peligro nuestras aspiraciones de ingresar en la Uni\u00f3n Europea en el futuro.<\/p>\n\n<p class=\"wp-block-paragraph\">En la protesta, carec\u00edamos de suministros y ropa adecuados, y nos enfrent\u00e1bamos a una larga jornada de pie que pas\u00f3 factura a nuestros cuerpos. Mientras la multitud se agolpaba en la avenida, nosotros ocup\u00e1bamos la calzada, gritando \u00ablibertad\u00bb y \u00abesclavo\u00bb cada vez que presenci\u00e1bamos acciones agresivas de las fuerzas policiales.<\/p>\n\n<p class=\"wp-block-paragraph\">Conscientes de la tensi\u00f3n que sufr\u00edan nuestras voces, ideamos un paquete inicial con silbatos. Estos silbatos nos serv\u00edan de voz cuando las palabras fallaban, expresando nuestra voluntad inquebrantable y nuestro desaf\u00edo frente a la intimidaci\u00f3n. Tambi\u00e9n llev\u00e1bamos mascarillas m\u00e9dicas KN-95 para proteger nuestra capacidad respiratoria. Esto era esencial porque la polic\u00eda utiliz\u00f3 gases contra los manifestantes. Mantener una visi\u00f3n clara era crucial, por lo que llev\u00e1bamos gafas para contrarrestar los efectos del gas. Descubrimos que caminar r\u00e1pido, en lugar de correr, era la mejor estrategia para escapar del gas, ya que correr consum\u00eda m\u00e1s ox\u00edgeno.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-police-tactics-escalates-and-protesters-seek-emergency-aid\"><strong>Se recrudecen las t\u00e1cticas policiales y los manifestantes solicitan ayuda urgente<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">A medida que avanzaban los d\u00edas, los manifestantes se trasladaron a distintos puntos de la avenida Rustaveli. Pasaron por teatros, por el edificio del Parlamento e incluso llegaron a la Plaza de la Libertad. <a href=\"https:\/\/www.aljazeera.com\/news\/2024\/7\/1\/angered-by-georgias-foreign-agent-law-gen-x-protesters-try-new-tactic\">Nuestro objetivo era captar la atenci\u00f3n del mundo <\/a> y difundir nuestra oposici\u00f3n a esta ley injusta. Simult\u00e1neamente, <a href=\"https:\/\/www.nbcnews.com\/news\/world\/georgia-tbilisi-protests-violence-foreign-agents-bill-russia-inspired-rcna150164\"> la polic\u00eda intensific\u00f3 su agresi\u00f3n.<\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Mis amigos y yo est\u00e1bamos juntos, manifest\u00e1ndonos pac\u00edficamente, cuando estall\u00f3 un momento de tensi\u00f3n. Un polic\u00eda intent\u00f3 detener por la fuerza a uno de nosotros. Sent\u00ed la frustraci\u00f3n surgir dentro de m\u00ed. De repente, la polic\u00eda dispar\u00f3 un proyectil de gas que cay\u00f3 justo delante de m\u00ed. Ya era de noche y la oscuridad se apoder\u00f3 de Tiflis. Tembl\u00e9 al ver c\u00f3mo el proyectil liberaba gases. En ese momento, reconoc\u00ed las limitaciones de los esfuerzos individuales y que el verdadero cambio requiere una acci\u00f3n colectiva.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"93579\" src=\"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-2-768x1024.jpg\" alt=\"\" class=\"wp-image-93579\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-2-768x1024.jpg 768w, https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-2-225x300.jpg 225w, https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-2-770x1027.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-2-300x400.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-2.jpg 843w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"751\" data-id=\"93583\" src=\"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-3-edited.jpg\" alt=\"\" class=\"wp-image-93583\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-3-edited.jpg 501w, https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-3-edited-200x300.jpg 200w, https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-3-edited-267x400.jpg 267w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Vache lleva una m\u00e1scara para respirar y protegerse en medio de los ataques con gases lacrim\u00f3genos de la polic\u00eda antidisturbios durante la manifestaci\u00f3n en Tiflis. <strong>| Foto cortes\u00eda de Vache Nikolaishvilli<\/strong><\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">En cuesti\u00f3n de segundos, una enorme nube de humo nos envolvi\u00f3. Gui\u00e9 instintivamente a los que me rodeaban, inst\u00e1ndoles a moverse sin p\u00e1nico. Sent\u00ed que un liderazgo tranquilo era importante en medio del caos. La nube de gas me ceg\u00f3, ahog\u00f3 mi respiraci\u00f3n y alter\u00f3 mis sentidos. Desesperado, segu\u00ed una d\u00e9bil luz al final de la avenida Rustaveli, que result\u00f3 ser un veh\u00edculo de emergencia. <\/p>\n\n<p class=\"wp-block-paragraph\">All\u00ed encontr\u00e9 a mi amigo Luca, que me alivi\u00f3 d\u00e1ndome leche para los ojos, calmando los efectos del gas t\u00f3xico. Al igual que despu\u00e9s de una comida picante, la leche se sinti\u00f3 como un alivio para mi visi\u00f3n ardiente. Tard\u00e9 varios minutos en calmarme. Cuando recuper\u00e9 la visi\u00f3n y se me despejaron los pulmones, me reincorpor\u00e9 a la manifestaci\u00f3n. El pueblo mostr\u00f3 una fuerza de voluntad inquebrantable, y yo me propuse demostrar la misma fuerza que ellos. Nadie nos pag\u00f3 por estar all\u00ed. Consideramos que las manifestaciones son una necesidad imperiosa para impedir que esta ley afecte al futuro de Georgia.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-georgians-struggles-for-the-possibility-of-eu-integration\"><strong>La lucha de los georgianos por la posibilidad de integrarse en la UE<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Llevamos semanas manifest\u00e1ndonos por las calles de Tiflis. La Presidenta Salome Zourabichvili hizo uso de su poder presidencial para vetar la ley de influencia extranjera. Por desgracia, nuestra esperanza de revertir la ley se desvaneci\u00f3 cuando el <a href=\"https:\/\/www.bbc.com\/news\/articles\/cxrre3qy2n4o\">Parlamento anul\u00f3 el veto.<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">Aunque la presidenta apoy\u00f3 al pueblo de Georgia, su influencia revel\u00f3 limitaciones. En \u00faltima instancia, el Parlamento ostenta el poder, y se inclina por una alineaci\u00f3n m\u00e1s estrecha con Rusia. Ya sab\u00eda que el Parlamento seguir\u00eda adelante con la ley, y me entristece profundamente.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-video aligncenter\"><video height=\"480\" style=\"aspect-ratio: 272 \/ 480;\" width=\"272\" controls=\"\" src=\"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-1.qt\"><\/video><figcaption class=\"wp-element-caption\">Im\u00e1genes de la represi\u00f3n policial de las protestas estudiantiles en Tiflis. <strong>| V\u00eddeo cortes\u00eda de Vache Nikolaishvilli<\/strong> <\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">En mi opini\u00f3n, la persistencia sigue siendo la clave del progreso. No debemos cesar en nuestras manifestaciones. El gobierno tiene que entender que no daremos marcha atr\u00e1s. Exigimos formar parte de la Uni\u00f3n Europea. <\/p>\n\n<p class=\"wp-block-paragraph\">Tanto las generaciones mayores como los j\u00f3venes deben alzar la voz porque juntos simbolizamos la unidad y la fuerza. Seguir\u00e9 al lado de las masas, demostrando nuestro deseo de un futuro alineado con la UE, no con Rusia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cuesti\u00f3n de segundos, una enorme nube de humo nos envolvi\u00f3. Gui\u00e9 instintivamente a los que me rodeaban, inst\u00e1ndoles a moverse sin p\u00e1nico&#8230; La nube de gas me ceg\u00f3, ahog\u00f3 mi respiraci\u00f3n y alter\u00f3 mis sentidos. <\/p>\n","protected":false},"author":221,"featured_media":93578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[260,874],"tags":[3498,6418,3060,8602,2672,934,9123,9122,8603,4019],"class_list":["post-94389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-crimen-y-corrupcion-es","tag-asia-es","tag-enfrentamiento-policial","tag-europa","tag-georgia-es","tag-protesta-es-2","tag-protesta-estudiantil","tag-proyecto-de-ley-sobre-agentes-extranjeros","tag-rustaveli-avenue-es","tag-tbilisi-es","tag-union-europea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Estudiantes georgianos se unen a las protestas contra el proyecto de ley de &quot;agentes extranjeros<\/title>\n<meta name=\"description\" content=\"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de &quot;agentes extranjeros&quot;, en medio de la represi\u00f3n policial en Tiflis por la integraci\u00f3n europea.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de &quot;agentes extranjeros&quot; en medio de la represi\u00f3n policial\" \/>\n<meta property=\"og:description\" content=\"En cuesti\u00f3n de segundos, una enorme nube de humo nos envolvi\u00f3. Gui\u00e9 instintivamente a los que me rodeaban, inst\u00e1ndoles a moverse sin p\u00e1nico... La nube de gas me ceg\u00f3, ahog\u00f3 mi respiraci\u00f3n y alter\u00f3 mis sentidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-20T01:15:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manus Boyle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manus Boyle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/\"},\"author\":{\"name\":\"Manus Boyle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/6ad93d30357d8926dade5d74d5f841a5\"},\"headline\":\"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \u00abagentes extranjeros\u00bb en medio de la represi\u00f3n policial\",\"datePublished\":\"2024-07-08T10:00:00+00:00\",\"dateModified\":\"2024-07-20T01:15:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/\"},\"wordCount\":1119,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/foreign-agents-bill-1.jpg\",\"keywords\":[\"Asia\",\"enfrentamiento policial\",\"Europa\",\"Georgia\",\"Protesta\",\"Protesta estudiantil\",\"Proyecto de ley sobre agentes extranjeros\",\"Rustaveli Avenue\",\"Tbilisi\",\"Uni\u00f3n Europea\"],\"articleSection\":[\"Conflicto\",\"Crimen y corrupci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/\",\"name\":\"Estudiantes georgianos se unen a las protestas contra el proyecto de ley de \\\"agentes extranjeros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/foreign-agents-bill-1.jpg\",\"datePublished\":\"2024-07-08T10:00:00+00:00\",\"dateModified\":\"2024-07-20T01:15:48+00:00\",\"description\":\"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \\\"agentes extranjeros\\\", en medio de la represi\u00f3n policial en Tiflis por la integraci\u00f3n europea.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/foreign-agents-bill-1.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/foreign-agents-bill-1.jpg\",\"width\":1280,\"height\":960,\"caption\":\"Vache Nikolaishvili, pictured on the right, demonstrating on Rustaveli Avenue in Tbilisi against the Foreign Agents Bill, while the riot police stand behind. | Photo courtesy of Vache Nikolaishvili\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/07\\\/08\\\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \u00abagentes extranjeros\u00bb en medio de la represi\u00f3n policial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/6ad93d30357d8926dade5d74d5f841a5\",\"name\":\"Manus Boyle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Manus Boyle\"},\"description\":\"Manus Boyle is a multimedia journalist based in Dublin, Ireland. He holds a double honors degree in English and History and a Master of Arts degree in Journalism from Dublin City University. With a passion for world news, environmental issues, and a perspective shaped by living in the Middle East, he brings cross-cultural awareness and unique experience to the field. He has reported on national and global environmental issues and has interviewed government officials, international ambassadors, and members of the European Parliament on a range of societal and global issues.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/manus-boyle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Estudiantes georgianos se unen a las protestas contra el proyecto de ley de \"agentes extranjeros","description":"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \"agentes extranjeros\", en medio de la represi\u00f3n policial en Tiflis por la integraci\u00f3n europea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \"agentes extranjeros\" en medio de la represi\u00f3n policial","og_description":"En cuesti\u00f3n de segundos, una enorme nube de humo nos envolvi\u00f3. Gui\u00e9 instintivamente a los que me rodeaban, inst\u00e1ndoles a moverse sin p\u00e1nico... La nube de gas me ceg\u00f3, ahog\u00f3 mi respiraci\u00f3n y alter\u00f3 mis sentidos.","og_url":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-07-08T10:00:00+00:00","article_modified_time":"2024-07-20T01:15:48+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg","type":"image\/jpeg"}],"author":"Manus Boyle","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Manus Boyle","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/"},"author":{"name":"Manus Boyle","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/6ad93d30357d8926dade5d74d5f841a5"},"headline":"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \u00abagentes extranjeros\u00bb en medio de la represi\u00f3n policial","datePublished":"2024-07-08T10:00:00+00:00","dateModified":"2024-07-20T01:15:48+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/"},"wordCount":1119,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg","keywords":["Asia","enfrentamiento policial","Europa","Georgia","Protesta","Protesta estudiantil","Proyecto de ley sobre agentes extranjeros","Rustaveli Avenue","Tbilisi","Uni\u00f3n Europea"],"articleSection":["Conflicto","Crimen y corrupci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/","url":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/","name":"Estudiantes georgianos se unen a las protestas contra el proyecto de ley de \"agentes extranjeros","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg","datePublished":"2024-07-08T10:00:00+00:00","dateModified":"2024-07-20T01:15:48+00:00","description":"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \"agentes extranjeros\", en medio de la represi\u00f3n policial en Tiflis por la integraci\u00f3n europea.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg","width":1280,"height":960,"caption":"Vache Nikolaishvili, pictured on the right, demonstrating on Rustaveli Avenue in Tbilisi against the Foreign Agents Bill, while the riot police stand behind. | Photo courtesy of Vache Nikolaishvili"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/07\/08\/cientos-de-estudiantes-georgianos-se-unen-a-las-protestas-contra-el-proyecto-de-ley-de-agentes-extranjeros-en-medio-de-la-represion-policial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Cientos de estudiantes georgianos se unen a las protestas contra el proyecto de ley de \u00abagentes extranjeros\u00bb en medio de la represi\u00f3n policial"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/6ad93d30357d8926dade5d74d5f841a5","name":"Manus Boyle","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Manus Boyle"},"description":"Manus Boyle is a multimedia journalist based in Dublin, Ireland. He holds a double honors degree in English and History and a Master of Arts degree in Journalism from Dublin City University. With a passion for world news, environmental issues, and a perspective shaped by living in the Middle East, he brings cross-cultural awareness and unique experience to the field. He has reported on national and global environmental issues and has interviewed government officials, international ambassadors, and members of the European Parliament on a range of societal and global issues.","url":"https:\/\/orato.world\/es\/author\/manus-boyle\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/foreign-agents-bill-1-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Manus Boyle","author_link":"https:\/\/orato.world\/es\/author\/manus-boyle\/"},"uagb_comment_info":0,"uagb_excerpt":"En cuesti\u00f3n de segundos, una enorme nube de humo nos envolvi\u00f3. Gui\u00e9 instintivamente a los que me rodeaban, inst\u00e1ndoles a moverse sin p\u00e1nico... La nube de gas me ceg\u00f3, ahog\u00f3 mi respiraci\u00f3n y alter\u00f3 mis sentidos.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/94389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/221"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=94389"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/94389\/revisions"}],"predecessor-version":[{"id":94390,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/94389\/revisions\/94390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/93578"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=94389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=94389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=94389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}