{"id":96409,"date":"2024-08-30T01:49:50","date_gmt":"2024-08-30T08:49:50","guid":{"rendered":"https:\/\/orato.world\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/"},"modified":"2024-09-04T12:28:56","modified_gmt":"2024-09-04T19:28:56","slug":"una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/","title":{"rendered":"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Chloe-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Chloe-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Chloe-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Chloe.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">notas del periodista<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Chloe Ward, 23 a\u00f1os, de Royston, Hertfordshire, ha vivido en Ema\u00fas Norfolk  Waveney durante dos a\u00f1os mientras superaba su adicci\u00f3n al alcohol, que comenz\u00f3 a los 11 a\u00f1os. Est\u00e1 participando en \u00abThe Walk of Kindness Challenge\u00bb, una caminata desde St. David, Gales, hasta Ditchingham, Reino Unido, para concienciar sobre la recuperaci\u00f3n de la adicci\u00f3n. <\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Un reciente informe de la <a href=\"https:\/\/www.who.int\/europe\/publications\/i\/item\/9789289060936\">Organizaci\u00f3n Mundial de la Salud (OMS)<\/a> revela que el Reino Unido registra las tasas de consumo de alcohol infantil m\u00e1s elevadas del mundo entre los ni\u00f1os de 11 a 13 a\u00f1os. El informe destaca que, a los 15 a\u00f1os, las chicas tienen m\u00e1s probabilidades que los chicos de haber consumido alcohol. Inglaterra registr\u00f3 la mayor prevalencia de consumo de alcohol entre los ni\u00f1os de 11 a\u00f1os (35% para los chicos, 34% para las chicas) y 13 a\u00f1os (50% para los chicos, 57% para las chicas). El informe subraya el grave impacto que el consumo de alcohol puede tener en el cerebro en desarrollo de los ni\u00f1os y vincula el problema a una actitud cultural m\u00e1s amplia en el Reino Unido respecto al alcohol. Para m\u00e1s informaci\u00f3n, consulte <a href=\"https:\/\/noticiaslatam.lat\/20240430\/consumo-excesivo-de-alcohol-entre-jovenes-un-problema-que-el-reino-unido-no-quiere-afrontar-1150110359.html\">este art\u00edculo<\/a> y <a href=\"https:\/\/noticiaslatam.lat\/20220308\/cuidado-beber-alcohol-podria-encoger-tu-cerebro-1122783561.html\">este estudio<\/a>.    <\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">ROYSTON, Reino Unido &#8211; Desde muy joven me sent\u00ed aislada y a la deriva. Me comparaba con los dem\u00e1s y la intimidaci\u00f3n consum\u00eda mis pensamientos, lo que me imped\u00eda concentrarme. A los 11 a\u00f1os, recurr\u00ed al alcohol con la esperanza de adormecer el dolor.  <\/p>\n\n<p class=\"wp-block-paragraph\">Tras a\u00f1os de lucha contra la adicci\u00f3n al alcohol, por fin encontr\u00e9 la paz en una vida tranquila, rodeada de un exuberante jard\u00edn de flores y plantas. En este lugar, me curo y abrazo la sobriedad. Este jard\u00edn representa ahora la calma que anhelaba, un refugio del caos y la lucha.  <\/p>\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/orato.world\/es\/category\/salud\/\"><strong>Lea m\u00e1s historias sobre salud en Orato World Media.<\/strong><\/a><\/em><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-alcohol-consumption-began-at-age-11\"><strong>El consumo de alcohol comenz\u00f3 a los 11 a\u00f1os<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Desde muy joven me sent\u00ed perdida y comparaba mi vida con la de los dem\u00e1s, siempre encontrando carencias en la m\u00eda. La escuela se convirti\u00f3 en una lucha constante, ya que el acoso me abrumaba y me imped\u00eda concentrarme en el aprendizaje. <\/p>\n\n<p class=\"wp-block-paragraph\">Un d\u00eda me aficion\u00e9 al alcohol, con la esperanza de mitigar el dolor como hac\u00eda con los dem\u00e1s. Cuando beb\u00eda, las partes de m\u00ed que odiaba parec\u00edan desvanecerse. Bajo la bruma del alcohol, me volv\u00ed audaz, sin miedo a enfrentarme al mundo.  <\/p>\n\n<p class=\"wp-block-paragraph\">El alcohol se convirti\u00f3 r\u00e1pidamente en mi v\u00eda de escape y cada vez depend\u00eda m\u00e1s de \u00e9l. En lugar de servirme para celebrar, se convirti\u00f3 en mi muleta en la tristeza y en mi fuente de confianza. En el colegio, estar borracha aliviaba el dolor del acoso escolar. Ya no me importaban los insultos, como si el alcohol encerrara todo el dolor. Durante un tiempo, me sent\u00ed bien, incluso liberada. Sin embargo, en casa las cosas no iban mejor. Los problemas que intentaba ahogar me persegu\u00edan y el alivio que me proporcionaba el alcohol era temporal.      <\/p>\n\n<p class=\"wp-block-paragraph\">Empec\u00e9 a robar para mantener mi provisi\u00f3n llena, a veces a mi familia y otras en las tiendas. La adrenalina se disparaba cuando met\u00eda botellas bajo la ropa. En el fondo, sab\u00eda que estaba mal, pero me convenc\u00ed de que lo necesitaba para sobrevivir. La idea de robar me parec\u00eda m\u00e1s emocionante que el acto en s\u00ed. Una vez que ten\u00eda la botella en la mano, la excitaci\u00f3n se desvanec\u00eda y s\u00f3lo quedaba el vac\u00edo. El subid\u00f3n que persegu\u00eda nunca duraba, y el ciclo se repet\u00eda.     <\/p>\n\n<p class=\"wp-block-paragraph\">A medida que pasaban los a\u00f1os, me resultaba m\u00e1s f\u00e1cil ocultar mi adicci\u00f3n. Los adultos suelen pasar por alto a los adolescentes, as\u00ed que mi forma de beber pasaba desapercibida. Se me daba bien disimularlo, vertiendo alcohol en botellas de refresco para que pareciera inofensivo.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-five-years-later-daily-alcohol-use-escalated-with-drug-mixing\"><strong>Cinco a\u00f1os despu\u00e9s, el consumo diario de alcohol se agrav\u00f3 con la mezcla de drogas<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Con el tiempo, mi comportamiento cambi\u00f3. La persona segura y extrovertida que proyectaba parec\u00eda real para todos los que me rodeaban. Nadie sospechaba que no era m\u00e1s que una m\u00e1scara que ocultaba el vac\u00edo y el dolor que hab\u00eda debajo. Mi fachada era tan convincente que hasta yo empec\u00e9 a cre\u00e9rmela.   <\/p>\n\n<p class=\"wp-block-paragraph\">Los peores momentos llegaron cuando se me pas\u00f3 el efecto del alcohol. Ca\u00eda en una profunda depresi\u00f3n, como si me deslizara por un acantilado. Me resultaba insoportable enfrentarme a mi verdadera yo. Despreciaba ser t\u00edmida e insegura. Incapaz de soportar ser yo misma ni un segundo, volv\u00ed a beber r\u00e1pidamente para convertirme en esa versi\u00f3n extrovertida y segura de m\u00ed misma. Siempre fingiendo, actuaba constantemente como otra persona. Para seguir actuando, necesitaba el alcohol. Se convirti\u00f3 en mi forma de mantener mi personaje.       <\/p>\n\n<p class=\"wp-block-paragraph\">Con el tiempo, el alcohol por s\u00ed solo result\u00f3 insuficiente, as\u00ed que empec\u00e9 a mezclarlo con otras drogas para conseguir un efecto m\u00e1s fuerte. Cuando cumpl\u00ed 16 a\u00f1os, me asalt\u00f3 la duda. Algunos de mis amigos dejaron de consumir y dieron un giro a sus vidas. Al verlos cambiar, pens\u00e9 que parec\u00edan rid\u00edculos. Me costaba entender por qu\u00e9 hab\u00edan abandonado nuestra forma de vida. Sin embargo, bajo mi burla, empec\u00e9 a preocuparme. \u00abQuiz\u00e1 no sean ellos los raros\u00bb, pens\u00e9, \u201cquiz\u00e1 sea yo quien tenga el verdadero problema\u201d.      <\/p>\n\n<p class=\"wp-block-paragraph\">Un d\u00eda, estando borracha y sola en casa, invit\u00e9 a unos amigos, que trajeron a m\u00e1s gente. La fiesta se descontrol\u00f3: ruidosa, ca\u00f3tica y llena de desconocidos. No me importaba. Cuando mi madre lleg\u00f3 a casa, se puso furiosa. Con calma, me dijo: \u00abTienes que irte\u00bb. El p\u00e1nico se apoder\u00f3 de m\u00ed. No ten\u00eda ad\u00f3nde ir. Cog\u00ed a mi gatito, algunas pertenencias y un m\u00f3vil muerto antes de ir a un bar a cargarlo. Pronto encontr\u00e9 a un amigo dispuesto a dejar que me quedara un tiempo.        <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-unwilling-to-accept-my-addiction-sober-patient-inspires-me-to-seek-rehab\"><strong>No estoy dispuesta a aceptar mi adicci\u00f3n: un paciente sobrio me anima a buscar rehabilitaci\u00f3n<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Ni siquiera entonces me di cuenta de que ten\u00eda un problema. La vida era dura, pero cre\u00eda que el alcohol me ayudaba a sobrellevarla. El alcohol me parec\u00eda una soluci\u00f3n, no un problema. Encontr\u00e9 trabajo en un pub que a su vez era hotel y restaurante. Sin hogar, guardaba mis pertenencias en el coche, que se convert\u00eda en mi dormitorio por la noche. Por fuera, intentaba mantener la compostura, pero por dentro era un caos total. Mi mente se quedaba en blanco, llena de desorden, y luchaba a diario, sin saber qu\u00e9 hacer ni ad\u00f3nde ir.      <\/p>\n\n<p class=\"wp-block-paragraph\">Me plante\u00e9 acabar con mi vida, sinti\u00e9ndome atrapada entre la necesidad del alcohol y la certeza de que me estaba destruyendo. No tom\u00e9 ninguna medida directa, sino que viv\u00ed imprudentemente, conduciendo borracha y chocando, como tentando al destino para que decidiera por m\u00ed. Entonces, en el trabajo me dijeron que no volviera hasta que me recuperara. Mi familia se hizo eco de la petici\u00f3n. \u00abTienes que hacer algo\u00bb, me dijeron. Sab\u00eda que no ten\u00eda elecci\u00f3n. Aunque una parte de m\u00ed segu\u00eda neg\u00e1ndolo, reacia a aceptar plenamente mi adicci\u00f3n, me sent\u00eda lo bastante desesperada como para intentar cambiar.      <\/p>\n\n<p class=\"wp-block-paragraph\">Paralizada por el miedo, entr\u00e9 en rehabilitaci\u00f3n por primera vez, sin saber qu\u00e9 esperar. Tras a\u00f1os de consumo diario de drogas, me sent\u00eda perdida. Al principio de la rehabilitaci\u00f3n, me sent\u00eda desorientada, alternando entre una habitaci\u00f3n peque\u00f1a y est\u00e9ril destinada a calmarme y las zonas comunes donde aprend\u00edamos sobre los efectos de la adicci\u00f3n en el cerebro. Un d\u00eda, vi a un hombre lleno de vida, que sonre\u00eda alegremente. Supuse que era un miembro del personal. Cuando supe que era un paciente, me sorprend\u00ed, pero me dio esperanza. Quiz\u00e1 yo tambi\u00e9n podr\u00eda mejorar.      <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-finding-myself-in-sobriety\"><strong>Encontrarme a m\u00ed misma en la sobriedad<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Una tarde, un grupo nos reunimos en el jard\u00edn para hablar. En rehabilitaci\u00f3n, pasas tanto tiempo con los dem\u00e1s que enseguida se crean conexiones profundas. Me encontr\u00e9 riendo -una risa real y sobria- por primera vez. Me sent\u00ed extra\u00f1a, casi inc\u00f3moda porque no me resultaba familiar. Al mirar a los dem\u00e1s que tambi\u00e9n re\u00edan, sent\u00ed algo maravilloso. Nunca hab\u00eda comprendido la felicidad. Pero tambi\u00e9n me asust\u00e9. Sent\u00ed como si conociera a la persona que hab\u00eda escondido con el alcohol durante tanto tiempo. En ese momento, necesitaba enfrentarme al vac\u00edo que hab\u00eda evitado.        <\/p>\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s, cambi\u00e9 de centro de rehabilitaci\u00f3n y encontr\u00e9 mi sitio en Ema\u00fas Norfolk Waveney. En cuanto llegu\u00e9, se sent\u00eda como si fuera demasiado bueno para m\u00ed. Sin embargo, los vastos terrenos, los campos abiertos y el ambiente sereno me aportaron al instante una sensaci\u00f3n de calma que nunca hab\u00eda sentido antes. Me instal\u00e9 r\u00e1pidamente, lo que me pareci\u00f3 ins\u00f3lito. Mi lugar favorito eran las orqu\u00eddeas, desde donde dominaba todo el jard\u00edn. Un lugar tranquilo, con poca gente, que me ofrec\u00eda unas puestas de sol impresionantes. Saboreo esos momentos de tranquilidad.      <\/p>\n\n<p class=\"wp-block-paragraph\">Mi vida es ahora radicalmente distinta, pero a veces me invade el miedo. Me aterroriza volver a caer en mis viejos h\u00e1bitos y perder todo lo que he construido. La vida no es perfecta. Tengo altibajos. En los momentos dif\u00edciles, me recuerdo a m\u00ed misma que siempre ser\u00e9 una adicta. No puedo beber despreocupadamente con los amigos, y esa es mi realidad para siempre. Cuando afloran esos miedos, salgo a pasear, a veces sola, a veces con mi perro. Tambi\u00e9n acudo a reuniones para despejar la mente. Al hacerlo, mantengo ese miedo a raya.         <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El alcohol se convirti\u00f3 r\u00e1pidamente en mi v\u00eda de escape y cada vez depend\u00eda m\u00e1s de \u00e9l. En lugar de usarlo para celebrar, se convirti\u00f3 en mi muleta en la tristeza y en mi fuente de confianza. En el colegio, estar borracha aliviaba el dolor del acoso escolar. Ya no me importaban los insultos, como si el alcohol encerrara todo el dolor. Durante un tiempo, me sent\u00ed bien, incluso liberada.     <\/p>\n","protected":false},"author":46,"featured_media":95901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[725,188],"tags":[9436,2309,1681,3060,5735,9437,3922,1791],"class_list":["post-96409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-salud","tag-alcohol-es","tag-alcoholicos-anonimos","tag-drogas","tag-europa","tag-rehabilitacion","tag-rehabilitacion-es","tag-reino-unido","tag-uk-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar y en rehabilitaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar, en rehabilitaci\u00f3n, y encontrando la paz en la sobriedad, abrazando los altibajos de la recuperaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad\" \/>\n<meta property=\"og:description\" content=\"El alcohol se convirti\u00f3 r\u00e1pidamente en mi v\u00eda de escape y cada vez depend\u00eda m\u00e1s de \u00e9l. En lugar de usarlo para celebrar, se convirti\u00f3 en mi muleta en la tristeza y en mi fuente de confianza. En el colegio, estar borracha aliviaba el dolor del acoso escolar. Ya no me importaban los insultos, como si el alcohol encerrara todo el dolor. Durante un tiempo, me sent\u00ed bien, incluso liberada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T08:49:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T19:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Juan Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/\"},\"author\":{\"name\":\"Juan Martinez\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\"},\"headline\":\"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad\",\"datePublished\":\"2024-08-30T08:49:50+00:00\",\"dateModified\":\"2024-09-04T19:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/\"},\"wordCount\":1475,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Rehab-1.png\",\"keywords\":[\"alcohol\",\"alcoholicos anonimos\",\"Drogas\",\"Europa\",\"rehabilitaci\u00f3n\",\"rehabilitaci\u00f3n\",\"Reino Unido\",\"UK\"],\"articleSection\":[\"Educaci\u00f3n\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/\",\"name\":\"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar y en rehabilitaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Rehab-1.png\",\"datePublished\":\"2024-08-30T08:49:50+00:00\",\"dateModified\":\"2024-09-04T19:28:56+00:00\",\"description\":\"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar, en rehabilitaci\u00f3n, y encontrando la paz en la sobriedad, abrazando los altibajos de la recuperaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Rehab-1.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Rehab-1.png\",\"width\":1280,\"height\":960,\"caption\":\"Chloe and other Emmaus Norfolk and Waveney patients | Photo courtesy of Emmaus Norfolk and Waveney\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/08\\\/30\\\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\",\"name\":\"Juan Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"caption\":\"Juan Martinez\"},\"description\":\"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/juan-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar y en rehabilitaci\u00f3n","description":"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar, en rehabilitaci\u00f3n, y encontrando la paz en la sobriedad, abrazando los altibajos de la recuperaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/","og_locale":"es_ES","og_type":"article","og_title":"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad","og_description":"El alcohol se convirti\u00f3 r\u00e1pidamente en mi v\u00eda de escape y cada vez depend\u00eda m\u00e1s de \u00e9l. En lugar de usarlo para celebrar, se convirti\u00f3 en mi muleta en la tristeza y en mi fuente de confianza. En el colegio, estar borracha aliviaba el dolor del acoso escolar. Ya no me importaban los insultos, como si el alcohol encerrara todo el dolor. Durante un tiempo, me sent\u00ed bien, incluso liberada.","og_url":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-08-30T08:49:50+00:00","article_modified_time":"2024-09-04T19:28:56+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png","type":"image\/png"}],"author":"Juan Martinez","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Juan Martinez","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/"},"author":{"name":"Juan Martinez","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d"},"headline":"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad","datePublished":"2024-08-30T08:49:50+00:00","dateModified":"2024-09-04T19:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/"},"wordCount":1475,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png","keywords":["alcohol","alcoholicos anonimos","Drogas","Europa","rehabilitaci\u00f3n","rehabilitaci\u00f3n","Reino Unido","UK"],"articleSection":["Educaci\u00f3n","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/","url":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/","name":"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar y en rehabilitaci\u00f3n","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png","datePublished":"2024-08-30T08:49:50+00:00","dateModified":"2024-09-04T19:28:56+00:00","description":"Luchando contra el alcohol desde los 11 a\u00f1os, sin hogar, en rehabilitaci\u00f3n, y encontrando la paz en la sobriedad, abrazando los altibajos de la recuperaci\u00f3n.","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png","width":1280,"height":960,"caption":"Chloe and other Emmaus Norfolk and Waveney patients | Photo courtesy of Emmaus Norfolk and Waveney"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/08\/30\/una-mujer-sin-hogar-que-lucho-contra-el-alcoholismo-desde-los-11-anos-encuentra-la-paz-en-la-rehabilitacion-y-la-sobriedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Una mujer sin hogar que luch\u00f3 contra el alcoholismo desde los 11 a\u00f1os encuentra la paz en la rehabilitaci\u00f3n y la sobriedad"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d","name":"Juan Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","url":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","caption":"Juan Martinez"},"description":"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.","url":"https:\/\/orato.world\/es\/author\/juan-martinez\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Rehab-1-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Juan Martinez","author_link":"https:\/\/orato.world\/es\/author\/juan-martinez\/"},"uagb_comment_info":0,"uagb_excerpt":"El alcohol se convirti\u00f3 r\u00e1pidamente en mi v\u00eda de escape y cada vez depend\u00eda m\u00e1s de \u00e9l. En lugar de usarlo para celebrar, se convirti\u00f3 en mi muleta en la tristeza y en mi fuente de confianza. En el colegio, estar borracha aliviaba el dolor del acoso escolar. Ya no me importaban los insultos, como&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=96409"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96409\/revisions"}],"predecessor-version":[{"id":96410,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96409\/revisions\/96410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/95901"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=96409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=96409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=96409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}