{"id":96413,"date":"2024-09-01T03:00:00","date_gmt":"2024-09-01T10:00:00","guid":{"rendered":"https:\/\/orato.world\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/"},"modified":"2024-09-04T15:41:34","modified_gmt":"2024-09-04T22:41:34","slug":"una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/","title":{"rendered":"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio"},"content":{"rendered":"\n<div class=\"wp-block-uagb-blockquote uagb-block-eeb5de9e uagb-blockquote__skin-border uagb-blockquote__with-tweet uagb-blockquote__tweet-style-classic uagb-blockquote__tweet-icon_text uagb-blockquote__stack-img-none\"><blockquote class=\"uagb-blockquote\"><div class=\"uagb-blockquote__content\"><strong><em>Bienvenido a la secci\u00f3n de Galer\u00eda fotogr\u00e1fica de Orato World Media<\/em><\/strong><em> donde publicamos im\u00e1genes de fot\u00f3grafos y fotoperiodistas de todo el mundo. Si desea m\u00e1s informaci\u00f3n sobre Orato World Media  <\/em><a href=\"https:\/\/orato.world\/es\/spanish-photos\/\">Secci\u00f3n de Galer\u00eda de fotos<\/a><em>,por favor, contacta a <\/em><strong><em>editor@orato.world<\/em><\/strong><em>.<\/em><\/div><footer><div class=\"uagb-blockquote__author-wrap uagb-blockquote__author-at-left\"><cite class=\"uagb-blockquote__author\">Para convertirse en <a href=\"https:\/\/orato.world\/es\/conviertete-en-nuestro-colaborador-2\/\">colaborador freelance autorizado<\/a> de Orato World Media, realice nuestra <a href=\"https:\/\/airtable.com\/appyJGParHdba6EUl\/shrwroWrdEB7bLuE5\">Evaluaci\u00f3n de colaboradores freelance.<\/a><\/cite><\/div><a href=\"\/\" class=\"uagb-blockquote__tweet-button\" target=\"_blank\" rel=\"noopener noreferrer\"><svg width=\"20\" height=\"20\" viewbox=\"0 0 512 512\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>Tweet<\/a><\/footer><\/blockquote><\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">DHAKA, Bangladesh En una naci\u00f3n nacida de la protesta, Bangladesh cuenta con una larga historia de movimientos significativos. Estos movimientos han conformado la identidad y la gobernanza de Bangladesh. En junio de 2023, esa historia de protestas se reaviv\u00f3. Los estudiantes rechazaron el restablecimiento por parte del Tribunal Supremo de <a href=\"https:\/\/www.bbc.com\/news\/articles\/cq5xye1d285o\">un sistema de cuotas <\/a>abolido en 2018. La cuota permite que un tercio de los puestos de trabajo en la administraci\u00f3n p\u00fablica vayan a parar a familiares de veteranos de la guerra por la independencia de 1971.    <\/p>\n\n<p class=\"wp-block-paragraph\">Desde que estallaron las movilizaciones, <a href=\"https:\/\/www3.nhk.or.jp\/nhkworld\/en\/news\/20240817_14\/#:~:text=The%20Office%20of%20the%20UN,of%20Prime%20Minister%20Sheikh%20Hasina.\">casi 650 personas<\/a> han muerto en Bangladesh. Aument\u00f3 la violencia de g\u00e9nero y religiosa, y cientos de casas han ardido. La Primera Ministra, Sheikh Hasina, <a href=\"https:\/\/www.lowyinstitute.org\/the-interpreter\/bangladesh-s-new-military-led-government-has-tough-job-ahead\">dimiti\u00f3 y abandon\u00f3 el pa\u00eds<\/a> despu\u00e9s de que los manifestantes asaltaran repetidamente su casa. El ej\u00e9rcito asumi\u00f3 entonces el gobierno provisional.   <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Universities-and-colleges-suspended-classes-and-telecommunications-were-widely-disrupted-as-authorities-tried-to-quell-the-unrest-1024x768.jpg\" alt=\"\" class=\"wp-image-96007\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Universities-and-colleges-suspended-classes-and-telecommunications-were-widely-disrupted-as-authorities-tried-to-quell-the-unrest-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Universities-and-colleges-suspended-classes-and-telecommunications-were-widely-disrupted-as-authorities-tried-to-quell-the-unrest-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Universities-and-colleges-suspended-classes-and-telecommunications-were-widely-disrupted-as-authorities-tried-to-quell-the-unrest-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Universities-and-colleges-suspended-classes-and-telecommunications-were-widely-disrupted-as-authorities-tried-to-quell-the-unrest-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/Universities-and-colleges-suspended-classes-and-telecommunications-were-widely-disrupted-as-authorities-tried-to-quell-the-unrest.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Los colegios y universidades suspendieron las clases tras el estallido de las protestas en Bangladesh. Los sistemas de telecomunicaciones sufrieron graves interrupciones mientras las autoridades intentaban sofocar los disturbios. Las protestas se tornaron violentas a principios de julio, tras enfrentamientos entre miles de manifestantes y la polic\u00eda, que recurri\u00f3 al uso de balas de goma, gases lacrim\u00f3genos y granadas de ruido para dispersar a las multitudes.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/In-July-2024-the-protests-began-again-after-the-Supreme-Court-temporarily-reinstated-the-quota-system-pending-a-final-decision-1024x768.jpg\" alt=\"\" class=\"wp-image-96009\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/In-July-2024-the-protests-began-again-after-the-Supreme-Court-temporarily-reinstated-the-quota-system-pending-a-final-decision-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/In-July-2024-the-protests-began-again-after-the-Supreme-Court-temporarily-reinstated-the-quota-system-pending-a-final-decision-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/In-July-2024-the-protests-began-again-after-the-Supreme-Court-temporarily-reinstated-the-quota-system-pending-a-final-decision-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/In-July-2024-the-protests-began-again-after-the-Supreme-Court-temporarily-reinstated-the-quota-system-pending-a-final-decision-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/In-July-2024-the-protests-began-again-after-the-Supreme-Court-temporarily-reinstated-the-quota-system-pending-a-final-decision.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-protests-begin-in-june-after-supreme-court-temporarily-reinstates-quota-system\"><strong>Las protestas comienzan en junio despu\u00e9s de que el Tribunal Supremo restablezca temporalmente el sistema de cuotas<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Aunque desde entonces se ha eliminado la cuota, las protestas continuaron como movimiento antigubernamental y la Primera Ministra dimiti\u00f3. La protesta actual tiene ra\u00edces hist\u00f3ricas. La primera gran protesta del pa\u00eds, conocida como Bhasha Andolan [<em>Movimiento por la Lengua Bengal\u00ed<\/em>], tuvo lugar a principios de la d\u00e9cada de 1950, cuando la regi\u00f3n era considerada Pakist\u00e1n Oriental.  <\/p>\n\n<p class=\"wp-block-paragraph\">En 1971, el ej\u00e9rcito indio apoy\u00f3 la guerra de independencia de Bangladesh contra Pakist\u00e1n, que acab\u00f3 convirti\u00e9ndose en su propio pa\u00eds. En 1972, la entonces Presidenta Sheikh Mujibur Rahman introdujo el sistema de cuotas para honrar y apoyar a los descendientes de los que lucharon por la independencia del pa\u00eds. Ofrec\u00eda el 30% de los empleos p\u00fablicos a las familias de los luchadores por la libertad, con cuotas adicionales para mujeres, minor\u00edas \u00e9tnicas y personas con discapacidad.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Trafic-police-carrying-a-placard-reading-Let-Reformation-Happen-from-Within-in-the-middle-of-the-city-1024x768.jpg\" alt=\"\" class=\"wp-image-96011\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Trafic-police-carrying-a-placard-reading-Let-Reformation-Happen-from-Within-in-the-middle-of-the-city-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Trafic-police-carrying-a-placard-reading-Let-Reformation-Happen-from-Within-in-the-middle-of-the-city-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Trafic-police-carrying-a-placard-reading-Let-Reformation-Happen-from-Within-in-the-middle-of-the-city-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Trafic-police-carrying-a-placard-reading-Let-Reformation-Happen-from-Within-in-the-middle-of-the-city-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/Trafic-police-carrying-a-placard-reading-Let-Reformation-Happen-from-Within-in-the-middle-of-the-city.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Bangladesh sigue siendo el<a href=\"https:\/\/www.bbc.com\/news\/articles\/cq5xye1d285o\"> hogar de 170 millones de personas con<\/a> \u00abuna de las econom\u00edas de m\u00e1s r\u00e1pido crecimiento del mundo\u00bb, pero 18 millones de licenciados universitarios luchan por encontrar trabajo. Su tasa de desempleo es m\u00e1s alta que la de sus hom\u00f3logos con menos estudios. La cuota me pareci\u00f3 una bofetada en la cara.  <\/p>\n\n<p class=\"wp-block-paragraph\">Aunque las cuotas se desmantelaron tras el inicio de las protestas, las manifestaciones continuaron y crecieron m\u00e1s all\u00e1 de los estudiantes universitarios, se\u00f1alando la corrupci\u00f3n en el gobierno. Aqu\u00ed, un ciudadano que dirige el tr\u00e1fico sostiene una pancarta en la que se lee \u00abDejemos que la reforma ocurra desde dentro\u00bb. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/The-High-Courts-decision-sparked-widespread-protest-among-university-students-1024x768.jpg\" alt=\"\" class=\"wp-image-96013\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/The-High-Courts-decision-sparked-widespread-protest-among-university-students-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/The-High-Courts-decision-sparked-widespread-protest-among-university-students-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/The-High-Courts-decision-sparked-widespread-protest-among-university-students-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/The-High-Courts-decision-sparked-widespread-protest-among-university-students-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/The-High-Courts-decision-sparked-widespread-protest-among-university-students.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-widespread-destruction-ravages-bangladesh\"><strong>La destrucci\u00f3n generalizada asola Bangladesh<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la Oficina del Alto Comisionado de la ONU para los Derechos Humanos, \u00abempezaron a surgir informes de destrucci\u00f3n generalizada de propiedades p\u00fablicas y privadas\u00bb. Citaron 235 instalaciones policiales da\u00f1adas y 69 puestos avanzados destruidos. \u00abCientos de otras instalaciones p\u00fablicas, incluidas estaciones de metro y autopistas r\u00e1pidas, tambi\u00e9n resultaron da\u00f1adas\u00bb. La televisi\u00f3n estatal Bangladesh Television de Dhaka fue incendiada. Tambi\u00e9n se produjeron ataques contra minor\u00edas, incluidos hind\u00faes.    <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Protestors-at-Central-Shaheed-Minar-Central-Martierd-Building-one-of-the-historical-landmarks-in-Dhaka-Bangladesh-1024x768.jpg\" alt=\"\" class=\"wp-image-96015\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Protestors-at-Central-Shaheed-Minar-Central-Martierd-Building-one-of-the-historical-landmarks-in-Dhaka-Bangladesh-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-at-Central-Shaheed-Minar-Central-Martierd-Building-one-of-the-historical-landmarks-in-Dhaka-Bangladesh-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-at-Central-Shaheed-Minar-Central-Martierd-Building-one-of-the-historical-landmarks-in-Dhaka-Bangladesh-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-at-Central-Shaheed-Minar-Central-Martierd-Building-one-of-the-historical-landmarks-in-Dhaka-Bangladesh-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-at-Central-Shaheed-Minar-Central-Martierd-Building-one-of-the-historical-landmarks-in-Dhaka-Bangladesh.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Los manifestantes se concentraron ampliamente, incluso aqu\u00ed, en el Central Shaheed Minar o Central Martierd Building, uno de los monumentos hist\u00f3ricos de Dhaka. <a href=\"https:\/\/www.ohchr.org\/sites\/default\/files\/2024-08\/OHCHR-Preliminary-Analysis-of-Recent-Protests-and-Unrest-in-Bangladesh-16082024_2.pdf\">La ONU confirm\u00f3<\/a> la muerte de m\u00e1s de 600 personas, entre manifestantes, transe\u00fantes, periodistas y algunos miembros de las fuerzas de seguridad. Otros miles de manifestantes y transe\u00fantes sufrieron heridas que saturaron los hospitales.  <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Thousands-of-protesters-stormed-her-official-residence-in-Gono-Bhaban-in-Dhaka-1024x768.jpg\" alt=\"\" class=\"wp-image-96017\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Thousands-of-protesters-stormed-her-official-residence-in-Gono-Bhaban-in-Dhaka-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Thousands-of-protesters-stormed-her-official-residence-in-Gono-Bhaban-in-Dhaka-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Thousands-of-protesters-stormed-her-official-residence-in-Gono-Bhaban-in-Dhaka-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Thousands-of-protesters-stormed-her-official-residence-in-Gono-Bhaban-in-Dhaka-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/Thousands-of-protesters-stormed-her-official-residence-in-Gono-Bhaban-in-Dhaka.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Con el sistema de cuotas, los estudiantes empezaron a sentir que ten\u00edan limitadas las oportunidades basadas en el m\u00e9rito. Las manifestaciones, que comenzaron formalmente en junio de 2024, degeneraron en violencia en julio, cuando la ex primera ministra Sheikh Hasin se neg\u00f3 a satisfacer las demandas de los estudiantes, alegando procedimientos judiciales. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/A-man-after-being-beaten-by-the-protestors-in-Dhaka-1024x768.jpg\" alt=\"\" class=\"wp-image-96019\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/A-man-after-being-beaten-by-the-protestors-in-Dhaka-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/A-man-after-being-beaten-by-the-protestors-in-Dhaka-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/A-man-after-being-beaten-by-the-protestors-in-Dhaka-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/A-man-after-being-beaten-by-the-protestors-in-Dhaka-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/A-man-after-being-beaten-by-the-protestors-in-Dhaka.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de las numerosas lesiones sufridas, a principios de agosto <a href=\"https:\/\/news.un.org\/en\/story\/2024\/08\/1152796\">UNICEF<\/a> inform\u00f3 de la muerte de al menos 32 ni\u00f1os. El informe tambi\u00e9n se\u00f1alaba que hab\u00eda ni\u00f1os detenidos. Bangladesh firm\u00f3 la Convenci\u00f3n de la ONU sobre los Derechos del Ni\u00f1o, que forma parte de la legislaci\u00f3n internacional sobre derechos humanos. Las autoridades internacionales han pedido que se ponga fin a esta detenci\u00f3n.    <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Protestors-climb-on-the-former-Prime-Ministers-offices-building-to-hoist-the-national-flag-of-the-country-1024x768.jpg\" alt=\"\" class=\"wp-image-96021\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Protestors-climb-on-the-former-Prime-Ministers-offices-building-to-hoist-the-national-flag-of-the-country-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-climb-on-the-former-Prime-Ministers-offices-building-to-hoist-the-national-flag-of-the-country-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-climb-on-the-former-Prime-Ministers-offices-building-to-hoist-the-national-flag-of-the-country-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-climb-on-the-former-Prime-Ministers-offices-building-to-hoist-the-national-flag-of-the-country-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/Protestors-climb-on-the-former-Prime-Ministers-offices-building-to-hoist-the-national-flag-of-the-country.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-minorities-in-bangladesh-suffer-in-protests\"><strong>Las minor\u00edas de Bangladesh sufren en las protestas<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.thehindu.com\/news\/international\/nearly-650-people-killed-in-recent-spate-of-violence-in-bangladesh-un-report\/article68535793.ece\">Las noticias citaban<\/a> las amenazas contra las minor\u00edas. La Gran Alianza Nacional Hind\u00fa de Bangladesh ha declarado que la comunidad minoritaria ha sufrido ataques y amenazas en 278 localidades de 48 distritos desde la ca\u00edda del gobierno dirigido por Sheikh Hasina, calific\u00e1ndolo de \u00abasalto a la religi\u00f3n hind\u00fa\u00bb. Varios templos hind\u00faes, hogares y negocios de la comunidad minoritaria en Bangladesh fueron destruidos este mes en medio de los disturbios\u00bb. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"96027\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Students-of-medical-college-of-Dhaka-University-protesting-against-the-High-Court-ruling-of-reinstating-the-30-per-cent-quota-favouring-the-descendants-of-the-1971-independence-war-fighters-1024x768.png\" alt=\"Estudiantes de la Facultad de Medicina de la Universidad de Dhaka protestan contra la decisi&#xF3;n del Tribunal Superior de restablecer la cuota del 30% en favor de los descendientes de los combatientes de la guerra de independencia de 1971.\" class=\"wp-image-96027\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Students-of-medical-college-of-Dhaka-University-protesting-against-the-High-Court-ruling-of-reinstating-the-30-per-cent-quota-favouring-the-descendants-of-the-1971-independence-war-fighters-1024x768.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Students-of-medical-college-of-Dhaka-University-protesting-against-the-High-Court-ruling-of-reinstating-the-30-per-cent-quota-favouring-the-descendants-of-the-1971-independence-war-fighters-300x225.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Students-of-medical-college-of-Dhaka-University-protesting-against-the-High-Court-ruling-of-reinstating-the-30-per-cent-quota-favouring-the-descendants-of-the-1971-independence-war-fighters-770x578.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Students-of-medical-college-of-Dhaka-University-protesting-against-the-High-Court-ruling-of-reinstating-the-30-per-cent-quota-favouring-the-descendants-of-the-1971-independence-war-fighters-533x400.png 533w, https:\/\/orato.world\/wp-content\/uploads\/Students-of-medical-college-of-Dhaka-University-protesting-against-the-High-Court-ruling-of-reinstating-the-30-per-cent-quota-favouring-the-descendants-of-the-1971-independence-war-fighters.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"96025\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Tens-of-thousands-of-protesters-surge-through-the-capital-of-Dhaka-after-the-prime-minister-Sheikh-Hasina-resigned-to-end-her-15-years-in-power-1024x768.jpg\" alt=\"Decenas de miles de manifestantes recorren la capital Dacca tras la dimisi&#xF3;n de la primera ministra Sheikh Hasina, que pone fin a 15 a&#xF1;os en el poder\" class=\"wp-image-96025\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Tens-of-thousands-of-protesters-surge-through-the-capital-of-Dhaka-after-the-prime-minister-Sheikh-Hasina-resigned-to-end-her-15-years-in-power-1024x768.jpg 1024w, https:\/\/orato.world\/wp-content\/uploads\/Tens-of-thousands-of-protesters-surge-through-the-capital-of-Dhaka-after-the-prime-minister-Sheikh-Hasina-resigned-to-end-her-15-years-in-power-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Tens-of-thousands-of-protesters-surge-through-the-capital-of-Dhaka-after-the-prime-minister-Sheikh-Hasina-resigned-to-end-her-15-years-in-power-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Tens-of-thousands-of-protesters-surge-through-the-capital-of-Dhaka-after-the-prime-minister-Sheikh-Hasina-resigned-to-end-her-15-years-in-power-533x400.jpg 533w, https:\/\/orato.world\/wp-content\/uploads\/Tens-of-thousands-of-protesters-surge-through-the-capital-of-Dhaka-after-the-prime-minister-Sheikh-Hasina-resigned-to-end-her-15-years-in-power.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>Todas las fotos son cortes\u00eda de Mime Hasan. Relato de Priyanka Chandani <\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bangladesh sigue siendo el hogar de 170 millones de personas con \u00abuna de las econom\u00edas de m\u00e1s r\u00e1pido crecimiento del mundo\u00bb, pero 18 millones de licenciados universitarios luchan por encontrar trabajo. Su tasa de desempleo es m\u00e1s alta que la de sus hom\u00f3logos con menos estudios. El sistema de cuotas laborales se siente como bofetada en la cara.  <\/p>\n","protected":false},"author":73,"featured_media":96032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,874,534],"tags":[9438,3637,1693,1260,1955,9440,9439],"class_list":["post-96413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-crimen-y-corrupcion-es","category-galeria-de-fotos","tag-antigubernamental","tag-asia-russia-es","tag-bangladesh-es","tag-disturbios","tag-protesta-es","tag-protestas-de-estudiantes-universitarios","tag-sistema-de-cuotas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Casi 650 muertos en Bangladesh desde que estallaron las protestas en julio<\/title>\n<meta name=\"description\" content=\"Una naci\u00f3n sumida en el caos: casi 650 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio por el sistema de cuotas laborales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio\" \/>\n<meta property=\"og:description\" content=\"Bangladesh sigue siendo el hogar de 170 millones de personas con \u00abuna de las econom\u00edas de m\u00e1s r\u00e1pido crecimiento del mundo\u00bb, pero 18 millones de licenciados universitarios luchan por encontrar trabajo. Su tasa de desempleo es m\u00e1s alta que la de sus hom\u00f3logos con menos estudios. El sistema de cuotas laborales se siente como bofetada en la cara.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-01T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-04T22:41:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pamela Say\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pamela Say\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/\"},\"author\":{\"name\":\"Pamela Say\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/8763f3be94965bec0c582d052c418b00\"},\"headline\":\"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio\",\"datePublished\":\"2024-09-01T10:00:00+00:00\",\"dateModified\":\"2024-09-04T22:41:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/\"},\"wordCount\":933,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg\",\"keywords\":[\"Antigubernamental\",\"Asia &amp; Russia\",\"Bangladesh\",\"Disturbios\",\"protesta\",\"protestas de estudiantes universitarios\",\"Sistema de cuotas\"],\"articleSection\":[\"Conflicto\",\"Crimen y corrupci\u00f3n\",\"Galer\u00eda de fotos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/\",\"name\":\"Casi 650 muertos en Bangladesh desde que estallaron las protestas en julio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg\",\"datePublished\":\"2024-09-01T10:00:00+00:00\",\"dateModified\":\"2024-09-04T22:41:34+00:00\",\"description\":\"Una naci\u00f3n sumida en el caos: casi 650 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio por el sistema de cuotas laborales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg\",\"width\":1280,\"height\":960,\"caption\":\"More than 650 people have been killed and 2500 have been brutally assaulted during the riots in Bangladesh in July and August 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/01\\\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/8763f3be94965bec0c582d052c418b00\",\"name\":\"Pamela Say\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Pamela Say\"},\"description\":\"Pamela H. Say, MBA, CFRE is a sought-after, nationally-published author and speaker, veteran administrator, and currently serves as the CEO for Orato World Media. She is a trained journalist and has been featured in Advancing Philanthropy Magazine, the Chronicle of Philanthropy, and the Wiley Journal Fundraising Success. Her award-winning work in fundraising, marketing, writing, and leading high-performance teams commands international attention.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/pamela-say\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Casi 650 muertos en Bangladesh desde que estallaron las protestas en julio","description":"Una naci\u00f3n sumida en el caos: casi 650 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio por el sistema de cuotas laborales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/","og_locale":"es_ES","og_type":"article","og_title":"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio","og_description":"Bangladesh sigue siendo el hogar de 170 millones de personas con \u00abuna de las econom\u00edas de m\u00e1s r\u00e1pido crecimiento del mundo\u00bb, pero 18 millones de licenciados universitarios luchan por encontrar trabajo. Su tasa de desempleo es m\u00e1s alta que la de sus hom\u00f3logos con menos estudios. El sistema de cuotas laborales se siente como bofetada en la cara.","og_url":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-09-01T10:00:00+00:00","article_modified_time":"2024-09-04T22:41:34+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg","type":"image\/jpeg"}],"author":"Pamela Say","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Pamela Say","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/"},"author":{"name":"Pamela Say","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/8763f3be94965bec0c582d052c418b00"},"headline":"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio","datePublished":"2024-09-01T10:00:00+00:00","dateModified":"2024-09-04T22:41:34+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/"},"wordCount":933,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg","keywords":["Antigubernamental","Asia &amp; Russia","Bangladesh","Disturbios","protesta","protestas de estudiantes universitarios","Sistema de cuotas"],"articleSection":["Conflicto","Crimen y corrupci\u00f3n","Galer\u00eda de fotos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/","url":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/","name":"Casi 650 muertos en Bangladesh desde que estallaron las protestas en julio","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg","datePublished":"2024-09-01T10:00:00+00:00","dateModified":"2024-09-04T22:41:34+00:00","description":"Una naci\u00f3n sumida en el caos: casi 650 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio por el sistema de cuotas laborales","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg","width":1280,"height":960,"caption":"More than 650 people have been killed and 2500 have been brutally assaulted during the riots in Bangladesh in July and August 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/09\/01\/una-nacion-sumida-en-el-caos-mas-de-600-muertos-en-bangladesh-desde-que-estallaron-las-protestas-antigubernamentales-en-julio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Una naci\u00f3n sumida en el caos: m\u00e1s de 600 muertos en Bangladesh desde que estallaron las protestas antigubernamentales en julio"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/8763f3be94965bec0c582d052c418b00","name":"Pamela Say","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Pamela Say"},"description":"Pamela H. Say, MBA, CFRE is a sought-after, nationally-published author and speaker, veteran administrator, and currently serves as the CEO for Orato World Media. She is a trained journalist and has been featured in Advancing Philanthropy Magazine, the Chronicle of Philanthropy, and the Wiley Journal Fundraising Success. Her award-winning work in fundraising, marketing, writing, and leading high-performance teams commands international attention.","url":"https:\/\/orato.world\/es\/author\/pamela-say\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-770x578.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-533x400.jpg",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/More-than-650-people-have-been-killed-and-2500-have-been-brutally-assaulted-during-the-riots-in-Bangladesh-in-July-and-August-2024-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Pamela Say","author_link":"https:\/\/orato.world\/es\/author\/pamela-say\/"},"uagb_comment_info":0,"uagb_excerpt":"Bangladesh sigue siendo el hogar de 170 millones de personas con \u00abuna de las econom\u00edas de m\u00e1s r\u00e1pido crecimiento del mundo\u00bb, pero 18 millones de licenciados universitarios luchan por encontrar trabajo. Su tasa de desempleo es m\u00e1s alta que la de sus hom\u00f3logos con menos estudios. El sistema de cuotas laborales se siente como bofetada&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=96413"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96413\/revisions"}],"predecessor-version":[{"id":96414,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96413\/revisions\/96414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/96032"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=96413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=96413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=96413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}