{"id":96816,"date":"2024-09-13T03:00:00","date_gmt":"2024-09-13T10:00:00","guid":{"rendered":"https:\/\/orato.world\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/"},"modified":"2024-09-13T07:20:37","modified_gmt":"2024-09-13T14:20:37","slug":"una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/","title":{"rendered":"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-500x500.jpg\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Pedro Evangelista Valois of San Isidro Colombia\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-500x500.jpg 500w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-300x300.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-100x100.jpg 100w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-400x400.jpg 400w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-150x150.jpg 150w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-70x70.jpg 70w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia-293x293.jpg 293w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-of-San-Isidro-Colombia.jpg 650w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Notas del periodista<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">Pedro Evangelista Valois, de 59 a\u00f1os, vive con su mujer en una peque\u00f1a casa de madera en San Isidro, Colombia, en plena selva. Trabaja cortando madera y plantando frutas y verduras. Durante dos a\u00f1os, a partir de 2022, \u00e9l y la mayor parte de su comunidad fueron desplazados de su hogar por la presencia de grupos armados dedicados a actividades il\u00edcitas. Temiendo por su seguridad, huyeron a la ciudad, donde Pedro y muchos otros vivieron en un estadio deportivo abandonado. Hace poco regresaron a casa y est\u00e1n empezando a reconstruir sus vidas.    <\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">En San Isidro, nueve comunidades pose\u00edan colectivamente 67.000 hect\u00e1reas (165.600 acres), donde las familias viv\u00edan de la agricultura, la pesca y la tala. El pueblo es tambi\u00e9n una parada estrat\u00e9gica en el comercio internacional de coca\u00edna, situado a lo largo de un corredor que los narcotraficantes utilizan para llegar a Buenaventura, el puerto m\u00e1s grande del pa\u00eds. La violencia se ha intensificado en el pueblo desde 2021, cuando el Clan del Golfo, el mayor cartel de la droga de Colombia, empez\u00f3 a expandirse por el territorio controlado por el Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN), el mayor grupo rebelde que queda. Cuando el Clan del Golfo recuper\u00f3 zonas alrededor de San Isidro, estallaron las tensiones. Hace dos a\u00f1os, el 10 de abril de 2022, tras varios tiroteos, un toque de queda impuesto y la desaparici\u00f3n de un aldeano, las familias huyeron del pueblo y subieron a dos autobuses que alquilaron con las pocas pertenencias que pod\u00edan llevar. Su huida les situ\u00f3 en medio de otra crisis: la del desplazamiento interno masivo. Millones de colombianos se han visto obligados a huir de sus hogares mientras el pa\u00eds se enfrenta a un conflicto que dura d\u00e9cadas y que enfrenta a las fuerzas gubernamentales con los c\u00e1rteles de la droga, los grupos armados y los paramilitares de derechas, todos ellos compitiendo por el poder y el territorio. <a href=\"https:\/\/elpais.com\/america-colombia\/2024-06-21\/esto-es-libertad-200-familias-retornan-a-sus-tierras-tras-dos-anos-hacinadas-en-un-coliseo-en-buenaventura.html\" target=\"_blank\" rel=\"noreferrer noopener\">El regreso<\/a> a su comunidad fue posible porque, seg\u00fan el gobierno, la seguridad en el Bajo Calima ha mejorado en el \u00faltimo a\u00f1o. Dennis Huffington, investigador para el Pac\u00edfico de la Fundaci\u00f3n Paz y Reconciliaci\u00f3n, afirma que esto se debe a que<a href=\"https:\/\/elpais.com\/america-colombia\/2024-03-18\/la-ambicion-de-la-paz-total-se-estrella-con-la-expansion-del-clan-del-golfo.html\" target=\"_blank\" rel=\"noreferrer noopener\"> el Clan del Golfo ha ganado la disputa<\/a> con el ELN y ha tomado el control de la regi\u00f3n, reduciendo los enfrentamientos.       <\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">SAN ISIDRO, Colombia Nacido y criado en San Isidro, con el r\u00edo y la selva como patio trasero, crec\u00ed corriendo por la playa, trepando a los \u00e1rboles y recogiendo fruta. Durante dos largos a\u00f1os, estuve desplazado de mi hogar despu\u00e9s de que unos hombres armados asaltaran nuestro pueblo. Mucha gente de mi comunidad escap\u00f3, viviendo durante dos a\u00f1os <a href=\"https:\/\/www.aljazeera.com\/news\/longform\/2024\/4\/10\/forced-from-home-these-colombians-struggle-to-live-in-a-basketball-stadium\">en un estadio deportivo<\/a> en condiciones terribles.  <\/p>\n\n<p class=\"wp-block-paragraph\">Por fin hemos podido volver a casa y a nuestra tierra -un lugar que nunca quisimos abandonar- y ahora nos enfrentamos al reto de recuperar lo que perdimos. Me esfuerzo cada d\u00eda por reconstruir mi vida, consol\u00e1ndome con que por fin puedo respirar el aire que siempre fue m\u00edo. De adulto, este suelo y lo que crece en \u00e9l se convirtieron en la fuente de mi trabajo y mi sustento.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/orato.world\/?s=Colombia\">Lea m\u00e1s reportajes sobre Colombia en Orato World Media.<\/a><\/em><\/strong><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-community-of-san-isidro-faces-the-growing-reality-their-home-was-not-their-own-anymore\"><strong>La comunidad de San Isidro se enfrenta a la creciente realidad: sus casa ya no eran suyas<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">En San Isidro aprend\u00ed a cortar madera con un hacha, golpe a golpe. Con el tiempo aprend\u00ed a utilizar la motosierra. Plant\u00e9 frutas y hortalizas para consumo propio en mi pr\u00f3diga tierra, donde todo crec\u00eda exuberantemente. En el r\u00edo, pescaba para alimentarme y entretenerme. La vida en San Isidro siempre result\u00f3 plena y satisfactoria.    <\/p>\n\n<p class=\"wp-block-paragraph\">Hace dos a\u00f1os, esa paz empez\u00f3 a desvanecerse. La selva ya no parec\u00eda un lugar seguro y la aldea se vio amenazada por nuevos peligros. Aparecieron hombres armados desconocidos. Aunque no formaban parte de nuestra comunidad, cada vez eran m\u00e1s visibles. Cuando iba a la selva a cortar le\u00f1a, su presencia me intimidaba. Creci\u00f3 un sentimiento al que no estaba acostumbrado: el miedo.     <\/p>\n\n<p class=\"wp-block-paragraph\">Hablando con los vecinos del pueblo, descubr\u00ed que muchos otros sent\u00edan lo mismo. Era como si nuestro territorio se nos estuviera escapando. Estos hombres se apoderaban de los espacios y se acercaban amenazadores, siempre con armas al hombro. Nos enteramos de que los hombres formaban grupos diferentes, enfrentados entre s\u00ed.   <\/p>\n\n<p class=\"wp-block-paragraph\">Inevitablemente, un grupo nos preguntaba por el otro. \u00ab\u00bfQu\u00e9 vieron?\u00bb, preguntaban. Nos encontramos en un callej\u00f3n sin salida. Hablar me parec\u00eda peligroso, y tambi\u00e9n lo era no decir nada. Dej\u00e9 de salir de casa, por miedo a cruzarme con alguien que no fuera mi mujer. En el lugar donde antes nos sent\u00edamos completamente libres, ahora nos sent\u00edamos abrumados.     <\/p>\n\n<p class=\"wp-block-paragraph\">La situaci\u00f3n se hizo insostenible, as\u00ed que los l\u00edderes de la comunidad se reunieron. Todos parec\u00edan asombrados por lo que sufr\u00edamos, y nadie entend\u00eda del todo lo que estaba pasando. Pero sab\u00edamos una cosa. No pod\u00edamos seguir en San Isidro.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-surrounded-by-rodents-and-insects-family-suffers-inhospitable-conditions-in-an-abandoned-sports-stadium\"><strong>Rodeada de roedores e insectos, una familia sufre condiciones inh\u00f3spitas en un estadio deportivo abandonado<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Collectively, we made the decision to leave our land and seek safety in the city. With only the clothes on our backs, we said goodbye to our homes and left our belongings behind. We boarded a chiva cargo truck and on April 10, 2022, we drove away. Looking through the window at the place I called home my whole life, it felt like something was squeezing at my heart.<\/p>\n\n<p class=\"wp-block-paragraph\">Aquella calurosa tarde, tras animarnos brevemente unos a otros, mis vecinos y yo viajamos en aquel cami\u00f3n en silencio, con la cabeza gacha. Cuando llegamos a Buenaventura, sentimos inmediatamente el impacto del cambio. Rodeados de cemento, los frutales y la exuberante naturaleza desaparecieron. Las autoridades nos llevaron al Coliseo El Cristal, un estadio deportivo abandonado. Desde fuera, parec\u00eda una mole ruinosa. No vimos signos de hospitalidad. Aparecieron familias esparcidas por lo que antes era la zona de juegos.      <\/p>\n\n<p class=\"wp-block-paragraph\">Mi mujer y yo nos instalamos en ba\u00f1o de la planta baja, el m\u00e1s alejado de la entrada principal. Viv\u00edamos entre el olor de los desechos de la gente. Acostados en un delgado colch\u00f3n en el suelo, dorm\u00edamos mal. El fr\u00edo cemento nos helaba los huesos y la dura superficie nos oprim\u00eda todo el cuerpo. Los verdaderos amos del lugar se paseaban libremente entre nosotros: cucarachas y ratas.    <\/p>\n\n<p class=\"wp-block-paragraph\">A medida que pasaba el tiempo, parec\u00eda que nunca volver\u00edamos a casa. No pod\u00edamos trabajar, consumiendo comida horrible y las condiciones de vida nos hac\u00edan enfermar. Cuando me quedaba sin gas, recog\u00eda botellas y materiales reciclables en la calle. Lo poco que ganaba me permit\u00eda comprar gas para cocinar. Me dol\u00edan los ri\u00f1ones de estar tumbada en el duro suelo y la tensi\u00f3n me sub\u00eda continuamente. A los quince d\u00edas so\u00f1aba con volver a San Isidro, pero era s\u00f3lo eso: un sue\u00f1o.     <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-returning-to-ruins-community-faces-the-hard-work-of-recovery\"><strong>De vuelta a las ruinas, la comunidad afronta la dura tarea de la recuperaci\u00f3n<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Durante los dos a\u00f1os que estuvimos encerrados en el estadio, nuestros l\u00edderes comunitarios se reunieron constantemente con la oficina del alcalde, en busca de respuestas. Un d\u00eda, los funcionarios se acercaron a nosotros. Ten\u00edan una mirada diferente: un brillo especial. Cuando nos informaron de que por fin era seguro volver a casa, estallamos en celebraci\u00f3n.   <\/p>\n\n<p class=\"wp-block-paragraph\">Abrac\u00e9 a mi mujer con fuerza, lleno de emoci\u00f3n, y not\u00e9 que, por primera vez en mucho tiempo, surg\u00edan grandes sonrisas en nuestros rostros. Mirando a mi alrededor, era una escena gloriosa, como si alguien hubiera inyectado a toda mi comunidad una dosis de alg\u00fan tipo de energizante. Aunque nuestros cuerpos y almas llevaban el peso de la tristeza y el deterioro f\u00edsico, de repente nos sent\u00edamos alegres y renovados.  <\/p>\n\n<p class=\"wp-block-paragraph\">El viernes 14 de junio de 2024, sub\u00ed tranquilo a la chiva para volver a casa. Imagin\u00e9 mi casita, la que dejamos de un momento a otro. \u00ab\u00bfC\u00f3mo se ver\u00e1 ahora?\u00bb, me preguntaba. Durante todo el viaje, unos cantaban y otros rezaban. Sin embargo, no pod\u00eda dejar de pensar: \u00ab\u00bfQu\u00e9 vamos a encontrar cuando lleguemos?\u00bb.    <\/p>\n\n<p class=\"wp-block-paragraph\">Nuestra llegada result\u00f3 agridulce. Las cosas cambiaron y me enfrent\u00e9 a un duro trabajo para volver a encarrilarnos. Mi casa, de madera, parec\u00eda en mal estado por falta de mantenimiento. La crecida del r\u00edo se llev\u00f3 muchas de nuestras cosas y esparci\u00f3 o arruin\u00f3 el resto.   <\/p>\n\n<p class=\"wp-block-paragraph\">Mi huerto, donde antes cultivaba frutas y verduras, estaba desolado. Vi los huesos esparcidos de mis perritos y las gallinas que criaba. El gallinero se convirti\u00f3 en una ruina de palos y alambres. La tristeza me invadi\u00f3 al ver lo que hab\u00eda sido de mi duro trabajo.   <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-adjusting-to-life-back-home-with-military-protection\"><strong>Adaptarse a la vida de vuelta a casa con protecci\u00f3n militar<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">A pesar de todo, al volver a San Isidro volv\u00ed a sentirme en casa. El aire libre con el que crec\u00ed llen\u00f3 mis pulmones y me sent\u00ed aliviado. Esa primera noche fue muy satisfactoria. Dorm\u00ed c\u00f3modo y contento despu\u00e9s de m\u00e1s de dos a\u00f1os.   <\/p>\n\n<p class=\"wp-block-paragraph\">Descans\u00e9 de una forma que hab\u00eda olvidado que era posible. Sin embargo, todo ese tiempo en el estadio no fue gratuito. Me segu\u00edan doliendo el cuerpo y los ri\u00f1ones. Las varices de la pierna derecha me la dejaron hinchada, lo que me imped\u00eda trabajar al mismo ritmo que antes.   <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" data-id=\"96441\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-in-his-home-in-San-Isidro-Colombia.jpg\" alt=\"\" class=\"wp-image-96441\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-in-his-home-in-San-Isidro-Colombia.jpg 960w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-in-his-home-in-San-Isidro-Colombia-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-in-his-home-in-San-Isidro-Colombia-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-in-his-home-in-San-Isidro-Colombia-533x400.jpg 533w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" data-id=\"96443\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-back-home-in-San-Isidro-Colombia.jpg\" alt=\"\" class=\"wp-image-96443\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-back-home-in-San-Isidro-Colombia.jpg 960w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-back-home-in-San-Isidro-Colombia-300x225.jpg 300w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-back-home-in-San-Isidro-Colombia-770x578.jpg 770w, https:\/\/orato.world\/wp-content\/uploads\/Pedro-Evangelista-Valois-back-home-in-San-Isidro-Colombia-533x400.jpg 533w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Pedro Evangelista Valois de vuelta a casa en San Isidro, Colombia. | <strong>Fotos cortes\u00eda de Pedro Evangelista Valois<\/strong> <\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Como puedo, sigo trabajando d\u00eda a d\u00eda, cortando la le\u00f1a que me permite el cuerpo y sembrando en la tierra. Esta tierra me alimenta como siempre lo ha hecho. Aqu\u00ed, la tierra es generosa y, si la trabajas, nunca te deja pasar hambre.  <\/p>\n\n<p class=\"wp-block-paragraph\">Una presencia militar permanece aqu\u00ed para nuestra protecci\u00f3n. Aunque me sentir\u00eda mejor si s\u00f3lo estuvi\u00e9ramos nosotros, los habitantes de San Isidro, intento acostumbrarme a nuestros protectores. Nos vigilan para evitar el regreso de los hombres armados. Aunque la vida se siente diferente a antes, es mejor estar en mi propia casa. Aqu\u00ed, donde pertenezco, puedo ser feliz.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viernes 14 de junio de 2024, sub\u00ed tranquilamente a la chiva para volver a casa. Imagin\u00e9 mi casita, la que dejamos de un momento a otro. \u00ab\u00bfQu\u00e9 aspecto tendr\u00e1 ahora?\u00bb, me preguntaba. Durante todo el viaje, unos cantaban y otros rezaban. Sin embargo, no pod\u00eda dejar de pensar: \u00ab\u00bfQu\u00e9 vamos a encontrar cuando lleguemos?\u00bb.     <\/p>\n","protected":false},"author":46,"featured_media":96439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[874],"tags":[1471,9515,9516,1682,2214,502,9125],"class_list":["post-96816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crimen-y-corrupcion-es","tag-colombia-es","tag-crimen-en-colombia","tag-desplazados-internos","tag-el-trafico-de-drogas","tag-latinoamerica","tag-refugee-es","tag-san-isidro-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una comunidad regresa a un pueblo colombiano tras dos a\u00f1os de haber sido desplazada<\/title>\n<meta name=\"description\" content=\"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de haber sido desplazados a manos de desconocidos armados\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados\" \/>\n<meta property=\"og:description\" content=\"El viernes 14 de junio de 2024, sub\u00ed tranquilamente a la chiva para volver a casa. Imagin\u00e9 mi casita, la que dejamos de un momento a otro. \u00ab\u00bfQu\u00e9 aspecto tendr\u00e1 ahora?\u00bb, me preguntaba. Durante todo el viaje, unos cantaban y otros rezaban. Sin embargo, no pod\u00eda dejar de pensar: \u00ab\u00bfQu\u00e9 vamos a encontrar cuando lleguemos?\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-13T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T14:20:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Martinez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Martinez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/\"},\"author\":{\"name\":\"Juan Martinez\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\"},\"headline\":\"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados\",\"datePublished\":\"2024-09-13T10:00:00+00:00\",\"dateModified\":\"2024-09-13T14:20:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/\"},\"wordCount\":1351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg\",\"keywords\":[\"Colombia\",\"Crimen en Colombia\",\"desplazados internos\",\"el tr\u00e1fico de drogas\",\"Latinoam\u00e9rica\",\"Refugee\",\"San Isidro\"],\"articleSection\":[\"Crimen y corrupci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/\",\"name\":\"Una comunidad regresa a un pueblo colombiano tras dos a\u00f1os de haber sido desplazada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg\",\"datePublished\":\"2024-09-13T10:00:00+00:00\",\"dateModified\":\"2024-09-13T14:20:37+00:00\",\"description\":\"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de haber sido desplazados a manos de desconocidos armados\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg\",\"width\":1067,\"height\":800,\"caption\":\"Lago Calima or Lake Calima in Colombia where the community was recently displaced by armed groups. | Photo courtesy of Juan Sebastian Aparicio on Wikimedia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/09\\\/13\\\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/1f0e64ccc9c920aa4149775a5a2bf05d\",\"name\":\"Juan Martinez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/cropped-unnamed-5-e1781599061749-96x96.jpg\",\"caption\":\"Juan Martinez\"},\"description\":\"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/juan-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una comunidad regresa a un pueblo colombiano tras dos a\u00f1os de haber sido desplazada","description":"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de haber sido desplazados a manos de desconocidos armados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/","og_locale":"es_ES","og_type":"article","og_title":"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados","og_description":"El viernes 14 de junio de 2024, sub\u00ed tranquilamente a la chiva para volver a casa. Imagin\u00e9 mi casita, la que dejamos de un momento a otro. \u00ab\u00bfQu\u00e9 aspecto tendr\u00e1 ahora?\u00bb, me preguntaba. Durante todo el viaje, unos cantaban y otros rezaban. Sin embargo, no pod\u00eda dejar de pensar: \u00ab\u00bfQu\u00e9 vamos a encontrar cuando lleguemos?\u00bb.","og_url":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-09-13T10:00:00+00:00","article_modified_time":"2024-09-13T14:20:37+00:00","og_image":[{"width":1067,"height":800,"url":"https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg","type":"image\/jpeg"}],"author":"Juan Martinez","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Juan Martinez","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/"},"author":{"name":"Juan Martinez","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d"},"headline":"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados","datePublished":"2024-09-13T10:00:00+00:00","dateModified":"2024-09-13T14:20:37+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/"},"wordCount":1351,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg","keywords":["Colombia","Crimen en Colombia","desplazados internos","el tr\u00e1fico de drogas","Latinoam\u00e9rica","Refugee","San Isidro"],"articleSection":["Crimen y corrupci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/","url":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/","name":"Una comunidad regresa a un pueblo colombiano tras dos a\u00f1os de haber sido desplazada","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg","datePublished":"2024-09-13T10:00:00+00:00","dateModified":"2024-09-13T14:20:37+00:00","description":"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de haber sido desplazados a manos de desconocidos armados","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg","width":1067,"height":800,"caption":"Lago Calima or Lake Calima in Colombia where the community was recently displaced by armed groups. | Photo courtesy of Juan Sebastian Aparicio on Wikimedia"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/09\/13\/una-comunidad-regresa-a-su-hogar-en-el-pueblo-colombiano-de-san-isidro-tras-dos-anos-de-desplazamiento-a-manos-de-hombres-armados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Una comunidad regresa a su hogar en el pueblo colombiano de San Isidro tras dos a\u00f1os de desplazamiento a manos de hombres armados"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/1f0e64ccc9c920aa4149775a5a2bf05d","name":"Juan Martinez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","url":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/cropped-unnamed-5-e1781599061749-96x96.jpg","caption":"Juan Martinez"},"description":"Journalist and broadcaster. He works in graphics and radio, and he is always looking for stories that deserve to be told. A devotee of Juan Rom\u00e1n Riquelme.","url":"https:\/\/orato.world\/es\/author\/juan-martinez\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg",1067,800,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-100x100.jpg",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-300x225.jpg",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-770x577.jpg",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-1024x768.jpg",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg",1067,800,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg",1067,800,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-534x400.jpg",534,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-360x240.jpg",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups.jpg",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Lago-Calima-or-Lake-Calima-in-Colombia-where-the-community-was-recently-displaced-by-armed-groups-500x500.jpg",500,500,true]},"uagb_author_info":{"display_name":"Juan Martinez","author_link":"https:\/\/orato.world\/es\/author\/juan-martinez\/"},"uagb_comment_info":0,"uagb_excerpt":"El viernes 14 de junio de 2024, sub\u00ed tranquilamente a la chiva para volver a casa. Imagin\u00e9 mi casita, la que dejamos de un momento a otro. \u00ab\u00bfQu\u00e9 aspecto tendr\u00e1 ahora?\u00bb, me preguntaba. Durante todo el viaje, unos cantaban y otros rezaban. Sin embargo, no pod\u00eda dejar de pensar: \u00ab\u00bfQu\u00e9 vamos a encontrar cuando lleguemos?\u00bb.","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=96816"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96816\/revisions"}],"predecessor-version":[{"id":96817,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/96816\/revisions\/96817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/96439"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=96816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=96816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=96816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}