{"id":97765,"date":"2024-10-08T03:00:00","date_gmt":"2024-10-08T10:00:00","guid":{"rendered":"https:\/\/orato.world\/?p=97765"},"modified":"2024-10-04T17:28:27","modified_gmt":"2024-10-05T00:28:27","slug":"una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/","title":{"rendered":"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Sergio-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Sergio-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Sergio-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Sergio.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">notas del periodista<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"> <a href=\"https:\/\/www.instagram.com\/mboi_jagua\/?hl=en\">Sergio Ant\u00fanez Rossi<\/a> es veterinario, especialista en ofidios y apasionado de la naturaleza. Su profundo amor por los reptiles le ha llevado por todo el mundo, donde trabaja para concienciar y rescatar a estas extraordinarias criaturas. Con m\u00e1s de 30.000 seguidores en Instagram, el p\u00fablico de Sergio espera con impaciencia su pr\u00f3xima aventura y proyecto.   <\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\"> La anaconda verde (Eunectes murinus), una de las serpientes m\u00e1s grandes del mundo, puede alcanzar los 10 metros de longitud. Su cuerpo gris verdoso, con manchas oscuras en el lomo y los flancos, y su vientre blanco amarillento la hacen inconfundible. Esta constrictora no venenosa se encuentra en r\u00edos, pantanos y selvas tropicales de toda Sudam\u00e9rica, incluidos Venezuela, Colombia, Per\u00fa y Brasil. M\u00e1s informaci\u00f3n sobre las fascinantes caracter\u00edsticas y h\u00e1bitat de la anaconda verde en este art\u00edculo de <a href=\"https:\/\/www.nationalgeographic.es\/animales\/2024\/02\/anaconda-secreto-serpiente-mas-pesada-mundo#:~:text=Las%20anacondas%20verdes%2C%20aut%C3%B3ctonas%20de,enormes%2C%20como%20capibaras%20y%20jaguares\">National Geographic.<\/a>   <\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">AMAZONAS, Per\u00fa &#8211; Me adentr\u00e9 en el Amazonas con un \u00fanico objetivo: encontrar a la legendaria anaconda verde en su h\u00e1bitat natural. Despu\u00e9s de a\u00f1os de encontrarme con serpientes y recopilar innumerables historias, este momento se me antoj\u00f3 ic\u00f3nico e inolvidable. Por fin me hab\u00eda encontrado cara a cara con uno de los espec\u00edmenes m\u00e1s grandes que jam\u00e1s hab\u00eda visto.  <\/p>\n\n<p class=\"wp-block-paragraph\">El encuentro fue extraordinario. Avistar una anaconda tan grande fue pura suerte. Los avistamientos de este tama\u00f1o son extremadamente raros. Este descubrimiento consolid\u00f3 mi relaci\u00f3n de por vida con estas extraordinarias criaturas.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em><a href=\"https:\/\/orato.world\/es\/category\/medio-ambiente\/\">Lea m\u00e1s historias sobre medio ambiente en Orato World Media.<\/a><\/em><\/strong><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-an-early-fascination-with-reptiles\"><strong>Una temprana fascinaci\u00f3n por los reptiles<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Desde muy joven me gustaron los animales y las aventuras en la naturaleza. Mi madre me encontraba a menudo sumergida en el monte o a orillas del r\u00edo en mi Chaco natal. Desde los cuatro a\u00f1os, la flora y la fauna me serv\u00edan de patio de recreo mientras inventaba historias y observaba animales e insectos en la verde naturaleza que me rodeaba. A los 10 a\u00f1os, mi cu\u00f1ado trajo a casa una serpiente. Tocarla por primera vez me transform\u00f3 por completo.    <\/p>\n\n<p class=\"wp-block-paragraph\">En 2001, a los 13 a\u00f1os, mis padres me sorprendieron con un viaje a \u00c1frica. Volamos a Sud\u00e1frica y vivimos momentos inolvidables rodeados de animales salvajes, abri\u00e9ndome un mundo que nunca quise abandonar. Recuerdo una visita a un santuario de serpientes donde me encontr\u00e9 cara a cara con una mamba negra.   <\/p>\n\n<p class=\"wp-block-paragraph\">Hab\u00eda visto la serpiente innumerables veces en libros y documentales, pero nunca de cerca. Apretando la cara contra el fr\u00edo cristal del tanque, me maravill\u00e9 con cada detalle. El color, el movimiento y los ojos de la serpiente me cautivaron. Ese mismo viaje me dio la oportunidad de manipular una pit\u00f3n. Sentir su fuerza mientras me rodeaba el brazo me dej\u00f3 extasiado.    <\/p>\n\n<p class=\"wp-block-paragraph\">Cuando volv\u00ed a casa, mi fascinaci\u00f3n por las serpientes se intensific\u00f3. Compr\u00e9 m\u00e1s libros, vi documentales interminables y adquir\u00ed varias especies a medida que mi pasi\u00f3n crec\u00eda d\u00eda a d\u00eda. Pronto trac\u00e9 el mapa de cinco destinos de ensue\u00f1o. Quer\u00eda explorar los entornos de las especies de serpientes m\u00e1s emblem\u00e1ticas de Australia, \u00c1frica, el Sudeste Asi\u00e1tico, el Amazonas y la India. Hoy tengo la suerte de haberlas conocido todas. Mi pasi\u00f3n por estos animales me inspir\u00f3 para estudiar veterinaria con especializaci\u00f3n en ofidios. Pronto busqu\u00e9 destinos donde poder observar y rescatar distintas especies de serpientes de todo el mundo. Esto me abri\u00f3 las puertas a una experiencia vital incre\u00edble.       <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-interacting-with-snakes-reveals-a-new-universe\"><strong>Interactuar con serpientes revela un nuevo universo<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Cada destino que visito en pos de grabar serpientes e interactuar con ellas me revela un universo nuevo. En la India, recuerdo v\u00edvidamente tener en la mano una peque\u00f1a cobra de anteojos, rompiendo todo tipo de barreras personales. En Indonesia, form\u00e9 equipo con Reptile Rescue para reubicar huevos de cobra rey, una de las serpientes m\u00e1s venenosas e inteligentes del mundo. Retiramos cuidadosamente los huevos del nido de su madre, garantizando su seguridad y minimizando los da\u00f1os. Cada experiencia profundiz\u00f3 mi conexi\u00f3n con estas fascinantes criaturas.    <\/p>\n\n<p class=\"wp-block-paragraph\">Las cobras rey pasan la mayor parte del a\u00f1o en lo alto de las monta\u00f1as sin apenas contacto con los humanos. Sin embargo, durante la \u00e9poca de cr\u00eda, descienden a los valles para construir nidos, algo que no hace ninguna otra especie de serpiente. Durante 70 d\u00edas, la madre se enrosca alrededor de sus huevos, volvi\u00e9ndose extremadamente vulnerable y agresiva. Por desgracia, durante este tiempo, los aldeanos suelen quemar sus nidos y matarlas por miedo.   <\/p>\n\n<p class=\"wp-block-paragraph\">Rescatar y reubicar sus huevos se convierte en algo cr\u00edtico. Me un\u00ed a los expertos en estas operaciones y observ\u00e9 atentamente c\u00f3mo manipulaban a las madres cobra rey, de casi cinco metros de largo, que estaban en modo de defensa total. Fue una experiencia impactante y sobrecogedora a la vez. Mientras retiraban con cuidado a las madres, reubicamos cuidadosamente los huevos en zonas seguras, asegur\u00e1ndonos de que permanec\u00edan cerca de sus madres pero fuera de peligro inmediato.   <\/p>\n\n<p class=\"wp-block-paragraph\">A lo largo de los a\u00f1os, mi pasi\u00f3n por los reptiles me llev\u00f3 por todo el mundo, desde las densas selvas de Asia hasta los desiertos de Australia. Explor\u00e9 Estados Unidos, las selvas de Colombia y Brasil, y casi todos los rincones de Latinoam\u00e9rica. Pero el coraz\u00f3n del Amazonas, por donde vaga la anaconda gigante, segu\u00eda siendo mi m\u00e1ximo sue\u00f1o.  <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-journey-to-the-peruvian-amazon-in-search-of-the-giant-anaconda\"><strong>Viaje a la Amazonia peruana: en busca de la anaconda gigante<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Finalmente, vol\u00e9 a Per\u00fa y me adentr\u00e9 en el sur del Amazonas, en la regi\u00f3n conocida como Madre de Dios. Los avistamientos de serpientes siguieron siendo escasos debido a los vientos fr\u00edos de las monta\u00f1as o friaje. Durante el d\u00eda segu\u00eda haciendo calor, pero las temperaturas bajaban por la noche. A medida que me adentraba en la selva, me topaba con un n\u00famero incre\u00edble de especies: grandes migraciones de hormigas, serpientes, ara\u00f1as, escorpiones, avispas, abejas e incluso jaguares. Cada paso requer\u00eda una intensa concentraci\u00f3n y exig\u00eda respeto a cada paso.    <\/p>\n\n<p class=\"wp-block-paragraph\">La b\u00fasqueda de una anaconda se realiza durante el d\u00eda, a diferencia de otras serpientes, que suelen encontrarse por la noche con linternas. Las anacondas pueden verse a menudo tomando el sol en las orillas del r\u00edo, por lo que el d\u00eda es el mejor momento para rastrearlas. Tras seis d\u00edas de intenso senderismo, s\u00f3lo encontramos una serpiente diminuta, de apenas 10 cent\u00edmetros.  <\/p>\n\n<p class=\"wp-block-paragraph\">Frustrado pero decidido, me fui y vol\u00e9 al coraz\u00f3n del Amazonas, a la legendaria Iquitos. All\u00ed pas\u00e9 cuatro d\u00edas en plena selva. En una de nuestras cacer\u00edas de anacondas, navegamos durante 10 horas por el r\u00edo Tahuayo, afluente del Amazonas. Me mantuve alerta, empap\u00e1ndome del ambiente, respirando el aire de la selva y capturando cada momento con mi c\u00e1mara.   <\/p>\n\n<p class=\"wp-block-paragraph\">Nos avisaron de un posible avistamiento de una enorme anaconda en la zona, as\u00ed que seguimos la pista. Viajar por el Amazonas era como adentrarse en un reino completamente distinto. Los r\u00edos, grandes y peque\u00f1os, serpentean por la espesa e imponente selva, creando un laberinto interminable de agua y \u00e1rboles. La energ\u00eda de la selva era palpable. Rebosaba de vida, desde microorganismos hasta \u00e1rboles de 30 a 40 metros de altura.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-mythical-m-boi-jagua-as-we-reached-the-bank-of-one-of-the-river-branches-i-saw-it-giant-and-coiled\"><strong>El m\u00edtico M&#8217;boi Jagu\u00e1: \u00abAl llegar a la orilla de uno de los brazos del r\u00edo, la vi: gigante y enroscada\u00bb.<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Navegamos entre la niebla y finalmente cambiamos a una embarcaci\u00f3n m\u00e1s peque\u00f1a para adentrarnos r\u00edo arriba durante otras dos o tres horas. Entrar en este entorno era como sumergirse en un universo h\u00famedo y vivo rebosante de biodiversidad. Todo parec\u00eda vivo: las enormes hojas, el aire empapado de agua y el propio suelo. A medida que me adentraba en la selva, mi mente bull\u00eda con mil posibilidades.    <\/p>\n\n<p class=\"wp-block-paragraph\">Recorr\u00ed todos los escenarios, analizando todas las variables, desde mi primer movimiento al encontrarme con la serpiente hasta c\u00f3mo podr\u00eda desarrollarse toda la interacci\u00f3n. Una cosa estaba clara: no quer\u00eda vivir el t\u00edpico encuentro en el que agarro a la serpiente por el cuello para evitar que me muerda o escape. Mi objetivo era interactuar con la anaconda respetando su espacio, minimizando el estr\u00e9s y evitando cualquier confrontaci\u00f3n.   <\/p>\n\n<p class=\"wp-block-paragraph\">Mis pensamientos se revolv\u00edan mientras elaboraba innumerables escenarios sobre c\u00f3mo lograr este encuentro pac\u00edfico. De repente, detectamos se\u00f1ales de la presencia de la anaconda. Cuando llegamos a la orilla de uno de los brazos del r\u00edo, la vi: gigante y enroscada. Parec\u00eda impresionante. All\u00ed estaba, la reina del Amazonas, la legendaria y m\u00edtica M&#8217;boi Jagu\u00e1.     <\/p>\n\n<p class=\"wp-block-paragraph\">Me sent\u00ed euf\u00f3rico. Una descarga de adrenalina me invadi\u00f3, inundando mis sentidos. En ese momento, volv\u00ed a sentirme como un ni\u00f1o, perdido en la magia de una nueva aventura. Afortunadamente, parec\u00eda tranquila, tomando el sol, acababa de comer. Esta hembra adulta probablemente estaba digiriendo un carpincho u otro mam\u00edfero de la zona. Su quietud nos brind\u00f3 la rara oportunidad de observarla en su h\u00e1bitat natural sin molestarla.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-a-creature-of-immense-power-colossal-anaconda-a-little-over-six-meters-long-and-weighing-around-100-kilos\"><strong>Una criatura de inmenso poder: anaconda colosal, de algo m\u00e1s de seis metros de largo y unos 100 kilos de peso.<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Si no acabara de comer, la habr\u00edamos pasado por alto f\u00e1cilmente. Cuando cazan, las anacondas se vuelven casi invisibles, perfectamente camufladas con su entorno. Tras una cacer\u00eda exitosa, ya no pueden sumergirse debido a su mayor peso. En su lugar, se asolean para digerir a sus presas, dej\u00e1ndolas expuestas y sin esconderse. Ante m\u00ed, contempl\u00e9 la colosal anaconda, de poco m\u00e1s de seis metros de largo y unos 100 kilos de peso, quiz\u00e1 m\u00e1s.     <\/p>\n\n<p class=\"wp-block-paragraph\">No pod\u00eda dejar de mirar a esta sobrecogedora criatura, una aut\u00e9ntica maravilla de la naturaleza. Era inmensamente musculosa, la mayor de las especies de boa y la segunda serpiente m\u00e1s grande del mundo. La observ\u00e9 durante un rato antes de decidirme a meterme en el r\u00edo y ba\u00f1arme a escasos cent\u00edmetros de ella. Me emocion\u00e9. El miedo nunca se me pas\u00f3 por la cabeza; entend\u00eda el comportamiento y los l\u00edmites de la anaconda, y apliqu\u00e9 ese conocimiento en mi interacci\u00f3n. S\u00f3lo ten\u00eda que mantenerme alerta y acercarme con respeto, con cuidado de no molestarla.      <\/p>\n\n<p class=\"wp-block-paragraph\">Si se sobresaltaba, pod\u00eda regurgitar su presa, lo que habr\u00eda sido desastroso. Mir\u00e9 su poderosa cabeza y vi su innegable fuerza. Si no hubiera comido recientemente, cualquier intento de manipularla podr\u00eda resultar fatal. La anaconda pod\u00eda envolverme la cabeza con facilidad y yo carec\u00eda de fuerzas para escapar. Sus cien dientes curvados hacia atr\u00e1s me causar\u00edan graves heridas si me mordiera. Esta especie es capaz de extender sus mand\u00edbulas lo suficiente como para rodear los hombros de un humano adulto: una criatura de inmenso poder.     <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-a-rare-glimpse-into-the-mysterious-world-of-amazonian-wildlife\"><strong>Un vistazo al misterioso mundo de la fauna amaz\u00f3nica<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">El gu\u00eda que estaba a mi lado me miraba con los ojos muy abiertos y una sonrisa indescriptible. Llevaba 10 a\u00f1os en la Amazonia peruana y era la primera vez que ve\u00eda un ejemplar tan enorme. Me siento privilegiado por dedicar mi vida a coleccionar experiencias \u00fanicas que muy pocos vivir\u00e1n. Aunque mis viajes son siempre en busca de serpientes, estar inmerso en la naturaleza me ense\u00f1a algo nuevo cada vez, me permite interactuar con el entorno y con las innumerables especies que viven en \u00e9l.    <\/p>\n\n<p class=\"wp-block-paragraph\">Aunque me enfrento a situaciones peligrosas y experimento situaciones cercanas -como ser mordido o evitar por poco la mordedura de varias serpientes-, siempre consigo escapar del verdadero riesgo. Hasta ahora, nunca he utilizado antiveneno en ninguna de mis experiencias, aunque sigue siendo un riesgo que asumo de buen grado. Conozco el peligro, pero prefiero confiar en mis conocimientos y mi experiencia. S\u00e9 lo cerca que puedo estar sin peligro y c\u00f3mo interpretar el comportamiento de cada especie.    <\/p>\n\n<p class=\"wp-block-paragraph\">Hay ciertas serpientes que no intentar\u00e9 manipular. Pronto continuar\u00e9 mis aventuras explorando los Esteros del Iber\u00e1 argentinos, el Impenetrable Chaque\u00f1o y el Chaco paraguayo. El a\u00f1o que viene tengo previsto aventurarme en Surinam y las Guayanas. Mirando al futuro a largo plazo, mi objetivo es Pap\u00faa Nueva Guinea, un lugar remoto, extremo y peligroso, hogar de animales salvajes y tribus can\u00edbales como los korowai.    <\/p>\n\n<p class=\"wp-block-paragraph\">Estas experiencias suelen estar lejos de los destinos tur\u00edsticos, y algunos exploradores incluso han desaparecido al intentar viajar a Pap\u00faa Nueva Guinea. A algunos quiz\u00e1 les parezca una locura, pero para m\u00ed el riesgo merece la pena. Aventurarme a lo desconocido, descubrir lo que esconde la selva y encontrarme con las especies m\u00e1s emblem\u00e1ticas del mundo es el camino que elijo seguir.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante m\u00ed, contempl\u00e9 la colosal anaconda, de poco m\u00e1s de seis metros de largo y unos 100 kilos de peso, quiz\u00e1 m\u00e1s. No pod\u00eda apartar los ojos de esta sobrecogedora criatura, una aut\u00e9ntica maravilla de la naturaleza. Era inmensamente musculosa, la mayor de las especies de boa y la segunda serpiente m\u00e1s grande del mundo. La observ\u00e9 durante un rato antes de decidirme a saltar al r\u00edo y nadar a escasos cent\u00edmetros de ella.   <\/p>\n","protected":false},"author":28,"featured_media":97497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[725,319],"tags":[5707,9623,9625,5453,6144,2214,6200,9624,7134],"class_list":["post-97765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-medio-ambiente","tag-amazon-es","tag-amazonas-es","tag-anaconda-es","tag-aventura","tag-junga","tag-latinoamerica","tag-peru-es","tag-serpiente","tag-vida-salvaje"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una expedici\u00f3n al Amazonas: un aventurero descubre la colosal Anaconda<\/title>\n<meta name=\"description\" content=\"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana, el esp\u00e9cimen alcanz\u00f3 los seis metros de longitud\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana\" \/>\n<meta property=\"og:description\" content=\"Ante m\u00ed, contempl\u00e9 la colosal anaconda, de poco m\u00e1s de seis metros de largo y unos 100 kilos de peso, quiz\u00e1 m\u00e1s. No pod\u00eda apartar los ojos de esta sobrecogedora criatura, una aut\u00e9ntica maravilla de la naturaleza. Era inmensamente musculosa, la mayor de las especies de boa y la segunda serpiente m\u00e1s grande del mundo. La observ\u00e9 durante un rato antes de decidirme a saltar al r\u00edo y nadar a escasos cent\u00edmetros de ella.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mariela Laksman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariela Laksman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/\"},\"author\":{\"name\":\"Mariela Laksman\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\"},\"headline\":\"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana\",\"datePublished\":\"2024-10-08T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/\"},\"wordCount\":2024,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Anaconda.png\",\"keywords\":[\"amazon\",\"Amazonas\",\"Anaconda\",\"aventura\",\"junga\",\"Latinoam\u00e9rica\",\"peru\",\"Serpiente\",\"Vida salvaje\"],\"articleSection\":[\"Educaci\u00f3n\",\"Medio ambiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/\",\"name\":\"Una expedici\u00f3n al Amazonas: un aventurero descubre la colosal Anaconda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Anaconda.png\",\"datePublished\":\"2024-10-08T10:00:00+00:00\",\"description\":\"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana, el esp\u00e9cimen alcanz\u00f3 los seis metros de longitud\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Anaconda.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/Anaconda.png\",\"width\":1280,\"height\":960,\"caption\":\"Sergio Ant\u00fanez Rossi face-to-face with a colossal green anaconda. | Photo courtesy of Sergio Ant\u00fanez Rossi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/08\\\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\",\"name\":\"Mariela Laksman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariela Laksman\"},\"description\":\"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \\\"Nuevo Sudaca Border\\\" with the microfiction book \\\"Un Tigre con la Boca Abierta\\\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariela-laksman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una expedici\u00f3n al Amazonas: un aventurero descubre la colosal Anaconda","description":"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana, el esp\u00e9cimen alcanz\u00f3 los seis metros de longitud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/","og_locale":"es_ES","og_type":"article","og_title":"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana","og_description":"Ante m\u00ed, contempl\u00e9 la colosal anaconda, de poco m\u00e1s de seis metros de largo y unos 100 kilos de peso, quiz\u00e1 m\u00e1s. No pod\u00eda apartar los ojos de esta sobrecogedora criatura, una aut\u00e9ntica maravilla de la naturaleza. Era inmensamente musculosa, la mayor de las especies de boa y la segunda serpiente m\u00e1s grande del mundo. La observ\u00e9 durante un rato antes de decidirme a saltar al r\u00edo y nadar a escasos cent\u00edmetros de ella.","og_url":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-10-08T10:00:00+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png","type":"image\/png"}],"author":"Mariela Laksman","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariela Laksman","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/"},"author":{"name":"Mariela Laksman","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90"},"headline":"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana","datePublished":"2024-10-08T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/"},"wordCount":2024,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png","keywords":["amazon","Amazonas","Anaconda","aventura","junga","Latinoam\u00e9rica","peru","Serpiente","Vida salvaje"],"articleSection":["Educaci\u00f3n","Medio ambiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/","url":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/","name":"Una expedici\u00f3n al Amazonas: un aventurero descubre la colosal Anaconda","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png","datePublished":"2024-10-08T10:00:00+00:00","description":"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana, el esp\u00e9cimen alcanz\u00f3 los seis metros de longitud","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png","width":1280,"height":960,"caption":"Sergio Ant\u00fanez Rossi face-to-face with a colossal green anaconda. | Photo courtesy of Sergio Ant\u00fanez Rossi"},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/10\/08\/una-expedicion-al-amazonas-un-aventurero-descubre-una-colosal-anaconda-verde-en-la-indomita-selva-peruana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Una expedici\u00f3n al Amazonas: un aventurero descubre una colosal Anaconda verde en la ind\u00f3mita selva peruana"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90","name":"Mariela Laksman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariela Laksman"},"description":"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \"Nuevo Sudaca Border\" with the microfiction book \"Un Tigre con la Boca Abierta\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.","url":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/Anaconda-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Mariela Laksman","author_link":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"},"uagb_comment_info":0,"uagb_excerpt":"Ante m\u00ed, contempl\u00e9 la colosal anaconda, de poco m\u00e1s de seis metros de largo y unos 100 kilos de peso, quiz\u00e1 m\u00e1s. No pod\u00eda apartar los ojos de esta sobrecogedora criatura, una aut\u00e9ntica maravilla de la naturaleza. Era inmensamente musculosa, la mayor de las especies de boa y la segunda serpiente m\u00e1s grande del mundo.&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/97765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=97765"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/97765\/revisions"}],"predecessor-version":[{"id":97766,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/97765\/revisions\/97766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/97497"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=97765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=97765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=97765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}