{"id":98871,"date":"2024-10-23T03:00:00","date_gmt":"2024-10-23T10:00:00","guid":{"rendered":"https:\/\/orato.world\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/"},"modified":"2024-10-24T09:28:37","modified_gmt":"2024-10-24T16:28:37","slug":"un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria","status":"publish","type":"post","link":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/","title":{"rendered":"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria"},"content":{"rendered":"<div class=\"lets-info-up-wrap  lets-info-up--right lets-info-up--m-1 lets-info-up-skin-1 lets-info-up--side\">\t\t\t<div class=\"lets-info-up\">\r\n\t\t\t<div class=\"lets-info-up-fi\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-500x500.png\" class=\"attachment-lets-info-up-d1 size-lets-info-up-d1\" alt=\"Dr. Lubna Al-Azaizeh&#039;s provides care at temporary clinic.\" srcset=\"https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-500x500.png 500w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-300x300.png 300w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-1024x1024.png 1024w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-100x100.png 100w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-770x770.png 770w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-400x400.png 400w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-150x150.png 150w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-70x70.png 70w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor-293x293.png 293w, https:\/\/orato.world\/wp-content\/uploads\/Gaza-doctor.png 1080w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div>\t\t\t<div class=\"lets-info-up-block-wrap\">\r\n\t\t\t\t<div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">notas del periodista<\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Protagonista<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">La Dra. Lubna Al-Azaizeh es pediatra y especialista en lactancia materna con m\u00e1s de 20 a\u00f1os de experiencia. Desde junio, junto a un entregado equipo de m\u00e9dicos y enfermeras, ha establecido una cl\u00ednica m\u00e9dica autofinanciada en una tienda de campa\u00f1a junto a su casa, ahora destruida. La cl\u00ednica ofrece atenci\u00f3n m\u00e9dica gratuita a los necesitados y es un salvavidas vital para la comunidad.<br>Gracias a diversas campa\u00f1as, la cl\u00ednica ha recibido algunos recursos para seguir funcionando, pero la creciente demanda de asistencia m\u00e9dica requiere cada d\u00eda m\u00e1s apoyo.  <\/div><\/div><div class=\"lets-info-up-block lets-info-up-meta-block\"><div class=\"lets-info-up-meta-title lets-info-up-pretitle font-h\">Contexto<\/div><div class=\"lets-info-up-meta-content lets-info-up-title font-b\">El cierre del paso fronterizo de Rafah, un punto de entrada vital para la ayuda humanitaria, est\u00e1 afectando gravemente a la entrega de suministros esenciales, dejando combustible, alimentos, medicinas y agua peligrosamente escasos mientras la poblaci\u00f3n sigue atrapada en medio de nuevos combates. Este punto de acceso clave, que sirve de salvavidas para toda la Franja de Gaza, ha sido completamente cerrado hasta nuevo aviso, poniendo en peligro la respuesta humanitaria.<br>Para m\u00e1s detalles, lea el informe completo de <a href=\"https:\/\/www.savethechildren.es\/notasprensa\/el-cierre-de-rafah-pone-en-peligro-la-vida-de-un-millon-de-ninos-y-ninas-en-gaza\">Save the Children aqu\u00ed<\/a>. <\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\n<p class=\"wp-block-paragraph\">DEIR AL-BALAH, Gaza &#8211; Antes trabajaba en el hospital Kamal Adwan, especializado en cuidados intensivos, urgencias y reci\u00e9n nacidos. Cuando los tanques israel\u00edes aislaron el norte de Gaza del sur del enclave asediado, como la mayor\u00eda de los m\u00e9dicos, me adapt\u00e9. Ahora, trato a los pacientes en una tienda de campa\u00f1a junto a mi casa destruida.  <\/p>\n\n<p class=\"wp-block-paragraph\"><em><strong><a href=\"https:\/\/orato.world\/?s=gaza\">Ver m\u00e1s reportajes sobre Gaza en Orato World Media.<\/a><\/strong><\/em><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-the-day-the-bomb-hit-the-situation-feels-miserable-and-exhausting\"><strong>El d\u00eda que estall\u00f3 la bomba: \u00abLa situaci\u00f3n se siente miserable y agotadora\u00bb<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Pocos d\u00edas despu\u00e9s del comienzo de la guerra, el 7 de octubre de 2023, mi familia y yo o\u00edmos un agudo silbido seguido de una explosi\u00f3n ensordecedora. Milagrosamente, la \u00fanica habitaci\u00f3n de nuestra casa que qued\u00f3 en pie fue la que ocup\u00e1bamos. Todo el piso de arriba estaba en ruinas. Mis hijos se cubrieron instintivamente la cabeza con sus bracitos.    <\/p>\n\n<p class=\"wp-block-paragraph\">Salimos corriendo, rodeados de humo y escombros. Varios miembros de la familia sufrieron heridas graves. Un peso asfixiante me oprim\u00eda el pecho mientras mis hijos me miraban conmocionados. Nos trasladamos temporalmente a casa de mi t\u00eda, pero pronto volvimos a la \u00fanica habitaci\u00f3n intacta entre los escombros.   <\/p>\n\n<p class=\"wp-block-paragraph\">Los hospitales, desbordados, s\u00f3lo daban prioridad a los casos m\u00e1s cr\u00edticos, incapaces de atender a todo el mundo. Mi equipo y yo empezamos r\u00e1pidamente a visitar los campos de desplazados, ofreciendo ayuda a madres desnutridas y ancianos. Nos encontramos con anemia generalizada, enfermedades cut\u00e1neas y problemas respiratorios causados por la hambruna derivada del bloqueo.  <\/p>\n\n<p class=\"wp-block-paragraph\">Armados con bolsas de medicamentos, mi equipo y yo comprobamos los niveles de az\u00facar en sangre, medimos la tensi\u00f3n arterial y visitamos a las familias para evaluar sus necesidades. Dada la situaci\u00f3n, establecimos una cl\u00ednica de campa\u00f1a a la entrada de mi casa en ruinas y bautizamos la iniciativa como \u00abUstedes son nuestra familia\u00bb. Completamente autogestionada, la cl\u00ednica presta servicios m\u00e9dicos gratuitos a todo el mundo.  <\/p>\n\n<p class=\"wp-block-paragraph\">Remitimos los casos graves a los hospitales, pero las mujeres y las ni\u00f1as sufren especialmente por la falta de suministros menstruales. Algunas utilizan trapos o trozos de pa\u00f1ales de beb\u00e9, ya que los art\u00edculos esenciales no est\u00e1n disponibles o son inasequibles. Muchas familias, a menudo con seis o m\u00e1s hijos, luchan sin ingresos. La ayuda no llega a todos. La situaci\u00f3n es miserable y agotadora.    <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-hygiene-products-and-medications-remain-scarce-in-gaza\"><strong>Los productos de higiene y los medicamentos siguen escaseando en Gaza<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Los productos de higiene personal siguen siendo escasos y caros, una lucha a la que yo tambi\u00e9n me enfrento. Durante un tiempo, no pude dar champ\u00fa ni jab\u00f3n a mis hijos porque sencillamente no estaban disponibles. La falta de higiene, combinada con el colapso de la recogida de basuras y el tratamiento de las aguas residuales, aliment\u00f3 la propagaci\u00f3n de enfermedades como la sarna, las infecciones f\u00fangicas y otras afecciones cut\u00e1neas. Como m\u00e9dicos, nos encontramos con algunas de estas afecciones por primera vez.   <\/p>\n\n<p class=\"wp-block-paragraph\">Sin agua potable ni medicamentos eficaces, las infecciones se propagan. Las picaduras de mosquitos empeoran la situaci\u00f3n. Las enfermedades contagiosas prosperan en las condiciones de hacinamiento de los campos de desplazados. El bloqueo provoc\u00f3 un colapso en la recogida de residuos y el tratamiento de las aguas residuales, lo que agrav\u00f3 la crisis sanitaria. El sistema de gesti\u00f3n de residuos s\u00f3lidos de Gaza se desmorona. Antes de la guerra, Gaza contaba con dos vertederos. Ahora esos vertederos permanecen inaccesibles, con 10 emplazamientos provisionales para sustituirlos. Sin embargo, surgieron cientos de vertederos informales.        <\/p>\n\n<p class=\"wp-block-paragraph\">Vemos c\u00f3mo esos lugares provisionales se convierten en grandes charcos de desechos humanos y basura. La gente monta tiendas de campa\u00f1a cerca de los emplazamientos, creando una grave emergencia de salud p\u00fablica. Los campamentos de tiendas se extienden ahora m\u00e1s de 16 kil\u00f3metros a lo largo de la costa de Gaza, llenando playas, terrenos bald\u00edos, campos y calles de la ciudad. Las familias cavan zanjas para construir retretes improvisados, mientras los padres buscan comida y agua. Los ni\u00f1os rebuscan entre los escombros madera o cart\u00f3n para cocinar. La situaci\u00f3n empeora a veces con 20 personas por tienda, sin acceso a agua potable ni electricidad.     <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-children-become-the-primary-victims-in-gaza\"><strong>Los ni\u00f1os se convierten en las principales v\u00edctimas en Gaza<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Algunas personas que sufren escasez de agua lavan a sus hijos con agua salada del Mediterr\u00e1neo. Las moscas pululan por todas partes y los ni\u00f1os juegan en la arena llena de basura. La tragedia parece abrumadora. Entre las tiendas, la gente se instala en estructuras de bloques de cemento, mientras que los afortunados encuentran refugio en escuelas, hospitales o garajes. Vivir con tales molestias y enfermedades sin estar en casa o en un hospital los destroza.    <\/p>\n\n<p class=\"wp-block-paragraph\">Mis pacientes me dicen que no pueden describir el dolor del desplazamiento constante y la p\u00e9rdida de seres queridos. Los destruye mentalmente. Ante la inasequibilidad de los medicamentos esenciales y la disminuci\u00f3n de la ayuda internacional, pedimos urgentemente la reapertura de la frontera de Rafah para aliviar el agravamiento de la crisis humanitaria. Los ni\u00f1os son las principales v\u00edctimas de Gaza. Esquivan las bombas, huyen por calles llenas de escombros y carecen de necesidades b\u00e1sicas como alimentos y agua potable. Obligados a dormir a la intemperie, experimentan una conmoci\u00f3n y un dolor sin precedentes.      <\/p>\n\n<p class=\"wp-block-paragraph\">Esta guerra, junto con las cicatrices f\u00edsicas y mentales que deja, erosiona su resiliencia a una escala devastadora. Recuerdo v\u00edvidamente a una madre que me contaba c\u00f3mo la salud mental de su hijo menor se hab\u00eda resquebrajado por completo. Cuando trabajo con ni\u00f1os, observo el mismo patr\u00f3n. Muestran miedo, ira y l\u00e1grimas incontrolables. Muchos adultos se ven afectados de forma similar. A veces, el peso de todo es tan abrumador que tengo que salir de la tienda para recuperar el aliento antes de poder continuar. Somos testigos de constantes bombas, balas, muerte, hambre, enfermedad y miseria. Mi hijo ya puede identificar diferentes tipos de explosivos por el sonido.       <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-survivor-stories-in-gaza-often-end-in-tragedy\"><strong>Las historias de supervivientes en Gaza suelen acabar en tragedia<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Hoy clasificamos a los ni\u00f1os como \u00abni\u00f1o herido, sin familia superviviente\u00bb. Muchas historias de supervivientes acaban en tragedia, como la de la ni\u00f1a de 12 a\u00f1os que perdi\u00f3 una pierna, a sus padres y a sus hermanos en un ataque a\u00e9reo, para luego perder la vida cuando un tanque del ej\u00e9rcito israel\u00ed bombarde\u00f3 el hospital. Recuerdo a un ni\u00f1o de dos a\u00f1os que sobrevivi\u00f3 a tres ataques a\u00e9reos que mataron a su madre y a su hermana.  <\/p>\n\n<p class=\"wp-block-paragraph\">Las madres embarazadas soportan un inmenso sufrimiento, a menudo dando a luz en tiendas de campa\u00f1a, calles o aseos p\u00fablicos. Algunas vieron morir a sus reci\u00e9n nacidos en sus brazos. Recuerdo a una madre que huy\u00f3 de su casa estando embarazada de seis meses, con un ni\u00f1o de 18 meses. Su peque\u00f1o se desnutri\u00f3 y, cuando lo vi, su cuerpo parec\u00eda esquel\u00e9tico.   <\/p>\n\n<p class=\"wp-block-paragraph\">Recuerdo a una ni\u00f1a sollozando mientras su madre me mostraba c\u00f3mo manchas rojas y blancas se extend\u00edan desde su cara hasta su pecho. Otra madre levant\u00f3 la ropa de su hijo, revelando erupciones en su cuerpo, con llagas abiertas en sus mu\u00f1ecas por rascarse. Un padre puso a su hija sobre una mesa para mostrarme las lesiones de sus pantorrillas, que desprend\u00edan un olor p\u00fatrido.  <\/p>\n\n<p class=\"wp-block-paragraph\">Un caso reciente me afect\u00f3 profundamente. Un ni\u00f1o de cinco a\u00f1os se aferr\u00f3 a su padre tras ser sacado de los escombros de un bombardeo. El ni\u00f1o fue sometido a cinco intervenciones quir\u00fargicas despu\u00e9s de que su cerebro se desplazara debido a la explosi\u00f3n, pero sobrevivi\u00f3 tras recibir reanimaci\u00f3n cardiopulmonar. Su padre explic\u00f3 que al principio creyeron que hab\u00eda muerto. A pesar de las m\u00faltiples operaciones, el ni\u00f1o se qued\u00f3 ciego y a\u00fan tiene esquirlas en el cuerpo. Necesitamos que su estado mejore antes de extraerlas. Este ni\u00f1o de cinco a\u00f1os parece ahora temeroso, ya no es capaz de ver ni de responder a nadie.      <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-gaza-needs-an-immediate-and-definitive-ceasefire\"><strong>Gaza necesita un alto el fuego inmediato y definitivo<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">La limpieza se hace imposible en las tiendas improvisadas, lo que provoca diarrea aguda e ictericia. Una madre se esforzaba porque sus hijos necesitaran pa\u00f1ales, por lo que recurr\u00eda a la tela y a las bolsas de pl\u00e1stico. Debido a la falta de productos de higiene, las infecciones bacterianas se extendieron por sus cuerpos sin que hubiera pomadas disponibles.  <\/p>\n\n<p class=\"wp-block-paragraph\">En las tiendas de campa\u00f1a derrumbadas, los ni\u00f1os se rascan las lesiones, contagi\u00e1ndose a s\u00ed mismos y a los dem\u00e1s. Las manchas de un ni\u00f1o se extendieron de la cara al cuerpo. Sin los medicamentos disponibles, no podemos tratarle. El imp\u00e9tigo, una infecci\u00f3n bacteriana com\u00fan, puede derivar en insuficiencia renal si no se trata, pero las cremas y pomadas siguen siendo escasas. Los ara\u00f1azos se infectan f\u00e1cilmente debido a la suciedad circundante.    <\/p>\n\n<p class=\"wp-block-paragraph\">Recuerdo a un ni\u00f1o llorando mientras le aplicaba crema en las llagas. Los adultos tambi\u00e9n sufren. Un hombre me mostr\u00f3 dolorosas llagas en los pies, mientras que las manos de una mujer estaban en carne viva y agrietadas. Las cremas que proporcionamos a menudo resultan ineficaces sin una higiene adecuada; las condiciones mejoran temporalmente pero vuelven al d\u00eda siguiente. Las moscas pululan constantemente, y la sarna, los piojos, las infecciones f\u00fangicas, bacterianas y v\u00edricas campan a sus anchas.     <\/p>\n\n<p class=\"wp-block-paragraph\">La dignidad y la autoestima de muchas personas se ven profundamente afectadas. Sentirse sucios y expuestos, sobre todo delante de los dem\u00e1s, les pasa factura. Al principio, trat\u00e1bamos a 10 personas al d\u00eda en la tienda m\u00e9dica, pero ahora atendemos entre 30 y 50 diariamente, trabajando las 24 horas del d\u00eda. A pesar de la abrumadora situaci\u00f3n, nos aferramos a la esperanza de que, con el apoyo adecuado, se pueda hacer frente al impacto de este conflicto.    <\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, nada de esto ser\u00e1 posible sin un alto el fuego inmediato y definitivo, as\u00ed como sin un acceso sin restricciones a la ayuda para los trabajadores humanitarios. Vivir con dignidad no deber\u00eda ser un privilegio. Sin un alto el fuego, la esperanza de un futuro pac\u00edfico seguir\u00e1 erosion\u00e1ndose. El cambio es esencial, o la vida aqu\u00ed ser\u00e1 imposible.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recuerdo a una ni\u00f1a sollozando mientras su madre me mostraba c\u00f3mo manchas rojas y blancas se extend\u00edan desde su cara hasta su pecho. Otra madre levant\u00f3 la ropa de su hijo, revelando erupciones en su cuerpo, con llagas abiertas en sus mu\u00f1ecas por rascarse. Un padre puso a su hija sobre una mesa para mostrarme las lesiones de sus pantorrillas, que desprend\u00edan un olor p\u00fatrido.  <\/p>\n","protected":false},"author":28,"featured_media":98472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[260,874],"tags":[3637,7888,8738,7334,1321,9319],"class_list":["post-98871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conflicto","category-crimen-y-corrupcion-es","tag-asia-russia-es","tag-conflicto-israel-gaza","tag-defendiendo","tag-franja-de-gaza","tag-gaza-es","tag-ninos-en-gaza"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra<\/title>\n<meta name=\"description\" content=\"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra, enfermedades y desplazamientos en medio de la crisis humanitaria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria\" \/>\n<meta property=\"og:description\" content=\"Recuerdo a una ni\u00f1a sollozando mientras su madre me mostraba c\u00f3mo manchas rojas y blancas se extend\u00edan desde su cara hasta su pecho. Otra madre levant\u00f3 la ropa de su hijo, revelando erupciones en su cuerpo, con llagas abiertas en sus mu\u00f1ecas por rascarse. Un padre puso a su hija sobre una mesa para mostrarme las lesiones de sus pantorrillas, que desprend\u00edan un olor p\u00fatrido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Orato\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OratoWorld\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-23T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-24T16:28:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mariela Laksman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:site\" content=\"@oratoworld\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariela Laksman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/\"},\"author\":{\"name\":\"Mariela Laksman\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\"},\"headline\":\"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria\",\"datePublished\":\"2024-10-23T10:00:00+00:00\",\"dateModified\":\"2024-10-24T16:28:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/\"},\"wordCount\":1766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/survivor-2.png\",\"keywords\":[\"Asia &amp; Russia\",\"Conflicto Israel-Gaza\",\"defendiendo\",\"Franja de Gaza\",\"Gaza\",\"ni\u00f1os en Gaza\"],\"articleSection\":[\"Conflicto\",\"Crimen y corrupci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/\",\"name\":\"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/survivor-2.png\",\"datePublished\":\"2024-10-23T10:00:00+00:00\",\"dateModified\":\"2024-10-24T16:28:37+00:00\",\"description\":\"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra, enfermedades y desplazamientos en medio de la crisis humanitaria\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/survivor-2.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/survivor-2.png\",\"width\":1280,\"height\":960,\"caption\":\"Dr. Lubna Al-Azaizeh, uses a stethoscope to examine a baby survivor lying on a table. | Photo courtesy of Dr. Lubna Al-Azaizeh.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/2024\\\/10\\\/23\\\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/orato.world\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"name\":\"Orato\",\"description\":\"True Stories. Real People\",\"publisher\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/orato.world\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#organization\",\"name\":\"Orato World Media Inc.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"contentUrl\":\"https:\\\/\\\/orato.world\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/orato-logo-transparent.png\",\"width\":78,\"height\":73,\"caption\":\"Orato World Media Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OratoWorld\\\/\",\"https:\\\/\\\/x.com\\\/oratoworld\",\"https:\\\/\\\/www.instagram.com\\\/oratoworld\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/42308818\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\",\"ownershipFundingInfo\":\"https:\\\/\\\/orato.world\\\/a-note-from-our-publisher-sam-yehia\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/orato.world\\\/es\\\/#\\\/schema\\\/person\\\/33dd7cf2c69fef26b0c46c8e65c68b90\",\"name\":\"Mariela Laksman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ad516503a11cd5ca435acc9bb6523536?s=96\",\"caption\":\"Mariela Laksman\"},\"description\":\"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \\\"Nuevo Sudaca Border\\\" with the microfiction book \\\"Un Tigre con la Boca Abierta\\\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.\",\"url\":\"https:\\\/\\\/orato.world\\\/es\\\/author\\\/mariela-laksman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra","description":"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra, enfermedades y desplazamientos en medio de la crisis humanitaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/","og_locale":"es_ES","og_type":"article","og_title":"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria","og_description":"Recuerdo a una ni\u00f1a sollozando mientras su madre me mostraba c\u00f3mo manchas rojas y blancas se extend\u00edan desde su cara hasta su pecho. Otra madre levant\u00f3 la ropa de su hijo, revelando erupciones en su cuerpo, con llagas abiertas en sus mu\u00f1ecas por rascarse. Un padre puso a su hija sobre una mesa para mostrarme las lesiones de sus pantorrillas, que desprend\u00edan un olor p\u00fatrido.","og_url":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/","og_site_name":"Orato","article_publisher":"https:\/\/www.facebook.com\/OratoWorld\/","article_published_time":"2024-10-23T10:00:00+00:00","article_modified_time":"2024-10-24T16:28:37+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png","type":"image\/png"}],"author":"Mariela Laksman","twitter_card":"summary_large_image","twitter_creator":"@oratoworld","twitter_site":"@oratoworld","twitter_misc":{"Escrito por":"Mariela Laksman","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#article","isPartOf":{"@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/"},"author":{"name":"Mariela Laksman","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90"},"headline":"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria","datePublished":"2024-10-23T10:00:00+00:00","dateModified":"2024-10-24T16:28:37+00:00","mainEntityOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/"},"wordCount":1766,"commentCount":0,"publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png","keywords":["Asia &amp; Russia","Conflicto Israel-Gaza","defendiendo","Franja de Gaza","Gaza","ni\u00f1os en Gaza"],"articleSection":["Conflicto","Crimen y corrupci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/","url":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/","name":"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra","isPartOf":{"@id":"https:\/\/orato.world\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#primaryimage"},"image":{"@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#primaryimage"},"thumbnailUrl":"https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png","datePublished":"2024-10-23T10:00:00+00:00","dateModified":"2024-10-24T16:28:37+00:00","description":"Una m\u00e9dica pide un alto el fuego inmediato mientras los ni\u00f1os de Gaza sufren la guerra, enfermedades y desplazamientos en medio de la crisis humanitaria","breadcrumb":{"@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#primaryimage","url":"https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png","width":1280,"height":960,"caption":"Dr. Lubna Al-Azaizeh, uses a stethoscope to examine a baby survivor lying on a table. | Photo courtesy of Dr. Lubna Al-Azaizeh."},{"@type":"BreadcrumbList","@id":"https:\/\/orato.world\/es\/2024\/10\/23\/un-medico-de-gaza-pide-un-alto-el-fuego-los-ninos-sufren-enfermedades-y-desplazamientos-en-medio-de-la-crisis-humanitaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/orato.world\/es\/"},{"@type":"ListItem","position":2,"name":"Un m\u00e9dico de Gaza pide un alto el fuego: los ni\u00f1os sufren enfermedades y desplazamientos en medio de la crisis humanitaria"}]},{"@type":"WebSite","@id":"https:\/\/orato.world\/es\/#website","url":"https:\/\/orato.world\/es\/","name":"Orato","description":"True Stories. Real People","publisher":{"@id":"https:\/\/orato.world\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/orato.world\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/orato.world\/es\/#organization","name":"Orato World Media Inc.","url":"https:\/\/orato.world\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/","url":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","contentUrl":"https:\/\/orato.world\/wp-content\/uploads\/2020\/07\/orato-logo-transparent.png","width":78,"height":73,"caption":"Orato World Media Inc."},"image":{"@id":"https:\/\/orato.world\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OratoWorld\/","https:\/\/x.com\/oratoworld","https:\/\/www.instagram.com\/oratoworld","https:\/\/www.linkedin.com\/company\/42308818\/"],"publishingPrinciples":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/","ownershipFundingInfo":"https:\/\/orato.world\/a-note-from-our-publisher-sam-yehia\/"},{"@type":"Person","@id":"https:\/\/orato.world\/es\/#\/schema\/person\/33dd7cf2c69fef26b0c46c8e65c68b90","name":"Mariela Laksman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","url":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad516503a11cd5ca435acc9bb6523536?s=96","caption":"Mariela Laksman"},"description":"Image and Sound Designer, Integral Audiovisual and Journalistic Producer, writer, and teacher. I started working when I was very young; Since 2001, I was a producer for different television programs, documentary films, radio, and generating creative content for different organizations and companies. I won the award: \"Nuevo Sudaca Border\" with the microfiction book \"Un Tigre con la Boca Abierta\", for Eloisa Cartonera Editorial. I am passionate about telling stories and writing.","url":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"}]}},"modified_by":null,"uagb_featured_image_src":{"full":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png",1280,960,false],"thumbnail":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-100x100.png",100,100,true],"medium":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-300x225.png",300,225,true],"medium_large":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-770x578.png",640,480,true],"large":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-1024x768.png",640,480,true],"1536x1536":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png",1280,960,false],"2048x2048":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png",1280,960,false],"gallery-size":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-533x400.png",533,400,true],"lets-review-360-240":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-360x240.png",360,240,true],"gform-image-choice-sm":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png",300,225,false],"gform-image-choice-md":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png",400,300,false],"gform-image-choice-lg":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2.png",600,450,false],"awsm_team":["https:\/\/orato.world\/wp-content\/uploads\/survivor-2-500x500.png",500,500,true]},"uagb_author_info":{"display_name":"Mariela Laksman","author_link":"https:\/\/orato.world\/es\/author\/mariela-laksman\/"},"uagb_comment_info":0,"uagb_excerpt":"Recuerdo a una ni\u00f1a sollozando mientras su madre me mostraba c\u00f3mo manchas rojas y blancas se extend\u00edan desde su cara hasta su pecho. Otra madre levant\u00f3 la ropa de su hijo, revelando erupciones en su cuerpo, con llagas abiertas en sus mu\u00f1ecas por rascarse. Un padre puso a su hija sobre una mesa para mostrarme&hellip;","_links":{"self":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/98871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/comments?post=98871"}],"version-history":[{"count":1,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/98871\/revisions"}],"predecessor-version":[{"id":98872,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/posts\/98871\/revisions\/98872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media\/98472"}],"wp:attachment":[{"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/media?parent=98871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/categories?post=98871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/orato.world\/es\/wp-json\/wp\/v2\/tags?post=98871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}